{"id":19712,"date":"2020-06-10T07:30:01","date_gmt":"2020-06-10T05:30:01","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/"},"modified":"2025-12-15T12:36:30","modified_gmt":"2025-12-15T11:36:30","slug":"dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/","title":{"rendered":"Dachser fa un bilancio intermedio dopo tre mesi di misure contro il Corona"},"content":{"rendered":"<p>Dachser descrive, attraverso l&#8217;esempio della filiale di Memmingen, come le misure contro il Corona influenzino la vita quotidiana. Anche se ci sono state diverse aperture, per il personale di magazzino e gli autisti non \u00e8 cambiato molto. I clienti richiedono a volte una disciplina rigorosa da parte degli autisti.<\/p>\n<p>(Memmingen) Gli autisti di camion sono &#8220;rilevanti per il sistema&#8221; e mantengono le catene di approvvigionamento in movimento in modo affidabile, anche in tempi di crisi. La vita professionale richiede molto agli autisti, ma vivono anche esperienze positive. Abbiamo chiesto a Christian Ludwig, autista e manager della flotta, e a J\u00fcrgen Schneider, responsabile dell&#8217;ingresso e del trasporto locale presso Dachser a Memmingen.<\/p>\n<p>Per fortuna, si sono poi dissolti: i lunghi ingorghi di camion ai confini verso l&#8217;Europa orientale, l&#8217;Austria e l&#8217;Italia. All&#8217;inizio della crisi del Corona, questi non promettevano nulla di buono per le catene di approvvigionamento. Anche se il traffico \u00e8 ripreso, molto \u00e8 cambiato nella vita quotidiana degli autisti professionisti durante la pandemia di Covid-19.<\/p>\n<p>Ad esempio, presso Dachser a Memmingen. Per prima cosa, sono state introdotte misure igieniche aggiuntive nella filiale di Dachser, sono state installate pareti di plexiglass con passaggi al banco e sono stati apposti segni di distanza sul pavimento per proteggere al meglio autisti e personale d&#8217;ufficio. &#8220;In seguito, nella mensa c&#8217;era solo cibo da asporto, e sono stati distribuiti mascherine, spray disinfettante e abbigliamento di ricambio agli autisti&#8221;, riporta Christian Ludwig, autista professionista. Gli incontri abituali nell&#8217;area fumatori avvengono al massimo in due e a distanza.<\/p>\n<p>Anche la consegna delle merci ora avviene in modo diverso. &#8220;Non c&#8217;\u00e8 quasi pi\u00f9 un contatto personale diretto con i clienti aziendali. Quanto siano rigorose le misure preventive varia da caso a caso e dipende molto dal settore specifico&#8221;, racconta Ludwig. Ad esempio, in un&#8217;azienda farmaceutica \u00e8 necessario compilare ogni volta un documento sanitario dettagliato prima della consegna, e viene misurata la febbre. Anche nel settore alimentare, mascherine e disinfezione rigorosa sono obbligatorie. Altrove, invece, la situazione \u00e8 gestita in modo pi\u00f9 rilassato. Ad esempio, molti clienti privati, il cui numero \u00e8 raddoppiato nella filiale di Dachser a Memmingen durante la crisi del Corona.<\/p>\n<h5><strong>Riconoscimento ricevuto<\/strong><\/h5>\n<p>La crisi del Corona \u00e8 quindi sempre presente nella vita quotidiana degli autisti. Mascherine, lavaggio e disinfezione frequente delle mani sono un imperativo. E naturalmente mantenere la distanza. Tuttavia, solo fisicamente. In effetti, Christian Ludwig ha l&#8217;esperienza che nella vita quotidiana ci si avvicina spesso in modo diverso e personale rispetto a prima. Quando, ad esempio, consegna una lavatrice o un&#8217;intera serra, molte persone chiedono della situazione attuale per gli autisti professionisti. A volte c&#8217;\u00e8 persino un piccolo omaggio o una tavoletta di cioccolato come ringraziamento. &#8220;Questo aumenta sicuramente la motivazione. Il riconoscimento che ricevo attualmente non \u00e8 mai stato cos\u00ec alto in tutta la mia carriera professionale&#8221;, afferma Christian Ludwig.<\/p>\n<p>J\u00fcrgen Schneider, responsabile dell&#8217;ingresso e del trasporto locale presso il centro logistico Dachser di Memmingen, pu\u00f2 solo confermare: &#8220;Sono 35 anni che lavoro per Dachser. Il settore della logistica gode di un riconoscimento particolarmente alto in questo periodo difficile. Non si dice pi\u00f9: &#8216;Gli autisti di camion bloccano la strada.&#8217; Ma: &#8216;Ottimo, che riusciate a ritirare e consegnare le merci puntualmente.&#8217; Improvvisamente, il nostro gruppo professionale \u00e8 diventato uno degli eroi della vita quotidiana \u2013 proprio come gli operatori sanitari.&#8221; Solo nella necessit\u00e0 si riconosce quanto siano importanti alcune professioni.<\/p>\n<p>Quando molte cose non sono pi\u00f9 scontate, l&#8217;importanza di un approvvigionamento di base funzionante diventa molto pi\u00f9 consapevole per le persone. Secondo Christian Ludwig, per\u00f2, nessuno degli autisti ha paura nell&#8217;esercitare il lavoro: &#8220;Ci siamo sentiti bene accolti fin dall&#8217;inizio da Dachser. Tutti hanno rispetto per questo virus, ma nessuno di noi ha provato un senso di paura anche grazie alle misure preventive adottate rapidamente.&#8221; Ora percepisce anche dai clienti che con l&#8217;inizio della riapertura della vita normale l&#8217;atmosfera sta migliorando, anche se la preoccupazione per l&#8217;esistenza professionale \u00e8 avvertita ovunque. In particolare nei settori dell&#8217;industria metalmeccanica ed elettrica, della ristorazione, degli hotel, degli eventi e del catering, molte aziende hanno perso l&#8217;80% o addirittura l&#8217;intero fatturato.<\/p>\n<p>&#8220;Il riconoscimento che ricevo attualmente non \u00e8 mai stato cos\u00ec alto in tutta la mia carriera professionale.&#8221; Christian Ludwig, autista e manager della flotta presso il centro logistico Dachser Allg\u00e4u a Memmingen<\/p>\n<p>&#8220;Presso Dachser, a causa delle norme di distanza, attualmente \u00e8 occupato solo ogni secondo posto di lavoro in ufficio&#8221;, afferma Ludwig. Questo potrebbe valere anche per l&#8217;esterno della ristorazione. O negli hotel. &#8220;Dipende cos\u00ec tanto da loro: che si tratti di orticoltori, macellerie o birrifici&#8221;, si preoccupa l&#8217;autista.<\/p>\n<p>Anche presso Dachser a Memmingen, il lockdown ha lasciato il segno. In molti settori economici, l&#8217;attivit\u00e0 \u00e8 ferma o \u00e8 stata drasticamente ridotta. Questo influisce naturalmente anche sul numero di trasporti.<\/p>\n<h5><strong>Affrontare insieme la crisi<\/strong><\/h5>\n<p>&#8220;Tuttavia, Dachser si impegna affinch\u00e9 gli effetti per le aziende di trasporto sotto contratto siano il pi\u00f9 contenuti possibile&#8221;, afferma J\u00fcrgen Schneider. &#8220;Lasciamo i veicoli in rotazione, in modo che le perdite per ogni azienda siano il pi\u00f9 ridotte possibile. Comunichiamo intensamente con i nostri partner di trasporto e vogliamo mostrare loro che fanno parte della famiglia Dachser e che insieme affronteremo questa crisi.&#8221; Non si tratta di essere pi\u00f9 veloci, pi\u00f9 alti, pi\u00f9 lontani, ma di responsabilit\u00e0 integrativa, onest\u00e0 e affidabilit\u00e0. &#8220;Quindi valori per cui Dachser \u00e8 sempre stato conosciuto&#8221;, afferma J\u00fcrgen Schneider.<\/p>\n<p>J\u00fcrgen Schneider spera che il settore della logistica mantenga il suo attuale valore nella societ\u00e0: &#8220;L&#8217;attuale empatia, solidariet\u00e0 e riconoscimento per la nostra professione offrono una base completamente diversa per la collaborazione e la convivenza a tutti i livelli. Questo influisce anche sull&#8217;attrattiva della professione di autista. E qui \u00e8 dove dobbiamo intervenire.&#8221;<\/p>\n<p>Foto: \u00a9 Dachser<\/p>\n<p>Didascalia: <em>Christian Ludwig e J\u00fcrgen Schneider del centro logistico DACHSER Allg\u00e4u a Memmingen<\/em><\/p>\n<p><a href=\"https:\/\/www.dachser.de\" target=\"_blank\" rel=\"noopener noreferrer\">www.dachser.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dachser descrive, attraverso l&#8217;esempio della filiale di Memmingen, come le misure contro il Corona influenzino la vita quotidiana. Anche se ci sono state diverse aperture, per<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1561],"tags":[],"class_list":["post-19712","post","type-post","status-publish","format-standard","hentry","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dachser fa un bilancio intermedio dopo tre mesi di misure contro il Corona - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dachser fa un bilancio intermedio dopo tre mesi di misure contro il Corona - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Dachser descrive, attraverso l&#8217;esempio della filiale di Memmingen, come le misure contro il Corona influenzino la vita quotidiana. Anche se ci sono state diverse aperture, per [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-10T05:30:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:36:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/06\\\/10\\\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/06\\\/10\\\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Dachser fa un bilancio intermedio dopo tre mesi di misure contro il Corona\",\"datePublished\":\"2020-06-10T05:30:01+00:00\",\"dateModified\":\"2025-12-15T11:36:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/06\\\/10\\\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\\\/\"},\"wordCount\":985,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/06\\\/10\\\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/06\\\/10\\\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/06\\\/10\\\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\\\/\",\"name\":\"Dachser fa un bilancio intermedio dopo tre mesi di misure contro il Corona - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2020-06-10T05:30:01+00:00\",\"dateModified\":\"2025-12-15T11:36:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/06\\\/10\\\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/06\\\/10\\\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/06\\\/10\\\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dachser fa un bilancio intermedio dopo tre mesi di misure contro il Corona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dachser fa un bilancio intermedio dopo tre mesi di misure contro il Corona - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/","og_locale":"it_IT","og_type":"article","og_title":"Dachser fa un bilancio intermedio dopo tre mesi di misure contro il Corona - Loginfo24","og_description":"Dachser descrive, attraverso l&#8217;esempio della filiale di Memmingen, come le misure contro il Corona influenzino la vita quotidiana. Anche se ci sono state diverse aperture, per [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-06-10T05:30:01+00:00","article_modified_time":"2025-12-15T11:36:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/"},"author":{"name":"","@id":""},"headline":"Dachser fa un bilancio intermedio dopo tre mesi di misure contro il Corona","datePublished":"2020-06-10T05:30:01+00:00","dateModified":"2025-12-15T11:36:30+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/"},"wordCount":985,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/","url":"https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/","name":"Dachser fa un bilancio intermedio dopo tre mesi di misure contro il Corona - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2020-06-10T05:30:01+00:00","dateModified":"2025-12-15T11:36:30+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2020\/06\/10\/dachser-fa-un-bilancio-intermedio-dopo-tre-mesi-di-misure-contro-il-corona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Dachser fa un bilancio intermedio dopo tre mesi di misure contro il Corona"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/19712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=19712"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/19712\/revisions"}],"predecessor-version":[{"id":35697,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/19712\/revisions\/35697"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=19712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=19712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=19712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}