{"id":18371,"date":"2020-07-07T06:00:24","date_gmt":"2020-07-07T04:00:24","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/"},"modified":"2025-12-15T12:31:01","modified_gmt":"2025-12-15T11:31:01","slug":"podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/","title":{"rendered":"Podcast: Qualcosa con Logistica Episodio 43: &#8220;Volando nel Magazzino&#8221;"},"content":{"rendered":"<h4><strong><br \/>\nEpisodio 43 sul tema &#8220;Volando nel Magazzino&#8221;<\/strong><\/h4>\n<p><strong>con Benjamin Federmann doks. innovation GmbH<br \/>\n<\/strong><\/p>\n<p>(Hamburgo) Il podcast Qualcosa con Logistica \u00e8 tornato. Dopo oltre due mesi di pausa forzata, torna ora settimanalmente.<br \/>\nL&#8217;apertura \u00e8 affidata oggi a Benjamin Federmann di doks. innovation GmbH. In conversazione con Jens &amp; Thomas, offre uno sguardo interessante sulle possibilit\u00e0 di raccolta dati nella logistica tramite droni.<\/p>\n<h5><a href=\"https:\/\/directory.libsyn.com\/shows\/view\/id\/think-ing\" target=\"_blank\" rel=\"noopener noreferrer\">Ascolta il podcast<\/a><\/h5>\n<p><a href=\"https:\/\/Irgendwas-mit-logistik.de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/Irgendwas-mit-logistik.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Episodio 43 sul tema &#8220;Volando nel Magazzino&#8221; con Benjamin Federmann doks. innovation GmbH (Hamburgo) Il podcast Qualcosa con Logistica \u00e8 tornato. Dopo oltre due mesi di<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1560,1561],"tags":[],"class_list":["post-18371","post","type-post","status-publish","format-standard","hentry","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Podcast: Qualcosa con Logistica Episodio 43: &quot;Volando nel Magazzino&quot; - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Podcast: Qualcosa con Logistica Episodio 43: &quot;Volando nel Magazzino&quot; - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Episodio 43 sul tema &#8220;Volando nel Magazzino&#8221; con Benjamin Federmann doks. innovation GmbH (Hamburgo) Il podcast Qualcosa con Logistica \u00e8 tornato. Dopo oltre due mesi di [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-07T04:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:31:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Podcast: Qualcosa con Logistica Episodio 43: &#8220;Volando nel Magazzino&#8221;\",\"datePublished\":\"2020-07-07T04:00:24+00:00\",\"dateModified\":\"2025-12-15T11:31:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\\\/\"},\"wordCount\":73,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"articleSection\":[\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\\\/\",\"name\":\"Podcast: Qualcosa con Logistica Episodio 43: \\\"Volando nel Magazzino\\\" - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"datePublished\":\"2020-07-07T04:00:24+00:00\",\"dateModified\":\"2025-12-15T11:31:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2020\\\/07\\\/07\\\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast: Qualcosa con Logistica Episodio 43: &#8222;Volando nel Magazzino&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Podcast: Qualcosa con Logistica Episodio 43: \"Volando nel Magazzino\" - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/","og_locale":"it_IT","og_type":"article","og_title":"Podcast: Qualcosa con Logistica Episodio 43: \"Volando nel Magazzino\" - Loginfo24","og_description":"Episodio 43 sul tema &#8220;Volando nel Magazzino&#8221; con Benjamin Federmann doks. innovation GmbH (Hamburgo) Il podcast Qualcosa con Logistica \u00e8 tornato. Dopo oltre due mesi di [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-07-07T04:00:24+00:00","article_modified_time":"2025-12-15T11:31:01+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/"},"author":{"name":"","@id":""},"headline":"Podcast: Qualcosa con Logistica Episodio 43: &#8220;Volando nel Magazzino&#8221;","datePublished":"2020-07-07T04:00:24+00:00","dateModified":"2025-12-15T11:31:01+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/"},"wordCount":73,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"articleSection":["Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/","url":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/","name":"Podcast: Qualcosa con Logistica Episodio 43: \"Volando nel Magazzino\" - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"datePublished":"2020-07-07T04:00:24+00:00","dateModified":"2025-12-15T11:31:01+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2020\/07\/07\/podcast-qualcosa-con-logistica-episodio-43-volando-nel-magazzino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Podcast: Qualcosa con Logistica Episodio 43: &#8222;Volando nel Magazzino&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/18371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=18371"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/18371\/revisions"}],"predecessor-version":[{"id":33073,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/18371\/revisions\/33073"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=18371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=18371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=18371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}