{"id":69843,"date":"2025-07-13T19:50:07","date_gmt":"2025-07-13T17:50:07","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/"},"modified":"2025-07-13T19:50:07","modified_gmt":"2025-07-13T17:50:07","slug":"marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/","title":{"rendered":"Marten Bosselman du BPEX sur l&rsquo;introduction d&rsquo;une taxe sur les colis"},"content":{"rendered":"<h5><strong>Marten Bosselmann, pr\u00e9sident de la F\u00e9d\u00e9ration allemande des services de colis et de logistique express (BPEX), s&rsquo;exprime sur la taxe sur les colis pr\u00e9vue. L&rsquo;Union europ\u00e9enne envisage une taxe de 2 euros pour les envois en provenance de pays tiers, comme la Chine, afin de couvrir les co\u00fbts accrus de d\u00e9douanement et de surveillance du march\u00e9, engendr\u00e9s par la croissance du commerce en ligne avec des fournisseurs \u00e0 bas prix tels que Temu et Shein. <span data-huuid=\"7711619831950023061\">La taxe devrait principalement s&rsquo;appliquer aux envois destin\u00e9s aux m\u00e9nages priv\u00e9s, tandis qu&rsquo;une taxe r\u00e9duite de 50 centimes est envisag\u00e9e pour les livraisons aux entrep\u00f4ts.<\/span><\/strong><\/h5>\n<p>(Berlin) Dans le cadre du d\u00e9bat actuel au niveau de l&rsquo;UE sur l&rsquo;introduction d&rsquo;une taxe sur les colis pour les envois en provenance de pays tiers, Marten Bosselmann, pr\u00e9sident de la F\u00e9d\u00e9ration allemande des services de colis et de logistique express (BPEX), d\u00e9clare :<\/p>\n<blockquote>\n<div id=\"attachment_29275\" style=\"width: 240px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-29275\" class=\"wp-image-29275\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BPEX_13.7.25_2-288x300.jpg\" alt=\"\" width=\"230\" height=\"239\" \/><p id=\"caption-attachment-29275\" class=\"wp-caption-text\">Marten Bosselmann<\/p><\/div>\n<p>\u00ab Le d\u00e9bat au Parlement europ\u00e9en sur l&rsquo;introduction d&rsquo;une taxe sur les colis pour les envois en provenance de pays tiers et la proposition de r\u00e9solution montrent que le sujet du commerce international de marchandises est de plus en plus au centre des pr\u00e9occupations politiques. Le secteur des colis se r\u00e9jouit que des solutions soient recherch\u00e9es au niveau europ\u00e9en pour renforcer les contr\u00f4les douaniers et garantir une concurrence \u00e9quitable. En tant que secteur, nous rendons le commerce international possible et sommes un partenaire fiable pour les autorit\u00e9s douani\u00e8res et de s\u00e9curit\u00e9. De nouvelles r\u00e8gles pour la quantit\u00e9 croissante d&rsquo;envois en provenance de pays tiers ne doivent pas compromettre cela.<\/p>\n<p>&nbsp;<\/p>\n<p>Les cha\u00eenes d&rsquo;approvisionnement efficaces et r\u00e9silientes des services de colis garantissent que le commerce ext\u00e9rieur et int\u00e9rieur europ\u00e9en en b\u00e9n\u00e9ficie. L&rsquo;objectif des mesures de l&rsquo;UE et de la r\u00e9forme douani\u00e8re doit \u00eatre de s&rsquo;attaquer de mani\u00e8re cibl\u00e9e \u00e0 des probl\u00e8mes concrets tels que la contournement des douanes et non de cr\u00e9er de nouvelles barri\u00e8res commerciales qui toucheraient en particulier les petits commer\u00e7ants ainsi que les consommateurs. Une taxe forfaitaire sur les colis ne doit par exemple pas entra\u00eener des charges bureaucratiques et fiscales suppl\u00e9mentaires pour les entreprises de logistique, ni les contraindre \u00e0 assumer des t\u00e2ches qui rel\u00e8vent \u00e0 l&rsquo;origine des autorit\u00e9s publiques.<\/p>\n<p>&nbsp;<\/p>\n<p>Il est clair pour nous : il doit y avoir une r\u00e9glementation uniforme pour tous les \u00c9tats membres. Les initiatives nationales isol\u00e9es mettent en p\u00e9ril le march\u00e9 int\u00e9rieur europ\u00e9en et entra\u00eenent des distorsions de concurrence. Les mesures \u00e9ventuelles doivent \u00eatre proportionn\u00e9es. Pour cela, des processus clairs et transparents, une infrastructure num\u00e9rique fonctionnelle et des d\u00e9lais de transition appropri\u00e9s sont n\u00e9cessaires.<\/p>\n<p>&nbsp;<\/p>\n<p>Les mesures discut\u00e9es, telles que la responsabilit\u00e9 des plateformes commerciales pour les biens qui ne respectent pas les normes de l&rsquo;UE, constituent une \u00e9tape n\u00e9cessaire pour am\u00e9liorer le march\u00e9 int\u00e9rieur. Les barri\u00e8res commerciales produisent l&rsquo;effet inverse. \u00bb<\/p><\/blockquote>\n<p>Photo de titre : \u00a9 Loginfo24<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marten Bosselmann, pr\u00e9sident de la F\u00e9d\u00e9ration allemande des services de colis et de logistique express (BPEX), s&rsquo;exprime sur la taxe sur les colis pr\u00e9vue. L&rsquo;Union europ\u00e9enne<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":4756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-69843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marten Bosselman du BPEX sur l&#039;introduction d&#039;une taxe sur les colis - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marten Bosselman du BPEX sur l&#039;introduction d&#039;une taxe sur les colis - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Marten Bosselmann, pr\u00e9sident de la F\u00e9d\u00e9ration allemande des services de colis et de logistique express (BPEX), s&rsquo;exprime sur la taxe sur les colis pr\u00e9vue. L&rsquo;Union europ\u00e9enne [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-13T17:50:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BPEX_13.7.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1221\" \/>\n\t<meta property=\"og:image:height\" content=\"927\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Marten Bosselman du BPEX sur l&rsquo;introduction d&rsquo;une taxe sur les colis\",\"datePublished\":\"2025-07-13T17:50:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/\"},\"wordCount\":556,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BPEX_13.7.25.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/\",\"name\":\"Marten Bosselman du BPEX sur l'introduction d'une taxe sur les colis - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BPEX_13.7.25.jpg\",\"datePublished\":\"2025-07-13T17:50:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BPEX_13.7.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BPEX_13.7.25.jpg\",\"width\":1221,\"height\":927},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/07\\\/13\\\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marten Bosselman du BPEX sur l&rsquo;introduction d&rsquo;une taxe sur les colis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marten Bosselman du BPEX sur l'introduction d'une taxe sur les colis - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/","og_locale":"fr_FR","og_type":"article","og_title":"Marten Bosselman du BPEX sur l'introduction d'une taxe sur les colis - Loginfo24.","og_description":"Marten Bosselmann, pr\u00e9sident de la F\u00e9d\u00e9ration allemande des services de colis et de logistique express (BPEX), s&rsquo;exprime sur la taxe sur les colis pr\u00e9vue. L&rsquo;Union europ\u00e9enne [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-07-13T17:50:07+00:00","og_image":[{"width":1221,"height":927,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BPEX_13.7.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/"},"author":{"name":"","@id":""},"headline":"Marten Bosselman du BPEX sur l&rsquo;introduction d&rsquo;une taxe sur les colis","datePublished":"2025-07-13T17:50:07+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/"},"wordCount":556,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BPEX_13.7.25.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/","url":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/","name":"Marten Bosselman du BPEX sur l'introduction d'une taxe sur les colis - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BPEX_13.7.25.jpg","datePublished":"2025-07-13T17:50:07+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BPEX_13.7.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BPEX_13.7.25.jpg","width":1221,"height":927},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2025\/07\/13\/marten-bosselman-du-bpex-sur-lintroduction-dune-taxe-sur-les-colis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Marten Bosselman du BPEX sur l&rsquo;introduction d&rsquo;une taxe sur les colis"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/69843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=69843"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/69843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/4756"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=69843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=69843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=69843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}