{"id":69380,"date":"2025-06-06T09:27:32","date_gmt":"2025-06-06T07:27:32","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/"},"modified":"2025-06-06T09:27:32","modified_gmt":"2025-06-06T07:27:32","slug":"forum-dvf-au-transport-logistic-sur-le-transport-combine","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/","title":{"rendered":"Forum DVF au transport logistic sur le transport combin\u00e9"},"content":{"rendered":"<h5>Selon le minist\u00e8re f\u00e9d\u00e9ral des Transports, le transport combin\u00e9 (TC) devrait presque doubler d&rsquo;ici 2040. Cela fait du TC un moteur de croissance dans le transport de marchandises. Avec la trimodalit\u00e9, la num\u00e9risation et des technologies de transbordement innovantes, le TC offre des solutions durables pour un volume de trafic en augmentation. Mais comment peut-on concr\u00e9tiser le chemin vers le \u00ab\u00a0Next Level\u00a0\u00bb et quelles d\u00e9cisions politiques doivent \u00eatre prises pour cr\u00e9er le cadre d&rsquo;action n\u00e9cessaire pour les entreprises ?<\/h5>\n<p>Lors du forum DVF \u00e0 la foire transport logistic, des experts du monde \u00e9conomique et politique ont expliqu\u00e9 leurs exigences et leurs approches de solutions.<\/p>\n<p>Dr. J\u00f6rg Mosolf, PDG de Mosolf SE, membre du pr\u00e9sidium DVF, a d&rsquo;abord \u00e9voqu\u00e9 quatre mesures essentielles n\u00e9cessaires \u00e0 l&rsquo;\u00e9volution du TC : \u00ab\u00a0Le TC est aujourd&rsquo;hui plus qu&rsquo;un simple transbordement et l&rsquo;organisation des transports avant et apr\u00e8s. Les technologies et la volont\u00e9 des entreprises sont pr\u00e9sentes. Mais il manque des investissements et de la flexibilit\u00e9 de la part de la politique. C&rsquo;est pourquoi nous avons besoin, premi\u00e8rement, de plus de redondance et de r\u00e9silience dans l&rsquo;infrastructure ferroviaire. Deuxi\u00e8mement, des r\u00e9seaux de terminaux doivent \u00eatre form\u00e9s et soutenus \u00e0 l&rsquo;\u00e9chelle europ\u00e9enne et au-del\u00e0 des fronti\u00e8res. Troisi\u00e8mement, il est important d&rsquo;utiliser le fonds sp\u00e9cial pour l&rsquo;infrastructure pour des technologies de transbordement innovantes et des concepts de r\u00e9seau. Et quatri\u00e8mement, il doit y avoir une automatisation du transport ferroviaire de marchandises et une approbation rapide par l&rsquo;Office f\u00e9d\u00e9ral des chemins de fer et l&rsquo;Agence ferroviaire europ\u00e9enne. La mise en r\u00e9seau commence dans la t\u00eate !\u00a0\u00bb<\/p>\n<p>Reinhard Oswald, directeur des ventes chez Ernst Frankenbach GmbH Spedition, a \u00e9galement plaid\u00e9 pour une extension du soutien au TC : \u00ab\u00a0La pr\u00e9sence d&rsquo;une infrastructure intacte est l&rsquo;un des crit\u00e8res d\u00e9cisifs dans la concurrence europ\u00e9enne. Il serait souhaitable de soutenir politiquement les investissements n\u00e9cessaires, par exemple dans l&rsquo;infrastructure TC d\u00e9j\u00e0 existante.\u00a0\u00bb<\/p>\n<p>Florian Dirr, du minist\u00e8re f\u00e9d\u00e9ral des Transports, d\u00e9partement G 14 \u00ab\u00a0Transport de marchandises et logistique\u00a0\u00bb, a \u00e9valu\u00e9 le soutien actuel du gouvernement f\u00e9d\u00e9ral comme un soutien extr\u00eamement efficace pour le transport combin\u00e9. \u00ab\u00a0Le remplacement des installations de transbordement TC existantes, vieillissantes, ainsi que les mesures de num\u00e9risation et d&rsquo;automatisation dans les installations de transbordement TC sont maintenant cibl\u00e9s pour \u00eatre soutenus.\u00a0\u00bb De plus, les investissements pr\u00e9vus dans le contrat de coalition pour l&rsquo;infrastructure de transport, ainsi que l&rsquo;acc\u00e9l\u00e9ration de la planification et de l&rsquo;approbation des projets d&rsquo;infrastructure, contribueront de mani\u00e8re significative \u00e0 \u00e9liminer les obstacles existants \u00e0 l&rsquo;expansion du TC.<\/p>\n<p>Pour exploiter davantage de potentiels dans le TC, selon Oswald, une num\u00e9risation plus forte est essentielle. \u00ab\u00a0Fondamentalement, le secteur devra encore franchir plusieurs \u00e9tapes pour, par exemple, r\u00e9duire les obstacles bureaucratiques. De plus, la num\u00e9risation est n\u00e9cessaire pour offrir des solutions individuelles et sur mesure.\u00a0\u00bb Cependant, pour exploiter davantage de potentiels dans le TC et \u00eatre pr\u00e9par\u00e9 aux phases de basses eaux, il ne peut finalement s&rsquo;agir que d&rsquo;une collaboration entre tous les modes de transport ainsi que de l&rsquo;utilisation des avantages respectifs. Et selon Oswald, l&rsquo;acquisition de personnel suppl\u00e9mentaire ayant des comp\u00e9tences en TC est un autre facteur d\u00e9cisif pour le secteur.<\/p>\n<p>\u00ab\u00a0Le TC jouera \u00e9galement \u00e0 l&rsquo;avenir un r\u00f4le central dans la logistique europ\u00e9enne et, en association avec des camions \u00e9lectrifi\u00e9s pour le transport avant et apr\u00e8s, fournira des solutions efficaces et neutres en CO<sub>2<\/sub> de porte \u00e0 porte pour le commerce et l&rsquo;industrie\u00a0\u00bb, a d\u00e9clar\u00e9 Nicole Tews, partenaire chez Oliver Wyman, sur le d\u00e9veloppement futur du TC. Pour cela, il faut \u00ab\u00a0une collaboration dans le secteur et un investissement dans l&rsquo;orientation client et l&rsquo;accessibilit\u00e9, dans la num\u00e9risation et l&rsquo;int\u00e9gration de bout en bout, ainsi qu&rsquo;une op\u00e9ration efficace et flexible.\u00a0\u00bb L&rsquo;\u00e9tude \u00ab\u00a0winning intermodal\u00a0\u00bb a examin\u00e9 cela plus en d\u00e9tail.<\/p>\n<p>\u00ab\u00a0Nous sommes pr\u00eats pour la r\u00e9novation\u00a0\u00bb, a d\u00e9clar\u00e9 Armin Riedl, directeur g\u00e9n\u00e9ral de Kombiverkehr GmbH &amp; Co KG, lorsqu&rsquo;il a \u00e9t\u00e9 question de l&rsquo;infrastructure ferroviaire. Cependant, il s&rsquo;inqui\u00e8te de la m\u00e9thode des fermetures compl\u00e8tes dans le r\u00e9seau ferroviaire : \u00ab\u00a0Personne n&rsquo;aurait l&rsquo;id\u00e9e de fermer compl\u00e8tement les autoroutes les plus importantes pendant six mois ou plus.\u00a0\u00bb Avec les fermetures de plusieurs mois des corridors ferroviaires, on risque de voir de nombreuses entreprises ferroviaires priv\u00e9es manquer d&rsquo;air. \u00ab\u00a0Alors, peut-\u00eatre que nous aurons \u00e0 la fin un r\u00e9seau ferroviaire plus performant, mais plus de concurrence.\u00a0\u00bb De plus, Riedl a appel\u00e9 \u00e0 une r\u00e9forme des prix des sillons. \u00ab\u00a0Et il faut des sillons privil\u00e9gi\u00e9s pour les trains TC - l\u00e0 o\u00f9 c&rsquo;est n\u00e9cessaire, m\u00eame au d\u00e9triment du transport de passagers. Il existe des solutions intelligentes si InfraGO investissait un peu plus dans les voies de d\u00e9passement urgentes\u00a0\u00bb, a poursuivi Riedl.<\/p>\n<h5>Combinaison du transport de passagers et de marchandises sur rail<\/h5>\n<p>Amazon utilise \u00e9galement le transport ferroviaire de passagers pour le transport de marchandises, a d\u00e9clar\u00e9 Spyros Kalpogiannis, directeur senior intermodal chez Amazon Transportation Services. Il a cit\u00e9 en exemple le transport \u00e0 grande vitesse entre Lyon et Paris, o\u00f9 cette ann\u00e9e, plus d&rsquo;un demi-million de colis ont \u00e9t\u00e9 transport\u00e9s par train \u00e0 grande vitesse \u00e0 320 km\/h. \u00ab\u00a0Une telle int\u00e9gration du transport de passagers et de marchandises cr\u00e9erait \u00e9galement de nouvelles possibilit\u00e9s pour des solutions logistiques plus durables en Allemagne. Amazon s&rsquo;est fix\u00e9 pour objectif d&rsquo;atteindre la neutralit\u00e9 carbone dans tous ses secteurs d&rsquo;activit\u00e9 d&rsquo;ici 2040, le transport intermodal jouant un r\u00f4le central. Au cours des derni\u00e8res ann\u00e9es, nous avons donc consid\u00e9rablement \u00e9largi notre r\u00e9seau de transport europ\u00e9en avec plus de 500 itin\u00e9raires intermodaux et utilisons de plus en plus les liaisons maritimes et ferroviaires pour le transport de colis et de marchandises.\u00a0\u00bb<\/p>\n<p>Photo : \u00a9 DVF \/ <em><strong>L\u00e9gende de l&rsquo;image<\/strong> : (de g. \u00e0 d.) : Constantin Lehnert, politique europ\u00e9enne, technologie ferroviaire, transport ferroviaire, DVF ; Dr. Florian Eck, directeur g\u00e9n\u00e9ral du DVF ; Karsten Keil, membre du conseil d&rsquo;administration, vice-pr\u00e9sident du groupe IT &amp; num\u00e9risation, Schnellecke Group AG &amp; Co. KG ; Mod\u00e9ration : Matthias Rathmann, Rathmann Communications ; Thomas Zysk, co-fondateur \/ COO, SWAP INNOVATIONS GmbH ; Daniela Paitzies, responsable de la num\u00e9risation, transport de marchandises et logistique, infrastructure, DVF ;\u200b\u200b\u200b\u200b\u200b Tobias Jerschke, membre du pr\u00e9sidium du Deutsches Verkehrsforum, pr\u00e9sident de la direction, K\u00fchne + Nagel (AG &amp; Co.) KG ; Steffen Bauer, directeur g\u00e9n\u00e9ral, HGK Shipping GmbH ; Ulrich Wrage, pr\u00e9sident du conseil d&rsquo;administration de Dakosy AG ; Dr. Heike van Hoorn, directrice g\u00e9n\u00e9rale du DVF.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon le minist\u00e8re f\u00e9d\u00e9ral des Transports, le transport combin\u00e9 (TC) devrait presque doubler d&rsquo;ici 2040. Cela fait du TC un moteur de croissance dans le transport<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":4933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-69380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Forum DVF au transport logistic sur le transport combin\u00e9 - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Forum DVF au transport logistic sur le transport combin\u00e9 - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Selon le minist\u00e8re f\u00e9d\u00e9ral des Transports, le transport combin\u00e9 (TC) devrait presque doubler d&rsquo;ici 2040. Cela fait du TC un moteur de croissance dans le transport [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-06T07:27:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_6.6.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1244\" \/>\n\t<meta property=\"og:image:height\" content=\"823\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Forum DVF au transport logistic sur le transport combin\u00e9\",\"datePublished\":\"2025-06-06T07:27:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/\"},\"wordCount\":1170,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DVF_6.6.25.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/\",\"name\":\"Forum DVF au transport logistic sur le transport combin\u00e9 - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DVF_6.6.25.jpg\",\"datePublished\":\"2025-06-06T07:27:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DVF_6.6.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DVF_6.6.25.jpg\",\"width\":1244,\"height\":823},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/06\\\/06\\\/forum-dvf-au-transport-logistic-sur-le-transport-combine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Forum DVF au transport logistic sur le transport combin\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Forum DVF au transport logistic sur le transport combin\u00e9 - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/","og_locale":"fr_FR","og_type":"article","og_title":"Forum DVF au transport logistic sur le transport combin\u00e9 - Loginfo24.","og_description":"Selon le minist\u00e8re f\u00e9d\u00e9ral des Transports, le transport combin\u00e9 (TC) devrait presque doubler d&rsquo;ici 2040. Cela fait du TC un moteur de croissance dans le transport [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-06-06T07:27:32+00:00","og_image":[{"width":1244,"height":823,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_6.6.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/"},"author":{"name":"","@id":""},"headline":"Forum DVF au transport logistic sur le transport combin\u00e9","datePublished":"2025-06-06T07:27:32+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/"},"wordCount":1170,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_6.6.25.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/","url":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/","name":"Forum DVF au transport logistic sur le transport combin\u00e9 - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_6.6.25.jpg","datePublished":"2025-06-06T07:27:32+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_6.6.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_6.6.25.jpg","width":1244,"height":823},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2025\/06\/06\/forum-dvf-au-transport-logistic-sur-le-transport-combine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Forum DVF au transport logistic sur le transport combin\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/69380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=69380"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/69380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/4933"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=69380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=69380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=69380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}