{"id":68989,"date":"2025-05-01T09:43:30","date_gmt":"2025-05-01T07:43:30","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/"},"modified":"2025-05-01T09:43:30","modified_gmt":"2025-05-01T07:43:30","slug":"le-special-interactif-sur-la-transport-logistic-est-en-ligne","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/","title":{"rendered":"Le sp\u00e9cial interactif sur la transport logistic est en ligne"},"content":{"rendered":"<h5><strong>Le nouveau <a href=\"https:\/\/online.fliphtml5.com\/bwrte\/mohr\/\" target=\"_blank\" rel=\"noopener\"><em>sp\u00e9cial \u00ab transport logistic + air cargo Europe 2025 \u00bb<\/em><\/a> est d\u00e9sormais en ligne. Cette \u00e9dition sp\u00e9ciale conjointe de <em>ITJ<\/em> <em>International Transport Journal<\/em> et de Loginfo24, qui appartiennent toutes deux au groupe Logismedia, para\u00eet environ un mois avant le d\u00e9but du salon mondial de la logistique \u00e0 Munich \u2013 et montre de mani\u00e8re concise quels sujets pr\u00e9occupent actuellement la logistique. Tous les liens et annonces peuvent \u00eatre ouverts directement \u00e0 partir de l&rsquo;E-Paper.<\/strong><\/h5>\n<p>(Basel\/Munich) De nombreux sujets pr\u00e9occupent actuellement le secteur de la logistique. On a d\u00e9j\u00e0 beaucoup \u00e9crit sur la durabilit\u00e9 et le manque de main-d&rsquo;\u0153uvre qualifi\u00e9e, qui est actuellement moins aigu qu&rsquo;auparavant, mais cela ressort dans la conversation avec Dr. Robert Sch\u00f6nberger. L&rsquo;intelligence artificielle est \u00e9galement souvent abord\u00e9e, mais elle n&rsquo;en est encore qu&rsquo;\u00e0 ses d\u00e9buts. L&rsquo;impression 3D ou l&rsquo;algorithme quantique ne sont pas encore au premier plan, mais gagnent rapidement en importance.<\/p>\n<h5><strong>R\u00e9sum\u00e9 du contenu<\/strong><\/h5>\n<p>Dr. Robert Sch\u00f6nberger, directeur de la transport logistic et air cargo Europe, parle dans une interview du r\u00f4le du salon en tant que moteur du secteur, des m\u00e9gatendances telles que l&rsquo;IA, des solutions de transport durables et du nearshoring \u2013 et d&rsquo;un nouveau format de salon avec douze halls et un espace ext\u00e9rieur complet.<\/p>\n<p>Il est \u00e9galement question des opportunit\u00e9s et des d\u00e9fis li\u00e9s \u00e0 l&rsquo;impression 3D \u2013 avec un <strong><a href=\"https:\/\/transportlogistic.de\/de\/event-programm\/konferenzprogramm\/vortrag\/3d-druck-und-die-auswirkungen-auf-den-weltweiten-transport-7520\/\" target=\"_blank\" rel=\"noopener\">forum sp\u00e9cialis\u00e9 le 4 juin par Logismedia<\/a><\/strong> sur ce sujet \u2013 ainsi qu&rsquo;un exemple pratique simple de l&rsquo;utilisation de l&rsquo;intelligence artificielle dans la logistique des marchandises dangereuses de DHN.digital avec le prestataire logistique Cretschmar.<\/p>\n<h5>Changement de g\u00e9n\u00e9ration et cha\u00eenes d&rsquo;approvisionnement int\u00e9gr\u00e9es<\/h5>\n<p>Saco Shipping offre un aper\u00e7u de la r\u00e9orientation et du changement de g\u00e9n\u00e9ration \u00e0 la t\u00eate de l&rsquo;entreprise.<br \/>\nBlue Yonder pr\u00e9sente ses derni\u00e8res solutions pour des cha\u00eenes d&rsquo;approvisionnement int\u00e9gr\u00e9es et une gestion du transport durable et cite trois raisons pour lesquelles une visite au salon de cette entreprise num\u00e9rique en vaut la peine.<\/p>\n<p>L&rsquo;European Institute for Pharma Logistics Services (EIPL) pr\u00e9sente des services GDP complets, sp\u00e9cialement pour les logisticiens pharmaceutiques de taille interm\u00e9diaire. Les d\u00e9fis actuels tels que la cybers\u00e9curit\u00e9 ou le r\u00f4le de l&rsquo;informatique quantique dans la logistique sont \u00e9galement abord\u00e9s \u2013 notamment avec des contributions de Maurice Teltscher (Inventry) et Rainer Stawarz (K&amp;S Informatik).<\/p>\n<p>Le Club of Logistics s&rsquo;implique avec deux panels de haut niveau dans le programme de la conf\u00e9rence et discute de l&rsquo;avenir des PME logistiques europ\u00e9ennes et des cons\u00e9quences des tensions g\u00e9opolitiques.<\/p>\n<h5>Au salon \u00e9galement en version imprim\u00e9e<\/h5>\n<p>Pendant le salon, le sp\u00e9cial (\u00e9galement en anglais), ainsi que d&rsquo;autres magazines, pourra \u00eatre r\u00e9cup\u00e9r\u00e9 au stand du groupe Logismedia AG dans le hall 3\/stand 300 en version imprim\u00e9e.<\/p>\n<h3><a href=\"https:\/\/online.fliphtml5.com\/bwrte\/mohr\/\" target=\"_blank\" rel=\"noopener\">Acc\u00e9dez \u00e0 l&rsquo;E-Paper ici<\/a><\/h3>\n<p>Photo : \u00a9 Loginfo24<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nouveau sp\u00e9cial \u00ab transport logistic + air cargo Europe 2025 \u00bb est d\u00e9sormais en ligne. Cette \u00e9dition sp\u00e9ciale conjointe de ITJ International Transport Journal et<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-68989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le sp\u00e9cial interactif sur la transport logistic est en ligne - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le sp\u00e9cial interactif sur la transport logistic est en ligne - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Le nouveau sp\u00e9cial \u00ab transport logistic + air cargo Europe 2025 \u00bb est d\u00e9sormais en ligne. Cette \u00e9dition sp\u00e9ciale conjointe de ITJ International Transport Journal et [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-01T07:43:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Special_30.4.25-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1177\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Le sp\u00e9cial interactif sur la transport logistic est en ligne\",\"datePublished\":\"2025-05-01T07:43:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/\"},\"wordCount\":515,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Special_30.4.25-1.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/\",\"name\":\"Le sp\u00e9cial interactif sur la transport logistic est en ligne - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Special_30.4.25-1.jpg\",\"datePublished\":\"2025-05-01T07:43:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Special_30.4.25-1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Special_30.4.25-1.jpg\",\"width\":1177,\"height\":687},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/05\\\/01\\\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le sp\u00e9cial interactif sur la transport logistic est en ligne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le sp\u00e9cial interactif sur la transport logistic est en ligne - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/","og_locale":"fr_FR","og_type":"article","og_title":"Le sp\u00e9cial interactif sur la transport logistic est en ligne - Loginfo24.","og_description":"Le nouveau sp\u00e9cial \u00ab transport logistic + air cargo Europe 2025 \u00bb est d\u00e9sormais en ligne. Cette \u00e9dition sp\u00e9ciale conjointe de ITJ International Transport Journal et [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-05-01T07:43:30+00:00","og_image":[{"width":1177,"height":687,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Special_30.4.25-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/"},"author":{"name":"","@id":""},"headline":"Le sp\u00e9cial interactif sur la transport logistic est en ligne","datePublished":"2025-05-01T07:43:30+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/"},"wordCount":515,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Special_30.4.25-1.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/","url":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/","name":"Le sp\u00e9cial interactif sur la transport logistic est en ligne - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Special_30.4.25-1.jpg","datePublished":"2025-05-01T07:43:30+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Special_30.4.25-1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Special_30.4.25-1.jpg","width":1177,"height":687},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2025\/05\/01\/le-special-interactif-sur-la-transport-logistic-est-en-ligne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le sp\u00e9cial interactif sur la transport logistic est en ligne"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/68989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=68989"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/68989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/5069"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=68989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=68989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=68989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}