{"id":68333,"date":"2025-03-05T21:23:36","date_gmt":"2025-03-05T20:23:36","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/"},"modified":"2025-03-05T21:23:36","modified_gmt":"2025-03-05T20:23:36","slug":"robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/","title":{"rendered":"Robert Brohl prend la responsabilit\u00e9 globale de la logistique chez Galaxus"},"content":{"rendered":"<h5>Le d\u00e9taillant en ligne Galaxus regroupe les domaines de la gestion de la cha\u00eene d&rsquo;approvisionnement et de la logistique sous la direction de Robert Brohl. Il est d\u00e9sormais responsable d&rsquo;environ 1 400 employ\u00e9s dans trois sites en Suisse et un en Allemagne. Environ 1 000 employ\u00e9s suppl\u00e9mentaires devraient rejoindre Neuch\u00e2tel sur le Rhin d&rsquo;ici 2030.<\/h5>\n<p>Brohl travaille chez Galaxus \u00e0 Krefeld depuis mi-2020. Il a d&rsquo;abord commenc\u00e9 en tant que responsable de site, puis en 2022, il est devenu responsable de la gestion de la cha\u00eene d&rsquo;approvisionnement pour Digitec Galaxus en Suisse et pour Galaxus Allemagne avec environ 30 experts. D\u00e9sormais, les responsables logistiques avec leurs \u00e9quipes \u00e0 Krefeld ainsi qu&rsquo;\u00e0 Wohlen en Suisse, dans les entrep\u00f4ts de Dintikon (CH), Roggwil (CH) et Oftringen (CH) rel\u00e8veront du sp\u00e9cialiste en logistique titulaire d&rsquo;un doctorat. Brohl est donc responsable d&rsquo;environ 1 400 employ\u00e9s.<\/p>\n<p>Les \u00e9quipes logistiques du site de Neuch\u00e2tel sur le Rhin, qui est actuellement en construction, lui rendront \u00e9galement compte \u00e0 l&rsquo;avenir. \u00c0 Neuch\u00e2tel, environ 1 000 nouveaux employ\u00e9s devraient \u00eatre recrut\u00e9s d&rsquo;ici 2030, dont une grande partie sera compos\u00e9e de logisticiens ainsi que d&rsquo;experts en informatique, en gestion des processus, en technique et plus encore, \u00e9galement sous la direction de Robert Brohl.<\/p>\n<p>Michael Stolle, directeur g\u00e9n\u00e9ral de Galaxus Allemagne et COO de Digitec Galaxus : \u00ab Robert Brohl allie une expertise logistique pratique, une exp\u00e9rience av\u00e9r\u00e9e dans la gestion de grands projets de croissance et un style de leadership inclusif et valorisant, en accord avec notre culture Galaxus. Je me r\u00e9jouis beaucoup de l&rsquo;\u00e9volution de notre organisation logistique sous sa direction. \u00bb<\/p>\n<h5>D\u00e9veloppement positif continu<\/h5>\n<p>Tant en Suisse qu&rsquo;en Allemagne, Galaxus continue de se d\u00e9velopper positivement. En 2024, le chiffre d&rsquo;affaires de Galaxus Deutschland GmbH a augment\u00e9 de 27 % pour atteindre 362 millions d&rsquo;euros. La soci\u00e9t\u00e9 m\u00e8re Digitec Galaxus a r\u00e9alis\u00e9 un chiffre d&rsquo;affaires total de 3,4 milliards d&rsquo;euros en 2024 (augmentation de 18 %).<\/p>\n<p>Photo : \u00a9 Galaxus<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9taillant en ligne Galaxus regroupe les domaines de la gestion de la cha\u00eene d&rsquo;approvisionnement et de la logistique sous la direction de Robert Brohl. Il<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-68333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Robert Brohl prend la responsabilit\u00e9 globale de la logistique chez Galaxus - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Robert Brohl prend la responsabilit\u00e9 globale de la logistique chez Galaxus - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Le d\u00e9taillant en ligne Galaxus regroupe les domaines de la gestion de la cha\u00eene d&rsquo;approvisionnement et de la logistique sous la direction de Robert Brohl. Il [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-05T20:23:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Galaxus_5.3.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1208\" \/>\n\t<meta property=\"og:image:height\" content=\"787\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Robert Brohl prend la responsabilit\u00e9 globale de la logistique chez Galaxus\",\"datePublished\":\"2025-03-05T20:23:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/\"},\"wordCount\":348,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Galaxus_5.3.25.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/\",\"name\":\"Robert Brohl prend la responsabilit\u00e9 globale de la logistique chez Galaxus - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Galaxus_5.3.25.jpg\",\"datePublished\":\"2025-03-05T20:23:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Galaxus_5.3.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Galaxus_5.3.25.jpg\",\"width\":1208,\"height\":787},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2025\\\/03\\\/05\\\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Robert Brohl prend la responsabilit\u00e9 globale de la logistique chez Galaxus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Robert Brohl prend la responsabilit\u00e9 globale de la logistique chez Galaxus - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/","og_locale":"fr_FR","og_type":"article","og_title":"Robert Brohl prend la responsabilit\u00e9 globale de la logistique chez Galaxus - Loginfo24.","og_description":"Le d\u00e9taillant en ligne Galaxus regroupe les domaines de la gestion de la cha\u00eene d&rsquo;approvisionnement et de la logistique sous la direction de Robert Brohl. Il [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-03-05T20:23:36+00:00","og_image":[{"width":1208,"height":787,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Galaxus_5.3.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/"},"author":{"name":"","@id":""},"headline":"Robert Brohl prend la responsabilit\u00e9 globale de la logistique chez Galaxus","datePublished":"2025-03-05T20:23:36+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/"},"wordCount":348,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Galaxus_5.3.25.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/","url":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/","name":"Robert Brohl prend la responsabilit\u00e9 globale de la logistique chez Galaxus - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Galaxus_5.3.25.jpg","datePublished":"2025-03-05T20:23:36+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Galaxus_5.3.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Galaxus_5.3.25.jpg","width":1208,"height":787},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2025\/03\/05\/robert-brohl-prend-la-responsabilite-globale-de-la-logistique-chez-galaxus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Robert Brohl prend la responsabilit\u00e9 globale de la logistique chez Galaxus"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/68333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=68333"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/68333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/5328"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=68333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=68333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=68333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}