{"id":67480,"date":"2024-12-03T20:04:17","date_gmt":"2024-12-03T19:04:17","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/"},"modified":"2024-12-03T20:04:17","modified_gmt":"2024-12-03T19:04:17","slug":"dhl-express-avec-enquete-et-ebook-sur-la-durabilite","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/","title":{"rendered":"DHL Express avec enqu\u00eate et eBook sur la durabilit\u00e9"},"content":{"rendered":"<h5>La durabilit\u00e9 est devenue une n\u00e9cessit\u00e9 strat\u00e9gique pour les petites et moyennes entreprises (PME), influen\u00e7ant consid\u00e9rablement leur valeur \u00e0 long terme et leur cr\u00e9dibilit\u00e9, comme le montre une enqu\u00eate internationale r\u00e9cente de DHL Express. Pour mieux comprendre l&rsquo;importance croissante de la durabilit\u00e9 dans la cha\u00eene d&rsquo;approvisionnement, DHL Express a men\u00e9 une enqu\u00eate d\u00e9taill\u00e9e aupr\u00e8s de 5 000 d\u00e9cideurs de PME dans 11 march\u00e9s : le Royaume-Uni, la France, l&rsquo;Allemagne, les Pays-Bas, l&rsquo;Australie, la Chine, Singapour, le Japon, le Mexique, le Canada et l&rsquo;Inde.<\/h5>\n<p>(Bonn) Les entreprises ayant particip\u00e9 \u00e0 l&rsquo;\u00e9tude proviennent de neuf secteurs : commerce de d\u00e9tail, biens de consommation, services professionnels, ing\u00e9nierie, mode, technologie, chimie, sciences de la vie et soins de sant\u00e9, ainsi que services financiers. Elles ont fourni des informations pr\u00e9cieuses pour aider les PME \u00e0 naviguer dans un environnement en constante \u00e9volution et \u00e0 saisir de nouvelles opportunit\u00e9s. L&rsquo;eBook qui en r\u00e9sulte montre les impacts de la durabilit\u00e9 sur les PME et la priorit\u00e9 croissante qu&rsquo;elle rev\u00eat dans leurs cha\u00eenes d&rsquo;approvisionnement.<\/p>\n<p class=\"has-rte\">\u00ab\u00a0La durabilit\u00e9 est aujourd&rsquo;hui en t\u00eate de l&rsquo;agenda de nombreuses entreprises. Mais le d\u00e9fi de d\u00e9velopper et de mettre en \u0153uvre une strat\u00e9gie de durabilit\u00e9 peut souvent sembler \u00e9crasant - de nombreux r\u00e9pondants ont d\u00e9clar\u00e9 ne pas savoir par o\u00f9 commencer. En collaborant avec une entreprise de logistique de confiance comme DHL Express, connue pour son portefeuille de solutions d&rsquo;exp\u00e9dition \u00e0 faibles \u00e9missions, les PME peuvent se positionner pour rester viables et comp\u00e9titives tout en assurant une croissance \u00e0 long terme\u00a0\u00bb, d\u00e9clare Michiel Greeven, Vice-Pr\u00e9sident Ex\u00e9cutif Global Commercial chez DHL Express.<\/p>\n<h5 class=\"has-rte\"><b>Haute pertinence, faible volont\u00e9 d&rsquo;investissement<\/b><\/h5>\n<p class=\"has-rte\">Au moins deux tiers des PME dans tous les secteurs interrog\u00e9s ont d\u00e9clar\u00e9 que la durabilit\u00e9 est soit \u00ab\u00a0tr\u00e8s importante\u00a0\u00bb, soit \u00ab\u00a0extr\u00eamement importante\u00a0\u00bb pour elles. Le secteur des services financiers et le secteur de la mode ont le plus fortement approuv\u00e9 cette \u00e9valuation, 81 % des r\u00e9pondants de chaque groupe ayant donn\u00e9 cette r\u00e9ponse. Malgr\u00e9 la compr\u00e9hension r\u00e9pandue de l&rsquo;importance du sujet, la plupart des PME sont r\u00e9ticentes \u00e0 allouer des fonds \u00e0 des initiatives durables. La plupart (53 %) ne sont pr\u00eates \u00e0 investir que 1 \u00e0 3 % de leur budget op\u00e9rationnel dans des pratiques durables. Seules 9 % des PME souhaitent investir plus de 5 %, tandis que 16 % ne souhaitent rien investir.<\/p>\n<h5 class=\"has-rte\"><b>L&rsquo;acceptation interne et c\u00f4t\u00e9 client reste un grand d\u00e9fi<\/b><\/h5>\n<p class=\"has-rte\">Alors que la moyenne mondiale des clients pr\u00eats \u00e0 investir davantage pour une exp\u00e9dition durable n&rsquo;est que de 23 %, la confiance des PME en Inde et en Chine est nettement plus \u00e9lev\u00e9e : 51 % et 47 % croient que leurs clients seraient pr\u00eats \u00e0 le faire. Lorsqu&rsquo;on leur a demand\u00e9 quels \u00e9taient les d\u00e9fis li\u00e9s \u00e0 la mise en \u0153uvre de leurs objectifs de durabilit\u00e9, la plupart des PME dans tous les march\u00e9s ont d\u00e9clar\u00e9 qu&rsquo;elles devaient garantir l&rsquo;acceptation interne et c\u00f4t\u00e9 client. Cela est particuli\u00e8rement marqu\u00e9 en Allemagne, o\u00f9 74 % des PME sont confront\u00e9es \u00e0 ce d\u00e9fi.<\/p>\n<h5 class=\"has-rte\"><b>Industrie de la mode et secteur des services financiers parmi les secteurs les plus durables<\/b><\/h5>\n<p class=\"has-rte\">Bien que l&rsquo;industrie de la mode soit souvent sous surveillance en ce qui concerne la durabilit\u00e9 de sa cha\u00eene d&rsquo;approvisionnement, la plupart des PME du secteur soutiennent la durabilit\u00e9. 81 % des r\u00e9pondants de ce secteur ont d\u00e9clar\u00e9 que c&rsquo;\u00e9tait \u00ab\u00a0tr\u00e8s important\u00a0\u00bb ou \u00ab\u00a0extr\u00eamement important\u00a0\u00bb pour leur entreprise, et plus des trois quarts (78 %) croient que l&rsquo;offre d&rsquo;options de livraison durables pourrait am\u00e9liorer leur image de marque (dans une certaine\/grande\/tr\u00e8s grande mesure). Les PME du secteur des services financiers sont celles qui d\u00e9clarent le plus souvent que la durabilit\u00e9 est \u00ab\u00a0extr\u00eamement importante\u00a0\u00bb pour leur entreprise (43 %). Ce secteur est le plus enclin \u00e0 allouer des budgets op\u00e9rationnels \u00e0 des pratiques de durabilit\u00e9 (88 %), et est \u00e9galement celui qui pense le plus que l&rsquo;offre d&rsquo;options de livraison durables pourrait conduire \u00e0 un plus grand succ\u00e8s commercial (47 % \u00ab\u00a0dans une grande\/tr\u00e8s grande mesure\u00a0\u00bb).<\/p>\n<p class=\"has-rte\">DHL Express travaille continuellement \u00e0 am\u00e9liorer la durabilit\u00e9 de ses op\u00e9rations et de ses services, contribuant ainsi aux objectifs de durabilit\u00e9 du groupe DHL, qui vise \u00e0 r\u00e9duire les \u00e9missions de gaz \u00e0 effet de serre annuelles \u00e0 moins de 29 millions de tonnes, \u00e0 \u00e9lectrifier 66 % des v\u00e9hicules pour le dernier kilom\u00e8tre et \u00e0 augmenter la part des carburants \u00e0 faibles \u00e9missions \u00e0 plus de 30 % d&rsquo;ici 2030. De plus, les clients de DHL Express peuvent prendre des mesures pour r\u00e9duire leurs \u00e9missions de Scope 3 gr\u00e2ce \u00e0 l&rsquo;utilisation de SAF (Sustainable Aviation Fuel) dans la flotte de fret a\u00e9rien de DHL Express gr\u00e2ce au service GoGreen Plus. Bas\u00e9 sur l&rsquo;approche \u00ab\u00a0Book and Claim\u00a0\u00bb, les \u00e9conomies r\u00e9alis\u00e9es (Scope 3) sont transmises aux clients sous forme de certificats.<\/p>\n<h5>La durabilit\u00e9 pourrait transformer l&rsquo;industrie logistique<\/h5>\n<p class=\"has-rte\">La durabilit\u00e9 va transformer l&rsquo;industrie dans les dix prochaines ann\u00e9es. Cet eBook complet a \u00e9t\u00e9 con\u00e7u pour aider les PME \u00e0 prendre des mesures concr\u00e8tes pour am\u00e9liorer la durabilit\u00e9 de leur logistique et \u00e0 relever tous les d\u00e9fis d\u00e9coulant des attentes de leurs clients. En tant que leader mondial du secteur logistique, DHL Express soutient des milliers de PME dans le monde entier dans divers secteurs et s&rsquo;engage \u00e0 fournir les bons outils, strat\u00e9gies et informations pour aider les PME dans leurs pratiques durables.<\/p>\n<h4><a href=\"https:\/\/www.dhl.com\/discover\/en-global\/logistics-advice\/sustainability-and-green-logistics\/sustainability-survey\" target=\"_blank\" rel=\"noopener\"><strong>T\u00e9l\u00e9chargez l&rsquo;eBook ici<\/strong><\/a><\/h4>\n<p>Photo : \u00a9 DHL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La durabilit\u00e9 est devenue une n\u00e9cessit\u00e9 strat\u00e9gique pour les petites et moyennes entreprises (PME), influen\u00e7ant consid\u00e9rablement leur valeur \u00e0 long terme et leur cr\u00e9dibilit\u00e9, comme le<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-67480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DHL Express avec enqu\u00eate et eBook sur la durabilit\u00e9 - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DHL Express avec enqu\u00eate et eBook sur la durabilit\u00e9 - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"La durabilit\u00e9 est devenue une n\u00e9cessit\u00e9 strat\u00e9gique pour les petites et moyennes entreprises (PME), influen\u00e7ant consid\u00e9rablement leur valeur \u00e0 long terme et leur cr\u00e9dibilit\u00e9, comme le [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-03T19:04:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_3.12.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1258\" \/>\n\t<meta property=\"og:image:height\" content=\"785\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DHL Express avec enqu\u00eate et eBook sur la durabilit\u00e9\",\"datePublished\":\"2024-12-03T19:04:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/\"},\"wordCount\":935,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_3.12.24.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/\",\"name\":\"DHL Express avec enqu\u00eate et eBook sur la durabilit\u00e9 - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_3.12.24.jpg\",\"datePublished\":\"2024-12-03T19:04:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_3.12.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_3.12.24.jpg\",\"width\":1258,\"height\":785},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/12\\\/03\\\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DHL Express avec enqu\u00eate et eBook sur la durabilit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DHL Express avec enqu\u00eate et eBook sur la durabilit\u00e9 - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/","og_locale":"fr_FR","og_type":"article","og_title":"DHL Express avec enqu\u00eate et eBook sur la durabilit\u00e9 - Loginfo24.","og_description":"La durabilit\u00e9 est devenue une n\u00e9cessit\u00e9 strat\u00e9gique pour les petites et moyennes entreprises (PME), influen\u00e7ant consid\u00e9rablement leur valeur \u00e0 long terme et leur cr\u00e9dibilit\u00e9, comme le [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-12-03T19:04:17+00:00","og_image":[{"width":1258,"height":785,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_3.12.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/"},"author":{"name":"","@id":""},"headline":"DHL Express avec enqu\u00eate et eBook sur la durabilit\u00e9","datePublished":"2024-12-03T19:04:17+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/"},"wordCount":935,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_3.12.24.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/","url":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/","name":"DHL Express avec enqu\u00eate et eBook sur la durabilit\u00e9 - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_3.12.24.jpg","datePublished":"2024-12-03T19:04:17+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_3.12.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_3.12.24.jpg","width":1258,"height":785},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2024\/12\/03\/dhl-express-avec-enquete-et-ebook-sur-la-durabilite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"DHL Express avec enqu\u00eate et eBook sur la durabilit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/67480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=67480"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/67480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/5633"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=67480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=67480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=67480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}