{"id":66651,"date":"2024-09-24T16:09:29","date_gmt":"2024-09-24T14:09:29","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/"},"modified":"2024-09-24T16:09:29","modified_gmt":"2024-09-24T14:09:29","slug":"timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/","title":{"rendered":"TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l&rsquo;IAA Transportation"},"content":{"rendered":"<h5><strong>TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l&rsquo;IAA Transportation. Le secteur du transport fait face \u00e0 de grands d\u00e9fis : les goulets d&rsquo;\u00e9tranglement dans les cha\u00eenes d&rsquo;approvisionnement, les nouvelles r\u00e9glementations et le manque de conducteurs qualifi\u00e9s nuisent \u00e0 la circulation fluide des marchandises. De plus, selon l&rsquo;Office f\u00e9d\u00e9ral des transports, plus de 37 % des transports routiers en Allemagne sont des trajets \u00e0 vide.<\/strong><\/h5>\n<p>(Erkrath) \u00ab Ces capacit\u00e9s doivent \u00eatre optimis\u00e9es gr\u00e2ce \u00e0 l&rsquo;aide num\u00e9rique tout en r\u00e9duisant le travail manuel \u00bb, souligne Gunnar Gburek, responsable des affaires commerciales chez TIMOCOM lors de l&rsquo;IAA Transportation 2024 \u00e0 Hanovre. L&rsquo;intelligence artificielle jouera un r\u00f4le d\u00e9cisif \u00e0 cet \u00e9gard \u00e0 l&rsquo;avenir.<\/p>\n<h5><strong>March\u00e9 du fret routier : Solutions num\u00e9riques globales<\/strong><\/h5>\n<p>TIMOCOM propose avec le March\u00e9 du fret routier une s\u00e9rie de services permettant aux entreprises de transport de num\u00e9riser et d&rsquo;optimiser leurs processus : de la tra\u00e7abilit\u00e9 en temps r\u00e9el des envois \u00e0 la bourse de fret ferm\u00e9e en passant par la v\u00e9rification des partenaires commerciaux, le March\u00e9 du fret routier regroupe diff\u00e9rentes solutions num\u00e9riques pour utiliser et d\u00e9ployer au mieux les ressources disponibles. Gr\u00e2ce \u00e0 l&rsquo;utilisation de la v\u00e9rification des partenaires commerciaux avec l&rsquo;aide de l&rsquo;IA et des interfaces vers des bases de donn\u00e9es ainsi que l&rsquo;Office f\u00e9d\u00e9ral de la logistique et de la mobilit\u00e9 (BALM), les documents peuvent \u00eatre v\u00e9rifi\u00e9s pour leur authenticit\u00e9 et leur validit\u00e9, ce qui aide \u00e0 respecter des r\u00e9glementations telles que la loi sur la diligence raisonnable en mati\u00e8re de cha\u00eenes d&rsquo;approvisionnement (LkSG) et la directive sur la diligence raisonnable en mati\u00e8re de durabilit\u00e9 des entreprises (CSDDD). Cela aide les entrepreneurs de transport et les planificateurs \u00e0 remplir leur devoir de diligence commerciale. \u00ab Ce service cr\u00e9e plus de transparence et de s\u00e9curit\u00e9 dans la collaboration dans le transport routier d\u00e8s le choix du partenaire commercial \u00bb, explique Gunnar Gburek.<\/p>\n<h5><strong>Utilisation de l&rsquo;IA pour la cr\u00e9ation automatique d&rsquo;offres<\/strong><\/h5>\n<p>Le sujet de l&rsquo;intelligence artificielle (IA) n&rsquo;est pas seulement une tendance actuelle, mais une technologie que TIMOCOM utilise d\u00e9j\u00e0 et d\u00e9veloppe continuellement. Avec une nouvelle int\u00e9gration de l&rsquo;IA, les utilisateurs de TIMOCOM peuvent transmettre une offre de fret en quelques clics. Il suffit de marquer et de copier le bon de transport, qui se pr\u00e9sente par exemple sous forme de PDF. Selon la m\u00e9thode du copier-coller, l&rsquo;IA de TIMOCOM reconna\u00eet les bons champs lors de la cr\u00e9ation d&rsquo;une nouvelle offre sur le march\u00e9 et les remplit automatiquement. Apr\u00e8s un bref contr\u00f4le, l&rsquo;offre de fret est rapidement et efficacement cr\u00e9\u00e9e. \u00ab Gr\u00e2ce \u00e0 l&rsquo;utilisation de l&rsquo;IA de TIMOCOM, nous pouvons simplifier consid\u00e9rablement des t\u00e2ches routini\u00e8res chronophages telles que la v\u00e9rification des documents et la cr\u00e9ation d&rsquo;offres de fret. Cela permet non seulement de gagner un temps pr\u00e9cieux, mais r\u00e9duit \u00e9galement les erreurs et permet aux employ\u00e9s de se concentrer sur leurs t\u00e2ches principales \u00bb, explique David Moog, responsable produit strat\u00e9gique chez TIMOCOM.<\/p>\n<p><strong>D\u00e9fis et nouvelles voies de collaboration dans le secteur du transport<\/strong><\/p>\n<p>Le manque de capacit\u00e9 ainsi que les nouvelles r\u00e9glementations ont un impact sur la collaboration dans le secteur du transport, ce sur quoi s&rsquo;accordaient \u00e9galement les experts du secteur du transport ainsi que du commerce et de l&rsquo;industrie lors des discussions au stand TIMOCOM lors de la foire. Des solutions plus efficaces et soutenues num\u00e9riquement sont urgemment n\u00e9cessaires pour rester comp\u00e9titifs. Lors des diff\u00e9rentes discussions, une chose est devenue particuli\u00e8rement claire : les goulets d&rsquo;\u00e9tranglement dans le recrutement de conducteurs, les exigences accrues en mati\u00e8re de durabilit\u00e9 ainsi que la complexit\u00e9 croissante des r\u00e9glementations de conformit\u00e9 font actuellement partie des plus grands d\u00e9fis \u00e0 relever. De nombreuses entreprises se voient contraintes d&rsquo;adapter leurs processus internes de mani\u00e8re complexe pour respecter les exigences l\u00e9gales tout en \u00e9tant efficaces.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-27055 alignleft\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TIMOCOM_24.9.24_2-154x300.jpg\" alt=\"\" width=\"207\" height=\"403\" \/>L&rsquo;une des solutions abord\u00e9es est la bourse de fret ferm\u00e9e. Contrairement au march\u00e9 spot ouvert, o\u00f9 les commandes de transport sont accessibles \u00e0 tous les utilisateurs, ce mod\u00e8le permet d&rsquo;adresser les offres de fret et d&rsquo;espace de chargement d&rsquo;abord \u00e0 un r\u00e9seau de partenaires pr\u00e9alablement \u00e9tabli. De cette mani\u00e8re, les donneurs d&rsquo;ordre peuvent r\u00e9duire le travail de v\u00e9rification des nouveaux partenaires commerciaux au sens du LkSG et de la CSDDD et privil\u00e9gier des partenaires connus et favoris. \u00ab Avec la bourse de fret ferm\u00e9e, les entreprises ont la possibilit\u00e9 de concentrer la collaboration sur des partenaires de confiance et ainsi de minimiser le travail bureaucratique engendr\u00e9 par les autres r\u00e9glementations \u00bb, explique Gunnar Gburek.<\/p>\n<h5><strong>Masquotte d&rsquo;entreprise : Mo, le h\u00e9ros du fret routier<\/strong><\/h5>\n<p>TIMOCOM pr\u00e9sente fi\u00e8rement son nouveau mascotte d&rsquo;entreprise au public : Mo, le h\u00e9ros du fret routier. Mais Mo est bien plus qu&rsquo;une simple mascotte \u2013 Mo, le h\u00e9ros du fret routier incarne les valeurs de TIMOCOM et fait d\u00e9sormais officiellement partie de TIMOCOM. Que ce soit lors de foires, en ligne, pendant l&rsquo;int\u00e9gration ou dans le centre d&rsquo;aide \u2013 Mo est toujours l\u00e0 quand il y a quelque chose de nouveau \u00e0 d\u00e9couvrir.<\/p>\n<p>Photo : \u00a9 TIMOCOM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l&rsquo;IAA Transportation. Le secteur du transport fait face \u00e0 de grands d\u00e9fis : les goulets d&rsquo;\u00e9tranglement dans les<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5968,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-66651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l&#039;IAA Transportation - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l&#039;IAA Transportation - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l&rsquo;IAA Transportation. Le secteur du transport fait face \u00e0 de grands d\u00e9fis : les goulets d&rsquo;\u00e9tranglement dans les [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-24T14:09:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TIMOCOM_24.9.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1217\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l&rsquo;IAA Transportation\",\"datePublished\":\"2024-09-24T14:09:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/\"},\"wordCount\":914,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/TIMOCOM_24.9.24.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/\",\"name\":\"TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l'IAA Transportation - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/TIMOCOM_24.9.24.jpg\",\"datePublished\":\"2024-09-24T14:09:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/TIMOCOM_24.9.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/TIMOCOM_24.9.24.jpg\",\"width\":1217,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l&rsquo;IAA Transportation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l'IAA Transportation - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/","og_locale":"fr_FR","og_type":"article","og_title":"TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l'IAA Transportation - Loginfo24.","og_description":"TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l&rsquo;IAA Transportation. Le secteur du transport fait face \u00e0 de grands d\u00e9fis : les goulets d&rsquo;\u00e9tranglement dans les [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-09-24T14:09:29+00:00","og_image":[{"width":1217,"height":720,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TIMOCOM_24.9.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/"},"author":{"name":"","@id":""},"headline":"TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l&rsquo;IAA Transportation","datePublished":"2024-09-24T14:09:29+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/"},"wordCount":914,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TIMOCOM_24.9.24.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/","url":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/","name":"TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l'IAA Transportation - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TIMOCOM_24.9.24.jpg","datePublished":"2024-09-24T14:09:29+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TIMOCOM_24.9.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TIMOCOM_24.9.24.jpg","width":1217,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/timocon-fait-le-bilan-de-sa-presentation-a-liaa-transportation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"TIMOCON fait le bilan de sa pr\u00e9sentation \u00e0 l&rsquo;IAA Transportation"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/66651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=66651"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/66651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/5968"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=66651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=66651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=66651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}