{"id":66645,"date":"2024-09-24T15:42:43","date_gmt":"2024-09-24T13:42:43","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/"},"modified":"2024-09-24T15:42:43","modified_gmt":"2024-09-24T13:42:43","slug":"kaufland-automatise-le-centre-logistique-de-geisenfeld","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/","title":{"rendered":"Kaufland automatise le centre logistique de Geisenfeld"},"content":{"rendered":"<h5><strong>\u00c0 une hauteur de 30 m\u00e8tres, de petits v\u00e9hicules navettes glissent automatiquement sur leurs longues voies et stockent des marchandises. \u00c0 un rythme constamment changeant, des bras robotiques pr\u00e9parent des palettes en fonction des besoins pour environ 125 magasins Kaufland dans le sud de l&rsquo;Allemagne. Comme guid\u00e9s par une main invisible, des unit\u00e9s de transport autonomes, semblables \u00e0 des cabines t\u00e9l\u00e9phoniques, livrent des palettes pr\u00eates \u00e0 l&rsquo;exp\u00e9dition \u00e0 la sortie des marchandises.<\/strong><\/h5>\n<p>(Neckarsulm\/Geisenfeld) Ce \u00e0 quoi ressemble le monde de la logistique de demain est d\u00e9j\u00e0 visible aujourd&rsquo;hui \u00e0 Geisenfeld, en Bavi\u00e8re. Apr\u00e8s plus de trois ans d&rsquo;extensions compl\u00e8tes et d&rsquo;une phase de mont\u00e9e en puissance r\u00e9ussie, les processus d&rsquo;entrep\u00f4t fonctionnent depuis septembre dans le centre logistique de Kaufland en grande partie de mani\u00e8re enti\u00e8rement automatis\u00e9e. Avec le nouvel entrep\u00f4t \u00e0 rayonnage haut mis en service, il est possible d&rsquo;augmenter les capacit\u00e9s sans utiliser d&rsquo;autres surfaces, qui souvent n&rsquo;existent m\u00eame plus. En m\u00eame temps, la s\u00e9curit\u00e9 des livraisons augmente.<\/p>\n<p>\u00ab On ne transforme pas un site logistique du jour au lendemain. C&rsquo;est pourquoi nous avons d\u00e9lib\u00e9r\u00e9ment pris la d\u00e9cision, il y a plusieurs ann\u00e9es, de transformer notre site de Geisenfeld en un entrep\u00f4t high-tech presque enti\u00e8rement automatis\u00e9. La technologie et la robotique ont \u00e9t\u00e9 d\u00e9velopp\u00e9es et int\u00e9gr\u00e9es de mani\u00e8re sp\u00e9cifique au site. Nous avons progressivement introduit les nouvelles technologies dans les diff\u00e9rentes sections de l&rsquo;entrep\u00f4t au cours des derni\u00e8res ann\u00e9es. Geisenfeld abrite ainsi l&rsquo;un des centres logistiques les plus modernes du commerce de d\u00e9tail alimentaire en Allemagne \u00bb, d\u00e9clare Konrad Ott, responsable du projet d&rsquo;automatisation \u00e0 Geisenfeld.<\/p>\n<h5><strong>Pr\u00e9paration automatis\u00e9e de plus de 200 000 colis par jour<\/strong><\/h5>\n<p>Dans le secteur alimentaire, jusqu&rsquo;\u00e0 185 000 colis sont pr\u00e9par\u00e9s automatiquement. Cela signifie qu&rsquo;apr\u00e8s la livraison, les palettes sont automatiquement rang\u00e9es dans l&rsquo;entrep\u00f4t \u00e0 rayonnage haut par des dispositifs de gestion de rayonnage et y sont conserv\u00e9es jusqu&rsquo;\u00e0 ce que les marchandises soient n\u00e9cessaires. Le d\u00e9palettisation se fait \u00e9galement en grande partie automatiquement. Douze bras robotiques assemblent ensuite les palettes de mani\u00e8re individuelle pour chaque magasin. Ils organisent les marchandises de mani\u00e8re \u00e0 ce que les employ\u00e9s du magasin puissent les ranger directement dans le bon ordre.<\/p>\n<p>Les palettes pr\u00e9par\u00e9es de mani\u00e8re autonome et manuelle sont emball\u00e9es et film\u00e9es automatiquement, puis transport\u00e9es dans le bon ordre vers la sortie des marchandises par des v\u00e9hicules de transport autonomes. Les robots de transport sont \u00e9quip\u00e9s de capteurs, de cam\u00e9ras et de technologies de moteur \u00e0 la pointe de la technologie, qui les aident \u00e0 suivre l&rsquo;itin\u00e9raire optimal et \u00e0 naviguer en toute s\u00e9curit\u00e9 autour des personnes et des objets.<\/p>\n<p>En plus de l&rsquo;entrep\u00f4t \u00e0 rayonnage haut, Geisenfeld dispose d&rsquo;un syst\u00e8me de pr\u00e9paration automatique (AKA) pour les fruits et l\u00e9gumes. Le syst\u00e8me peut traiter jusqu&rsquo;\u00e0 50 000 colis par jour et peut g\u00e9rer diff\u00e9rentes combinaisons de diff\u00e9rentes caisses de transport. Tous les fruits et l\u00e9gumes fra\u00eechement livr\u00e9s doivent donc simplement \u00eatre plac\u00e9s dans la machine, et des caisses de salade ou de bananes sont retir\u00e9es de la palette et assembl\u00e9es individuellement pour les magasins via l&rsquo;AKA.<\/p>\n<h5><strong>Formation des employ\u00e9s pour la nouvelle technologie<\/strong><\/h5>\n<p>L&rsquo;automatisation facilite \u00e9norm\u00e9ment le quotidien des employ\u00e9s sur place. Gr\u00e2ce \u00e0 l&rsquo;utilisation de robots et d&rsquo;\u00e9tag\u00e8res mobiles, les trajets et les travaux p\u00e9nibles sont par exemple \u00e9limin\u00e9s. En particulier pour les marchandises lourdes, les robots offrent un soutien id\u00e9al. Les pr\u00e9parateurs de commandes peuvent ainsi se concentrer davantage sur des t\u00e2ches telles que le contr\u00f4le des marchandises et le chargement d&rsquo;articles sensibles.<\/p>\n<p>De plus, de nouvelles t\u00e2ches passionnantes apparaissent. En effet, \u00e0 Geisenfeld, la technologie de pointe est utilis\u00e9e, ce qui signifie que des esprits num\u00e9riques sont \u00e9galement n\u00e9cessaires dans la logistique. 90 % des employ\u00e9s n\u00e9cessaires pour les postes de contr\u00f4le, de maintenance et d&rsquo;entretien ont \u00e9t\u00e9 pourvus par la formation de pr\u00e9parateurs de commandes.<\/p>\n<p>Photo : \u00a9 Kaufland<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 une hauteur de 30 m\u00e8tres, de petits v\u00e9hicules navettes glissent automatiquement sur leurs longues voies et stockent des marchandises. \u00c0 un rythme constamment changeant, des<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-66645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kaufland automatise le centre logistique de Geisenfeld - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kaufland automatise le centre logistique de Geisenfeld - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"\u00c0 une hauteur de 30 m\u00e8tres, de petits v\u00e9hicules navettes glissent automatiquement sur leurs longues voies et stockent des marchandises. \u00c0 un rythme constamment changeant, des [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-24T13:42:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kaufland_24.9.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1405\" \/>\n\t<meta property=\"og:image:height\" content=\"889\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Kaufland automatise le centre logistique de Geisenfeld\",\"datePublished\":\"2024-09-24T13:42:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/\"},\"wordCount\":728,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kaufland_24.9.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/\",\"name\":\"Kaufland automatise le centre logistique de Geisenfeld - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kaufland_24.9.24.jpg\",\"datePublished\":\"2024-09-24T13:42:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kaufland_24.9.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kaufland_24.9.24.jpg\",\"width\":1405,\"height\":889},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/09\\\/24\\\/kaufland-automatise-le-centre-logistique-de-geisenfeld\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kaufland automatise le centre logistique de Geisenfeld\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kaufland automatise le centre logistique de Geisenfeld - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/","og_locale":"fr_FR","og_type":"article","og_title":"Kaufland automatise le centre logistique de Geisenfeld - Loginfo24.","og_description":"\u00c0 une hauteur de 30 m\u00e8tres, de petits v\u00e9hicules navettes glissent automatiquement sur leurs longues voies et stockent des marchandises. \u00c0 un rythme constamment changeant, des [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-09-24T13:42:43+00:00","og_image":[{"width":1405,"height":889,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kaufland_24.9.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/"},"author":{"name":"","@id":""},"headline":"Kaufland automatise le centre logistique de Geisenfeld","datePublished":"2024-09-24T13:42:43+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/"},"wordCount":728,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kaufland_24.9.24.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/","url":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/","name":"Kaufland automatise le centre logistique de Geisenfeld - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kaufland_24.9.24.jpg","datePublished":"2024-09-24T13:42:43+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kaufland_24.9.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kaufland_24.9.24.jpg","width":1405,"height":889},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2024\/09\/24\/kaufland-automatise-le-centre-logistique-de-geisenfeld\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Kaufland automatise le centre logistique de Geisenfeld"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/66645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=66645"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/66645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/5970"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=66645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=66645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=66645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}