{"id":65749,"date":"2024-07-09T16:36:14","date_gmt":"2024-07-09T14:36:14","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/"},"modified":"2024-07-09T16:36:14","modified_gmt":"2024-07-09T14:36:14","slug":"dachser-est-present-en-autriche-depuis-20-ans","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/","title":{"rendered":"DACHSER est pr\u00e9sent en Autriche depuis 20 ans"},"content":{"rendered":"<h5>Avec la cr\u00e9ation de DACHSER Austria il y a 20 ans, DACHSER a \u00e9largi son r\u00e9seau international et a ainsi marqu\u00e9 une nouvelle \u00e9tape pour une croissance r\u00e9ussie et durable. Aujourd&rsquo;hui, la filiale autrichienne dispose d&rsquo;un solide r\u00e9seau d&rsquo;agences avec ses neuf sites, emploie pr\u00e8s de 700 collaborateurs et g\u00e9n\u00e8re un chiffre d&rsquo;affaires annuel de 202 millions d&rsquo;euros. Situ\u00e9e en Autriche, un important carrefour logistique en Europe, DACHSER Austria joue un r\u00f4le d\u00e9cisif dans le r\u00e9seau du prestataire logistique mondial.<\/h5>\n<div class=\"article__item-wrap\">\n<div class=\"article__item\">\n<p>(Kempten\/H\u00f6rsching) Logistique au c\u0153ur de l&rsquo;Europe : il y a 20 ans, DACHSER a lanc\u00e9 une organisation nationale en Autriche. La r\u00e9ussite repose non seulement sur des normes de performance et des crit\u00e8res de qualit\u00e9 uniformes, mais surtout sur l&rsquo;engagement des employ\u00e9s de l&rsquo;entreprise familiale. En Autriche, DACHSER propose \u00e0 ses clients des services de logistique de transport, d&rsquo;entreposage et des services personnalis\u00e9s dans les deux domaines d&rsquo;activit\u00e9 \u00ab\u00a0European Logistics\u00a0\u00bb et \u00ab\u00a0Air &amp; Sea Logistics\u00a0\u00bb, tout en \u00e9tant connect\u00e9 au r\u00e9seau mondial de DACHSER avec 382 sites dans 43 pays.<\/p>\n<p>\u00c0 l&rsquo;occasion de son 20e anniversaire, DACHSER Austria a organis\u00e9 un \u00e9v\u00e9nement presse \u00e0 la mi-juin sur le site de Himberg pour c\u00e9l\u00e9brer cette \u00e9tape. \u00ab\u00a0Nous sommes fiers de notre histoire et des progr\u00e8s que nous avons r\u00e9alis\u00e9s au cours des deux derni\u00e8res d\u00e9cennies\u00a0\u00bb, d\u00e9clare G\u00fcnter Hirschbeck, directeur g\u00e9n\u00e9ral de European Logistics Austria. \u00ab\u00a0Notre engagement envers la qualit\u00e9, l&rsquo;innovation et la durabilit\u00e9 continuera de propulser notre succ\u00e8s \u00e0 l&rsquo;avenir. Les besoins de nos clients ont \u00e9volu\u00e9. Rapidit\u00e9, pr\u00e9cision, flexibilit\u00e9 et fiabilit\u00e9 sont des facteurs de comp\u00e9titivit\u00e9 d\u00e9cisifs pour eux. DACHSER repr\u00e9sente des solutions logistiques modernes, efficaces et pilot\u00e9es par l&rsquo;IT. Cela est rendu possible gr\u00e2ce \u00e0 l&rsquo;int\u00e9gration \u00e9troite de nos r\u00e9seaux de transport et d&rsquo;entreposage \u00e0 l&rsquo;\u00e9chelle mondiale, \u00e0 des partenariats \u00e0 long terme et \u00e0 une num\u00e9risation coh\u00e9rente \u00e0 l&rsquo;\u00e9chelle mondiale.\u00a0\u00bb Peter Deutschbauer, qui est directeur g\u00e9n\u00e9ral de Air &amp; Sea Logistics Eastern Europe et Austria depuis 2023, ajoute : \u00ab\u00a0En tant qu&rsquo;expert en logistique a\u00e9rienne et maritime mondiale, nous proposons des solutions de cha\u00eene d&rsquo;approvisionnement int\u00e9gr\u00e9es et efficaces \u00e0 l&rsquo;\u00e9chelle mondiale.\u00a0\u00bb<\/p>\n<\/div>\n<\/div>\n<div class=\"article__item-wrap\">\n<div class=\"article__item\">\n<h5>La trajectoire de succ\u00e8s de DACHSER Austria<\/h5>\n<\/div>\n<\/div>\n<div class=\"article__item-wrap\">\n<div class=\"article__item\">\n<p>Comme tous les sites de DACHSER fonctionnent selon les m\u00eames r\u00e8gles et processus, les clients autrichiens en b\u00e9n\u00e9ficient \u00e9galement. \u00ab\u00a0Un avantage est nos agences d\u00e9centralis\u00e9es, qui sont situ\u00e9es \u00e0 proximit\u00e9 de nos clients. Cela permet des temps de r\u00e9action rapides, et nos \u00e9quipes de service client personnelles agissent comme premiers interlocuteurs sur place\u00a0\u00bb, explique Hirschbeck.<\/p>\n<\/div>\n<\/div>\n<div class=\"article__item-wrap\">\n<div class=\"article__item text-highlighted\">\n<p>\u00ab\u00a0Nous sommes fiers de notre histoire et des progr\u00e8s que nous avons r\u00e9alis\u00e9s au cours des deux derni\u00e8res d\u00e9cennies\u00a0\u00bb, d\u00e9clare G\u00fcnter Hirschbeck, directeur g\u00e9n\u00e9ral de European Logistics Austria.<\/p>\n<\/div>\n<\/div>\n<div class=\"article__item-wrap\">\n<div class=\"article__item\">\n<p>Les sites sont continuellement \u00e9tendus et modernis\u00e9s. L&rsquo;ann\u00e9e derni\u00e8re, DACHSER Austria a commenc\u00e9 l&rsquo;extension et le d\u00e9veloppement du site de Himberg pr\u00e8s de Vienne. En m\u00eame temps, des travaux d&rsquo;extension ont de nouveau commenc\u00e9 ce printemps au centre logistique de Linz \u00e0 H\u00f6rsching. \u00ab\u00a0Cela souligne encore une fois l&rsquo;importance de DACHSER en Autriche en tant que carrefour logistique en Europe\u00a0\u00bb, explique Hirschbeck en revenant sur les \u00e9tapes cl\u00e9s.<\/p>\n<div class=\"text-with-image\">\n<div class=\"text-with-image__text text-with-image__text--align-right\">\n<h5>La logistique est un m\u00e9tier de personnes<\/h5>\n<p>\u00ab\u00a0La logistique est un m\u00e9tier de personnes\u00a0\u00bb \u2013 cette devise souligne que les employ\u00e9s de DACHSER sont le facteur cl\u00e9 du succ\u00e8s de l&rsquo;entreprise. Par cons\u00e9quent, la recherche de bons professionnels devient de plus en plus importante. \u00ab\u00a0Chez DACHSER Austria, la formation de qualit\u00e9 a donc une grande importance traditionnelle\u00a0\u00bb, d\u00e9clare G\u00fcnter Hirschbeck. Actuellement, environ 80 jeunes logisticiens sont form\u00e9s. Lors de l&rsquo;\u00e9v\u00e9nement, Anja Schlesinger, responsable de la formation au centre logistique de Vienne, a pr\u00e9sent\u00e9 le concept de formation avec ses nombreuses possibilit\u00e9s et collaborations.<\/p>\n<\/div>\n<\/div>\n<div class=\"article__item-wrap\">\n<div class=\"article__item\">\n<h5>Strat\u00e9gie de protection climatique \u00e0 long terme<\/h5>\n<\/div>\n<\/div>\n<div class=\"article__item-wrap\">\n<div class=\"article__item\">\n<p>DACHSER poursuit une strat\u00e9gie de protection climatique \u00e0 long terme et, avec un accent sur l&rsquo;efficacit\u00e9, l&rsquo;innovation et la responsabilit\u00e9 int\u00e9grative, fait avancer la transition vers une logistique plus durable en collaboration avec ses clients et partenaires.<\/p>\n<p>Depuis 2018, l&rsquo;entreprise utilise des v\u00e9hicules enti\u00e8rement \u00e9lectriques dans le cadre du concept de livraison urbaine durable \u00ab\u00a0DACHSER Emission-Free Delivery\u00a0\u00bb. En fonction des exigences locales, ce concept utilise des fourgonnettes et des camions \u00e9lectriques ainsi que des v\u00e9los cargo assist\u00e9s \u00e9lectriquement. Ces derniers sont sp\u00e9cialement con\u00e7us pour le fret et les marchandises palettis\u00e9es. Avec ces v\u00e9hicules \u00e0 z\u00e9ro \u00e9mission, toutes les exp\u00e9ditions sont livr\u00e9es sans \u00e9missions dans une zone d\u00e9finie du centre-ville.<\/p>\n<p>Le concept est d\u00e9sormais mis en \u0153uvre dans le domaine d&rsquo;activit\u00e9 Road Logistics en exploitation r\u00e9guli\u00e8re \u2013 dans 13 villes \u00e0 travers l&rsquo;Europe, a expliqu\u00e9 Manuel Schmelz, responsable du d\u00e9veloppement commercial des solutions en Autriche, lors de l&rsquo;\u00e9v\u00e9nement presse \u00e0 Himberg. La livraison sans \u00e9missions devrait \u00e9galement commencer dans la capitale.<\/p>\n<p>Pour illustrer cela, deux FUSO E-Canter et un camion \u00e9lectrique QUANTRON ont \u00e9t\u00e9 pr\u00e9sent\u00e9s lors de l&rsquo;\u00e9v\u00e9nement du 20e anniversaire, qui circuleront \u00e0 l&rsquo;avenir sans \u00e9missions dans le centre-ville de Vienne. De plus, un v\u00e9lo cargo assist\u00e9 \u00e9lectriquement a \u00e9t\u00e9 montr\u00e9, qui est actuellement en circulation dans diff\u00e9rentes villes europ\u00e9ennes.<\/p>\n<p>DACHSER Austria a d\u00e9j\u00e0 sign\u00e9 d\u00e9but juin la d\u00e9claration d&rsquo;intention pour le projet \u00ab\u00a0Zero Emission Transport\u00a0\u00bb \u00e0 Vienne. Le projet pilote est une initiative de la chambre de commerce de la ville et comprend la participation de plus de 30 entreprises de diff\u00e9rents secteurs. La livraison par camions \u00e9lectriques devrait commencer dans les prochaines semaines.<\/p>\n<p>Photo de titre : \u00a9 Dachser \/ <em><strong>L\u00e9gende de l&rsquo;image<\/strong> (de g. \u00e0 d.) : Mario Freiberger M.A. (Magister FH), responsable de l&rsquo;agence de Schwechat de la chambre de commerce de Basse-Autriche, (\u00e0 gauche) et Mathias Past M.A. (Magister), pr\u00e9sident de l&rsquo;agence de Schwechat de la chambre de commerce de Basse-Autriche, (\u00e0 droite) ont remis \u00e0 G\u00fcnter Hirschbeck, directeur g\u00e9n\u00e9ral de European Logistics Austria, un certificat \u00e0 l&rsquo;occasion du 20e anniversaire de DACHSER Austria<\/em><\/p>\n<div class=\"text-with-image__text text-with-image__text--align-left\">\n<blockquote>\n<h5>Distinction en tant qu'\u00a0\u00bbEntreprise mod\u00e8le d&rsquo;Autriche\u00a0\u00bb<\/h5>\n<p>DACHSER Austria a \u00e9t\u00e9 certifi\u00e9 en tant qu'\u00a0\u00bbEntreprise mod\u00e8le d&rsquo;Autriche\u00a0\u00bb lors de l&rsquo;\u00e9v\u00e9nement. Monica Rintersbacher M.A. (Magistra), directrice de Leitbetriebe Austria, a remis le certificat \u00e0 G\u00fcnter Hirschbeck et Peter Deutschbauer lors des c\u00e9l\u00e9brations de l&rsquo;anniversaire.<\/p>\n<p>\u00ab\u00a0DACHSER n&rsquo;est pas seulement l&rsquo;un des prestataires logistiques les plus performants, mais il montre \u00e9galement l&rsquo;exemple en ce qui concerne les employ\u00e9s et promeut activement l&rsquo;innovation et la durabilit\u00e9 au sein de l&rsquo;entreprise. Leitbetriebe Austria f\u00e9licite chaleureusement DACHSER pour ses 20 ans d&rsquo;anniversaire et pour sa certification en tant qu&rsquo;entreprise mod\u00e8le\u00a0\u00bb, a d\u00e9clar\u00e9 Rintersbacher M.A.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26463 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_9.7.2024_2.jpg\" alt=\"\" width=\"1276\" height=\"714\" \/><\/p><\/blockquote>\n<blockquote><p>(de g. \u00e0 d.) : G\u00fcnter Hirschbeck, directeur g\u00e9n\u00e9ral de European Logistics DACHSER Austria ; Monica Rintersbacher M.A. (Magistra), Leitbetriebe Austria ; et Peter Deutschbauer, directeur g\u00e9n\u00e9ral de Air &amp; Sea Logistics DACHSER Eastern Europe et Austria (\u00a9 Dachser)<\/p><\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Avec la cr\u00e9ation de DACHSER Austria il y a 20 ans, DACHSER a \u00e9largi son r\u00e9seau international et a ainsi marqu\u00e9 une nouvelle \u00e9tape pour une<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-65749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DACHSER est pr\u00e9sent en Autriche depuis 20 ans - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DACHSER est pr\u00e9sent en Autriche depuis 20 ans - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Avec la cr\u00e9ation de DACHSER Austria il y a 20 ans, DACHSER a \u00e9largi son r\u00e9seau international et a ainsi marqu\u00e9 une nouvelle \u00e9tape pour une [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-09T14:36:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_9.7.2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1210\" \/>\n\t<meta property=\"og:image:height\" content=\"713\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DACHSER est pr\u00e9sent en Autriche depuis 20 ans\",\"datePublished\":\"2024-07-09T14:36:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/\"},\"wordCount\":1226,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_9.7.2024.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/\",\"name\":\"DACHSER est pr\u00e9sent en Autriche depuis 20 ans - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_9.7.2024.jpg\",\"datePublished\":\"2024-07-09T14:36:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_9.7.2024.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_9.7.2024.jpg\",\"width\":1210,\"height\":713},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/07\\\/09\\\/dachser-est-present-en-autriche-depuis-20-ans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DACHSER est pr\u00e9sent en Autriche depuis 20 ans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DACHSER est pr\u00e9sent en Autriche depuis 20 ans - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/","og_locale":"fr_FR","og_type":"article","og_title":"DACHSER est pr\u00e9sent en Autriche depuis 20 ans - Loginfo24.","og_description":"Avec la cr\u00e9ation de DACHSER Austria il y a 20 ans, DACHSER a \u00e9largi son r\u00e9seau international et a ainsi marqu\u00e9 une nouvelle \u00e9tape pour une [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-07-09T14:36:14+00:00","og_image":[{"width":1210,"height":713,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_9.7.2024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/"},"author":{"name":"","@id":""},"headline":"DACHSER est pr\u00e9sent en Autriche depuis 20 ans","datePublished":"2024-07-09T14:36:14+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/"},"wordCount":1226,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_9.7.2024.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/","url":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/","name":"DACHSER est pr\u00e9sent en Autriche depuis 20 ans - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_9.7.2024.jpg","datePublished":"2024-07-09T14:36:14+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_9.7.2024.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_9.7.2024.jpg","width":1210,"height":713},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2024\/07\/09\/dachser-est-present-en-autriche-depuis-20-ans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"DACHSER est pr\u00e9sent en Autriche depuis 20 ans"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/65749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=65749"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/65749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/6324"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=65749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=65749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=65749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}