{"id":65682,"date":"2024-06-20T19:24:37","date_gmt":"2024-06-20T17:24:37","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/"},"modified":"2024-06-20T19:24:37","modified_gmt":"2024-06-20T17:24:37","slug":"topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/","title":{"rendered":"TOPREGAL \u00e9tend ses surfaces dans le parc Berlin-Stettin \u00e0 Pasewalk"},"content":{"rendered":"<h5><strong>Seulement trois ans apr\u00e8s son implantation, la soci\u00e9t\u00e9 TOPREGAL GmbH a c\u00e9l\u00e9br\u00e9 le 20 juin, par un temps magnifique et en pr\u00e9sence de nombreux visiteurs, une nouvelle c\u00e9r\u00e9monie de pose de la premi\u00e8re pierre dans le parc industriel Berlin-Stettin \u00e0 Pasewalk. Sur une surface adjacente de 30 000 m\u00e8tres carr\u00e9s, deux nouveaux halls de 5 000 m\u00e8tres carr\u00e9s chacun seront construits au cours de l&rsquo;ann\u00e9e prochaine, et devraient \u00eatre pr\u00eats \u00e0 partir de la deuxi\u00e8me moiti\u00e9 de l&rsquo;ann\u00e9e 2025.<\/strong><\/h5>\n<p>(Filderstadt\/Pasewalk) Avec cette extension, TOPREGAL augmente consid\u00e9rablement ses capacit\u00e9s de production et cr\u00e9e au moins 20 nouveaux emplois. Comme pour les quatre premiers halls, TOPREGAL collabore avec la soci\u00e9t\u00e9 Goldbeck. \u00ab Nous sommes tr\u00e8s heureux d&rsquo;\u00e9largir notre site \u00e0 Pasewalk avec un total de six halls. Avec l&rsquo;espace suppl\u00e9mentaire, nous pouvons r\u00e9pondre \u00e0 la forte demande pour notre abri solaire et d&rsquo;autres produits de la marque SoloPort \u00bb, d\u00e9clare J\u00fcrgen Effner, directeur g\u00e9n\u00e9ral de TOPREGAL GmbH.<\/p>\n<p>L&rsquo;entreprise, originaire de Filderstadt et sp\u00e9cialis\u00e9e dans l&rsquo;am\u00e9nagement de stockage et la technique d&rsquo;exploitation, a ouvert ses portes \u00e0 Pasewalk seulement un an apr\u00e8s la premi\u00e8re pierre pos\u00e9e en 2021. En mai 2023, le coup d&rsquo;envoi a \u00e9t\u00e9 donn\u00e9 pour l&rsquo;abri solaire sp\u00e9cialement d\u00e9velopp\u00e9, qui est fabriqu\u00e9 \u00e0 Pasewalk. D&rsquo;autres nouveaut\u00e9s de la marque SoloPort, comme des abris de stationnement solaires, ont suivi et sont en constante \u00e9volution. Avec l&rsquo;espace suppl\u00e9mentaire, le site de production et d&rsquo;entreposage s&rsquo;\u00e9tend \u00e0 un total de 82 000 m\u00e8tres carr\u00e9s.<\/p>\n<p>En plus de sa croissance rapide, l&rsquo;entreprise familiale se distingue par ses mesures de durabilit\u00e9. C&rsquo;est pourquoi TOPREGAL n&rsquo;augmente pas seulement sa capacit\u00e9, mais continue \u00e9galement d&rsquo;am\u00e9liorer son efficacit\u00e9 \u00e9nerg\u00e9tique.<\/p>\n<h5><strong>Photovolta\u00efque sur les toits<\/strong><\/h5>\n<p>Comme d\u00e9j\u00e0 r\u00e9alis\u00e9 pour le premier hall, les trois halls existants ainsi que les deux nouvelles surfaces de toit seront \u00e9quip\u00e9s de syst\u00e8mes photovolta\u00efques. Au total, les six halls produiront alors 3,4 m\u00e9gawatts-cr\u00eate de puissance. Une partie de l&rsquo;\u00e9nergie produite sera utilis\u00e9e par TOPREGAL pour ses propres besoins, alimentant directement la production. La plus grande partie sera cependant inject\u00e9e dans le r\u00e9seau pour approvisionner la r\u00e9gion. \u00ab Un m\u00e9nage de quatre personnes consomme en moyenne 3 000 kWh par an \u00bb, explique Effner. \u00ab Avec l&rsquo;\u00e9lectricit\u00e9 des six halls, nous pouvons approvisionner plus de 1 000 m\u00e9nages par an et ainsi contribuer \u00e0 la transition \u00e9nerg\u00e9tique. \u00bb<\/p>\n<p>Photo : \u00a9 TOPREGAL \/ <strong><em>L\u00e9gende de l&rsquo;image :<\/em><\/strong> <em>Ont particip\u00e9 \u00e0 la pose de la premi\u00e8re pierre (de g. \u00e0 dr.) : Joachim K\u00f6nig de K\u00f6nig + Patner PartmbB, Ralf Sippel du minist\u00e8re de l&rsquo;\u00c9conomie, du Travail et de la Sant\u00e9 du Mecklembourg-Pom\u00e9ranie-Occidentale, J\u00f6rg Heuer de Goldbeck Nordost GmbH, le secr\u00e9taire d&rsquo;\u00c9tat Jochen Schulte, minist\u00e8re de l&rsquo;\u00c9conomie, des Infrastructures, du Tourisme et du Travail du Land du Mecklembourg-Pom\u00e9ranie-Occidentale, le pr\u00e9sident du conseil de district Michael Sack, district de Vorpommern-Greifswald, J\u00fcrgen Effner, directeur g\u00e9n\u00e9ral de TOPREGAL GmbH, Danny Rodewald, maire de la ville de Pasewalk, Marko Schmidt, ville de Pasewalk<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seulement trois ans apr\u00e8s son implantation, la soci\u00e9t\u00e9 TOPREGAL GmbH a c\u00e9l\u00e9br\u00e9 le 20 juin, par un temps magnifique et en pr\u00e9sence de nombreux visiteurs, une<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6350,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-65682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TOPREGAL \u00e9tend ses surfaces dans le parc Berlin-Stettin \u00e0 Pasewalk - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TOPREGAL \u00e9tend ses surfaces dans le parc Berlin-Stettin \u00e0 Pasewalk - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Seulement trois ans apr\u00e8s son implantation, la soci\u00e9t\u00e9 TOPREGAL GmbH a c\u00e9l\u00e9br\u00e9 le 20 juin, par un temps magnifique et en pr\u00e9sence de nombreux visiteurs, une [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-20T17:24:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Topregal_20.6.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1337\" \/>\n\t<meta property=\"og:image:height\" content=\"795\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"TOPREGAL \u00e9tend ses surfaces dans le parc Berlin-Stettin \u00e0 Pasewalk\",\"datePublished\":\"2024-06-20T17:24:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/\"},\"wordCount\":548,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Topregal_20.6.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/\",\"name\":\"TOPREGAL \u00e9tend ses surfaces dans le parc Berlin-Stettin \u00e0 Pasewalk - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Topregal_20.6.24.jpg\",\"datePublished\":\"2024-06-20T17:24:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Topregal_20.6.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Topregal_20.6.24.jpg\",\"width\":1337,\"height\":795},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/20\\\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TOPREGAL \u00e9tend ses surfaces dans le parc Berlin-Stettin \u00e0 Pasewalk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TOPREGAL \u00e9tend ses surfaces dans le parc Berlin-Stettin \u00e0 Pasewalk - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/","og_locale":"fr_FR","og_type":"article","og_title":"TOPREGAL \u00e9tend ses surfaces dans le parc Berlin-Stettin \u00e0 Pasewalk - Loginfo24.","og_description":"Seulement trois ans apr\u00e8s son implantation, la soci\u00e9t\u00e9 TOPREGAL GmbH a c\u00e9l\u00e9br\u00e9 le 20 juin, par un temps magnifique et en pr\u00e9sence de nombreux visiteurs, une [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-06-20T17:24:37+00:00","og_image":[{"width":1337,"height":795,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Topregal_20.6.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/"},"author":{"name":"","@id":""},"headline":"TOPREGAL \u00e9tend ses surfaces dans le parc Berlin-Stettin \u00e0 Pasewalk","datePublished":"2024-06-20T17:24:37+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/"},"wordCount":548,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Topregal_20.6.24.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/","url":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/","name":"TOPREGAL \u00e9tend ses surfaces dans le parc Berlin-Stettin \u00e0 Pasewalk - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Topregal_20.6.24.jpg","datePublished":"2024-06-20T17:24:37+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Topregal_20.6.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Topregal_20.6.24.jpg","width":1337,"height":795},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/20\/topregal-etend-ses-surfaces-dans-le-parc-berlin-stettin-a-pasewalk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"TOPREGAL \u00e9tend ses surfaces dans le parc Berlin-Stettin \u00e0 Pasewalk"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/65682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=65682"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/65682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/6350"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=65682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=65682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=65682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}