{"id":65658,"date":"2024-06-17T21:24:36","date_gmt":"2024-06-17T19:24:36","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/"},"modified":"2024-06-17T21:24:36","modified_gmt":"2024-06-17T19:24:36","slug":"tgw-recompense-aux-supplytech-breakthrough-awards","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/","title":{"rendered":"TGW r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards"},"content":{"rendered":"<h5><strong>Le robot de pr\u00e9l\u00e8vement intelligent TGW a \u00e9t\u00e9 r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards en tant qu&rsquo;Innovation en mati\u00e8re de manutention de l&rsquo;ann\u00e9e 2024. Gr\u00e2ce \u00e0 l&rsquo;intelligence artificielle, RovoFlex apprend \u00e0 chaque pr\u00e9l\u00e8vement et s&rsquo;optimise en permanence. Que ce soit pour des aliments, des articles de mode ou des biens industriels et de consommation. Des processus tels que le tri, la consolidation ou le d\u00e9groupage peuvent ainsi \u00eatre automatis\u00e9s de mani\u00e8re efficace.<\/strong><\/h5>\n<p>(Marchtrenk) Le robot intelligent, avec son syst\u00e8me de cam\u00e9ras intelligent, est utilis\u00e9 en combinaison avec le TGW PickCenter et forme une station de pr\u00e9l\u00e8vement hybride. Les utilisateurs peuvent passer facilement entre le mode manuel et le mode automatique et couvrir les pics de commandes. Un autre avantage : le robot de pr\u00e9l\u00e8vement peut \u00eatre int\u00e9gr\u00e9 dans des installations existantes en quelques jours.<\/p>\n<h5><strong>D\u00e9bit allant jusqu&rsquo;\u00e0 1 000 articles par heure<\/strong><\/h5>\n<p>RovoFlex s&rsquo;attaque \u00e0 des d\u00e9fis tels que la p\u00e9nurie croissante de main-d&rsquo;\u0153uvre dans de nombreux secteurs ou des changements de gamme de plus en plus rapides. M\u00eame des marchandises exigeantes comme les produits surgel\u00e9s ou les objets pointus ne posent aucun probl\u00e8me en mati\u00e8re de manutention. RovoFlex atteint un d\u00e9bit allant jusqu&rsquo;\u00e0 1 000 articles par heure \u2013 et ce, avec une performance et une pr\u00e9cision constantes. Que ce soit pour des aliments, des articles de mode ou des biens industriels et de consommation. Dans un fonctionnement en deux \u00e9quipes, le retour sur investissement est d\u00e9j\u00e0 atteint apr\u00e8s environ deux ans et demi.<\/p>\n<h5><strong>Un changeur de jeu pour l&rsquo;intralogistique<\/strong><\/h5>\n<p>\u00ab Nous sommes tr\u00e8s heureux de cette distinction en tant qu&rsquo;Innovation en mati\u00e8re de manutention de l&rsquo;ann\u00e9e. Le SupplyTech Breakthrough Award est une belle confirmation de notre travail de d\u00e9veloppement centr\u00e9 sur le client \u00bb, souligne Christoph Wolkerstorfer, directeur technique de TGW Logistics. \u00ab TGW Logistics apporte plus de 50 ans d&rsquo;exp\u00e9rience dans le d\u00e9veloppement de syst\u00e8mes et de solutions innovants. Ce savoir-faire a \u00e9t\u00e9 int\u00e9gr\u00e9 par nos experts dans un robot de pr\u00e9l\u00e8vement qui \u00e9l\u00e8ve l&rsquo;efficacit\u00e9 de pr\u00e9l\u00e8vement \u00e0 un nouveau niveau \u2013 et qui est ainsi un changeur de jeu pour le secteur. \u00bb<\/p>\n<p>Photo : \u00a9 TGW<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le robot de pr\u00e9l\u00e8vement intelligent TGW a \u00e9t\u00e9 r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards en tant qu&rsquo;Innovation en mati\u00e8re de manutention de l&rsquo;ann\u00e9e 2024. Gr\u00e2ce \u00e0 l&rsquo;intelligence<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1560,1561],"tags":[],"class_list":["post-65658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TGW r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TGW r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Le robot de pr\u00e9l\u00e8vement intelligent TGW a \u00e9t\u00e9 r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards en tant qu&rsquo;Innovation en mati\u00e8re de manutention de l&rsquo;ann\u00e9e 2024. Gr\u00e2ce \u00e0 l&rsquo;intelligence [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-17T19:24:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_17.6.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1266\" \/>\n\t<meta property=\"og:image:height\" content=\"838\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"TGW r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards\",\"datePublished\":\"2024-06-17T19:24:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/\"},\"wordCount\":391,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/TGW_17.6.24.jpg\",\"articleSection\":[\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/\",\"name\":\"TGW r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/TGW_17.6.24.jpg\",\"datePublished\":\"2024-06-17T19:24:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/TGW_17.6.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/TGW_17.6.24.jpg\",\"width\":1266,\"height\":838},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/06\\\/17\\\/tgw-recompense-aux-supplytech-breakthrough-awards\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TGW r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TGW r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/","og_locale":"fr_FR","og_type":"article","og_title":"TGW r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards - Loginfo24.","og_description":"Le robot de pr\u00e9l\u00e8vement intelligent TGW a \u00e9t\u00e9 r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards en tant qu&rsquo;Innovation en mati\u00e8re de manutention de l&rsquo;ann\u00e9e 2024. Gr\u00e2ce \u00e0 l&rsquo;intelligence [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-06-17T19:24:36+00:00","og_image":[{"width":1266,"height":838,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_17.6.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/"},"author":{"name":"","@id":""},"headline":"TGW r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards","datePublished":"2024-06-17T19:24:36+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/"},"wordCount":391,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_17.6.24.jpg","articleSection":["Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/","url":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/","name":"TGW r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_17.6.24.jpg","datePublished":"2024-06-17T19:24:36+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_17.6.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_17.6.24.jpg","width":1266,"height":838},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2024\/06\/17\/tgw-recompense-aux-supplytech-breakthrough-awards\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"TGW r\u00e9compens\u00e9 aux SupplyTech Breakthrough Awards"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/65658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=65658"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/65658\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/6358"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=65658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=65658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=65658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}