{"id":65317,"date":"2024-05-21T19:38:13","date_gmt":"2024-05-21T17:38:13","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/"},"modified":"2024-05-21T19:38:13","modified_gmt":"2024-05-21T17:38:13","slug":"le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/","title":{"rendered":"Le groupe pfenning acquiert le logisticien pharmaceutique LOGOSYS"},"content":{"rendered":"<h5><strong>Le groupe pfenning \u00e9largit son portefeuille de services gr\u00e2ce \u00e0 l&rsquo;acquisition strat\u00e9gique du groupe de logistique pharmaceutique LOGOSYS bas\u00e9 \u00e0 Darmstadt. La transaction, r\u00e9troactive au 1er janvier 2024, a \u00e9t\u00e9 r\u00e9alis\u00e9e avec une participation de 100 %. Le groupe pfenning fait ainsi un pas suppl\u00e9mentaire dans sa strat\u00e9gie de croissance et \u00e9largit son portefeuille de services et de secteurs, car LOGOSYS est un groupe logistique renomm\u00e9 avec une expertise de longue date dans des solutions logistiques hautement sp\u00e9cialis\u00e9es dans les segments de l&rsquo;industrie pharmaceutique, de la sant\u00e9, des cosm\u00e9tiques, des produits de soins et de la chimie.<\/strong><\/h5>\n<p>(Heddesheim\/Darmstadt) Le groupe LOGOSYS se compose de trois soci\u00e9t\u00e9s avec des unit\u00e9s de logistique, de transport et de services de personnel, toutes orient\u00e9es vers des services de cha\u00eene d&rsquo;approvisionnement pour l&rsquo;industrie pharmaceutique et chimique. Parmi les clients de longue date de l&rsquo;entreprise figurent des grandes marques de l&rsquo;industrie pharmaceutique et de la sant\u00e9, pour lesquelles la logistique d&rsquo;entrep\u00f4t, le conditionnement, la pr\u00e9paration de commandes, le transport et la distribution vers le commerce ou le client final sont effectu\u00e9s. Avec environ 250 employ\u00e9s sur 3 sites dans la r\u00e9gion de Rhein-Main, plus de 60 000 m\u00b2 avec plus de 100 000 emplacements de palettes et une flotte propre, LOGOSYS repr\u00e9sente un compl\u00e9ment id\u00e9al au monde de pfenning. De plus, le sp\u00e9cialiste dispose d&rsquo;un syst\u00e8me de gestion de la qualit\u00e9 complet avec les certifications et autorisations n\u00e9cessaires pour la logistique pharmaceutique : notamment GDP, GMP, autorisation de gros ou autorisation de fabrication selon l&rsquo;article 13 AMG.<\/p>\n<h5>Transaction pour des raisons de succession<\/h5>\n<p>La transaction a eu lieu pour des raisons de succession, car Hans-J\u00fcrgen N\u00fctzel, fondateur et directeur g\u00e9n\u00e9ral de LOGOSYS, s&rsquo;est retir\u00e9 de la direction op\u00e9rationnelle pour des raisons d&rsquo;\u00e2ge, posant ainsi les bases de l&rsquo;avenir de l&rsquo;entreprise. La direction du groupe LOGOSYS, dirig\u00e9e par J\u00fcrgen Reinhard et Marcel N\u00fctzel, reste en place. Hans-J\u00fcrgen N\u00fctzel a comment\u00e9 l&rsquo;acquisition comme suit : <em>\u00ab\u00a0La pr\u00e9sence europ\u00e9enne et la philosophie de leadership commune entre LOGOSYS et le groupe pfenning \u00e9taient des crit\u00e8res d\u00e9cisifs pour cette transaction. Nous sommes convaincus que cette int\u00e9gration cr\u00e9e une situation gagnant-gagnant pour les deux entreprises et renforce notre capacit\u00e9 \u00e0 offrir des solutions innovantes.\u00a0\u00bb<\/em> Gr\u00e2ce \u00e0 la proximit\u00e9 g\u00e9ographique entre Heddesheim et Darmstadt, on s&rsquo;attend \u00e9galement \u00e0 une int\u00e9gration rapide et \u00e0 l&rsquo;utilisation de synergies mutuelles, a ajout\u00e9 N\u00fctzel.<\/p>\n<h5>\u00c9largissement de la gamme de services<\/h5>\n<p>Rana Matthias Nag, directeur g\u00e9n\u00e9ral du groupe pfenning, a ajout\u00e9 : \u00ab\u00a0<em>L&rsquo;int\u00e9gration de LOGOSYS dans notre groupe \u00e9largit notre gamme de services, en particulier dans les domaines de la pharmacie, de la sant\u00e9 et des cosm\u00e9tiques. Nous sommes confiants que cela nous permettra de r\u00e9pondre de mani\u00e8re encore plus cibl\u00e9e aux exigences dynamiques des cha\u00eenes d&rsquo;approvisionnement. Gr\u00e2ce \u00e0 l&rsquo;acquisition, nous \u00e9largissons non seulement notre expertise sectorielle, mais aussi nos activit\u00e9s dans la r\u00e9gion de Rhein-Main.<\/em>\u00a0\u00bb Dans le cadre de sa strat\u00e9gie de croissance, le groupe pfenning a d\u00e9j\u00e0 acquis sept autres entreprises depuis 2021, renfor\u00e7ant ainsi son portefeuille de services dans les domaines du commerce \u00e9lectronique et du traitement des commandes, des solutions de mobilit\u00e9, de la logistique de produits frais, des services de personnel, des services de transport, du r\u00e9seau de fret, de la gestion \u00e0 deux hommes et du co-emballage\/construction d&rsquo;affichages. Aujourd&rsquo;hui, le groupe pfenning emploie 7 000 personnes en Europe.<\/p>\n<p>Photo : \u00a9 pfenning logistics<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le groupe pfenning \u00e9largit son portefeuille de services gr\u00e2ce \u00e0 l&rsquo;acquisition strat\u00e9gique du groupe de logistique pharmaceutique LOGOSYS bas\u00e9 \u00e0 Darmstadt. La transaction, r\u00e9troactive au 1er<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-65317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le groupe pfenning acquiert le logisticien pharmaceutique LOGOSYS - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le groupe pfenning acquiert le logisticien pharmaceutique LOGOSYS - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Le groupe pfenning \u00e9largit son portefeuille de services gr\u00e2ce \u00e0 l&rsquo;acquisition strat\u00e9gique du groupe de logistique pharmaceutique LOGOSYS bas\u00e9 \u00e0 Darmstadt. La transaction, r\u00e9troactive au 1er [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-21T17:38:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_21.5.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1241\" \/>\n\t<meta property=\"og:image:height\" content=\"796\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Le groupe pfenning acquiert le logisticien pharmaceutique LOGOSYS\",\"datePublished\":\"2024-05-21T17:38:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/\"},\"wordCount\":617,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/pfenning_21.5.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/\",\"name\":\"Le groupe pfenning acquiert le logisticien pharmaceutique LOGOSYS - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/pfenning_21.5.24.jpg\",\"datePublished\":\"2024-05-21T17:38:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/pfenning_21.5.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/pfenning_21.5.24.jpg\",\"width\":1241,\"height\":796},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/21\\\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le groupe pfenning acquiert le logisticien pharmaceutique LOGOSYS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le groupe pfenning acquiert le logisticien pharmaceutique LOGOSYS - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/","og_locale":"fr_FR","og_type":"article","og_title":"Le groupe pfenning acquiert le logisticien pharmaceutique LOGOSYS - Loginfo24.","og_description":"Le groupe pfenning \u00e9largit son portefeuille de services gr\u00e2ce \u00e0 l&rsquo;acquisition strat\u00e9gique du groupe de logistique pharmaceutique LOGOSYS bas\u00e9 \u00e0 Darmstadt. La transaction, r\u00e9troactive au 1er [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-05-21T17:38:13+00:00","og_image":[{"width":1241,"height":796,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_21.5.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/"},"author":{"name":"","@id":""},"headline":"Le groupe pfenning acquiert le logisticien pharmaceutique LOGOSYS","datePublished":"2024-05-21T17:38:13+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/"},"wordCount":617,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_21.5.24.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/","url":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/","name":"Le groupe pfenning acquiert le logisticien pharmaceutique LOGOSYS - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_21.5.24.jpg","datePublished":"2024-05-21T17:38:13+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_21.5.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_21.5.24.jpg","width":1241,"height":796},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/21\/le-groupe-pfenning-acquiert-le-logisticien-pharmaceutique-logosys\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le groupe pfenning acquiert le logisticien pharmaceutique LOGOSYS"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/65317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=65317"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/65317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/6506"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=65317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=65317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=65317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}