{"id":65203,"date":"2024-05-10T19:35:22","date_gmt":"2024-05-10T17:35:22","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/"},"modified":"2024-05-10T19:35:22","modified_gmt":"2024-05-10T17:35:22","slug":"trailer-dynamics-et-thermo-king-unissent-leurs-forces","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/","title":{"rendered":"Trailer Dynamics et Thermo King unissent leurs forces"},"content":{"rendered":"<h5>Trailer Dynamics, un innovateur technologique d&rsquo;eTrailers, a annonc\u00e9 que Trane Technologies (NYSE: TT), un leader mondial de l&rsquo;innovation climatique, ax\u00e9 sur des solutions durables pour les b\u00e2timents, les logements et le transport, ainsi que sa marque Thermo King, sont devenus investisseurs minoritaires strat\u00e9giques et partenaires de coop\u00e9ration de Trailer Dynamics, aux c\u00f4t\u00e9s du fabricant de remorques allemand Krone. La coop\u00e9ration stimulera les innovations qui am\u00e9lioreront l&rsquo;efficacit\u00e9, acc\u00e9l\u00e9reront la transition vers un transport sans \u00e9missions en Europe et r\u00e9duiront les \u00e9missions de gaz \u00e0 effet de serre.<\/h5>\n<p>(Eschweiler) L&rsquo;eTrailer de Trailer Dynamics offre une assistance \u00e9lectrique qui, en combinaison avec des tracteurs conventionnels \u00e0 moteur \u00e0 combustion, permet une r\u00e9duction significative des \u00e9missions de diesel et de CO\u2082, augmente l&rsquo;autonomie en combinaison avec un tracteur \u00e9lectrique et offre la possibilit\u00e9 d&rsquo;alimenter des unit\u00e9s de r\u00e9frig\u00e9ration de remorque (TRUs) \u00e9lectrifi\u00e9es ou conventionnelles.<\/p>\n<p>Thermo King apportera son expertise en mati\u00e8re d&rsquo;\u00e9lectrification et de r\u00e9frig\u00e9ration du transport. La collaboration permettra l&rsquo;int\u00e9gration de technologies qui r\u00e9volutionneront l&rsquo;industrie et offriront de meilleures possibilit\u00e9s logistiques pour le commerce, l&rsquo;industrie et les transporteurs lors du transport de marchandises fra\u00eeches et congel\u00e9es. Abdullah Jaber, directeur g\u00e9n\u00e9ral et PDG de Trailer Dynamics, est enthousiaste \u00e0 propos du partenariat. \u00ab\u00a0Nous sommes impatients de combiner notre technologie et notre exp\u00e9rience d&rsquo;eTrailer avec le savoir-faire de Thermo King, leader du secteur, pour d\u00e9velopper ensemble des produits exceptionnels et acc\u00e9l\u00e9rer la transition de l&rsquo;Europe vers un transport sans \u00e9missions.\u00a0\u00bb<\/p>\n<h5>Am\u00e9lioration de la capacit\u00e9 d&rsquo;innovation et du portefeuille de produits<\/h5>\n<p>Gr\u00e2ce \u00e0 l&rsquo;int\u00e9gration de la technologie innovante de Trailer Dynamics, Thermo King am\u00e9liorera sa capacit\u00e9 d&rsquo;innovation et son portefeuille de produits, renforcera son engagement en faveur de la durabilit\u00e9, fera avancer des changements positifs dans l&rsquo;industrie et r\u00e9pondra aux exigences des clients et des r\u00e9glementations. \u00ab\u00a0Nous sommes ravis de combiner nos forces avec Trailer Dynamics et d&rsquo;investir ensemble dans une technologie de remorque \u00e9lectrifi\u00e9e \u00e0 la pointe, qui contribuera \u00e0 acc\u00e9l\u00e9rer les efforts de d\u00e9carbonisation dans l&rsquo;industrie du transport commercial et de la cha\u00eene du froid\u00a0\u00bb, a d\u00e9clar\u00e9 Claudio Zanframundo, pr\u00e9sident de Thermo King EMEA. \u00ab\u00a0Nous sommes fiers de nos actions audacieuses et de notre engagement envers l&rsquo;introduction de nouvelles technologies, et la collaboration avec d&rsquo;autres pionniers technologiques acc\u00e9l\u00e9rera notre impact.\u00a0\u00bb<\/p>\n<h5>La transformation sera nettement acc\u00e9l\u00e9r\u00e9e<\/h5>\n<p>Dr. Stefan Binnewies, pr\u00e9sident du conseil de Trailer Dynamics, a ajout\u00e9 : \u00ab\u00a0La d\u00e9carbonisation du transport routier de marchandises ne peut r\u00e9ussir rapidement qu&rsquo;avec de solides partenariats. Avec Trane Technologies en tant que nouvel actionnaire strat\u00e9gique de Trailer Dynamics aux c\u00f4t\u00e9s de Krone, la transformation n\u00e9cessaire sera nettement acc\u00e9l\u00e9r\u00e9e.\u00a0\u00bb<\/p>\n<p>Photo : \u00a9 Trailer Dynamics<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trailer Dynamics, un innovateur technologique d&rsquo;eTrailers, a annonc\u00e9 que Trane Technologies (NYSE: TT), un leader mondial de l&rsquo;innovation climatique, ax\u00e9 sur des solutions durables pour les<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6546,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-65203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trailer Dynamics et Thermo King unissent leurs forces - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trailer Dynamics et Thermo King unissent leurs forces - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Trailer Dynamics, un innovateur technologique d&rsquo;eTrailers, a annonc\u00e9 que Trane Technologies (NYSE: TT), un leader mondial de l&rsquo;innovation climatique, ax\u00e9 sur des solutions durables pour les [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-10T17:35:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Trailer_Dynamics_10.5.24_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1269\" \/>\n\t<meta property=\"og:image:height\" content=\"769\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trailer Dynamics et Thermo King unissent leurs forces\",\"datePublished\":\"2024-05-10T17:35:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/\"},\"wordCount\":501,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Trailer_Dynamics_10.5.24_2.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/\",\"name\":\"Trailer Dynamics et Thermo King unissent leurs forces - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Trailer_Dynamics_10.5.24_2.jpg\",\"datePublished\":\"2024-05-10T17:35:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Trailer_Dynamics_10.5.24_2.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Trailer_Dynamics_10.5.24_2.jpg\",\"width\":1269,\"height\":769},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/10\\\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trailer Dynamics et Thermo King unissent leurs forces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trailer Dynamics et Thermo King unissent leurs forces - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/","og_locale":"fr_FR","og_type":"article","og_title":"Trailer Dynamics et Thermo King unissent leurs forces - Loginfo24.","og_description":"Trailer Dynamics, un innovateur technologique d&rsquo;eTrailers, a annonc\u00e9 que Trane Technologies (NYSE: TT), un leader mondial de l&rsquo;innovation climatique, ax\u00e9 sur des solutions durables pour les [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-05-10T17:35:22+00:00","og_image":[{"width":1269,"height":769,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Trailer_Dynamics_10.5.24_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/"},"author":{"name":"","@id":""},"headline":"Trailer Dynamics et Thermo King unissent leurs forces","datePublished":"2024-05-10T17:35:22+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/"},"wordCount":501,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Trailer_Dynamics_10.5.24_2.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/","url":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/","name":"Trailer Dynamics et Thermo King unissent leurs forces - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Trailer_Dynamics_10.5.24_2.jpg","datePublished":"2024-05-10T17:35:22+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Trailer_Dynamics_10.5.24_2.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Trailer_Dynamics_10.5.24_2.jpg","width":1269,"height":769},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/10\/trailer-dynamics-et-thermo-king-unissent-leurs-forces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Trailer Dynamics et Thermo King unissent leurs forces"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/65203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=65203"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/65203\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/6546"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=65203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=65203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=65203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}