{"id":65149,"date":"2024-05-06T20:43:21","date_gmt":"2024-05-06T18:43:21","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/"},"modified":"2024-05-06T20:43:21","modified_gmt":"2024-05-06T18:43:21","slug":"mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/","title":{"rendered":"Mercedes-Benz Trucks envoie l&rsquo;eActros en longue p\u00e9riode d&rsquo;essai"},"content":{"rendered":"<h5>Mercedes-Benz Trucks pr\u00e9voit de r\u00e9aliser cet \u00e9t\u00e9 la plus grande p\u00e9riode d&rsquo;essai de son histoire \u2013 avec son nouveau vaisseau amiral \u00e9lectrique, l&rsquo;eActros 600. Deux prototypes proches de la s\u00e9rie du camion de transport longue distance \u00e0 batterie \u00e9lectrique doivent parcourir plus de 13 000 kilom\u00e8tres \u00e0 travers plus de 20 pays europ\u00e9ens, chacun avec un poids total de 40 tonnes.<\/h5>\n<p>(Leinfelden-Echterdingen\/W\u00f6rth am Rhein) Mercedes-Benz Trucks vise d&rsquo;une part \u00e0 acqu\u00e9rir une vaste exp\u00e9rience sur des itin\u00e9raires vari\u00e9s dans diff\u00e9rentes topographies et zones climatiques en ce qui concerne la consommation d&rsquo;\u00e9nergie. Le fabricant souhaite ensuite partager ces connaissances avec des clients int\u00e9ress\u00e9s. D&rsquo;autre part, Mercedes-Benz Trucks veut prouver avec cette tourn\u00e9e qu&rsquo;un transport longue distance enti\u00e8rement \u00e9lectrique avec l&rsquo;eActros 600 est possible en Europe. Les batteries doivent \u00eatre recharg\u00e9es exclusivement \u00e0 des stations de recharge publiques. Bien que la mise en place d&rsquo;une infrastructure de recharge publique pour camions soit encore n\u00e9cessaire pour le d\u00e9veloppement ult\u00e9rieur du march\u00e9 des camions \u00e9lectriques, la \u00ab\u00a0eActros 600 European Testing Tour 2024\u00a0\u00bb \u2013 tel est le nom de ce voyage \u2013 doit envoyer un signal positif \u00e0 tous les acteurs concern\u00e9s. La grande capacit\u00e9 de la batterie de plus de 600 kilowattheures<sup>[1]<\/sup> ainsi qu&rsquo;un nouvel essieu de traction \u00e9lectrique particuli\u00e8rement efficace d\u00e9velopp\u00e9 en interne permettent une autonomie de 500 kilom\u00e8tres<sup>[2]<\/sup> sans recharge interm\u00e9diaire.<\/p>\n<p>Dr. Christof Weber, Responsable des essais mondiaux chez Mercedes-Benz Trucks : \u00ab Nous avons d\u00e9j\u00e0 test\u00e9 intensivement diff\u00e9rents prototypes de l&rsquo;eActros 600 ces derni\u00e8res ann\u00e9es. Que ce soit dans le nord de la Finlande ou dans le sud de l&rsquo;Espagne, il a d\u00e9j\u00e0 prouv\u00e9 ses capacit\u00e9s. Avec le d\u00e9veloppement de la s\u00e9rie, nous sommes maintenant sur la ligne d&rsquo;arriv\u00e9e. Avec la \u00ab\u00a0eActros 600 European Testing Tour 2024&Prime;, nous envoyons un message clair quelques mois avant le lancement de la s\u00e9rie \u00e0 la fin de l&rsquo;ann\u00e9e : nous sommes convaincus que les deux prototypes de l&rsquo;eActros 600 r\u00e9ussiront tr\u00e8s bien cet \u00e9norme d\u00e9fi, la plus grande p\u00e9riode d&rsquo;essai de Mercedes-Benz Trucks \u00e0 ce jour.\u00a0\u00bb<\/p>\n<h5>L&rsquo;int\u00e9r\u00eat des clients est tr\u00e8s \u00e9lev\u00e9<\/h5>\n<p>Stina Fagerman, Responsable Marketing, Ventes et Services chez Mercedes-Benz Trucks : \u00ab L&rsquo;int\u00e9r\u00eat des clients pour l&rsquo;eActros 600 est tr\u00e8s \u00e9lev\u00e9. Depuis le lancement des ventes \u00e0 la fin de l&rsquo;ann\u00e9e derni\u00e8re, nous avons d\u00e9j\u00e0 enregistr\u00e9 plus de 1 000 commandes fermes et nous avons \u00e9galement des d\u00e9clarations d&rsquo;intention dans le domaine des milliers. Cela est d&rsquo;autant plus impressionnant compte tenu du fait que les v\u00e9hicules de d\u00e9monstration pour les clients ne seront lanc\u00e9s qu&rsquo;au second semestre. De nombreux clients sont d\u00e9j\u00e0 convaincus par le v\u00e9hicule \u00e0 l&rsquo;avance. \u00bb<\/p>\n<p>Fagerman ajoute : \u00ab Avec la \u00ab\u00a0eActros 600 European Testing Tour 2024\u00a0\u00bb, notre objectif est d&rsquo;\u00e9largir notre expertise en mati\u00e8re de consommation et d&rsquo;applications des camions \u00e9lectriques dans des conditions vari\u00e9es, afin de pouvoir conseiller nos clients de mani\u00e8re encore plus approfondie. De plus, nous souhaitons informer les d\u00e9cideurs politiques et du secteur de l&rsquo;\u00e9nergie ainsi que le grand public sur les possibilit\u00e9s de la propulsion enti\u00e8rement \u00e9lectrique dans le segment du transport longue distance et ainsi augmenter l&rsquo;\u00e9lan pour la mise en place de l&rsquo;infrastructure n\u00e9cessaire. \u00bb<\/p>\n<p>La eActros 600 European Testing Tour doit commencer le 11 juin \u00e0 Francfort-sur-le-Main et sera accompagn\u00e9e de mani\u00e8re m\u00e9diatique. De mani\u00e8re informelle, elle commence d\u00e9j\u00e0 la veille sur le site de Mercedes-Benz Trucks \u00e0 W\u00f6rth am Rhein ainsi qu&rsquo;au si\u00e8ge de Daimler Truck AG \u00e0 Leinfelden-Echterdingen. Mercedes-Benz Trucks pr\u00e9voit de communiquer d&rsquo;autres d\u00e9tails, par exemple sur l&rsquo;itin\u00e9raire autour du lancement de la tourn\u00e9e.<\/p>\n<h5><strong>Exp\u00e9riences de la E-Tour \u00e0 travers l&rsquo;Europe<\/strong><\/h5>\n<p>Mercedes-Benz Trucks a d\u00e9j\u00e0 r\u00e9alis\u00e9 l&rsquo;ann\u00e9e derni\u00e8re une tourn\u00e9e de vente \u00e0 travers l&rsquo;Europe autour de l&rsquo;eActros 300\/400 pour le transport lourd de distribution. Trois camions \u00e9lectriques ont parcouru chacun plus de 5 000 kilom\u00e8tres \u00e0 travers l&rsquo;Allemagne, l&rsquo;Autriche, l&rsquo;Italie, les Pays-Bas et la Belgique. Au total, la vente de Mercedes-Benz Trucks a organis\u00e9 14 \u00e9v\u00e9nements clients avec plus de 1 500 invit\u00e9s et 1 250 essais de conduite.<\/p>\n<p>Photo : \u00a9 Mercedes-Benz Truck<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercedes-Benz Trucks pr\u00e9voit de r\u00e9aliser cet \u00e9t\u00e9 la plus grande p\u00e9riode d&rsquo;essai de son histoire \u2013 avec son nouveau vaisseau amiral \u00e9lectrique, l&rsquo;eActros 600. Deux prototypes<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-65149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercedes-Benz Trucks envoie l&#039;eActros en longue p\u00e9riode d&#039;essai - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercedes-Benz Trucks envoie l&#039;eActros en longue p\u00e9riode d&#039;essai - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Mercedes-Benz Trucks pr\u00e9voit de r\u00e9aliser cet \u00e9t\u00e9 la plus grande p\u00e9riode d&rsquo;essai de son histoire \u2013 avec son nouveau vaisseau amiral \u00e9lectrique, l&rsquo;eActros 600. Deux prototypes [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-06T18:43:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mercedes_Truck_6.5.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1331\" \/>\n\t<meta property=\"og:image:height\" content=\"713\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mercedes-Benz Trucks envoie l&rsquo;eActros en longue p\u00e9riode d&rsquo;essai\",\"datePublished\":\"2024-05-06T18:43:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/\"},\"wordCount\":733,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Mercedes_Truck_6.5.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/\",\"name\":\"Mercedes-Benz Trucks envoie l'eActros en longue p\u00e9riode d'essai - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Mercedes_Truck_6.5.24.jpg\",\"datePublished\":\"2024-05-06T18:43:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Mercedes_Truck_6.5.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Mercedes_Truck_6.5.24.jpg\",\"width\":1331,\"height\":713},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/05\\\/06\\\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercedes-Benz Trucks envoie l&rsquo;eActros en longue p\u00e9riode d&rsquo;essai\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercedes-Benz Trucks envoie l'eActros en longue p\u00e9riode d'essai - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/","og_locale":"fr_FR","og_type":"article","og_title":"Mercedes-Benz Trucks envoie l'eActros en longue p\u00e9riode d'essai - Loginfo24.","og_description":"Mercedes-Benz Trucks pr\u00e9voit de r\u00e9aliser cet \u00e9t\u00e9 la plus grande p\u00e9riode d&rsquo;essai de son histoire \u2013 avec son nouveau vaisseau amiral \u00e9lectrique, l&rsquo;eActros 600. Deux prototypes [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-05-06T18:43:21+00:00","og_image":[{"width":1331,"height":713,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mercedes_Truck_6.5.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/"},"author":{"name":"","@id":""},"headline":"Mercedes-Benz Trucks envoie l&rsquo;eActros en longue p\u00e9riode d&rsquo;essai","datePublished":"2024-05-06T18:43:21+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/"},"wordCount":733,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mercedes_Truck_6.5.24.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/","url":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/","name":"Mercedes-Benz Trucks envoie l'eActros en longue p\u00e9riode d'essai - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mercedes_Truck_6.5.24.jpg","datePublished":"2024-05-06T18:43:21+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mercedes_Truck_6.5.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mercedes_Truck_6.5.24.jpg","width":1331,"height":713},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2024\/05\/06\/mercedes-benz-trucks-envoie-leactros-en-longue-periode-dessai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Mercedes-Benz Trucks envoie l&rsquo;eActros en longue p\u00e9riode d&rsquo;essai"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/65149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=65149"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/65149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/6572"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=65149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=65149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=65149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}