{"id":64693,"date":"2024-03-26T16:53:29","date_gmt":"2024-03-26T15:53:29","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/"},"modified":"2024-03-26T16:53:29","modified_gmt":"2024-03-26T15:53:29","slug":"alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/","title":{"rendered":"Alltron distribue le drone de charge \u00abFlyCart 30\u00bb de DJI en Suisse"},"content":{"rendered":"<div class=\"article-block article-block__p viewport-section in-viewport\">\n<h5><strong>Alltron a obtenu de DJI, le leader mondial des multicopt\u00e8res industriels, le contrat pour la distribution en Suisse du drone de charge \u00abFlyCart 30\u00bb. Le FlyCart 30, large de 3,2 m\u00e8tres, est \u00e9quip\u00e9 d&rsquo;un multirotor \u00e0 quatre axes avec huit h\u00e9lices ainsi que de batteries de vol doubles en configuration de redondance. La charge utile peut \u00eatre transport\u00e9e via une bo\u00eete de chargement avec optimisation automatique de la r\u00e9partition du poids ou un treuil avec l\u00e2cher de c\u00e2ble d&rsquo;urgence.<\/strong><\/h5>\n<\/div>\n<div class=\"article-block article-block__p viewport-section in-viewport\">(M\u00e4genwil) Pour une meilleure stabilit\u00e9 de vol et une s\u00e9curit\u00e9 accrue, la \u00abFlyCart 30\u00bb est dot\u00e9e de syst\u00e8mes tels que l&rsquo;\u00e9vitement intelligent des obstacles via des syst\u00e8mes optiques et radar, un parachute int\u00e9gr\u00e9, un r\u00e9cepteur ADS-B pour les donn\u00e9es de position des a\u00e9ronefs et une projection en r\u00e9alit\u00e9 augment\u00e9e. Le pilote fait voler le syst\u00e8me \u2013 \u00e0 distance \u00abau-del\u00e0 de la ligne de vue\u00bb \u2013 sur un itin\u00e9raire programm\u00e9. Bien s\u00fbr, il est \u00e9galement possible de voler directement \u00e0 vue via la t\u00e9l\u00e9commande.<\/p>\n<div class=\"article-block article-block__h2 viewport-section in-viewport\">\n<h5>Exploitation soumise \u00e0 autorisation<\/h5>\n<\/div>\n<div class=\"article-block article-block__p viewport-section in-viewport\">Le DJI FlyCart 30 peut transporter une charge utile allant jusqu&rsquo;\u00e0 30 kilogrammes sur une distance allant jusqu&rsquo;\u00e0 16 kilom\u00e8tres dans des conditions optimales. En Chine, il est par exemple utilis\u00e9 pour des livraisons depuis le continent vers des navires de fret naviguant sur le fleuve Yangts\u00e9, rempla\u00e7ant ainsi les transports par bateau ou les vols en h\u00e9licopt\u00e8re. En Suisse, Alltron envisage des op\u00e9rations de drones en haute montagne pour atteindre des chantiers isol\u00e9s, des refuges de montagne ou des installations de production d&rsquo;\u00e9lectricit\u00e9. Des interventions en cas de catastrophe, pour approvisionner des zones coup\u00e9es du monde, sont \u00e9galement envisageables. L&rsquo;exploitation de tels drones de charge est bien entendu strictement r\u00e9glement\u00e9e et soumise \u00e0 autorisation. Comme l&rsquo;explique le distributeur argovien, il ne fournit pas seulement la solution de drone, mais pr\u00e9voit \u00e9galement \u2013 en collaboration avec un sp\u00e9cialiste de la s\u00e9curit\u00e9 et de la conformit\u00e9 l\u00e9gale pour les vols de drones \u2013 des services d&rsquo;accompagnement appropri\u00e9s pour aider les partenaires int\u00e9ress\u00e9s \u00e0 travers le processus d&rsquo;autorisation \u00abSpecific Operations Risk Assessment\u00bb pour les op\u00e9rations de drones. Une \u00e9tude de faisabilit\u00e9 a confirm\u00e9 les chances de succ\u00e8s du projet, et il y a d\u00e9j\u00e0 des premiers int\u00e9ress\u00e9s pour des applications de transport par drone, indique-t-on depuis M\u00e4genwil.<\/p>\n<div class=\"article-block article-block__h2 viewport-section in-viewport\">\n<h5>Extension de la collaboration<\/h5>\n<\/div>\n<div class=\"article-block article-block__p viewport-section in-viewport\">Alltron collabore avec DJI Enterprise au niveau de la distribution depuis 2020 et a d\u00e9j\u00e0 vendu un nombre \u00e0 quatre chiffres de drones pour un usage professionnel\/industriel. Cette collaboration fructueuse constitue \u00e9galement la base pour qu&rsquo;Alltron ait pu remporter l&rsquo;appel d&rsquo;offres pour la distribution des nouveaux drones de livraison de DJI. \u00abNous remercions DJI Enterprise pour la confiance accord\u00e9e, permettant aux partenaires d&rsquo;Alltron d&rsquo;\u00eatre parfaitement soutenus pour r\u00e9aliser des op\u00e9rations de drones s\u00fbres, conformes et r\u00e9ussies\u00bb, d\u00e9clare Andrea Savoca, responsable des solutions ICT chez Alltron. Le cr\u00e9neau de march\u00e9 n&rsquo;est pas particuli\u00e8rement grand, mais il est tout de m\u00eame int\u00e9ressant, r\u00e9pond Savoca \u00e0 la question de savoir si cela vaut \u00e9conomiquement la peine pour Alltron. Contrairement aux fabrications sur mesure, le FlyCart 30 est sur le plan technique une solution quasi pr\u00eate \u00e0 l&#8217;emploi, selon Savoca. Compar\u00e9 aux vols de petites charges par h\u00e9licopt\u00e8re, les co\u00fbts d&rsquo;acquisition et d&rsquo;exploitation sont relativement bas, gr\u00e2ce \u00e0 l&rsquo;alimentation par batterie, l&rsquo;op\u00e9ration de drone est selon Andrea Savoca quasiment sans \u00e9missions, et le niveau sonore est \u00e9galement plus agr\u00e9able que celui d&rsquo;un h\u00e9licopt\u00e8re.<br \/>Photo\/Video: \u00a9 Alltron<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alltron a obtenu de DJI, le leader mondial des multicopt\u00e8res industriels, le contrat pour la distribution en Suisse du drone de charge \u00abFlyCart 30\u00bb. Le FlyCart<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558,1557,1561],"tags":[],"class_list":["post-64693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-air-freight","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alltron distribue le drone de charge \u00abFlyCart 30\u00bb de DJI en Suisse - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alltron distribue le drone de charge \u00abFlyCart 30\u00bb de DJI en Suisse - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Alltron a obtenu de DJI, le leader mondial des multicopt\u00e8res industriels, le contrat pour la distribution en Suisse du drone de charge \u00abFlyCart 30\u00bb. Le FlyCart [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-26T15:53:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/alltron_26.3.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1202\" \/>\n\t<meta property=\"og:image:height\" content=\"742\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Alltron distribue le drone de charge \u00abFlyCart 30\u00bb de DJI en Suisse\",\"datePublished\":\"2024-03-26T15:53:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/\"},\"wordCount\":633,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/alltron_26.3.24.jpg\",\"articleSection\":[\"Air Freight\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/\",\"name\":\"Alltron distribue le drone de charge \u00abFlyCart 30\u00bb de DJI en Suisse - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/alltron_26.3.24.jpg\",\"datePublished\":\"2024-03-26T15:53:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/alltron_26.3.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/alltron_26.3.24.jpg\",\"width\":1202,\"height\":742},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/03\\\/26\\\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alltron distribue le drone de charge \u00abFlyCart 30\u00bb de DJI en Suisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alltron distribue le drone de charge \u00abFlyCart 30\u00bb de DJI en Suisse - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/","og_locale":"fr_FR","og_type":"article","og_title":"Alltron distribue le drone de charge \u00abFlyCart 30\u00bb de DJI en Suisse - Loginfo24.","og_description":"Alltron a obtenu de DJI, le leader mondial des multicopt\u00e8res industriels, le contrat pour la distribution en Suisse du drone de charge \u00abFlyCart 30\u00bb. Le FlyCart [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-03-26T15:53:29+00:00","og_image":[{"width":1202,"height":742,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/alltron_26.3.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/"},"author":{"name":"","@id":""},"headline":"Alltron distribue le drone de charge \u00abFlyCart 30\u00bb de DJI en Suisse","datePublished":"2024-03-26T15:53:29+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/"},"wordCount":633,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/alltron_26.3.24.jpg","articleSection":["Air Freight","Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/","url":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/","name":"Alltron distribue le drone de charge \u00abFlyCart 30\u00bb de DJI en Suisse - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/alltron_26.3.24.jpg","datePublished":"2024-03-26T15:53:29+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/alltron_26.3.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/alltron_26.3.24.jpg","width":1202,"height":742},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2024\/03\/26\/alltron-distribue-le-drone-de-charge-flycart-30-de-dji-en-suisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Alltron distribue le drone de charge \u00abFlyCart 30\u00bb de DJI en Suisse"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/64693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=64693"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/64693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/6749"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=64693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=64693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=64693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}