{"id":64032,"date":"2024-02-04T15:12:38","date_gmt":"2024-02-04T14:12:38","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/"},"modified":"2024-02-04T15:12:38","modified_gmt":"2024-02-04T14:12:38","slug":"raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/","title":{"rendered":"Raben teste le carburant diesel renouvelable HVO100 \u00e0 Hambourg"},"content":{"rendered":"<h5>Le groupe Raben souhaite faire avancer la transition des transports et voit un grand potentiel dans les carburants alternatifs. C&rsquo;est pourquoi le prestataire logistique europ\u00e9en a lanc\u00e9 un projet pilote avec le carburant diesel renouvelable HVO100 \u00e0 des fins de recherche et d&rsquo;essai, visant \u00e0 r\u00e9duire significativement les \u00e9missions. Depuis la mi-octobre, des v\u00e9hicules utilitaires fonctionnant au HVO100 sont en service dans le nord de l&rsquo;Allemagne. Ils circulent dans le transport de fret de Hambourg, dans le nord de l&rsquo;Allemagne et jusqu&rsquo;en Scandinavie. Par rapport au diesel fossile, Raben r\u00e9duit ainsi les \u00e9missions de transport jusqu&rsquo;\u00e0 86 %.<\/h5>\n<p>(Mannheim\/Hambourg) HVO \u2013 Huile V\u00e9g\u00e9tale Hydrog\u00e9n\u00e9e (huile v\u00e9g\u00e9tale hydrog\u00e9n\u00e9e) \u2013 est un carburant de remplacement synth\u00e9tique et hautement pur pour le diesel conventionnel, produit \u00e0 partir de graisses et d&rsquo;huiles r\u00e9siduelles hydrog\u00e9n\u00e9es par r\u00e9action. Il remplit, \u00e0 l&rsquo;exception de la densit\u00e9, toutes les caract\u00e9ristiques du carburant diesel. Il peut \u00eatre utilis\u00e9 sans restriction et sans souci dans tous les v\u00e9hicules diesel courants qui sont homologu\u00e9s selon la norme europ\u00e9enne 15940.<\/p>\n<h5><strong>Avec HVO100, r\u00e9duire les \u00e9missions de 703.339 kilogrammes de CO2 par an<\/strong><\/h5>\n<p>Raben a commenc\u00e9 \u00e0 utiliser deux camions HVO100 \u00e0 la mi-octobre. \u00c0 ce jour, huit poids lourds fonctionnant avec le carburant alternatif sont d\u00e9j\u00e0 sur la route. Ils ont jusqu&rsquo;\u00e0 pr\u00e9sent \u00e9t\u00e9 aliment\u00e9s exclusivement sur le site de l&rsquo;entreprise \u00e0 Hambourg. Suite \u00e0 la d\u00e9cision du cabinet f\u00e9d\u00e9ral, qui pr\u00e9voit que les stations-service puissent \u00e9galement proposer le HVO100 \u00e0 des fins de recherche et d&rsquo;essai, Raben souhaite, dans le cadre du projet, alimenter encore plus de camions de sa propre flotte avec le diesel paraffinique provenant de mati\u00e8res r\u00e9siduelles et de d\u00e9chets biologiques cette ann\u00e9e. Selon le fournisseur de HVO, Biofuel Express, Raben \u00e9conomise environ 86 % de CO2 gr\u00e2ce au carburant HVO100 par rapport \u00e0 un moteur fonctionnant au diesel, ce qui, pour huit v\u00e9hicules utilitaires, repr\u00e9sente une r\u00e9duction de 703.339 kilogrammes de CO2. Cette estimation est bas\u00e9e sur les environ 1.080.000 kilom\u00e8tres que Raben parcourt chaque ann\u00e9e avec les huit camions, ce qui correspond \u00e0 une consommation d&rsquo;environ 291.600 litres de diesel. Un litre de diesel \u00e9quivaut \u00e0 2,68 kilogrammes d&rsquo;\u00e9missions de CO2. Cela donne une \u00e9mission de CO2 d&rsquo;environ 781.488 kilogrammes.<\/p>\n<h5><strong>L&rsquo;utilisation simple du HVO100 est le principal avantage pour Raben<\/strong><\/h5>\n<p>Jusqu&rsquo;\u00e0 pr\u00e9sent, le test pilote a montr\u00e9 que l&rsquo;huile v\u00e9g\u00e9tale hydrog\u00e9n\u00e9e peut remplacer le diesel fossile de mani\u00e8re \u00e9quivalente. Le prestataire logistique n&rsquo;a \u00e9galement pas \u00e0 faire de compromis sur l&rsquo;autonomie. \u00ab\u00a0Pour nous, ce projet est une \u00e9tape importante vers la d\u00e9carbonisation de la flotte, afin d&rsquo;atteindre les ambitieux objectifs de r\u00e9duction des CO2\u00a0\u00bb, d\u00e9clare Philip Hansen, directeur des ventes et du marketing. Raben consid\u00e8re l&rsquo;utilisation simple du HVO100 comme un grand avantage. Pour pouvoir rouler avec ce carburant respectueux de l&rsquo;environnement, aucune adaptation des v\u00e9hicules ou des moteurs n&rsquo;est n\u00e9cessaire. Cependant, l&rsquo;utilisation est coordonn\u00e9e avec les fabricants des v\u00e9hicules. Le HVO peut \u00eatre utilis\u00e9 pur ou m\u00e9lang\u00e9 dans n&rsquo;importe quelle proportion avec du diesel fossile. L&rsquo;infrastructure existante des stations-service peut \u00e9galement \u00eatre utilis\u00e9e pour le HVO100. \u00ab\u00a0Nous savons quel impact a l&rsquo;exploitation de notre flotte sur l&rsquo;environnement, c&rsquo;est pourquoi nous ne voulons pas attendre, mais agir maintenant. C&rsquo;est pourquoi nous utilisons un carburant d&rsquo;origine biologique \u00e0 partir de graisses alimentaires usag\u00e9es qui ne sont pas en concurrence avec la production alimentaire\u00a0\u00bb, explique M. Hansen.<\/p>\n<h5><strong>Les carburants alternatifs sont un \u00e9l\u00e9ment cl\u00e9 de la strat\u00e9gie Eco2Way<\/strong><\/h5>\n<p>Le projet pilote est un \u00e9l\u00e9ment cl\u00e9 de la strat\u00e9gie d&rsquo;entreprise \u00ab\u00a0Eco2Way\u00a0\u00bb de Raben, qui vise \u00e0 r\u00e9duire significativement les \u00e9missions du transport et celles g\u00e9n\u00e9r\u00e9es par l&rsquo;entretien des b\u00e2timents et des infrastructures de chargement d&rsquo;ici 2030. En Pologne, Raben a test\u00e9 des camions \u00e9lectriques en collaboration avec IKEA pour le transport interne. Il y a quelques semaines, la nouvelle succursale \u00e0 Regensburg-Neutraubling a commenc\u00e9 ses activit\u00e9s. Comme le d\u00e9p\u00f4t \u00e0 Herborn, dans le Hesse, il s&rsquo;agit d&rsquo;un b\u00e2timent \u00e0 z\u00e9ro \u00e9mission. Chaque nouveau site doit \u00e9galement \u00eatre construit selon cette norme.<br \/>\nPhoto : \u00a9 Raben Group<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le groupe Raben souhaite faire avancer la transition des transports et voit un grand potentiel dans les carburants alternatifs. C&rsquo;est pourquoi le prestataire logistique europ\u00e9en a<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7008,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-64032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raben teste le carburant diesel renouvelable HVO100 \u00e0 Hambourg - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raben teste le carburant diesel renouvelable HVO100 \u00e0 Hambourg - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Le groupe Raben souhaite faire avancer la transition des transports et voit un grand potentiel dans les carburants alternatifs. C&rsquo;est pourquoi le prestataire logistique europ\u00e9en a [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-04T14:12:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Raben_4.2.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1303\" \/>\n\t<meta property=\"og:image:height\" content=\"756\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Raben teste le carburant diesel renouvelable HVO100 \u00e0 Hambourg\",\"datePublished\":\"2024-02-04T14:12:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/\"},\"wordCount\":737,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Raben_4.2.24.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/\",\"name\":\"Raben teste le carburant diesel renouvelable HVO100 \u00e0 Hambourg - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Raben_4.2.24.jpg\",\"datePublished\":\"2024-02-04T14:12:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Raben_4.2.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Raben_4.2.24.jpg\",\"width\":1303,\"height\":756},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2024\\\/02\\\/04\\\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raben teste le carburant diesel renouvelable HVO100 \u00e0 Hambourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raben teste le carburant diesel renouvelable HVO100 \u00e0 Hambourg - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/","og_locale":"fr_FR","og_type":"article","og_title":"Raben teste le carburant diesel renouvelable HVO100 \u00e0 Hambourg - Loginfo24.","og_description":"Le groupe Raben souhaite faire avancer la transition des transports et voit un grand potentiel dans les carburants alternatifs. C&rsquo;est pourquoi le prestataire logistique europ\u00e9en a [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-02-04T14:12:38+00:00","og_image":[{"width":1303,"height":756,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Raben_4.2.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/"},"author":{"name":"","@id":""},"headline":"Raben teste le carburant diesel renouvelable HVO100 \u00e0 Hambourg","datePublished":"2024-02-04T14:12:38+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/"},"wordCount":737,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Raben_4.2.24.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/","url":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/","name":"Raben teste le carburant diesel renouvelable HVO100 \u00e0 Hambourg - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Raben_4.2.24.jpg","datePublished":"2024-02-04T14:12:38+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Raben_4.2.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Raben_4.2.24.jpg","width":1303,"height":756},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2024\/02\/04\/raben-teste-le-carburant-diesel-renouvelable-hvo100-a-hambourg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Raben teste le carburant diesel renouvelable HVO100 \u00e0 Hambourg"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/64032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=64032"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/64032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/7008"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=64032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=64032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=64032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}