{"id":63328,"date":"2023-11-07T19:40:10","date_gmt":"2023-11-07T18:40:10","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/"},"modified":"2023-11-07T19:40:10","modified_gmt":"2023-11-07T18:40:10","slug":"blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/","title":{"rendered":"BLV-pro e.V. manifeste \u00e0 Heilbronn contre l&rsquo;augmentation des p\u00e9ages"},"content":{"rendered":"<h5><strong>Les entrepreneurs de transport et BLV-pro e.V. manifestent contre la concurrence logistique d\u00e9loyale et l&rsquo;augmentation des p\u00e9ages. Le 4 novembre, pr\u00e8s de 300 v\u00e9hicules ont r\u00e9pondu \u00e0 l&rsquo;appel \u00e0 une manifestation de protestation des entrepreneurs de transport en coop\u00e9ration avec le BLV-pro e.V. L&rsquo;\u00e9v\u00e9nement a eu lieu sur la Theresienwiese \u00e0 Heilbronn.<\/strong><\/h5>\n<p>(Zossen\/Heilbronn) Konstantin Popov, pr\u00e9sident du BLV-pro e.V., a expliqu\u00e9 de mani\u00e8re impressionnante la situation actuelle de la concurrence logistique d\u00e9loyale dans l&rsquo;UE et les cons\u00e9quences de l&rsquo;augmentation des p\u00e9ages. La manifestation de protestation a mis en \u00e9vidence le m\u00e9contentement, la col\u00e8re et la d\u00e9ception des citoyens, des entrepreneurs et des agriculteurs face \u00e0 la m\u00e9thode de la coalition Ampel. Les klaxons des camions faisaient entendre le m\u00e9contentement de mani\u00e8re bruyante. Les participants ont envoy\u00e9 un message clair contre l&rsquo;augmentation des p\u00e9ages, la concurrence d\u00e9loyale et les prix \u00e9lev\u00e9s.<\/p>\n<p>Le BLV-pro e.V. se distancie express\u00e9ment de tout groupe de droite ou extr\u00e9miste qui pourrait tenter de d\u00e9tourner le mouvement de protestation \u00e0 ses fins. Au centre se trouve uniquement la protestation commune des entreprises de transport avec leurs conducteurs. Le BLV-pro e.V. est convaincu que d&rsquo;autres manifestations de protestation suivront, comme le m\u00eame jour \u00e0 B\u00fcnde\/NRW avec environ 100 camions \u00e0 l&rsquo;initiative des entrepreneurs de transport.<\/p>\n<h5><strong>La prochaine fois, cela pourrait \u00eatre 1&rsquo;000 v\u00e9hicules<\/strong><\/h5>\n<p>Un hiver de protestation tumultueux se profile, et la politique devrait s&rsquo;y pr\u00e9parer. \u00c0 partir du 1er d\u00e9cembre 2023, lorsque les petites et moyennes entreprises de transport souffriront et que les cha\u00eenes d&rsquo;approvisionnement seront menac\u00e9es, il sera clair pour tous : le train n&rsquo;arrivera pas au champ et pas non plus au supermarch\u00e9 ! Thomas Hansche, porte-parole du BLV pro e.V., a soulign\u00e9 : Le 4 novembre, il y avait pr\u00e8s de 300 v\u00e9hicules, mais la prochaine fois, cela pourrait \u00eatre 1 000. Les transporteurs ne doivent pas \u00eatre contrari\u00e9s, car toute l&rsquo;\u00e9conomie et l&rsquo;approvisionnement en d\u00e9pendent. Des manifestations pourraient avoir lieu \u00e0 l&rsquo;\u00e9chelle nationale pendant plusieurs jours \u00e0 l&rsquo;avenir. Les petites et moyennes entreprises repr\u00e9sentent 80 % de l&rsquo;ensemble de la flotte de camions en Allemagne, tandis que les grands logisticiens ne poss\u00e8dent souvent m\u00eame pas leurs propres camions. Des lois ont \u00e9t\u00e9 adopt\u00e9es sans tenir compte des voix du secteur de mani\u00e8re ad\u00e9quate. Lorsque les roues s&rsquo;arr\u00eatent, les rayons des supermarch\u00e9s sont menac\u00e9s de se vider apr\u00e8s deux jours. Le BLV pro e.V. exhorte la politique \u00e0 reconsid\u00e9rer l&rsquo;augmentation des p\u00e9ages de 83 %.<\/p>\n<p>Konstantin Popov a ajout\u00e9 que les alternatives de propulsion et l&rsquo;infrastructure sur le march\u00e9 ne sont tout simplement pas disponibles. Par cons\u00e9quent, l&rsquo;augmentation des p\u00e9ages \u00e9tait une mauvaise d\u00e9cision politique qui n&rsquo;atteint pas les objectifs climatiques. Il a soutenu que l&rsquo;augmentation des p\u00e9ages est tout aussi inefficace pour la protection de l&rsquo;environnement et les objectifs climatiques que la taxe sur les v\u00e9hicules \u00e0 moteur en ce qui concerne les dommages caus\u00e9s aux routes. De plus, l&rsquo;augmentation des p\u00e9ages est le plus grand moteur d&rsquo;inflation de l&rsquo;histoire allemande et p\u00e8se \u00e9galement sur les citoyens.<\/p>\n<h5><strong>Le diesel professionnel pourrait signifier un all\u00e8gement possible<\/strong><\/h5>\n<p>Les entreprises de transport ne peuvent que partiellement r\u00e9percuter l&rsquo;augmentation des p\u00e9ages, mais doivent n\u00e9anmoins les pr\u00e9financer. La liquidit\u00e9 des entrepreneurs est d\u00e9j\u00e0 \u00e9puis\u00e9e et repr\u00e9sente une menace s\u00e9rieuse. Les entrepreneurs ont besoin de d\u00e9lais de paiement l\u00e9gaux raccourcis de 14 jours maximum, afin de ne pas avoir \u00e0 attendre leur argent, alors que dans le secteur, des d\u00e9lais de 60 jours et plus sont actuellement courants. L&rsquo;introduction du diesel professionnel \u00e0 partir du 1er janvier 2024 pourrait \u00eatre un all\u00e8gement possible pour les entreprises qui ne peuvent pas r\u00e9percuter les co\u00fbts sur leurs clients, et aussi pour les citoyens, car les co\u00fbts de transport n&rsquo;augmenteraient pas aussi rapidement.<\/p>\n<p>Photo : \u00a9 BLV-pro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les entrepreneurs de transport et BLV-pro e.V. manifestent contre la concurrence logistique d\u00e9loyale et l&rsquo;augmentation des p\u00e9ages. Le 4 novembre, pr\u00e8s de 300 v\u00e9hicules ont r\u00e9pondu<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-63328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BLV-pro e.V. manifeste \u00e0 Heilbronn contre l&#039;augmentation des p\u00e9ages - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BLV-pro e.V. manifeste \u00e0 Heilbronn contre l&#039;augmentation des p\u00e9ages - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Les entrepreneurs de transport et BLV-pro e.V. manifestent contre la concurrence logistique d\u00e9loyale et l&rsquo;augmentation des p\u00e9ages. Le 4 novembre, pr\u00e8s de 300 v\u00e9hicules ont r\u00e9pondu [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-07T18:40:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BLV_pro_6.11.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1304\" \/>\n\t<meta property=\"og:image:height\" content=\"814\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"BLV-pro e.V. manifeste \u00e0 Heilbronn contre l&rsquo;augmentation des p\u00e9ages\",\"datePublished\":\"2023-11-07T18:40:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/\"},\"wordCount\":700,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BLV_pro_6.11.23.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/\",\"name\":\"BLV-pro e.V. manifeste \u00e0 Heilbronn contre l'augmentation des p\u00e9ages - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BLV_pro_6.11.23.jpg\",\"datePublished\":\"2023-11-07T18:40:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BLV_pro_6.11.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BLV_pro_6.11.23.jpg\",\"width\":1304,\"height\":814},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/11\\\/07\\\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BLV-pro e.V. manifeste \u00e0 Heilbronn contre l&rsquo;augmentation des p\u00e9ages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BLV-pro e.V. manifeste \u00e0 Heilbronn contre l'augmentation des p\u00e9ages - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/","og_locale":"fr_FR","og_type":"article","og_title":"BLV-pro e.V. manifeste \u00e0 Heilbronn contre l'augmentation des p\u00e9ages - Loginfo24.","og_description":"Les entrepreneurs de transport et BLV-pro e.V. manifestent contre la concurrence logistique d\u00e9loyale et l&rsquo;augmentation des p\u00e9ages. Le 4 novembre, pr\u00e8s de 300 v\u00e9hicules ont r\u00e9pondu [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-11-07T18:40:10+00:00","og_image":[{"width":1304,"height":814,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BLV_pro_6.11.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/"},"author":{"name":"","@id":""},"headline":"BLV-pro e.V. manifeste \u00e0 Heilbronn contre l&rsquo;augmentation des p\u00e9ages","datePublished":"2023-11-07T18:40:10+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/"},"wordCount":700,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BLV_pro_6.11.23.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/","url":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/","name":"BLV-pro e.V. manifeste \u00e0 Heilbronn contre l'augmentation des p\u00e9ages - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BLV_pro_6.11.23.jpg","datePublished":"2023-11-07T18:40:10+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BLV_pro_6.11.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BLV_pro_6.11.23.jpg","width":1304,"height":814},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2023\/11\/07\/blv-pro-e-v-manifeste-a-heilbronn-contre-laugmentation-des-peages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"BLV-pro e.V. manifeste \u00e0 Heilbronn contre l&rsquo;augmentation des p\u00e9ages"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/63328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=63328"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/63328\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/7317"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=63328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=63328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=63328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}