{"id":62497,"date":"2023-08-31T19:57:16","date_gmt":"2023-08-31T17:57:16","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/"},"modified":"2023-08-31T19:57:16","modified_gmt":"2023-08-31T17:57:16","slug":"loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/","title":{"rendered":"L&rsquo;op\u00e9rateur du terminal \u00e0 conteneurs de Straubing-Sand est choisi"},"content":{"rendered":"<h5><strong>Un consortium d&rsquo;offres, compos\u00e9 du r\u00e9seau logistique Contargo, de la SFI GmbH et du groupe Ziegler, a remport\u00e9 un appel d&rsquo;offres europ\u00e9en pour l&rsquo;exploitation du nouveau terminal \u00e0 conteneurs bimodal \u00e0 Straubing-Sand. Le 30 ao\u00fbt, la nouvelle soci\u00e9t\u00e9 commune des soumissionnaires, la Contargo Combitrac Straubing-Sand GmbH, a sign\u00e9 le contrat de location d&rsquo;exploitation pour le terminal. Le d\u00e9but du contrat pour l&rsquo;exploitation du terminal est pr\u00e9vu pour le 2\u00e8me trimestre 2025.<\/strong><\/h5>\n<p>(Straubing) L&rsquo;installation sera construite par le port de Straubing-Sand sur une superficie d&rsquo;environ 50 000 m\u00e8tres carr\u00e9s. La phase de construction a d\u00e9j\u00e0 commenc\u00e9, et l&rsquo;ach\u00e8vement ainsi que la mise en service sont pr\u00e9vus pour le 2\u00e8me trimestre 2025. \u00c0 l&rsquo;avenir, jusqu&rsquo;\u00e0 dix trains par semaine devraient circuler au nouveau terminal. Gr\u00e2ce \u00e0 des \u00e9quipements de manutention mobiles, les marchandises, principalement des conteneurs, seront transf\u00e9r\u00e9es de la route vers le rail, c&rsquo;est-\u00e0-dire lev\u00e9es. Jusqu&rsquo;\u00e0 vingt emplois devraient \u00eatre cr\u00e9\u00e9s sur le site.<\/p>\n<p>\u00ab Le port de Straubing-Sand est depuis de nombreuses ann\u00e9es un pionnier dans le domaine de la durabilit\u00e9 gr\u00e2ce \u00e0 ses implantations et ses th\u00e8mes prioritaires \u00bb, d\u00e9clare Andreas L\u00f6ffert, directeur g\u00e9n\u00e9ral de Hafen Straubing-Sand GmbH. \u00ab Pour nous, la construction d&rsquo;une installation terminale pour le transport combin\u00e9 \u00e9tait une cons\u00e9quence logique, en accord avec nos objectifs de durabilit\u00e9. En effet, de telles installations de transport combin\u00e9 entra\u00eenent un transfert de biens \u00e9conomiques de la route vers le rail, contribuant ainsi \u00e0 la protection du climat et \u00e0 la r\u00e9duction de la circulation sur les routes nationales. \u00bb<\/p>\n<p>\u00ab Le transfert de conteneurs de la route vers le rail entra\u00eene une r\u00e9duction de 80 % des \u00e9missions de CO<sub>2<\/sub> li\u00e9es au transport \u00bb, d\u00e9clare Markus Schmid, directeur g\u00e9n\u00e9ral de SFI GmbH. \u00ab Nous avons une longue exp\u00e9rience dans les transports combin\u00e9s, c&rsquo;est-\u00e0-dire des transports tr\u00e8s respectueux de l&rsquo;environnement. Nous utilisons toujours l&rsquo;\u00e9quipement le plus moderne. \u00c0 l&rsquo;avenir, des camions \u00e0 motorisation alternative pourraient \u00e9galement jouer un r\u00f4le pour les livraisons, c&rsquo;est-\u00e0-dire les derniers kilom\u00e8tres du conteneur depuis l&rsquo;installation de transport combin\u00e9 jusqu&rsquo;aux lieux de chargement et de d\u00e9chargement. \u00bb<\/p>\n<p>La nouvelle installation de transport combin\u00e9 efficace et moderne devrait accro\u00eetre l&rsquo;attractivit\u00e9 des r\u00e9gions de Basse-Bavi\u00e8re et de Haute-Palatinat pour d&rsquo;autres implantations d&rsquo;entreprises. En particulier, les logisticiens, mais aussi l&rsquo;industrie manufacturi\u00e8re, appr\u00e9cient les avantages de telles installations, selon le consortium d&rsquo;offres. Dans un contexte de p\u00e9nurie croissante de conducteurs, les installations de transport combin\u00e9 offrent une fiabilit\u00e9 accrue dans le transport tout en r\u00e9duisant les co\u00fbts de transport.<\/p>\n<h5>Tr\u00e8s int\u00e9ressant pour la connexion ferroviaire<\/h5>\n<p>\u00ab L&#8217;emplacement du site dans le port de Straubing-Sand est tr\u00e8s int\u00e9ressant pour la connexion ferroviaire \u00bb, d\u00e9clare Andreas Sandner, directeur g\u00e9n\u00e9ral de Ziegler Holding GmbH. \u00ab Les marchandises produites \u00e0 l&rsquo;\u00e9tranger trouvent leur chemin vers les magasins locaux via les ports maritimes. Notre objectif est de connecter la r\u00e9gion non seulement aux grands ports maritimes d&rsquo;Allemagne, des Pays-Bas et de Belgique, mais aussi aux ports de l&rsquo;Adriatique. Cela permettra \u00e0 l&rsquo;\u00e9conomie exp\u00e9ditrice d&rsquo;avoir plus de flexibilit\u00e9. \u00bb<\/p>\n<p>La flexibilit\u00e9 accrue du transport devient de plus en plus importante dans un contexte de p\u00e9nurie de conducteurs et de cha\u00eenes d&rsquo;approvisionnement perturb\u00e9es. Le site de Straubing-Sand offrira donc \u00e9galement de la place pour le stockage de jusqu&rsquo;\u00e0 1 000 EVP (\u00c9quivalent Vingt Pieds \/ conteneurs de 20 pieds). Gr\u00e2ce \u00e0 des surfaces adjacentes, la zone de stockage peut m\u00eame \u00eatre \u00e9tendue. La possibilit\u00e9 de stockage temporaire des marchandises est significative, car les marchandises saisonni\u00e8res sont souvent livr\u00e9es \u00e0 l&rsquo;avance. Si les capacit\u00e9s du terminal ne suffisent pas, Contargo peut soutenir avec ses 24 installations.<\/p>\n<p>\u00ab Avec le nouveau site, nous \u00e9largissons non seulement notre r\u00e9seau en Bavi\u00e8re, mais nous r\u00e9pondons \u00e9galement \u00e0 la demande des clients pour des services de conteneurs neutres dans cette r\u00e9gion \u00bb, d\u00e9clare Thomas L\u00f6ffler, directeur g\u00e9n\u00e9ral de Contargo GmbH &amp; Co. KG. \u00ab Nous avons d\u00e9j\u00e0 plusieurs demandes de clients que nous ne pouvons actuellement pas satisfaire. Le site cr\u00e9e de nouveaux emplois, des capacit\u00e9s et de nouvelles opportunit\u00e9s dont toute la r\u00e9gion b\u00e9n\u00e9ficiera. \u00bb<\/p>\n<h5>Un site \u00e9tabli \u00e0 un bon emplacement<\/h5>\n<p>Le port de Straubing-Sand est un site \u00e9tabli o\u00f9, en raison de sa bonne situation avec acc\u00e8s \u00e0 la voie navigable, \u00e0 l&rsquo;autoroute f\u00e9d\u00e9rale et au r\u00e9seau ferroviaire, plusieurs entreprises logistiques se sont install\u00e9es ces derni\u00e8res ann\u00e9es. L&rsquo;\u00e9conomie biobas\u00e9e trouve \u00e9galement de bonnes conditions dans le port de Straubing-Sand, y compris un centre technologique et d&rsquo;incubation, une installation de d\u00e9monstration polyvalente pour la biotechnologie industrielle et des \u00e9tablissements de recherche extra-universitaires. Au total, 3 600 personnes sont employ\u00e9es dans les entreprises situ\u00e9es dans le port.<\/p>\n<p>Photo : \u00a9 Contargo \/ <em><strong>L\u00e9gende de l&rsquo;image <\/strong>(de g. \u00e0 d.) : Gerhard Sch\u00f6nbucher, responsable des biens, planification &amp; technique de Hafen Straubing-Sand GmbH, Benedikt Rupp, responsable de l&rsquo;expansion du r\u00e9seau Contargo GmbH &amp; Co.KG, J\u00f6rg Schubert, directeur g\u00e9n\u00e9ral de Contargo Combitrac Straubing-Sand GmbH, Andreas Sandner, directeur g\u00e9n\u00e9ral de Ziegler Holding GmbH, Markus Schmid, directeur g\u00e9n\u00e9ral de SFI GmbH, Thomas L\u00f6ffler, directeur g\u00e9n\u00e9ral de Contargo GmbH &amp; Co.KG, Andreas L\u00f6ffert, directeur g\u00e9n\u00e9ral de Hafen Straubing-Sand GmbH\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un consortium d&rsquo;offres, compos\u00e9 du r\u00e9seau logistique Contargo, de la SFI GmbH et du groupe Ziegler, a remport\u00e9 un appel d&rsquo;offres europ\u00e9en pour l&rsquo;exploitation du nouveau<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-62497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;op\u00e9rateur du terminal \u00e0 conteneurs de Straubing-Sand est choisi - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;op\u00e9rateur du terminal \u00e0 conteneurs de Straubing-Sand est choisi - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Un consortium d&rsquo;offres, compos\u00e9 du r\u00e9seau logistique Contargo, de la SFI GmbH et du groupe Ziegler, a remport\u00e9 un appel d&rsquo;offres europ\u00e9en pour l&rsquo;exploitation du nouveau [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-31T17:57:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Staubing_31.8.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1394\" \/>\n\t<meta property=\"og:image:height\" content=\"857\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"L&rsquo;op\u00e9rateur du terminal \u00e0 conteneurs de Straubing-Sand est choisi\",\"datePublished\":\"2023-08-31T17:57:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/\"},\"wordCount\":938,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Staubing_31.8.23.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/\",\"name\":\"L'op\u00e9rateur du terminal \u00e0 conteneurs de Straubing-Sand est choisi - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Staubing_31.8.23.jpg\",\"datePublished\":\"2023-08-31T17:57:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Staubing_31.8.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Staubing_31.8.23.jpg\",\"width\":1394,\"height\":857},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/31\\\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;op\u00e9rateur du terminal \u00e0 conteneurs de Straubing-Sand est choisi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'op\u00e9rateur du terminal \u00e0 conteneurs de Straubing-Sand est choisi - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/","og_locale":"fr_FR","og_type":"article","og_title":"L'op\u00e9rateur du terminal \u00e0 conteneurs de Straubing-Sand est choisi - Loginfo24.","og_description":"Un consortium d&rsquo;offres, compos\u00e9 du r\u00e9seau logistique Contargo, de la SFI GmbH et du groupe Ziegler, a remport\u00e9 un appel d&rsquo;offres europ\u00e9en pour l&rsquo;exploitation du nouveau [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-08-31T17:57:16+00:00","og_image":[{"width":1394,"height":857,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Staubing_31.8.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/"},"author":{"name":"","@id":""},"headline":"L&rsquo;op\u00e9rateur du terminal \u00e0 conteneurs de Straubing-Sand est choisi","datePublished":"2023-08-31T17:57:16+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/"},"wordCount":938,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Staubing_31.8.23.jpg","articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/","url":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/","name":"L'op\u00e9rateur du terminal \u00e0 conteneurs de Straubing-Sand est choisi - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Staubing_31.8.23.jpg","datePublished":"2023-08-31T17:57:16+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Staubing_31.8.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Staubing_31.8.23.jpg","width":1394,"height":857},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/31\/loperateur-du-terminal-a-conteneurs-de-straubing-sand-est-choisi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;op\u00e9rateur du terminal \u00e0 conteneurs de Straubing-Sand est choisi"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/62497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=62497"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/62497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/7659"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=62497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=62497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=62497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}