{"id":62223,"date":"2023-08-08T18:45:18","date_gmt":"2023-08-08T16:45:18","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/"},"modified":"2023-08-08T18:45:18","modified_gmt":"2023-08-08T16:45:18","slug":"yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/","title":{"rendered":"Yusen Logistics augmente ses capacit\u00e9s sur le site d&rsquo;Alzenau"},"content":{"rendered":"<h5>Yusen Logistics (Allemagne) GmbH s&rsquo;agrandit et augmente ses capacit\u00e9s sur le site bavarois d&rsquo;Alzenau \u00e0 environ 18 500 m\u00e8tres carr\u00e9s. Depuis le 1er juillet 2023, le prestataire mondial de services logistiques int\u00e9gr\u00e9s a \u00e9largi l&#8217;emplacement existant d&rsquo;environ 9 500 m\u00e8tres carr\u00e9s d&rsquo;espace de stockage et de bureaux. Le centre logistique d&rsquo;Alzenau est situ\u00e9 \u00e0 l&rsquo;est de Francfort, \u00e0 environ 30 minutes.<\/h5>\n<p>(Alzenau) La r\u00e9gion constitue un important n\u0153ud logistique, notamment gr\u00e2ce \u00e0 la proximit\u00e9 de l&rsquo;a\u00e9roport de Francfort, l&rsquo;un des plus grands a\u00e9roports d&rsquo;Europe. L&rsquo;autre succursale op\u00e9rationnelle de Yusen Logistics se trouve \u00e0 Cargo City S\u00fcd, directement sur le territoire de l&rsquo;a\u00e9roport de Francfort, dans une installation propre. La porte d&rsquo;entr\u00e9e de fret a\u00e9rien \u00e0 Francfort est certifi\u00e9e GDP. L&rsquo;entrep\u00f4t de 4 500 m\u00b2 \u00e0 Francfort est g\u00e9r\u00e9 par du personnel interne 24\/7, y compris la construction de palettes ULD (Unit Load Device) sur place.<\/p>\n<p>Avec un doublement de l&rsquo;entrep\u00f4t et du centre de distribution \u00e0 Alzenau, Yusen Logistics r\u00e9pond aux besoins de ses clients. L&rsquo;installation agrandie, situ\u00e9e directement le long de l&rsquo;autoroute A45, offre environ 15 000 emplacements pour palettes Euro et une zone de cross-dock.<\/p>\n<p>\u00ab Yusen Logistics Allemagne a connu une forte croissance ces derni\u00e8res ann\u00e9es. L&rsquo;expansion de notre r\u00e9seau dans le sud de l&rsquo;Allemagne reste d&rsquo;une grande importance pour nous, car cela nous permet de cro\u00eetre durablement avec nos clients et de r\u00e9pondre \u00e0 la demande croissante dans la r\u00e9gion \u00bb, d\u00e9clare Ivan Spikic, directeur r\u00e9gional de la logistique contractuelle et des transports terrestres chez Yusen Logistics (Allemagne) GmbH. En tant que sp\u00e9cialiste mondial des solutions compl\u00e8tes de cha\u00eene d&rsquo;approvisionnement, des transports de bout en bout ainsi que du stockage et de la distribution, Yusen Logistics offre \u00e0 ses clients un soutien professionnel de haute qualit\u00e9 dans tous les processus logistiques.<\/p>\n<h5>Divers services logistiques sur le site<\/h5>\n<p>Sur le site logistique d&rsquo;Alzenau, le prestataire international 3PL propose \u00e0 ses clients des travaux de pr\u00e9production externalis\u00e9s, y compris des travaux de tri, de reconditionnement dans des caisses de production (bo\u00eetes KLT), d&rsquo;autres travaux de pr\u00e9paration de commandes, des contr\u00f4les de qualit\u00e9 et des travaux de finition, du cross-docking, ainsi que de la logistique de distribution et d&rsquo;approvisionnement avec une flotte moderne propre.<\/p>\n<p>Le site d&rsquo;Alzenau, avec une surface de stockage consid\u00e9rablement grande, \u00e9quip\u00e9e de rayonnages, offre \u00e0 Yusen Logistics et \u00e0 ses clients beaucoup d&rsquo;espace avec d&rsquo;autres possibilit\u00e9s d&rsquo;expansion. L&rsquo;installation dispose de 20 quais et de 2 acc\u00e8s de plain-pied. L&rsquo;extension du site de Yusen Logistics \u00e0 Alzenau doit notamment contribuer au d\u00e9veloppement \u00e9conomique local en cr\u00e9ant des emplois suppl\u00e9mentaires tant dans le domaine commercial que dans le secteur de la production.<\/p>\n<h5>Plus de 160 000 m\u00e8tres carr\u00e9s d&rsquo;espace logistique \u00e0 l&rsquo;\u00e9chelle nationale<\/h5>\n<p>Avec l&rsquo;extension \u00e0 Alzenau en Bavi\u00e8re, Yusen Logistics Allemagne dispose de 13 sites \u00e0 l&rsquo;\u00e9chelle nationale avec plus de 160 000 m\u00e8tres carr\u00e9s d&rsquo;espace de stockage et de distribution. \u00c0 l&rsquo;\u00e9chelle mondiale, Yusen Logistics est pr\u00e9sent dans 47 pays \u00e0 plus de 680 sites avec plus de 2,9 millions de m\u00e8tres carr\u00e9s d&rsquo;espace de stockage.<\/p>\n<p>Photo : \u00a9 Yusen Logistics<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yusen Logistics (Allemagne) GmbH s&rsquo;agrandit et augmente ses capacit\u00e9s sur le site bavarois d&rsquo;Alzenau \u00e0 environ 18 500 m\u00e8tres carr\u00e9s. Depuis le 1er juillet 2023, le<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-62223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yusen Logistics augmente ses capacit\u00e9s sur le site d&#039;Alzenau - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yusen Logistics augmente ses capacit\u00e9s sur le site d&#039;Alzenau - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Yusen Logistics (Allemagne) GmbH s&rsquo;agrandit et augmente ses capacit\u00e9s sur le site bavarois d&rsquo;Alzenau \u00e0 environ 18 500 m\u00e8tres carr\u00e9s. Depuis le 1er juillet 2023, le [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-08T16:45:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Yusen_8.8.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1344\" \/>\n\t<meta property=\"og:image:height\" content=\"739\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Yusen Logistics augmente ses capacit\u00e9s sur le site d&rsquo;Alzenau\",\"datePublished\":\"2023-08-08T16:45:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/\"},\"wordCount\":564,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Yusen_8.8.23.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/\",\"name\":\"Yusen Logistics augmente ses capacit\u00e9s sur le site d'Alzenau - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Yusen_8.8.23.jpg\",\"datePublished\":\"2023-08-08T16:45:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Yusen_8.8.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Yusen_8.8.23.jpg\",\"width\":1344,\"height\":739},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/08\\\/08\\\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yusen Logistics augmente ses capacit\u00e9s sur le site d&rsquo;Alzenau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yusen Logistics augmente ses capacit\u00e9s sur le site d'Alzenau - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/","og_locale":"fr_FR","og_type":"article","og_title":"Yusen Logistics augmente ses capacit\u00e9s sur le site d'Alzenau - Loginfo24.","og_description":"Yusen Logistics (Allemagne) GmbH s&rsquo;agrandit et augmente ses capacit\u00e9s sur le site bavarois d&rsquo;Alzenau \u00e0 environ 18 500 m\u00e8tres carr\u00e9s. Depuis le 1er juillet 2023, le [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-08-08T16:45:18+00:00","og_image":[{"width":1344,"height":739,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Yusen_8.8.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/"},"author":{"name":"","@id":""},"headline":"Yusen Logistics augmente ses capacit\u00e9s sur le site d&rsquo;Alzenau","datePublished":"2023-08-08T16:45:18+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/"},"wordCount":564,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Yusen_8.8.23.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/","url":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/","name":"Yusen Logistics augmente ses capacit\u00e9s sur le site d'Alzenau - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Yusen_8.8.23.jpg","datePublished":"2023-08-08T16:45:18+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Yusen_8.8.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Yusen_8.8.23.jpg","width":1344,"height":739},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2023\/08\/08\/yusen-logistics-augmente-ses-capacites-sur-le-site-dalzenau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Yusen Logistics augmente ses capacit\u00e9s sur le site d&rsquo;Alzenau"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/62223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=62223"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/62223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/7785"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=62223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=62223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=62223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}