{"id":61216,"date":"2023-04-18T18:24:33","date_gmt":"2023-04-18T16:24:33","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/"},"modified":"2023-04-18T18:24:33","modified_gmt":"2023-04-18T16:24:33","slug":"kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/","title":{"rendered":"Kardex installe un syst\u00e8me AutoStore chez SABAG \u00e0 Rothenburg"},"content":{"rendered":"<h5><strong>Pour optimiser la logistique des petites pi\u00e8ces, Kardex r\u00e9alise pour SABAG Luzern AG un syst\u00e8me AutoStore hautement efficace au si\u00e8ge de l&rsquo;entreprise \u00e0 Rothenburg (Suisse). \u00c0 l&rsquo;avenir, de petits produits pour le march\u00e9 de la construction (sanitaire) seront stock\u00e9s de mani\u00e8re compacte.<\/strong> Depuis sa cr\u00e9ation en 1913, SABAG Holding est en pleine croissance dans le commerce des mat\u00e9riaux de construction et l&rsquo;am\u00e9nagement int\u00e9rieur. Aujourd&rsquo;hui, l&rsquo;entreprise familiale, dirig\u00e9e par la quatri\u00e8me g\u00e9n\u00e9ration, emploie plus de 1 000 personnes.<\/h5>\n<p>(Bellheim\/Rothenburg) SABAG Luzern AG, avec une surface logistique totale de 28 000 m\u00b2 (dont 2 000 m\u00b2 pour le secteur sanitaire), est situ\u00e9e \u00e0 CH-Rothenburg. De l\u00e0, toutes les commandes pour la Suisse centrale et Zurich sont exp\u00e9di\u00e9es \u2013 la pr\u00e9paration des commandes se faisait jusqu&rsquo;\u00e0 pr\u00e9sent manuellement.<\/p>\n<p><span id=\"hs_cos_wrapper_post_body\" class=\"hs_cos_wrapper hs_cos_wrapper_meta_field hs_cos_wrapper_type_rich_text\" data-hs-cos-general-type=\"meta_field\" data-hs-cos-type=\"rich_text\">Face \u00e0 l&rsquo;augmentation des assortiments dans le domaine des petites pi\u00e8ces, le stockage classique selon le principe \u00ab\u00a0Personne vers Marchandise\u00a0\u00bb est devenu de plus en plus difficile. Pour r\u00e9pondre aux exigences croissantes, le centre logistique existant doit maintenant \u00eatre automatis\u00e9. La recherche d&rsquo;une solution de stockage pour petites pi\u00e8ces, \u00e9conomisant de l&rsquo;espace, \u00e9volutive et rentable \u00e0 long terme, a finalement conduit Roland Wechsler, responsable logistique sanitaire chez SABAG, au concept AutoStore. \u00c0 l&rsquo;avenir, le syst\u00e8me robotis\u00e9 \u00ab\u00a0Marchandise vers Personne\u00a0\u00bb permettra une gestion efficace de toutes les petites pi\u00e8ces du secteur sanitaire et simplifiera consid\u00e9rablement la r\u00e9ception des marchandises, la pr\u00e9paration des commandes, les livraisons aux clients, les commandes d&rsquo;atelier ainsi que le traitement des retours. Le contrat pour la planification et la r\u00e9alisation de l&rsquo;installation a \u00e9t\u00e9 attribu\u00e9 \u00e0 l&rsquo;expert en intralogistique et partenaire mondial d&rsquo;AutoStore, Kardex.<\/span><\/p>\n<p><span id=\"hs_cos_wrapper_post_body\" class=\"hs_cos_wrapper hs_cos_wrapper_meta_field hs_cos_wrapper_type_rich_text\" data-hs-cos-general-type=\"meta_field\" data-hs-cos-type=\"rich_text\">\u00ab\u00a0La solution AutoStore, qui sera int\u00e9gr\u00e9e de mani\u00e8re optimale dans notre b\u00e2timent existant, permet en plus d&rsquo;une utilisation maximale de l&rsquo;espace un traitement plus rapide des commandes, ainsi qu&rsquo;un all\u00e8gement consid\u00e9rable de nos employ\u00e9s dans les t\u00e2ches quotidiennes au sein de l&rsquo;entrep\u00f4t\u00a0\u00bb, d\u00e9clare Roland Wechsler, responsable logistique sanitaire chez SABAG. \u00ab\u00a0Avec Kardex, nous avons trouv\u00e9 un partenaire fiable et comp\u00e9tent qui a compris nos besoins et d\u00e9fis tr\u00e8s rapidement. Nous sommes impatients de travailler avec Kardex pour rendre notre logistique efficace et performante pour l&rsquo;avenir.\u00a0\u00bb<\/span><\/p>\n<h5 data-hs-responsive-table=\"true\">Utilisation maximale de l&rsquo;espace et processus efficaces<\/h5>\n<p data-hs-responsive-table=\"true\">La solution AutoStore, planifi\u00e9e par Kardex et sur mesure pour SABAG, comprend une surface d&rsquo;environ 100 m\u00b2 pour 3 100 conteneurs. Ceux-ci sont empil\u00e9s dans un syst\u00e8me de grille en aluminium flexible sans espaces, ce qui maximise la densit\u00e9 de stockage et permet une capacit\u00e9 quatre fois sup\u00e9rieure par rapport au stockage manuel traditionnel sur la m\u00eame surface. Pour la gestion des conteneurs, trois robots aliment\u00e9s par batterie sont utilis\u00e9s, se d\u00e9pla\u00e7ant sur les rails du syst\u00e8me de grille.<\/p>\n<p data-hs-responsive-table=\"true\"><span id=\"hs_cos_wrapper_post_body\" class=\"hs_cos_wrapper hs_cos_wrapper_meta_field hs_cos_wrapper_type_rich_text\" data-hs-cos-general-type=\"meta_field\" data-hs-cos-type=\"rich_text\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-22902 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kardex_Mlog_18.4.23_2.jpg\" alt=\"\" width=\"1729\" height=\"968\" \/>Les robots prennent en charge les conteneurs, les r\u00e9organisent et les mettent \u00e0 disposition \u00e0 trois stations de travail ergonomiques de type ConveyorPort. Deux des ports seront install\u00e9s au rez-de-chauss\u00e9e et utilis\u00e9s pour l&rsquo;entr\u00e9e et la sortie des articles. Au premier \u00e9tage, le troisi\u00e8me port sera r\u00e9alis\u00e9 pour l&rsquo;approvisionnement de l&rsquo;atelier. Cela simplifie consid\u00e9rablement les processus manuels et am\u00e9liore et acc\u00e9l\u00e8re la pr\u00e9paration des commandes en fonction des besoins.<\/span><\/p>\n<h5 data-hs-responsive-table=\"true\">Zone de maintenance peu encombrante pour les robots<\/h5>\n<p data-hs-responsive-table=\"true\"><span id=\"hs_cos_wrapper_post_body\" class=\"hs_cos_wrapper hs_cos_wrapper_meta_field hs_cos_wrapper_type_rich_text\" data-hs-cos-general-type=\"meta_field\" data-hs-cos-type=\"rich_text\">La zone de maintenance pour les robots sera install\u00e9e de mani\u00e8re peu encombrante au premier \u00e9tage sur la plateforme en b\u00e9ton existante. La construction modulaire d&rsquo;AutoStore permet des extensions en termes de performance et de capacit\u00e9 de stockage \u00e0 tout moment pendant l&rsquo;exploitation \u2013 ainsi, l&rsquo;installation peut \u00e9voluer avec les besoins de l&rsquo;entreprise.<\/span><\/p>\n<p>Photos : \u00a9 Kardex Germany<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour optimiser la logistique des petites pi\u00e8ces, Kardex r\u00e9alise pour SABAG Luzern AG un syst\u00e8me AutoStore hautement efficace au si\u00e8ge de l&rsquo;entreprise \u00e0 Rothenburg (Suisse). \u00c0<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1560,1561],"tags":[],"class_list":["post-61216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kardex installe un syst\u00e8me AutoStore chez SABAG \u00e0 Rothenburg - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kardex installe un syst\u00e8me AutoStore chez SABAG \u00e0 Rothenburg - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Pour optimiser la logistique des petites pi\u00e8ces, Kardex r\u00e9alise pour SABAG Luzern AG un syst\u00e8me AutoStore hautement efficace au si\u00e8ge de l&rsquo;entreprise \u00e0 Rothenburg (Suisse). \u00c0 [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-18T16:24:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kardex_Mlog_18.4.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1311\" \/>\n\t<meta property=\"og:image:height\" content=\"786\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Kardex installe un syst\u00e8me AutoStore chez SABAG \u00e0 Rothenburg\",\"datePublished\":\"2023-04-18T16:24:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/\"},\"wordCount\":647,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kardex_Mlog_18.4.23.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/\",\"name\":\"Kardex installe un syst\u00e8me AutoStore chez SABAG \u00e0 Rothenburg - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kardex_Mlog_18.4.23.jpg\",\"datePublished\":\"2023-04-18T16:24:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kardex_Mlog_18.4.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kardex_Mlog_18.4.23.jpg\",\"width\":1311,\"height\":786},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/04\\\/18\\\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kardex installe un syst\u00e8me AutoStore chez SABAG \u00e0 Rothenburg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kardex installe un syst\u00e8me AutoStore chez SABAG \u00e0 Rothenburg - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/","og_locale":"fr_FR","og_type":"article","og_title":"Kardex installe un syst\u00e8me AutoStore chez SABAG \u00e0 Rothenburg - Loginfo24.","og_description":"Pour optimiser la logistique des petites pi\u00e8ces, Kardex r\u00e9alise pour SABAG Luzern AG un syst\u00e8me AutoStore hautement efficace au si\u00e8ge de l&rsquo;entreprise \u00e0 Rothenburg (Suisse). \u00c0 [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-04-18T16:24:33+00:00","og_image":[{"width":1311,"height":786,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kardex_Mlog_18.4.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/"},"author":{"name":"","@id":""},"headline":"Kardex installe un syst\u00e8me AutoStore chez SABAG \u00e0 Rothenburg","datePublished":"2023-04-18T16:24:33+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/"},"wordCount":647,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kardex_Mlog_18.4.23.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/","url":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/","name":"Kardex installe un syst\u00e8me AutoStore chez SABAG \u00e0 Rothenburg - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kardex_Mlog_18.4.23.jpg","datePublished":"2023-04-18T16:24:33+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kardex_Mlog_18.4.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kardex_Mlog_18.4.23.jpg","width":1311,"height":786},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2023\/04\/18\/kardex-installe-un-systeme-autostore-chez-sabag-a-rothenburg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Kardex installe un syst\u00e8me AutoStore chez SABAG \u00e0 Rothenburg"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/61216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=61216"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/61216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/8247"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=61216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=61216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=61216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}