{"id":61043,"date":"2023-03-23T19:45:51","date_gmt":"2023-03-23T18:45:51","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/"},"modified":"2023-03-23T19:45:51","modified_gmt":"2023-03-23T18:45:51","slug":"cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/","title":{"rendered":"Cognex am\u00e9liore les processus logistiques gr\u00e2ce \u00e0 l&rsquo;apprentissage en p\u00e9riph\u00e9rie"},"content":{"rendered":"<h5><strong>La soci\u00e9t\u00e9 Cognex pr\u00e9sente le d\u00e9tecteur In-Sight 2800 pour la logistique. Ce syst\u00e8me de d\u00e9tection d&rsquo;objets est bas\u00e9 sur la plateforme In-Sight de Cognex et utilise la technologie d&rsquo;apprentissage en p\u00e9riph\u00e9rie bas\u00e9e sur l&rsquo;IA pour automatiser les processus de tri et am\u00e9liorer la pr\u00e9cision des inspections logistiques.<\/strong><\/h5>\n<p>(Natick, \u00c9tats-Unis) \u00ab\u00a0Le d\u00e9tecteur In-Sight 2800 repr\u00e9sente une avanc\u00e9e dans l&rsquo;innovation logistique\u00a0\u00bb, d\u00e9clare Shweta Kabadi, vice-pr\u00e9sidente des solutions chez Cognex. \u00ab\u00a0Les inspections bas\u00e9es sur l&rsquo;apprentissage en p\u00e9riph\u00e9rie r\u00e9duisent les co\u00fbts, augmentent le d\u00e9bit, rendent l&rsquo;IA accessible aux installations de toutes tailles et ouvrent finalement la voie \u00e0 une automatisation logistique plus efficace.\u00a0\u00bb<\/p>\n<p>Le nouveau syst\u00e8me de d\u00e9tection d&rsquo;objets de Cognex est adapt\u00e9 aux applications exigeantes de d\u00e9tection d&rsquo;objets, telles que la v\u00e9rification de la pr\u00e9sence d&rsquo;un article sur des syst\u00e8mes de tri, dans des conteneurs ou des plateaux, la classification des types de colis et l&rsquo;identification des probl\u00e8mes de processus, tels que les embouteillages sur les bandes transporteuses. La technologie d&rsquo;apprentissage en p\u00e9riph\u00e9rie int\u00e9gr\u00e9e peut m\u00eame d\u00e9tecter des articles sur des arri\u00e8re-plans agit\u00e9s ou \u00e0 faible contraste.<\/p>\n<p>La configuration du d\u00e9tecteur In-Sight 2800 prend moins de 15 minutes. Avec la technologie d&rsquo;apprentissage en p\u00e9riph\u00e9rie, l&rsquo;entra\u00eenement se fait directement sur l&rsquo;appareil et n\u00e9cessite un nombre r\u00e9duit d&rsquo;images, sans qu&rsquo;un expert soit requis. Les installations logistiques peuvent rapidement tirer parti de cette technologie et \u00e9viter des temps d&rsquo;arr\u00eat co\u00fbteux.<\/p>\n<p>\u00ab\u00a0Avec le d\u00e9tecteur In-Sight 2800, nous avons pu reconna\u00eetre imm\u00e9diatement des produits qui ne pouvaient pas \u00eatre d\u00e9tect\u00e9s par d&rsquo;autres solutions\u00a0\u00bb, d\u00e9clare Dave Bodenheimer, VP, recherche et d\u00e9veloppement produit chez SDI Industries Inc, un client de Cognex. \u00ab\u00a0Nos clients \u00e9taient tr\u00e8s satisfaits des r\u00e9sultats. Le d\u00e9tecteur In-Sight 2800 est un facteur cl\u00e9 pour la d\u00e9tection de pr\u00e9sence et d&rsquo;absence, la d\u00e9tection des probl\u00e8mes de processus et la classification facile.\u00a0\u00bb<\/p>\n<p>Photo : \u00a9 Cognex Corporation<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La soci\u00e9t\u00e9 Cognex pr\u00e9sente le d\u00e9tecteur In-Sight 2800 pour la logistique. Ce syst\u00e8me de d\u00e9tection d&rsquo;objets est bas\u00e9 sur la plateforme In-Sight de Cognex et utilise<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-61043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cognex am\u00e9liore les processus logistiques gr\u00e2ce \u00e0 l&#039;apprentissage en p\u00e9riph\u00e9rie - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cognex am\u00e9liore les processus logistiques gr\u00e2ce \u00e0 l&#039;apprentissage en p\u00e9riph\u00e9rie - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"La soci\u00e9t\u00e9 Cognex pr\u00e9sente le d\u00e9tecteur In-Sight 2800 pour la logistique. Ce syst\u00e8me de d\u00e9tection d&rsquo;objets est bas\u00e9 sur la plateforme In-Sight de Cognex et utilise [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-23T18:45:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cognex_23.03.2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1373\" \/>\n\t<meta property=\"og:image:height\" content=\"969\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cognex am\u00e9liore les processus logistiques gr\u00e2ce \u00e0 l&rsquo;apprentissage en p\u00e9riph\u00e9rie\",\"datePublished\":\"2023-03-23T18:45:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/\"},\"wordCount\":379,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cognex_23.03.2023.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/\",\"name\":\"Cognex am\u00e9liore les processus logistiques gr\u00e2ce \u00e0 l'apprentissage en p\u00e9riph\u00e9rie - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cognex_23.03.2023.jpg\",\"datePublished\":\"2023-03-23T18:45:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cognex_23.03.2023.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cognex_23.03.2023.jpg\",\"width\":1373,\"height\":969},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/23\\\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cognex am\u00e9liore les processus logistiques gr\u00e2ce \u00e0 l&rsquo;apprentissage en p\u00e9riph\u00e9rie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cognex am\u00e9liore les processus logistiques gr\u00e2ce \u00e0 l'apprentissage en p\u00e9riph\u00e9rie - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/","og_locale":"fr_FR","og_type":"article","og_title":"Cognex am\u00e9liore les processus logistiques gr\u00e2ce \u00e0 l'apprentissage en p\u00e9riph\u00e9rie - Loginfo24.","og_description":"La soci\u00e9t\u00e9 Cognex pr\u00e9sente le d\u00e9tecteur In-Sight 2800 pour la logistique. Ce syst\u00e8me de d\u00e9tection d&rsquo;objets est bas\u00e9 sur la plateforme In-Sight de Cognex et utilise [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-03-23T18:45:51+00:00","og_image":[{"width":1373,"height":969,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cognex_23.03.2023.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/"},"author":{"name":"","@id":""},"headline":"Cognex am\u00e9liore les processus logistiques gr\u00e2ce \u00e0 l&rsquo;apprentissage en p\u00e9riph\u00e9rie","datePublished":"2023-03-23T18:45:51+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/"},"wordCount":379,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cognex_23.03.2023.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/","url":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/","name":"Cognex am\u00e9liore les processus logistiques gr\u00e2ce \u00e0 l'apprentissage en p\u00e9riph\u00e9rie - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cognex_23.03.2023.jpg","datePublished":"2023-03-23T18:45:51+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cognex_23.03.2023.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cognex_23.03.2023.jpg","width":1373,"height":969},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/23\/cognex-ameliore-les-processus-logistiques-grace-a-lapprentissage-en-peripherie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Cognex am\u00e9liore les processus logistiques gr\u00e2ce \u00e0 l&rsquo;apprentissage en p\u00e9riph\u00e9rie"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/61043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=61043"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/61043\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/8327"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=61043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=61043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=61043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}