{"id":60877,"date":"2023-03-09T13:30:39","date_gmt":"2023-03-09T12:30:39","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/03\/09\/designwerk-sagrandit-en-suede\/"},"modified":"2023-03-09T13:30:39","modified_gmt":"2023-03-09T12:30:39","slug":"designwerk-sagrandit-en-suede","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/","title":{"rendered":"Designwerk s&rsquo;agrandit en Su\u00e8de"},"content":{"rendered":"<h5><strong>La Designwerk Technologies AG s&rsquo;agrandit en Scandinavie : Depuis le d\u00e9but de l&rsquo;ann\u00e9e, les chargeurs rapides mobiles pour v\u00e9hicules utilitaires du sp\u00e9cialiste suisse de la mobilit\u00e9 \u00e9lectrique sont \u00e9galement disponibles en Su\u00e8de. Designwerk est soutenu dans cette d\u00e9marche par son nouveau partenaire de distribution, Svensk Fordonsladdning (R\u00e4ttvik, Su\u00e8de). \u00ab Avec Svensk Fordonsladdning, nous avons gagn\u00e9 un partenaire excellent qui promeut la mobilit\u00e9 \u00e9lectrique et r\u00e9pond \u00e0 la demande croissante de technologies de propulsion sans \u00e9missions \u00bb, commente le directeur g\u00e9n\u00e9ral de Designwerk, Adrian Melliger.<\/strong><\/h5>\n<p> (Winterthur) La mobilit\u00e9 \u00e9lectrique est essentielle pour la transition \u00e9nerg\u00e9tique et l&rsquo;atteinte des objectifs climatiques. La Su\u00e8de joue un r\u00f4le de pionnier \u00e0 cet \u00e9gard. Pour le distributeur officiel, ainsi que pour Designwerk et les clients, ce partenariat de distribution est une situation gagnant-gagnant : Designwerk renforce sa position sur le march\u00e9 europ\u00e9en, tandis que le partenaire su\u00e9dois \u00e9largit son portefeuille de produits avec des solutions de recharge mobiles. \u00c9tant donn\u00e9 que la mobilit\u00e9 \u00e9lectrique progresse \u00e0 un rythme rapide en Su\u00e8de, les exigences en mati\u00e8re d&rsquo;infrastructure de recharge augmentent. \u00ab Gr\u00e2ce \u00e0 notre collaboration \u00e9troite avec Designwerk, nous pouvons \u00e9largir notre offre avec un produit leader mondial dans ce domaine. Nous constatons d\u00e9j\u00e0 une forte demande pour les produits de qualit\u00e9 de Designwerk, en particulier pour les chargeurs DC mobiles \u00bb, d\u00e9clare Robert Nilsson, pr\u00e9sident de Svensk Fordonsladdning.<\/p>\n<h5><strong>Les solutions de recharge rapide DC de Designwerk \u00e9largissent l&rsquo;offre du partenaire commercial<\/strong><\/h5>\n<p> Le partenaire de distribution officiel, Svensk Fordonsladdning, jouit depuis des ann\u00e9es d&rsquo;une excellente r\u00e9putation en tant que fournisseur leader de solutions compl\u00e8tes pour les syst\u00e8mes de recharge rapide DC. Son portefeuille comprend des solutions de recharge pour les entreprises et les municipalit\u00e9s. \u00ab Notre objectif est de fournir des installations de haute qualit\u00e9 qui soient durables \u00e0 long terme \u00bb, explique Nilsson. Les solutions de recharge rapide DC mobiles de Designwerk Technologies AG \u00e9largissent l&rsquo;offre du partenaire commercial su\u00e9dois, qui n&rsquo;avait jusqu&rsquo;\u00e0 pr\u00e9sent distribu\u00e9 que des chargeurs fixes. Avec les nouveaux chargeurs portables, Svensk Fordonsladdning peut proposer des solutions de recharge exactement l\u00e0 o\u00f9 les clients en ont besoin : directement sur le v\u00e9hicule utilitaire. Les chargeurs rapides mobiles peuvent charger jusqu&rsquo;\u00e0 600 kilom\u00e8tres par heure. Avec une puissance de 22 \u00e0 88 kilowatts et jusqu&rsquo;\u00e0 1000 volts de tension, ces appareils garantissent des cycles de charge rapides et stables. Gr\u00e2ce \u00e0 un syst\u00e8me de changement de c\u00e2ble int\u00e9gr\u00e9, les clients peuvent facilement et librement passer d&rsquo;une norme de charge \u00e0 l&rsquo;autre. L&rsquo;entretien et la r\u00e9paration des appareils sont actuellement encore pris en charge par le centre de service \u00e0 Lottstetten, en Bade-Wurtemberg. \u00c0 moyen terme, cela devrait \u00e9galement \u00eatre possible en Su\u00e8de. La distribution du Mega Charger sur place est \u00e9galement pr\u00e9vue. La station de recharge au format conteneur permet de recharger rapidement des poids lourds en 45 minutes.<br \/>Photo : \u00a9 Designwerk Technologies AG \/ <strong><em>L\u00e9gende de l&rsquo;image :<\/em><\/strong><em> Designwerk Mobile Charger MDC44-920<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Designwerk Technologies AG s&rsquo;agrandit en Scandinavie : Depuis le d\u00e9but de l&rsquo;ann\u00e9e, les chargeurs rapides mobiles pour v\u00e9hicules utilitaires du sp\u00e9cialiste suisse de la mobilit\u00e9<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-60877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Designwerk s&#039;agrandit en Su\u00e8de - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Designwerk s&#039;agrandit en Su\u00e8de - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"La Designwerk Technologies AG s&rsquo;agrandit en Scandinavie : Depuis le d\u00e9but de l&rsquo;ann\u00e9e, les chargeurs rapides mobiles pour v\u00e9hicules utilitaires du sp\u00e9cialiste suisse de la mobilit\u00e9 [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-09T12:30:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Designwerk_09.03.2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"997\" \/>\n\t<meta property=\"og:image:height\" content=\"663\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Designwerk s&rsquo;agrandit en Su\u00e8de\",\"datePublished\":\"2023-03-09T12:30:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/\"},\"wordCount\":511,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Designwerk_09.03.2023.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/\",\"name\":\"Designwerk s'agrandit en Su\u00e8de - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Designwerk_09.03.2023.jpg\",\"datePublished\":\"2023-03-09T12:30:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Designwerk_09.03.2023.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Designwerk_09.03.2023.jpg\",\"width\":997,\"height\":663},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/03\\\/09\\\/designwerk-sagrandit-en-suede\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Designwerk s&#8217;agrandit en Su\u00e8de\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Designwerk s'agrandit en Su\u00e8de - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/","og_locale":"fr_FR","og_type":"article","og_title":"Designwerk s'agrandit en Su\u00e8de - Loginfo24.","og_description":"La Designwerk Technologies AG s&rsquo;agrandit en Scandinavie : Depuis le d\u00e9but de l&rsquo;ann\u00e9e, les chargeurs rapides mobiles pour v\u00e9hicules utilitaires du sp\u00e9cialiste suisse de la mobilit\u00e9 [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-03-09T12:30:39+00:00","og_image":[{"width":997,"height":663,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Designwerk_09.03.2023.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/"},"author":{"name":"","@id":""},"headline":"Designwerk s&rsquo;agrandit en Su\u00e8de","datePublished":"2023-03-09T12:30:39+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/"},"wordCount":511,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Designwerk_09.03.2023.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/","url":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/","name":"Designwerk s'agrandit en Su\u00e8de - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Designwerk_09.03.2023.jpg","datePublished":"2023-03-09T12:30:39+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Designwerk_09.03.2023.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Designwerk_09.03.2023.jpg","width":997,"height":663},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2023\/03\/09\/designwerk-sagrandit-en-suede\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Designwerk s&#8217;agrandit en Su\u00e8de"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/60877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=60877"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/60877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/8390"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=60877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=60877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=60877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}