{"id":60410,"date":"2023-02-02T17:11:05","date_gmt":"2023-02-02T16:11:05","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/"},"modified":"2023-02-02T17:11:05","modified_gmt":"2023-02-02T16:11:05","slug":"la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/","title":{"rendered":"La Poste suisse ne livre plus qu&rsquo;avec des v\u00e9hicules \u00e9lectriques \u00e0 Berne et Zurich"},"content":{"rendered":"<h5>\u00c0 partir de maintenant, la Poste suisse livre des lettres et des colis dans les grandes villes de Zurich et Berne exclusivement avec des v\u00e9hicules \u00e9lectriques. Cela marque une \u00e9tape importante vers une logistique durable. Avec un total de 568 v\u00e9hicules \u00e9lectriques, les facteurs livrent des lettres et des colis de mani\u00e8re climatiquement neutre dans les deux villes. Les scooters \u00e9lectriques et les fourgonnettes contribuent \u00e9galement \u00e0 r\u00e9duire le bruit du trafic.<\/h5>\n<p>(Berne\/Zurich) Le fait que la Poste ne livre plus qu&rsquo;avec des v\u00e9hicules \u00e9lectriques \u00e0 Zurich et Berne n&rsquo;est que le d\u00e9but : d&rsquo;ici 2030, l&rsquo;ensemble de la flotte de livraison de la Poste sera \u00e9quip\u00e9e de moteurs alternatifs, c&rsquo;est-\u00e0-dire de 100 % d&rsquo;\u00e9lectricit\u00e9 provenant de sources d&rsquo;\u00e9nergie renouvelables telles que l&rsquo;\u00e9lectricit\u00e9 verte.<\/p>\n<div class=\"ppm-richtext\" data-init=\"richtext\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-xs-12 col-lg-8 offset-lg-2 \">\n<div class=\"ppm-richtext__content\">\n<p>Les gens en Suisse s&rsquo;attendent \u00e0 ce que des entreprises comme la Poste prennent \u00e0 c\u0153ur le sujet de la durabilit\u00e9. La Poste le voit \u00e9galement tr\u00e8s concr\u00e8tement dans les besoins de ses clientes et clients. Les petites et grandes entreprises attendent une logistique respectueuse de l&rsquo;environnement. Et la population suisse a \u00e9galement ce besoin. On attend des entreprises qu&rsquo;elles emballent et livrent les commandes de mani\u00e8re durable. Pour la Poste, la durabilit\u00e9 n&rsquo;est pas un mot \u00e0 la mode, mais une conviction. Et cette conviction se traduit par des actions \u2013 depuis des ann\u00e9es. En tant qu&rsquo;entreprise \u00e0 forte intensit\u00e9 de transport avec une infrastructure \u00e9tendue, la Poste a la plus grande consommation de CO<sub>2<\/sub> dans les domaines des v\u00e9hicules et des b\u00e2timents. C&rsquo;est pourquoi elle agit et a maintenant atteint une nouvelle \u00e9tape vers une logistique climatiquement neutre : \u00c0 partir de maintenant, la Poste livre des lettres et des colis dans les grandes villes de Zurich et Berne exclusivement avec des v\u00e9hicules \u00e9lectriques.<\/p>\n<h5>Environ 40 millions de colis livr\u00e9s avec des v\u00e9hicules \u00e9lectriques<\/h5>\n<p>Cela signifie que la Poste utilise enti\u00e8rement l&rsquo;\u00e9lectricit\u00e9 pour ses propres v\u00e9hicules de livraison dans les villes de Zurich et Berne. Au total, il y a maintenant 568 v\u00e9hicules dans les deux villes qui fonctionnent uniquement \u00e0 l&rsquo;\u00e9lectricit\u00e9. Parmi eux, 374 scooters \u00e9lectriques et 194 fourgonnettes \u00e9lectriques. L&rsquo;\u00e9lectricit\u00e9 pour les v\u00e9hicules provient \u00e0 100 % de sources d&rsquo;\u00e9nergie renouvelables en Suisse. Cela contribue \u00e9galement \u00e0 un trafic plus durable dans les villes.<\/p>\n<p>Gr\u00e2ce \u00e0 cette transition, la Poste livre chaque ann\u00e9e environ 40 millions de colis de mani\u00e8re \u00e9lectrique \u00e0 l&rsquo;\u00e9chelle nationale. Rien qu&rsquo;\u00e0 Zurich, ce sont 7,9 millions de colis par an, et \u00e0 Berne, 3,4 millions de colis. Pour rendre cela possible, la Poste a progressivement \u00e9quip\u00e9 les sites de v\u00e9hicules \u00e9lectriques et d&rsquo;une infrastructure de recharge \u00e9lectrique. La livraison \u00e9lectrique repr\u00e9sente \u00e9galement de grands d\u00e9fis pour la Poste, qui ont d\u00fb \u00eatre r\u00e9solus et qui existent encore en partie. L&rsquo;un des d\u00e9fis est l&rsquo;autonomie, qui est limit\u00e9e \u2013 cela implique un effort suppl\u00e9mentaire selon le parcours de livraison. D&rsquo;autre part, le sujet de l&rsquo;infrastructure de recharge repr\u00e9sente \u00e9galement un d\u00e9fi. Selon que le b\u00e2timent appartient \u00e0 la Poste ou est lou\u00e9, l&rsquo;installation peut \u00eatre plus ou moins complexe. Parmi les quelque 450 points de livraison de la Poste en Suisse, environ 140 sont aujourd&rsquo;hui enti\u00e8rement \u00e9quip\u00e9s de stations de recharge.<\/p>\n<h5>Poser un signe avec un engagement pour la mobilit\u00e9 \u00e9lectrique<\/h5>\n<p>Que la Poste pose un signe avec son engagement pour la mobilit\u00e9 \u00e9lectrique est \u00e9vident pour Johannes Cramer, membre de la direction du groupe et responsable du secteur des services logistiques de la Poste : \u00ab En tant qu&rsquo;entreprise appartenant \u00e0 l&rsquo;\u00c9tat, la Poste a toujours une fonction de mod\u00e8le. Nous en avons pleinement conscience. Avec l&rsquo;\u00e9lectrification de notre flotte de livraison et la logistique respectueuse des ressources qui en d\u00e9coule, nos clients peuvent \u00e9galement r\u00e9duire leur empreinte carbone. \u00bb Le fait que la Poste ne soit plus qu&rsquo;\u00e9lectrique \u00e0 Zurich et Berne n&rsquo;est que le d\u00e9but : d&rsquo;ici la fin de l&rsquo;ann\u00e9e 2024, la Poste sera \u00e9galement enti\u00e8rement \u00e9lectrique dans les villes de Gen\u00e8ve et B\u00e2le, ainsi qu&rsquo;\u00e0 environ 50 autres emplacements. La Poste utilise de l&rsquo;\u00e9lectricit\u00e9 verte, qui est produite \u00e0 100 % \u00e0 partir de sources renouvelables en Suisse. Les v\u00e9hicules de livraison \u00e9lectriques fonctionnent m\u00eame avec de l&rsquo;\u00e9lectricit\u00e9 verte certifi\u00e9e \u00ab naturemade star \u00bb. D&rsquo;ici 2030, environ 10 500 v\u00e9hicules de livraison dans toute la Suisse seront \u00e9quip\u00e9s d&rsquo;une technologie de propulsion \u00e9lectrique ou d&rsquo;une autre technologie respectueuse de l&rsquo;environnement. La Poste livre ainsi des lettres et des colis de mani\u00e8re compl\u00e8tement climatiquement neutre.<\/p>\n<blockquote>\n<h5 class=\"ppm-title ppm-product-card__title\" data-productcards-section-child=\"title\"><span class=\"ppm-title__main\">D\u00e9j\u00e0 aujourd&rsquo;hui la plus grande flotte de v\u00e9hicules \u00e9lectriques de Suisse<\/span><\/h5>\n<p class=\"ppm-title ppm-product-card__title\" data-productcards-section-child=\"title\">La Poste travaille depuis 2010 \u00e0 l&rsquo;\u00e9lectrification de ses v\u00e9hicules de livraison. Aujourd&rsquo;hui, la flotte comprend environ 7230 v\u00e9hicules \u00e9lectriques, qui sont utilis\u00e9s dans tous les sites de la Poste. Ainsi, la Poste poss\u00e8de d\u00e9j\u00e0 aujourd&rsquo;hui la plus grande flotte de v\u00e9hicules \u00e9lectriques de Suisse. Depuis 2017, les environ 6000 scooters \u00e9lectriques \u00e0 trois roues sont utilis\u00e9s pour la livraison \u00e0 100 % de mani\u00e8re \u00e9lectrique. De plus, environ 500 v\u00e9hicules de livraison \u00e9lectriques \u00e0 quatre roues sont d\u00e9j\u00e0 en service pour la livraison de colis et de plus en plus de lettres. En outre, environ 650 v\u00e9hicules \u00e9lectriques sont utilis\u00e9s par la Poste dans divers domaines \u2013 donc des v\u00e9hicules qui ne sont pas utilis\u00e9s pour la livraison, mais par exemple par des techniciens, des v\u00e9hicules de traction ou des chariots \u00e9l\u00e9vateurs. Pr\u00e8s de 4000 autres v\u00e9hicules de livraison seront \u00e9galement ajout\u00e9s \u00e0 l&rsquo;\u00e9chelle suisse d&rsquo;ici 2030 au plus tard. Pour cela, les sites de livraison seront progressivement \u00e9quip\u00e9s de v\u00e9hicules \u00e9lectriques et d&rsquo;une infrastructure de recharge \u00e9lectrique.<\/p>\n<\/blockquote>\n<p>Photo : \u00a9 Poste suisse<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 partir de maintenant, la Poste suisse livre des lettres et des colis dans les grandes villes de Zurich et Berne exclusivement avec des v\u00e9hicules \u00e9lectriques.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-60410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Poste suisse ne livre plus qu&#039;avec des v\u00e9hicules \u00e9lectriques \u00e0 Berne et Zurich - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Poste suisse ne livre plus qu&#039;avec des v\u00e9hicules \u00e9lectriques \u00e0 Berne et Zurich - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"\u00c0 partir de maintenant, la Poste suisse livre des lettres et des colis dans les grandes villes de Zurich et Berne exclusivement avec des v\u00e9hicules \u00e9lectriques. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-02T16:11:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_2.2.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1268\" \/>\n\t<meta property=\"og:image:height\" content=\"777\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Poste suisse ne livre plus qu&rsquo;avec des v\u00e9hicules \u00e9lectriques \u00e0 Berne et Zurich\",\"datePublished\":\"2023-02-02T16:11:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/\"},\"wordCount\":984,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_2.2.23.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/\",\"name\":\"La Poste suisse ne livre plus qu'avec des v\u00e9hicules \u00e9lectriques \u00e0 Berne et Zurich - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_2.2.23.jpg\",\"datePublished\":\"2023-02-02T16:11:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_2.2.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_2.2.23.jpg\",\"width\":1268,\"height\":777},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2023\\\/02\\\/02\\\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Poste suisse ne livre plus qu&rsquo;avec des v\u00e9hicules \u00e9lectriques \u00e0 Berne et Zurich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Poste suisse ne livre plus qu'avec des v\u00e9hicules \u00e9lectriques \u00e0 Berne et Zurich - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/","og_locale":"fr_FR","og_type":"article","og_title":"La Poste suisse ne livre plus qu'avec des v\u00e9hicules \u00e9lectriques \u00e0 Berne et Zurich - Loginfo24.","og_description":"\u00c0 partir de maintenant, la Poste suisse livre des lettres et des colis dans les grandes villes de Zurich et Berne exclusivement avec des v\u00e9hicules \u00e9lectriques. [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-02-02T16:11:05+00:00","og_image":[{"width":1268,"height":777,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_2.2.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/"},"author":{"name":"","@id":""},"headline":"La Poste suisse ne livre plus qu&rsquo;avec des v\u00e9hicules \u00e9lectriques \u00e0 Berne et Zurich","datePublished":"2023-02-02T16:11:05+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/"},"wordCount":984,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_2.2.23.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/","url":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/","name":"La Poste suisse ne livre plus qu'avec des v\u00e9hicules \u00e9lectriques \u00e0 Berne et Zurich - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_2.2.23.jpg","datePublished":"2023-02-02T16:11:05+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_2.2.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_2.2.23.jpg","width":1268,"height":777},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2023\/02\/02\/la-poste-suisse-ne-livre-plus-quavec-des-vehicules-electriques-a-berne-et-zurich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La Poste suisse ne livre plus qu&rsquo;avec des v\u00e9hicules \u00e9lectriques \u00e0 Berne et Zurich"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/60410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=60410"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/60410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/8577"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=60410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=60410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=60410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}