{"id":58381,"date":"2022-09-12T19:25:00","date_gmt":"2022-09-12T17:25:00","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/"},"modified":"2022-09-12T19:25:00","modified_gmt":"2022-09-12T17:25:00","slug":"rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/","title":{"rendered":"Rails par le bas : NRS de L\u00fcbeck donne un aper\u00e7u de l&rsquo;atelier de wagons"},"content":{"rendered":"<h5><strong>\u00c0 l&rsquo;occasion de la journ\u00e9e nationale des rails, la L\u00fcbecker Hafenbahn invite petits et grands \u00e0 jeter un \u0153il derri\u00e8re les coulisses. Le 16 et 17 septembre, le lieu de rendez-vous est l&rsquo;atelier de wagons de Nordic Rail Service (NRS), filiale de la L\u00fcbecker Hafen-Gesellschaft (LHG). Parmi les attractions, il y aura \u00e9galement des v\u00e9hicules et des \u00e9quipements lourds.<\/strong><\/h5>\n<p>(L\u00fcbeck) Qui sait ce qu&rsquo;est une V100, qui sait comment fonctionne le moteur d&rsquo;une V60 ou une \u00ab\u00a0K\u00f6f\u00a0\u00bb ? Qui a envie d&rsquo;essayer ses comp\u00e9tences de conduite sur un simulateur de ligne ferroviaire ? Ceux qui se reconnaissent dans cette description trouveront leur bonheur lors de la journ\u00e9e des rails chez NRS. On pourra y voir, entre autres, un wagon de marchandises sous un angle inhabituel, \u00e0 savoir par le dessous, des Unimogs \u00e0 2 voies et une machine \u00e0 bourrer. Des locomotives de la Deutsche Bahn (DB) sont \u00e9galement attendues.<\/p>\n<p>\u00ab Nous voulons faire de la publicit\u00e9 pour notre secteur \u00bb, explique Thomas Toschka, responsable des op\u00e9rations ferroviaires chez NRS. \u00ab Nous esp\u00e9rons surtout susciter l&rsquo;int\u00e9r\u00eat des jeunes pour notre m\u00e9tier. Nous sommes toujours \u00e0 la recherche de nouveaux apprentis, mais aussi de professionnels exp\u00e9riment\u00e9s partageant notre passion pour le rail. \u00bb De plus, nous souhaitons, en collaboration avec l&rsquo;Autorit\u00e9 portuaire de L\u00fcbeck (LPA), montrer l&rsquo;importance du chemin de fer \u00e0 cet endroit pour L\u00fcbeck et le transport de marchandises par rail.<\/p>\n<p>Le site de NRS se trouve au 6, rue Einsiedel, \u00e0 proximit\u00e9 imm\u00e9diate du chantier naval de Gollan (quartier des chantiers navals). Des places de parking sont disponibles gratuitement. L&rsquo;atelier de wagons de NRS est \u00e9galement le point de d\u00e9part d&rsquo;un voyage avec des voitures de voyageurs de plus de 60 ans. Les trains nostalgiques organis\u00e9s par la LPA partent de la gare principale de L\u00fcbeck et se dirigent d&rsquo;abord vers le Konstinkai. L\u00e0, l&rsquo;entreprise l\u00fcbeckoise Claus Rodenberg Waldkontor montre comment elle d\u00e9charge le bois import\u00e9 par bateau et par rail.<\/p>\n<p>Ensuite, le train se rend \u00e0 l&rsquo;atelier de wagons dans le quartier des chantiers navals. Des camions de vente avec grillades et boissons s&rsquo;occupent de la restauration. Apr\u00e8s un arr\u00eat de 40 minutes, le train retourne \u00e0 la gare principale.<\/p>\n<p>Photo : \u00a9 Daniel Kahns<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l&rsquo;occasion de la journ\u00e9e nationale des rails, la L\u00fcbecker Hafenbahn invite petits et grands \u00e0 jeter un \u0153il derri\u00e8re les coulisses. Le 16 et 17<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":9414,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-58381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rails par le bas : NRS de L\u00fcbeck donne un aper\u00e7u de l&#039;atelier de wagons - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rails par le bas : NRS de L\u00fcbeck donne un aper\u00e7u de l&#039;atelier de wagons - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"\u00c0 l&rsquo;occasion de la journ\u00e9e nationale des rails, la L\u00fcbecker Hafenbahn invite petits et grands \u00e0 jeter un \u0153il derri\u00e8re les coulisses. Le 16 et 17 [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-12T17:25:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_12.09.2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2245\" \/>\n\t<meta property=\"og:image:height\" content=\"1278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Rails par le bas : NRS de L\u00fcbeck donne un aper\u00e7u de l&rsquo;atelier de wagons\",\"datePublished\":\"2022-09-12T17:25:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/\"},\"wordCount\":401,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LHG_12.09.2022.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/\",\"name\":\"Rails par le bas : NRS de L\u00fcbeck donne un aper\u00e7u de l'atelier de wagons - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LHG_12.09.2022.jpg\",\"datePublished\":\"2022-09-12T17:25:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LHG_12.09.2022.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LHG_12.09.2022.jpg\",\"width\":2245,\"height\":1278},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/09\\\/12\\\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rails par le bas : NRS de L\u00fcbeck donne un aper\u00e7u de l&rsquo;atelier de wagons\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rails par le bas : NRS de L\u00fcbeck donne un aper\u00e7u de l'atelier de wagons - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/","og_locale":"fr_FR","og_type":"article","og_title":"Rails par le bas : NRS de L\u00fcbeck donne un aper\u00e7u de l'atelier de wagons - Loginfo24.","og_description":"\u00c0 l&rsquo;occasion de la journ\u00e9e nationale des rails, la L\u00fcbecker Hafenbahn invite petits et grands \u00e0 jeter un \u0153il derri\u00e8re les coulisses. Le 16 et 17 [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-09-12T17:25:00+00:00","og_image":[{"width":2245,"height":1278,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_12.09.2022.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/"},"author":{"name":"","@id":""},"headline":"Rails par le bas : NRS de L\u00fcbeck donne un aper\u00e7u de l&rsquo;atelier de wagons","datePublished":"2022-09-12T17:25:00+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/"},"wordCount":401,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_12.09.2022.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/","url":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/","name":"Rails par le bas : NRS de L\u00fcbeck donne un aper\u00e7u de l'atelier de wagons - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_12.09.2022.jpg","datePublished":"2022-09-12T17:25:00+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_12.09.2022.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_12.09.2022.jpg","width":2245,"height":1278},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2022\/09\/12\/rails-par-le-bas-nrs-de-lubeck-donne-un-apercu-de-latelier-de-wagons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Rails par le bas : NRS de L\u00fcbeck donne un aper\u00e7u de l&rsquo;atelier de wagons"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/58381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=58381"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/58381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/9414"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=58381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=58381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=58381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}