{"id":56757,"date":"2022-06-05T20:43:24","date_gmt":"2022-06-05T18:43:24","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/"},"modified":"2022-06-05T20:43:24","modified_gmt":"2022-06-05T18:43:24","slug":"audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/","title":{"rendered":"Audi transporte des modules de batterie de Hongrie vers la Belgique par train"},"content":{"rendered":"<div class=\"page-row\">\n<div id=\"item-4d8a6643-c8c2-44e9-a2fc-de12d8eb348e\" class=\"page-item--intro\">\n<div class=\"intro-text\">\n<h4>Une approche globale pour une logistique neutre en CO<sub>2<\/sub> fait ses d\u00e9buts : les modules et cellules de batterie en provenance de Hongrie seront d\u00e9sormais transport\u00e9s par rail plut\u00f4t que par camion vers Bruxelles. Ce changement permet d&rsquo;\u00e9conomiser environ 2 600 tonnes de CO<sub>2<\/sub> par an \u2013 et sert de mod\u00e8le pour la transition de tous les transports de composants de batterie du constructeur automobile. La r\u00e9duction de l&#8217;empreinte \u00e9cologique est l&rsquo;objectif central du programme environnemental inter-sites Mission:Zero<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page-row\">\n<div id=\"item-29e8755a-1648-40c5-b714-8060f6abdd5b\" class=\"page-item--text\">\n<div class=\"text-block style-links-for-body-text\">\n<p>(Ingolstadt\/Bruxelles) C&rsquo;est une \u00e9tape majeure qui marque pour Audi un grand pas vers une durabilit\u00e9 compl\u00e8te : les composants pour la fabrication de batteries \u00e0 l&rsquo;usine Audi de Bruxelles ne seront plus livr\u00e9s par camion depuis la Hongrie, mais par rail avec DB Cargo. Cela permet \u00e0 Audi de r\u00e9duire radicalement les \u00e9missions de CO<sub>2<\/sub> nuisibles \u00e0 l&rsquo;environnement et d&rsquo;\u00e9conomiser beaucoup d&rsquo;argent. La transition des transports entre la Hongrie et Bruxelles, qui a commenc\u00e9 en mai et devrait \u00eatre achev\u00e9e d\u00e9but 2023, est un aper\u00e7u de l&rsquo;avenir du constructeur automobile : \u00ab Bruxelles joue un r\u00f4le de pionnier, mais nous avons d\u00e9velopp\u00e9 ce concept logistique durable pour les modules et cellules de batterie pour l&rsquo;ensemble du r\u00e9seau de production d&rsquo;Audi \u00bb, d\u00e9clare Dieter Braun, responsable de la cha\u00eene d&rsquo;approvisionnement chez AUDI AG \u2013 \u00e0 terme, tous les sites de production devraient mettre en \u0153uvre cette solution.<\/p>\n<h4>Le passage au rail \u00e9conomise du CO<sub>2<\/sub> et de l&rsquo;argent<\/h4>\n<p>Le potentiel immense de ce concept de cha\u00eene d&rsquo;approvisionnement est illustr\u00e9 par le projet \u00e0 Bruxelles : les modules et cellules de batterie n\u00e9cessaires pour l&rsquo;Audi <span class=\"nowrap\">e-tron<\/span> et l&rsquo;Audi <span class=\"nowrap\">e-tron<\/span> Sportback en Belgique sont actuellement transport\u00e9s par camion sur environ 1 300 kilom\u00e8tres depuis le fournisseur en Hongrie. Pour cela, douze \u00e0 quinze v\u00e9hicules enti\u00e8rement charg\u00e9s traversent l&rsquo;Europe chaque jour. Cette caravane de camions est d\u00e9sormais remplac\u00e9e par le transport ferroviaire. Cela permet d&rsquo;\u00e9conomiser environ 2 600 tonnes de CO<sub>2<\/sub> par an. L\u00e0 o\u00f9 c&rsquo;est possible, Audi utilise l&rsquo;offre DB<em>eco plus<\/em> de DB Cargo \u2013 actuellement pour les sections de trajet en Autriche et en Allemagne : ici, la quantit\u00e9 d&rsquo;\u00e9lectricit\u00e9 consomm\u00e9e provient exclusivement de sources renouvelables telles que l&rsquo;\u00e9nergie \u00e9olienne, hydraulique ou solaire, le transport \u00e9tant donc sans CO<sub>2<\/sub>. En Hongrie et en Belgique, Audi utilise le produit DB<em>eco neutral<\/em>, ce qui signifie que l&rsquo;entreprise compense la quantit\u00e9 d&rsquo;\u00e9lectricit\u00e9 consomm\u00e9e par des certificats climatiques. Le CO<sub>2<\/sub> produit lors du transport est ainsi compens\u00e9 ailleurs.<\/p>\n<p>L&rsquo;importance de cette approche pour l&rsquo;usine de Bruxelles est expliqu\u00e9e par Volker Germann, pr\u00e9sident du conseil d&rsquo;administration d&rsquo;Audi Brussels : \u00ab Notre site est d\u00e9j\u00e0 neutre en CO<sub>2<\/sub> depuis 2018. Nous visons donc \u00e9galement une orientation durable dans la cha\u00eene d&rsquo;approvisionnement et contribuons \u00e0 la protection de l&rsquo;environnement \u00e0 tous les niveaux. \u00bb Les co\u00fbts de processus diminuent \u00e9galement chaque ann\u00e9e de plusieurs millions. Les \u00e9conomies r\u00e9sultent non seulement du passage au rail, mais l&rsquo;ensemble du processus de livraison jusqu&rsquo;\u00e0 l&rsquo;usine de Bruxelles a \u00e9t\u00e9 optimis\u00e9.<\/p>\n<h5>Centre logistique par DB Cargo<\/h5>\n<p>Le fournisseur de modules de batterie en Hongrie ne dispose pas de sa propre connexion ferroviaire. DB Cargo, partenaire de projet de longue date de l&rsquo;AUDI AG, a donc r\u00e9cemment mis en service un Centre logistique (CL) sur le site de Gy\u0151r. C&rsquo;est ici que le transbordement des modules de batterie de la route vers le rail se fait \u00e0 l&rsquo;abri des intemp\u00e9ries. Ceux-ci sont r\u00e9cup\u00e9r\u00e9s par camion chez le fabricant et transport\u00e9s par rail vers Bruxelles sur plus de 1 000 kilom\u00e8tres \u00e0 partir du CL Gy\u0151r. Dans un premier temps, un hall l\u00e9ger a \u00e9t\u00e9 construit \u00e0 proximit\u00e9 de l&rsquo;usine Audi \u00e0 Gy\u0151r, et une extension est d\u00e9j\u00e0 pr\u00e9vue. Pour r\u00e9pondre aux exigences \u00e9lev\u00e9es de qualit\u00e9 et de s\u00e9curit\u00e9 pour les modules et cellules de batterie, l&rsquo;\u00e9quipe de la cha\u00eene d&rsquo;approvisionnement d&rsquo;Audi surveille la temp\u00e9rature et les \u00e9ventuels chocs dans les wagons \u00e0 l&rsquo;aide de capteurs sp\u00e9ciaux via une plateforme d&rsquo;information num\u00e9rique.<\/p>\n<h4>Un concept pour toute l&rsquo;entreprise<\/h4>\n<p>Ce que Bruxelles montre en exemple devrait \u00eatre \u00e9tendu \u00e0 l&rsquo;ensemble de l&rsquo;entreprise dans un avenir proche : les composants \u00e0 fort d\u00e9bit tels que les modules et cellules de batterie passent de plus en plus au rail \u2013 d&rsquo;ici 2025, Audi vise \u00e0 transporter ces composants exclusivement par train. Au si\u00e8ge d&rsquo;Audi \u00e0 Ingolstadt, par exemple, tout est d\u00e9j\u00e0 pr\u00eat pour la production de batteries \u00e0 partir de modules et cellules livr\u00e9s par train, qui seront ensuite utilis\u00e9s dans les mod\u00e8les Audi fabriqu\u00e9s sur place. De nouvelles installations et processus ont \u00e9t\u00e9 sp\u00e9cialement install\u00e9s pour cela. D&rsquo;autres usines sont \u00e9galement pr\u00eates \u00e0 passer au transport ferroviaire des composants de batterie. De m\u00eame, le transport des produits finis se fait en grande partie par rail : d\u00e9j\u00e0 aujourd&rsquo;hui, environ 68 % des v\u00e9hicules Audi quittent les usines en Europe par train. Ce pourcentage devrait \u00e9galement augmenter \u00e0 l&rsquo;avenir.<\/p>\n<h4>Int\u00e9gration dans le programme environnemental Mission:Zero<\/h4>\n<p>Ces objectifs s&rsquo;inscrivent dans le programme environnemental global Mission:Zero, avec lequel Audi souhaite devenir neutre en CO<sub>2<\/sub> d&rsquo;ici 2025 sur tous ses sites. En plus de la d\u00e9carbonisation de la production et de la logistique, l&rsquo;utilisation de l&rsquo;eau, l&rsquo;efficacit\u00e9 des ressources et la biodiversit\u00e9 sont des domaines d&rsquo;action centraux de Mission:Zero.<\/p>\n<p>Photo : Copyright Audi<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Une approche globale pour une logistique neutre en CO2 fait ses d\u00e9buts : les modules et cellules de batterie en provenance de Hongrie seront d\u00e9sormais transport\u00e9s<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10113,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-56757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Audi transporte des modules de batterie de Hongrie vers la Belgique par train - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Audi transporte des modules de batterie de Hongrie vers la Belgique par train - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Une approche globale pour une logistique neutre en CO2 fait ses d\u00e9buts : les modules et cellules de batterie en provenance de Hongrie seront d\u00e9sormais transport\u00e9s [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-05T18:43:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Audi_5.6.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1489\" \/>\n\t<meta property=\"og:image:height\" content=\"951\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Audi transporte des modules de batterie de Hongrie vers la Belgique par train\",\"datePublished\":\"2022-06-05T18:43:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/\"},\"wordCount\":951,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Audi_5.6.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/\",\"name\":\"Audi transporte des modules de batterie de Hongrie vers la Belgique par train - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Audi_5.6.22.jpg\",\"datePublished\":\"2022-06-05T18:43:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Audi_5.6.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Audi_5.6.22.jpg\",\"width\":1489,\"height\":951},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/05\\\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Audi transporte des modules de batterie de Hongrie vers la Belgique par train\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Audi transporte des modules de batterie de Hongrie vers la Belgique par train - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/","og_locale":"fr_FR","og_type":"article","og_title":"Audi transporte des modules de batterie de Hongrie vers la Belgique par train - Loginfo24.","og_description":"Une approche globale pour une logistique neutre en CO2 fait ses d\u00e9buts : les modules et cellules de batterie en provenance de Hongrie seront d\u00e9sormais transport\u00e9s [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-06-05T18:43:24+00:00","og_image":[{"width":1489,"height":951,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Audi_5.6.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/"},"author":{"name":"","@id":""},"headline":"Audi transporte des modules de batterie de Hongrie vers la Belgique par train","datePublished":"2022-06-05T18:43:24+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/"},"wordCount":951,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Audi_5.6.22.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/","url":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/","name":"Audi transporte des modules de batterie de Hongrie vers la Belgique par train - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Audi_5.6.22.jpg","datePublished":"2022-06-05T18:43:24+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Audi_5.6.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Audi_5.6.22.jpg","width":1489,"height":951},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/05\/audi-transporte-des-modules-de-batterie-de-hongrie-vers-la-belgique-par-train\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Audi transporte des modules de batterie de Hongrie vers la Belgique par train"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/56757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=56757"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/56757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/10113"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=56757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=56757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=56757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}