{"id":56728,"date":"2022-06-02T14:16:30","date_gmt":"2022-06-02T12:16:30","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/"},"modified":"2022-06-02T14:16:30","modified_gmt":"2022-06-02T12:16:30","slug":"hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/","title":{"rendered":"Hans-Peter Trachsler succ\u00e8de \u00e0 Urs H\u00e4ner chez Dachser Suisse"},"content":{"rendered":"<h5><strong>Hans-Peter Trachsler dirige depuis mars 2022 le <\/strong><strong>bureau r\u00e9gional de Suisse de Dachser European Logistics situ\u00e9 \u00e0 Regensdorf (ZH). \u00c0 partir du 1er octobre 2022, <\/strong><strong>il reprend la <\/strong><strong>responsabilit\u00e9 g\u00e9n\u00e9rale de la soci\u00e9t\u00e9 nationale suisse d&rsquo;Urs H\u00e4ner, qui partira \u00e0 la retraite. <\/strong><strong>La r\u00e9daction a discut\u00e9 avec les deux hommes des conditions-cadres de la prochaine passation de pouvoir ainsi que des d\u00e9fis \u00e0 relever.<\/strong><\/h5>\n<p>L&rsquo;interview a \u00e9t\u00e9 r\u00e9alis\u00e9e par Lorenzo Rigliaco<\/p>\n<p><em><strong>Monsieur Trachsler, vous partagez actuellement un bureau avec Monsieur H\u00e4ner. Cela se passe bien ?<\/strong><\/em><\/p>\n<p>T.: Oui, cela fonctionne m\u00eame tr\u00e8s bien. Nous nous entendons tr\u00e8s bien. La proximit\u00e9 physique favorise un \u00e9change d&rsquo;id\u00e9es intense et facilite les ajustements n\u00e9cessaires. Urs H\u00e4ner est chez Dachser depuis 25 ans. Il sait comment fonctionne l&rsquo;entreprise, il aime cette soci\u00e9t\u00e9 et peut tr\u00e8s bien me transmettre l&rsquo;\u00ab esprit de Dachser \u00bb. Je le trouve tr\u00e8s ouvert et collaboratif. Dans nos discussions, nous parlons notamment des nouvelles impulsions que je souhaite donner. Ce qui fonctionne bien doit \u00eatre pr\u00e9serv\u00e9 et l&rsquo;agilit\u00e9 dans nos temps complexes doit \u00eatre augment\u00e9e. La passation de t\u00e2ches est un processus fluide. L\u00e0 o\u00f9 cela a du sens, nous d\u00e9cidons ensemble. Sinon, Urs H\u00e4ner continue de g\u00e9rer les affaires comme auparavant.<\/p>\n<p><em><strong>Monsieur H\u00e4ner, comment va l&rsquo;entreprise que vous transmettez maintenant \u00e0 Monsieur Trachsler ?<\/strong><\/em><\/p>\n<p>H.: Dachser Suisse a un mod\u00e8le commercial \u00e9prouv\u00e9 et robuste, des employ\u00e9s motiv\u00e9s et un bon portefeuille clients. Pour 2020 et 2021, nous avons pr\u00e9sent\u00e9 un excellent bilan et un compte de r\u00e9sultats malgr\u00e9 la pand\u00e9mie. M\u00eame au premier trimestre 2022, nos attentes se sont r\u00e9alis\u00e9es. Cependant, il est difficile d&rsquo;estimer comment l&rsquo;entreprise \u00e9voluera en raison des circonstances connues (guerre en Ukraine, inflation, p\u00e9nurie de main-d&rsquo;\u0153uvre, Covid-19). Actuellement, nous pr\u00e9voyons une l\u00e9g\u00e8re croissance pour l&rsquo;ann\u00e9e 2022.<\/p>\n<p><em><strong>Monsieur Trachsler, quels sont les d\u00e9fis de votre nouvelle fonction ?<\/strong><\/em><\/p>\n<p>T.: J&rsquo;ai \u00e9t\u00e9 \u00ab socialis\u00e9 \u00bb pendant de nombreuses ann\u00e9es chez DB Schenker. Je connaissais l&rsquo;entreprise sur le bout des doigts. Je savais comment y \u00e9voluer, quels leviers activer pour r\u00e9ussir. Chez Dachser, j&rsquo;apprends maintenant une nouvelle culture. Je dois m&rsquo;immerger dans de nouveaux processus, en gros : apprendre de nouvelles choses. Dachser est une entreprise prosp\u00e8re. Cela a ses raisons. Je souhaite les d\u00e9couvrir progressivement. En m\u00eame temps, je dois tester comment je peux m&rsquo;impliquer dans l&rsquo;entreprise et ce que je peux apporter \u00e0 l&rsquo;augmentation du succ\u00e8s de l&rsquo;entreprise.<\/p>\n<div id=\"attachment_19479\" style=\"width: 1302px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19479\" class=\"wp-image-19479 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_2.6.22_1.jpg\" alt=\"\" width=\"1292\" height=\"657\" \/><p id=\"caption-attachment-19479\" class=\"wp-caption-text\">\u00a9 Dachser<\/p><\/div>\n<p><em><strong>Groupe vs. entreprise familiale \u2013 comment g\u00e9rez-vous le changement culturel ?<\/strong><\/em><\/p>\n<p>T: Le nouveau, le passage \u00e0 une entreprise familiale m&rsquo;a attir\u00e9. Mais Dachser a aussi certaines structures de groupe. Je fais actuellement des kilom\u00e8tres, pour mieux conna\u00eetre l&rsquo;entreprise. Cela implique par exemple des rencontres personnelles avec les employ\u00e9s de Dachser Suisse et avec la client\u00e8le.<\/p>\n<p><em><strong>Quels objectifs vous \u00eates-vous fix\u00e9s ?<\/strong><\/em><\/p>\n<p>T.: Dachser a fortement grandi au cours de la derni\u00e8re d\u00e9cennie. Malgr\u00e9 la pand\u00e9mie et la guerre en Ukraine, l&rsquo;entreprise est bien positionn\u00e9e et a de grandes ambitions pour les prochaines ann\u00e9es. Je souhaite faire avancer Dachser Suisse dans ce contexte de groupe \u2013 avec tous les employ\u00e9s qui travaillent chez nous. Je vois encore un grand potentiel pour nous en tant que prestataire logistique r\u00e9ussi en Suisse.<\/p>\n<p><em><strong>Monsieur H\u00e4ner, que va-t-il concr\u00e8tement arriver \u00e0 Dachser Suisse \u00e0 moyen terme ?<\/strong><\/em><\/p>\n<p>H.: L&rsquo;entreprise continuera \u00e0 avancer dans la num\u00e9risation de ses processus. Parmi les projets qui seront mis en \u0153uvre prochainement figurent, entre autres, l&rsquo;adaptation du logiciel douanier suisse, la facturation \u00e9lectronique (e-Invoicing), le transport de proximit\u00e9 num\u00e9ris\u00e9 2.0 ainsi que des mesures pour la protection du climat. Ainsi, notre succursale de Regensdorf (ZH) sera agrandie et \u00e9lectrifi\u00e9e de mani\u00e8re \u00e9cologique en 2024, et celle de Lyss (BE) en 2025 (panneaux solaires, e-mobilit\u00e9, etc.).<\/p>\n<p><em><strong>Monsieur Trachsler, quelle importance accordez-vous \u00e0 l&rsquo;orientation vers la performance et \u00e0 la responsabilit\u00e9 sociale ?<\/strong><\/em><\/p>\n<p>T: Pour moi, la performance va de pair avec la responsabilit\u00e9 sociale et les ressources. Dachser est fier de sa culture d&rsquo;entreprise. Les \u00e9l\u00e9ments importants de cette culture sont l&rsquo;humanit\u00e9, le professionnalisme ainsi que des principes clairs et une pens\u00e9e innovante. Dans une telle culture, l&rsquo;orientation vers le profit durable et la responsabilit\u00e9 sociale ne s&rsquo;excluent pas.<\/p>\n<p><em><strong>Quelles sont vos forces particuli\u00e8res ?<\/strong><\/em><\/p>\n<p>T.: Je suis une personne authentique, qui dirige de mani\u00e8re coll\u00e9giale, un joueur d&rsquo;\u00e9quipe qui implique ses employ\u00e9s dans les processus d\u00e9cisionnels. De plus, je suis tr\u00e8s orient\u00e9 client. Il est important pour moi que nous \u00e9coutions les clients, qu&rsquo;ils comprennent nos services et qu&rsquo;ils dialoguent avec nous. Ce n&rsquo;est qu&rsquo;ainsi que cela devient une situation gagnant-gagnant.<\/p>\n<p><em><strong>Avez-vous une devise ?<\/strong><\/em><\/p>\n<p>T.: Le travail doit \u00eatre amusant pour moi et mes employ\u00e9s.<\/p>\n<p><em><strong>Monsieur H\u00e4ner, vous avez \u00e9t\u00e9 presque 25 ans chez Dachser Suisse, dont les huit derni\u00e8res ann\u00e9es en tant que directeur g\u00e9n\u00e9ral de la logistique europ\u00e9enne en Suisse. Quels sont vos projets pour l&rsquo;apr\u00e8s ?<\/strong><\/em><\/p>\n<p>H.: D&rsquo;abord, je veux voyager au Cap Nord. Ensuite, am\u00e9liorer mes comp\u00e9tences en italien en Italie. De plus, des missions de travail caritatif en Afrique du Sud sont pr\u00e9vues. Enfin, je veux travailler sur mon handicap au golf. Il y a encore un potentiel d&rsquo;optimisation.<\/p>\n<p>&nbsp;<\/p>\n<p>Photo : \u00a9 Gion Pfander \/ <strong><em>L\u00e9gende de l&rsquo;image :<\/em><\/strong> <em>Urs H\u00e4ner (\u00e0 gauche) passe la direction de Dachser Suisse \u00e0 Hans-Peter Trachsler<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hans-Peter Trachsler dirige depuis mars 2022 le bureau r\u00e9gional de Suisse de Dachser European Logistics situ\u00e9 \u00e0 Regensdorf (ZH). \u00c0 partir du 1er octobre 2022, il<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10125,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1560,1561],"tags":[],"class_list":["post-56728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hans-Peter Trachsler succ\u00e8de \u00e0 Urs H\u00e4ner chez Dachser Suisse - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hans-Peter Trachsler succ\u00e8de \u00e0 Urs H\u00e4ner chez Dachser Suisse - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Hans-Peter Trachsler dirige depuis mars 2022 le bureau r\u00e9gional de Suisse de Dachser European Logistics situ\u00e9 \u00e0 Regensdorf (ZH). \u00c0 partir du 1er octobre 2022, il [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-02T12:16:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_2.6.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1492\" \/>\n\t<meta property=\"og:image:height\" content=\"930\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hans-Peter Trachsler succ\u00e8de \u00e0 Urs H\u00e4ner chez Dachser Suisse\",\"datePublished\":\"2022-06-02T12:16:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/\"},\"wordCount\":959,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_2.6.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/\",\"name\":\"Hans-Peter Trachsler succ\u00e8de \u00e0 Urs H\u00e4ner chez Dachser Suisse - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_2.6.22.jpg\",\"datePublished\":\"2022-06-02T12:16:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_2.6.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_2.6.22.jpg\",\"width\":1492,\"height\":930},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/06\\\/02\\\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hans-Peter Trachsler succ\u00e8de \u00e0 Urs H\u00e4ner chez Dachser Suisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hans-Peter Trachsler succ\u00e8de \u00e0 Urs H\u00e4ner chez Dachser Suisse - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/","og_locale":"fr_FR","og_type":"article","og_title":"Hans-Peter Trachsler succ\u00e8de \u00e0 Urs H\u00e4ner chez Dachser Suisse - Loginfo24.","og_description":"Hans-Peter Trachsler dirige depuis mars 2022 le bureau r\u00e9gional de Suisse de Dachser European Logistics situ\u00e9 \u00e0 Regensdorf (ZH). \u00c0 partir du 1er octobre 2022, il [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-06-02T12:16:30+00:00","og_image":[{"width":1492,"height":930,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_2.6.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/"},"author":{"name":"","@id":""},"headline":"Hans-Peter Trachsler succ\u00e8de \u00e0 Urs H\u00e4ner chez Dachser Suisse","datePublished":"2022-06-02T12:16:30+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/"},"wordCount":959,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_2.6.22.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/","url":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/","name":"Hans-Peter Trachsler succ\u00e8de \u00e0 Urs H\u00e4ner chez Dachser Suisse - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_2.6.22.jpg","datePublished":"2022-06-02T12:16:30+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_2.6.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_2.6.22.jpg","width":1492,"height":930},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2022\/06\/02\/hans-peter-trachsler-succede-a-urs-haner-chez-dachser-suisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Hans-Peter Trachsler succ\u00e8de \u00e0 Urs H\u00e4ner chez Dachser Suisse"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/56728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=56728"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/56728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/10125"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=56728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=56728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=56728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}