{"id":56388,"date":"2022-05-16T21:00:25","date_gmt":"2022-05-16T19:00:25","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/"},"modified":"2022-05-16T21:00:25","modified_gmt":"2022-05-16T19:00:25","slug":"geis-regroupe-les-processus-logistiques-pour-kneipp","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/","title":{"rendered":"Geis regroupe les processus logistiques pour Kneipp"},"content":{"rendered":"<h5><strong>D\u00e9but avril, le groupe Geis a mis en service le deuxi\u00e8me b\u00e2timent de son centre logistique et technologique \u00e0 Gochsheim, pr\u00e8s de Schweinfurt. La majeure partie de l&rsquo;installation de 20 000 m\u00e8tres carr\u00e9s est utilis\u00e9e par le groupe Kneipp : d\u00e8s maintenant, tous les processus logistiques seront regroup\u00e9s dans la nouvelle installation et trait\u00e9s avec des technologies et infrastructures innovantes \u2013 jusqu&rsquo;\u00e0 120 000 commandes par an, tendance \u00e0 la hausse.<\/strong><\/h5>\n<p>(Gochsheim \/ Bad Neustadt \/ Nuremberg) Depuis sa cr\u00e9ation il y a plus de 130 ans, de plus en plus de personnes font confiance aux produits de Kneipp. Que ce soit pour le bain, la douche, les soins, la sant\u00e9 ou le style de vie \u2013 plus de 1 200 articles diff\u00e9rents sont distribu\u00e9s par Kneipp dans le monde entier. Jusqu&rsquo;\u00e0 pr\u00e9sent, l&rsquo;entreprise distribuait ses produits de mani\u00e8re autonome. Cela change maintenant, car Kneipp a des objectifs de croissance ambitieux et souhaite offrir encore plus de services \u00e0 ses clients, notamment en mati\u00e8re d&rsquo;exp\u00e9dition.<\/p>\n<p>C&rsquo;est l\u00e0 que Geis entre en jeu : \u00ab Nous avons une longue partenariat avec Kneipp \u00bb, expliquent Dr. Johannes S\u00f6llner, directeur g\u00e9n\u00e9ral de Geis Holding, et Henry Portisch, responsable de l&rsquo;agence Geis \u00e0 W\u00fcrzburg. \u00ab Nous g\u00e9rons un grand entrep\u00f4t externe pour le client et agissons \u00e9galement en tant que transporteur. Nous avons maintenant pu convaincre avec notre concept logistique orient\u00e9 vers l&rsquo;avenir. \u00bb<\/p>\n<h5><strong>Construction sur mesure<\/strong><\/h5>\n<p>Le point central est le nouveau centre logistique et technologique de Gochsheim, que Geis a construit sur un terrain d&rsquo;environ dix hectares. Il se trouve juste \u00e0 c\u00f4t\u00e9 de l&rsquo;installation logistique existante.<\/p>\n<p>Cela permet \u00e0 Geis, en combinaison avec d&rsquo;autres projets logistiques sur place, de r\u00e9agir de mani\u00e8re tr\u00e8s flexible aux fluctuations saisonni\u00e8res \u2013 tant sur le plan personnel que technique et spatial.<\/p>\n<p>D\u00e8s la construction, Geis a pris en compte les besoins particuliers de Kneipp. Le b\u00e2timent est approuv\u00e9 pour la manipulation et le stockage de m\u00e9dicaments gr\u00e2ce \u00e0 des mesures de construction et organisationnelles. De plus, Geis a mis en place deux entrep\u00f4ts de mati\u00e8res dangereuses, qui couvrent ensemble environ 5 000 m\u00e8tres carr\u00e9s. Des produits tels que des huiles de bain ou des pommades \u00e0 l&rsquo;arnica y sont stock\u00e9s.<\/p>\n<h5><strong>Large \u00e9ventail de t\u00e2ches<\/strong><\/h5>\n<p>Les t\u00e2ches de l&rsquo;\u00e9quipe de Gochsheim comprennent les transports par navette depuis l&rsquo;usine Kneipp \u00e0 Ochsenfurt-Hohestadt, le traitement des entr\u00e9es de marchandises, le stockage et la pr\u00e9paration des commandes, la cr\u00e9ation des documents de transport, le traitement des exp\u00e9ditions ainsi que, en partie, des prestations de transport. Des services \u00e0 valeur ajout\u00e9e tels que la gestion douani\u00e8re, la gestion des retours et la construction d&rsquo;affichages font \u00e9galement partie de l&rsquo;\u00e9ventail des services.<\/p>\n<p>Pour des processus efficaces, Geis utilise des innovations techniques \u00e0 Gochsheim. Ainsi, les employ\u00e9s pr\u00e9parent notamment les commandes \u00e0 l&rsquo;aide de smartphones en combinaison avec des scanners \u00e0 gants. Et lors de la pr\u00e9paration et de l&#8217;emballage des commandes en ligne, un syst\u00e8me de transport enti\u00e8rement automatique avec dix stations de pr\u00e9paration des commandes est \u00e0 leur disposition.<\/p>\n<h5><strong>Plus de 120 000 commandes par an<\/strong><\/h5>\n<p>Il est pr\u00e9vu que Geis traite plus de 120 000 commandes pour Kneipp par an et puisse accueillir d&rsquo;autres envois \u00e0 l&rsquo;avenir. \u00ab Les possibilit\u00e9s d&rsquo;extension sur place font partie int\u00e9grante de notre concept logistique commun \u00bb, d\u00e9clare Christian Kempf, responsable de la gestion des mat\u00e9riaux et de la logistique internationale du groupe Kneipp. \u00ab Apr\u00e8s tout, nous voulons cro\u00eetre continuellement \u2013 ensemble avec Geis \u00e0 Gochsheim. \u00bb<\/p>\n<p>Photo : \u00a9 Geis Gruppe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9but avril, le groupe Geis a mis en service le deuxi\u00e8me b\u00e2timent de son centre logistique et technologique \u00e0 Gochsheim, pr\u00e8s de Schweinfurt. La majeure partie<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-56388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geis regroupe les processus logistiques pour Kneipp - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geis regroupe les processus logistiques pour Kneipp - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"D\u00e9but avril, le groupe Geis a mis en service le deuxi\u00e8me b\u00e2timent de son centre logistique et technologique \u00e0 Gochsheim, pr\u00e8s de Schweinfurt. La majeure partie [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-16T19:00:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Geis_17.05.2022-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Geis regroupe les processus logistiques pour Kneipp\",\"datePublished\":\"2022-05-16T19:00:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/\"},\"wordCount\":616,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Geis_17.05.2022-scaled-1.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/\",\"name\":\"Geis regroupe les processus logistiques pour Kneipp - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Geis_17.05.2022-scaled-1.jpg\",\"datePublished\":\"2022-05-16T19:00:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Geis_17.05.2022-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Geis_17.05.2022-scaled-1.jpg\",\"width\":2560,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/16\\\/geis-regroupe-les-processus-logistiques-pour-kneipp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geis regroupe les processus logistiques pour Kneipp\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geis regroupe les processus logistiques pour Kneipp - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/","og_locale":"fr_FR","og_type":"article","og_title":"Geis regroupe les processus logistiques pour Kneipp - Loginfo24.","og_description":"D\u00e9but avril, le groupe Geis a mis en service le deuxi\u00e8me b\u00e2timent de son centre logistique et technologique \u00e0 Gochsheim, pr\u00e8s de Schweinfurt. La majeure partie [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-05-16T19:00:25+00:00","og_image":[{"width":2560,"height":1333,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Geis_17.05.2022-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/"},"author":{"name":"","@id":""},"headline":"Geis regroupe les processus logistiques pour Kneipp","datePublished":"2022-05-16T19:00:25+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/"},"wordCount":616,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Geis_17.05.2022-scaled-1.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/","url":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/","name":"Geis regroupe les processus logistiques pour Kneipp - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Geis_17.05.2022-scaled-1.jpg","datePublished":"2022-05-16T19:00:25+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Geis_17.05.2022-scaled-1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Geis_17.05.2022-scaled-1.jpg","width":2560,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/16\/geis-regroupe-les-processus-logistiques-pour-kneipp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Geis regroupe les processus logistiques pour Kneipp"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/56388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=56388"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/56388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/10249"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=56388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=56388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=56388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}