{"id":56137,"date":"2022-05-05T11:23:17","date_gmt":"2022-05-05T09:23:17","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/"},"modified":"2022-05-05T11:23:17","modified_gmt":"2022-05-05T09:23:17","slug":"logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/","title":{"rendered":"LOGISTIQUE URBAINE DERNI\u00c8RE MILE avec premi\u00e8re fin juin \u00e0 Berlin"},"content":{"rendered":"<h5><strong>Des solutions durables et intelligentes pour faire face \u00e0 l&rsquo;afflux de colis et \u00e0 la livraison de marchandises dans les centres-villes seront pr\u00e9sent\u00e9es et discut\u00e9es. La rencontre se d\u00e9roulera du 29 au 30 juin au Motorwerk \u00e0 Berlin. Le programme des experts et l&rsquo;Expo s&rsquo;adressent au commerce et \u00e0 la logistique, aux urbanistes et aux planificateurs de quartiers, ainsi qu&rsquo;\u00e0 tous ceux qui recherchent de nouvelles formes de mobilit\u00e9 pour la livraison de colis et de marchandises.<\/strong><\/h5>\n<p>(Karlsruhe\/Berlin) La livraison de colis dans les centres-villes et les zones r\u00e9sidentielles devient un d\u00e9fi de plus en plus important. L&rsquo;augmentation constante du commerce en ligne et la livraison de marchandises, tant dans le secteur commercial que priv\u00e9, sur le dernier kilom\u00e8tre, entra\u00eenent un accroissement du trafic de livraison dans les zones dens\u00e9ment peupl\u00e9es et les centres-villes, o\u00f9 l&rsquo;espace sur les routes est d\u00e9j\u00e0 limit\u00e9. La demande d&rsquo;espaces suppl\u00e9mentaires sous forme de halls ou de b\u00e2timents vacants dans les villes pour stocker temporairement les colis augmente \u00e9galement. Et le d\u00e9fi ne cesse de cro\u00eetre : l&rsquo;Association f\u00e9d\u00e9rale des colis et de la logistique express (BIEK) \u00e9voque dans son \u00e9tude de 2021 une croissance annuelle de 7 % jusqu&rsquo;en 2025 pour les livraisons de coursiers, express et colis, ce qui repr\u00e9sente jusqu&rsquo;\u00e0 environ 6 milliards de livraisons de colis par an en Allemagne.<\/p>\n<p>Les experts, les grandes entreprises de logistique et les jeunes innovateurs du secteur sont donc d\u00e9j\u00e0 activement \u00e0 la recherche de solutions \u00e9conomiquement et \u00e9cologiquement durables pour optimiser la livraison des colis aux clients. Les questions concernant le retour des produits ou le retour des emballages font \u00e9galement partie des pr\u00e9occupations, tout comme l&rsquo;achat lui-m\u00eame, et ne peuvent \u00eatre r\u00e9solues qu&rsquo;avec la participation des entreprises sur le dernier kilom\u00e8tre de livraison. Pour les fournisseurs de commerce \u00e9lectronique, la question se pose donc de savoir avec quels partenaires et solutions ils peuvent garantir une livraison de marchandises optimale, qui soit \u00e0 la fois \u00e9cologiquement durable et moderne.<\/p>\n<h5><strong>Le march\u00e9 des fournisseurs de v\u00e9los cargo se d\u00e9veloppe<\/strong><\/h5>\n<p>Le march\u00e9 des fournisseurs pour la livraison de colis et de marchandises sur le dernier kilom\u00e8tre est tr\u00e8s dynamique. De nombreuses startups \u00e9mergent avec des solutions intelligentes pr\u00e9cis\u00e9ment l\u00e0 o\u00f9 les probl\u00e8mes sont visibles. Rien qu&rsquo;en 2020, le march\u00e9 des fournisseurs de v\u00e9los cargo a cr\u00fb de plus de la moiti\u00e9. Les micro-d\u00e9p\u00f4ts en tant que points de transit et de livraison sont d\u00e9j\u00e0 en service \u00e0 de nombreux endroits.<\/p>\n<p>Pour la premi\u00e8re fois, la LOGISTIQUE URBAINE DERNI\u00c8RE MILE (LMCL) rassemble les acteurs du dernier kilom\u00e8tre \u00e0 Berlin pour une grande rencontre en direct du secteur. Le programme d&rsquo;experts de deux jours et l&rsquo;Expo s&rsquo;adressent au commerce et \u00e0 la logistique, aux urbanistes et aux planificateurs de quartiers, ainsi qu&rsquo;\u00e0 tous ceux qui recherchent de nouvelles formes de mobilit\u00e9 pour la livraison de colis et de marchandises, et permettent de trouver et d&rsquo;\u00e9changer des solutions globales et coop\u00e9ratives.<\/p>\n<h5><strong>Les exposants pr\u00e9sentent leurs solutions<\/strong><\/h5>\n<p>En plus des ateliers, des conf\u00e9rences et des tables rondes, une Expo avec 50 entreprises \u2013 des grandes entreprises de logistique aux jeunes innovateurs du secteur \u2013 ainsi que des espaces et du temps pour le r\u00e9seautage sont propos\u00e9s. L&rsquo;Association f\u00e9d\u00e9rale des services de coursiers-express-poste (BdKEP) proposera le premier jour de la LMCL BERLIN une conf\u00e9rence sp\u00e9cialis\u00e9e pour les entreprises KEP.<\/p>\n<h5><strong>Impatience pour l&rsquo;\u00e9v\u00e9nement en pr\u00e9sentiel<\/strong><\/h5>\n<p>Andreas Schumann, pr\u00e9sident du BdKEP, se r\u00e9jouit de la rencontre : \u00ab L&rsquo;\u00e9v\u00e9nement en pr\u00e9sentiel cr\u00e9e la confiance n\u00e9cessaire pour des projets communs. \u00bb Daniel Katzer de l&rsquo;organisateur HINTE ajoute : \u00ab La plateforme communautaire num\u00e9rique de la LMCL, disponible 365 jours par an, ainsi que les rencontres num\u00e9riques d\u00e9j\u00e0 r\u00e9alis\u00e9es, offrent un contexte solide et important avec des informations de march\u00e9 et de projet toujours \u00e0 jour. Cependant, cela ne peut remplacer le contact personnel et les \u00e9changes. C&rsquo;est pourquoi nous attendons avec impatience la rencontre en direct de ce jeune secteur ! \u00bb<\/p>\n<h5><strong>\u00c0 propos de la LOGISTIQUE URBAINE DERNI\u00c8RE MILE<\/strong><\/h5>\n<p>En plus de la plateforme communautaire en ligne tout au long de l&rsquo;ann\u00e9e, l&rsquo;\u00e9change aura lieu apr\u00e8s deux \u00e9v\u00e9nements num\u00e9riques r\u00e9ussis du 29 au 30 juin 2022 au Motorwerk Berlin. Les fournisseurs de micromobilit\u00e9 et de d\u00e9p\u00f4ts, les op\u00e9rateurs de biens immobiliers commerciaux et les urbanistes, les entreprises de commerce \u00e9lectronique et les prestataires de services de colis se rencontreront pour \u00e9changer et comme lancement de projets.<\/p>\n<h5><strong>Inscrivez-vous maintenant et obtenez 50 % de r\u00e9duction avec Loginfo24<\/strong><\/h5>\n<p>Suivez le lien : <a href=\"https:\/\/bit.ly\/38TdPxx\" target=\"_blank\" rel=\"noopener\">https:\/\/bit.ly\/38TdPxx<\/a><\/p>\n<p>et entrez le code suivant : <strong>LMCL22-Loginfo24<\/strong><\/p>\n<p>Graphiques : \u00a9 HINTE\/Loginfo24<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des solutions durables et intelligentes pour faire face \u00e0 l&rsquo;afflux de colis et \u00e0 la livraison de marchandises dans les centres-villes seront pr\u00e9sent\u00e9es et discut\u00e9es. La<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-56137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LOGISTIQUE URBAINE DERNI\u00c8RE MILE avec premi\u00e8re fin juin \u00e0 Berlin - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LOGISTIQUE URBAINE DERNI\u00c8RE MILE avec premi\u00e8re fin juin \u00e0 Berlin - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Des solutions durables et intelligentes pour faire face \u00e0 l&rsquo;afflux de colis et \u00e0 la livraison de marchandises dans les centres-villes seront pr\u00e9sent\u00e9es et discut\u00e9es. La [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-05T09:23:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Last_Mile_5.5.22_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1315\" \/>\n\t<meta property=\"og:image:height\" content=\"736\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"LOGISTIQUE URBAINE DERNI\u00c8RE MILE avec premi\u00e8re fin juin \u00e0 Berlin\",\"datePublished\":\"2022-05-05T09:23:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/\"},\"wordCount\":818,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Last_Mile_5.5.22_2.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/\",\"name\":\"LOGISTIQUE URBAINE DERNI\u00c8RE MILE avec premi\u00e8re fin juin \u00e0 Berlin - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Last_Mile_5.5.22_2.jpg\",\"datePublished\":\"2022-05-05T09:23:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Last_Mile_5.5.22_2.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Last_Mile_5.5.22_2.jpg\",\"width\":1315,\"height\":736},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/05\\\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LOGISTIQUE URBAINE DERNI\u00c8RE MILE avec premi\u00e8re fin juin \u00e0 Berlin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LOGISTIQUE URBAINE DERNI\u00c8RE MILE avec premi\u00e8re fin juin \u00e0 Berlin - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/","og_locale":"fr_FR","og_type":"article","og_title":"LOGISTIQUE URBAINE DERNI\u00c8RE MILE avec premi\u00e8re fin juin \u00e0 Berlin - Loginfo24.","og_description":"Des solutions durables et intelligentes pour faire face \u00e0 l&rsquo;afflux de colis et \u00e0 la livraison de marchandises dans les centres-villes seront pr\u00e9sent\u00e9es et discut\u00e9es. La [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-05-05T09:23:17+00:00","og_image":[{"width":1315,"height":736,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Last_Mile_5.5.22_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/"},"author":{"name":"","@id":""},"headline":"LOGISTIQUE URBAINE DERNI\u00c8RE MILE avec premi\u00e8re fin juin \u00e0 Berlin","datePublished":"2022-05-05T09:23:17+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/"},"wordCount":818,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Last_Mile_5.5.22_2.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/","url":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/","name":"LOGISTIQUE URBAINE DERNI\u00c8RE MILE avec premi\u00e8re fin juin \u00e0 Berlin - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Last_Mile_5.5.22_2.jpg","datePublished":"2022-05-05T09:23:17+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Last_Mile_5.5.22_2.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Last_Mile_5.5.22_2.jpg","width":1315,"height":736},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/05\/logistique-urbaine-derniere-mile-avec-premiere-fin-juin-a-berlin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"LOGISTIQUE URBAINE DERNI\u00c8RE MILE avec premi\u00e8re fin juin \u00e0 Berlin"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/56137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=56137"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/56137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/10355"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=56137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=56137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=56137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}