{"id":56131,"date":"2022-05-04T18:23:16","date_gmt":"2022-05-04T16:23:16","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/"},"modified":"2022-05-04T18:23:16","modified_gmt":"2022-05-04T16:23:16","slug":"la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/","title":{"rendered":"La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre un site \u00e0 Bucarest"},"content":{"rendered":"<h5><strong>La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre une nouvelle succursale \u00e0 Bucarest, en Roumanie, devenant ainsi le premier transporteur num\u00e9rique \u00e0 entrer sur le march\u00e9. Avec un total de onze succursales \u00e0 travers l&rsquo;Europe, sennder poursuit sa croissance strat\u00e9gique pour renforcer son r\u00e9seau d&rsquo;entreprises de transport.<\/strong><\/h5>\n<p>(Berlin\/Bucarest) Avec les succursales d\u00e9j\u00e0 existantes de sennder en Pologne et en Lettonie, le nouveau site en Roumanie contribue \u00e0 la pr\u00e9sence croissante de sennder en Europe centrale et orientale.<\/p>\n<p>Avec plus de 90 000 conducteurs et 25 000 entreprises de transport, la Roumanie est l&rsquo;un des march\u00e9s logistiques \u00e0 la croissance la plus rapide en Europe et un point d&rsquo;entr\u00e9e majeur entre l&rsquo;Europe centrale et orientale. Sennder est un pionnier dans la r\u00e9gion et est d\u00e9j\u00e0 pr\u00e9sent avec des sites \u00e0 Wroc\u0142aw, Pologne (septembre 2019) et \u00e0 Riga, Lettonie (mai 2020). Gr\u00e2ce \u00e0 son offre visant \u00e0 accro\u00eetre l&rsquo;efficacit\u00e9 et la transparence dans la logistique routi\u00e8re, la soci\u00e9t\u00e9 de transport num\u00e9rique a pu d\u00e9velopper sa pr\u00e9sence dans la r\u00e9gion \u00e0 un rythme rapide.<\/p>\n<p>\u00ab Nous sommes ravis d&rsquo;annoncer notre expansion en Roumanie, l&rsquo;un des plus grands march\u00e9s logistiques d&rsquo;Europe. L&rsquo;ouverture de cette succursale est une \u00e9tape importante pour r\u00e9aliser notre vision de rendre la logistique durable gr\u00e2ce \u00e0 la technologie dans cette r\u00e9gion. Nous continuons notre expansion en Europe et cr\u00e9ons de nouveaux services innovants pour les entreprises de transport et les exp\u00e9diteurs commerciaux en permettant une logistique routi\u00e8re plus efficace et transparente dans un environnement de march\u00e9 complexe et difficile \u00e0 pr\u00e9voir \u00bb, explique Tom Christenson, COO de sennder.<\/p>\n<h5><strong>40 employ\u00e9s d&rsquo;ici la fin de l&rsquo;ann\u00e9e<\/strong><\/h5>\n<p>Les op\u00e9rations de sennder en Roumanie seront dirig\u00e9es par Bogdan-Gabriel Steliean. Steliean apporte plus de dix ans d&rsquo;exp\u00e9rience dans le secteur de la logistique. Il a pr\u00e9c\u00e9demment occup\u00e9 des postes de direction chez cargo partners, DHL Freight et le groupe GEFCO. Sennder pr\u00e9voit d&rsquo;augmenter l&rsquo;\u00e9quipe \u00e0 Bucarest de onze employ\u00e9s actuellement \u00e0 40 employ\u00e9s d&rsquo;ici la fin de l&rsquo;ann\u00e9e. Sennder recrute dans tous les domaines, y compris les ressources humaines, la finance et les ventes.<\/p>\n<p>Bogdan-Gabriel Steliean, Senior Manager Operations, commente : \u00ab L&rsquo;ouverture de notre succursale en Roumanie est pour nous la prochaine \u00e9tape logique pour renforcer notre r\u00e9seau d&rsquo;entreprises de transport - d\u00e9sormais le plus grand d&rsquo;Europe. Dans un march\u00e9 volatile, nous renfor\u00e7ons notre position en Europe centrale et orientale en connectant des entreprises de transport et des exp\u00e9diteurs commerciaux suppl\u00e9mentaires. Nous serons un partenaire fiable pour les entreprises de transport et les exp\u00e9diteurs commerciaux en Roumanie. Ils b\u00e9n\u00e9ficieront de notre plateforme num\u00e9rique qui les aide \u00e0 compenser les p\u00e9nuries de capacit\u00e9 sur le march\u00e9. \u00bb<\/p>\n<h5><strong>Plus d&rsquo;un million de transports<\/strong><\/h5>\n<p>Sennder a pour mission de construire un r\u00e9seau de transport efficace dans la logistique routi\u00e8re gr\u00e2ce \u00e0 l&rsquo;utilisation et \u00e0 l&rsquo;analyse des donn\u00e9es. Via sa plateforme num\u00e9rique, sennder connecte directement les exp\u00e9diteurs commerciaux avec des entreprises de transport petites et moyennes. De cette mani\u00e8re, sennder offre aux exp\u00e9diteurs commerciaux et aux entreprises de transport une multitude d&rsquo;itin\u00e9raires, une plus grande visibilit\u00e9 et des \u00e9conomies de co\u00fbts tout en r\u00e9duisant les \u00e9missions. La plateforme comprend plus de 40 000 camions - plus de dix des 30 entreprises DAX allemandes et 11 des transporteurs Euro Stoxx 50 utilisent d\u00e9j\u00e0 la plateforme num\u00e9rique de sennder - qui a jusqu&rsquo;\u00e0 pr\u00e9sent r\u00e9alis\u00e9 plus d&rsquo;un million de chargements de transport.<\/p>\n<p>Photo : \u00a9 sennder<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre une nouvelle succursale \u00e0 Bucarest, en Roumanie, devenant ainsi le premier transporteur num\u00e9rique \u00e0 entrer sur le march\u00e9. Avec<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10357,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1561],"tags":[],"class_list":["post-56131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre un site \u00e0 Bucarest - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre un site \u00e0 Bucarest - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre une nouvelle succursale \u00e0 Bucarest, en Roumanie, devenant ainsi le premier transporteur num\u00e9rique \u00e0 entrer sur le march\u00e9. Avec [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-04T16:23:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/sennder_4.5.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1213\" \/>\n\t<meta property=\"og:image:height\" content=\"695\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre un site \u00e0 Bucarest\",\"datePublished\":\"2022-05-04T16:23:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/\"},\"wordCount\":622,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/sennder_4.5.22.jpg\",\"articleSection\":[\"Categories\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/\",\"name\":\"La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre un site \u00e0 Bucarest - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/sennder_4.5.22.jpg\",\"datePublished\":\"2022-05-04T16:23:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/sennder_4.5.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/sennder_4.5.22.jpg\",\"width\":1213,\"height\":695},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/05\\\/04\\\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre un site \u00e0 Bucarest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre un site \u00e0 Bucarest - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/","og_locale":"fr_FR","og_type":"article","og_title":"La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre un site \u00e0 Bucarest - Loginfo24.","og_description":"La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre une nouvelle succursale \u00e0 Bucarest, en Roumanie, devenant ainsi le premier transporteur num\u00e9rique \u00e0 entrer sur le march\u00e9. Avec [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-05-04T16:23:16+00:00","og_image":[{"width":1213,"height":695,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/sennder_4.5.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/"},"author":{"name":"","@id":""},"headline":"La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre un site \u00e0 Bucarest","datePublished":"2022-05-04T16:23:16+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/"},"wordCount":622,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/sennder_4.5.22.jpg","articleSection":["Categories","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/","url":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/","name":"La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre un site \u00e0 Bucarest - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/sennder_4.5.22.jpg","datePublished":"2022-05-04T16:23:16+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/sennder_4.5.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/sennder_4.5.22.jpg","width":1213,"height":695},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2022\/05\/04\/la-societe-de-transport-numerique-sennder-ouvre-un-site-a-bucarest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La soci\u00e9t\u00e9 de transport num\u00e9rique sennder ouvre un site \u00e0 Bucarest"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/56131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=56131"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/56131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/10357"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=56131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=56131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=56131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}