{"id":55627,"date":"2022-04-06T15:11:24","date_gmt":"2022-04-06T13:11:24","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/"},"modified":"2022-04-06T15:11:24","modified_gmt":"2022-04-06T13:11:24","slug":"chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/","title":{"rendered":"Chariots \u00e9lectriques de Goldhofer en service avec Lufthansa LEOS"},"content":{"rendered":"<h5><strong>Le chariot d&rsquo;avion sans remorque \u00e0 propulsion \u00e9lectrique par batterie \u00bbPHOENIX\u00ab E de Goldhofer est en service avec succ\u00e8s \u00e0 l&rsquo;a\u00e9roport de Francfort. Sous le slogan \u00ab Un transport a\u00e9rien respectueux de l&rsquo;environnement commence au sol \u00bb, LEOS continue d&rsquo;\u00e9largir sa strat\u00e9gie visant \u00e0 op\u00e9rer le service au sol de mani\u00e8re durable et sans \u00e9missions, et a acquis en d\u00e9cembre le premier chariot d&rsquo;avion sans remorque \u00e0 propulsion \u00e9lectrique par batterie.<\/strong><\/h5>\n<p>(Francfort\/Main) Le \u00bbPHOENIX\u00ab E est le fleuron des chariots d&rsquo;avion sans remorque de Goldhofer. Gr\u00e2ce \u00e0 sa puissance, il peut m\u00eame \u00eatre utilis\u00e9 pour des remorquages de maintenance \u00e0 des vitesses allant jusqu&rsquo;\u00e0 25 km\/h. Gr\u00e2ce \u00e0 sa polyvalence, il est capable de traiter toute la gamme d&rsquo;avions jusqu&rsquo;\u00e0 un poids maximal au d\u00e9collage (MTOW) de 352 t (Boeing B777 \/ Airbus A350), couvrant ainsi environ 80 % du trafic a\u00e9rien. Cela fait de la s\u00e9rie \u00bbPHOENIX\u00ab l&rsquo;un des v\u00e9hicules de remorquage les plus demand\u00e9s sur le march\u00e9. Goldhofer a r\u00e9ussi \u00e0 d\u00e9velopper la version \u00e9lectrique \u00e0 batterie avec les m\u00eames caract\u00e9ristiques de performance que son pr\u00e9d\u00e9cesseur \u00e0 moteur diesel.<\/p>\n<h5><strong>Co\u00fbts d&rsquo;exploitation r\u00e9duits avec moins d&rsquo;\u00e9missions<\/strong><\/h5>\n<p>Le chariot sans \u00e9missions, et donc durable, offre par rapport \u00e0 la version diesel non seulement un spectre de performance identique en traction, man\u0153uvrabilit\u00e9 et fiabilit\u00e9, mais \u00e9galement des co\u00fbts d&rsquo;exploitation r\u00e9duits et des cycles de maintenance plus longs. Avec son concept de batterie modulaire, le \u00bbPHOENIX\u00ab E dispose d&rsquo;une capacit\u00e9 de batterie variant de 66 \u00e0 165 kWh selon les exigences d&rsquo;utilisation. Sur demande, une solution hybride avec un prolongateur d&rsquo;autonomie est \u00e9galement disponible.<br \/>\nDans le cadre de son utilisation op\u00e9rationnelle de trois mois jusqu&rsquo;\u00e0 pr\u00e9sent chez Lufthansa LEOS, de nombreuses donn\u00e9es op\u00e9rationnelles ont d\u00e9j\u00e0 \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es. Des premi\u00e8res conclusions sur la praticit\u00e9 quotidienne du chariot \u00e9lectrique Goldhofer ont d\u00e9j\u00e0 \u00e9t\u00e9 tir\u00e9es. \u00ab Non seulement les conducteurs, mais aussi, par exemple, les m\u00e9caniciens dans le hangar sont ravis de ce v\u00e9hicule \u00bb, d\u00e9clare Peter Unger, directeur g\u00e9n\u00e9ral de LEOS. \u00ab Les premi\u00e8res \u00e9valuations montrent des \u00e9conomies meilleures que ce que nous avions pr\u00e9vu et planifi\u00e9. \u00bb<\/p>\n<h5><strong>20 missions de remorquage par jour sans perte de performance<\/strong><\/h5>\n<p>Le \u00bbPHOENIX\u00ab E fonctionne jusqu&rsquo;\u00e0 10 heures par jour et effectue jusqu&rsquo;\u00e0 20 missions de remorquage sans perte de performance. Cela est rendu possible gr\u00e2ce \u00e0 la technologie \u00bbIonMaster\u00ab utilis\u00e9e par Goldhofer. Un concept de propulsion \u00e9lectrique hautement efficace et puissant avec une technologie de batterie lithium-ion de 700 V d&rsquo;Akasol. De plus, le TMS (syst\u00e8me de gestion thermique) utilis\u00e9 dans la technologie \u00bbIonMaster\u00ab permet de maintenir une temp\u00e9rature de batterie constante entre +15 et +40 degr\u00e9s, ce qui entra\u00eene une autonomie jusqu&rsquo;\u00e0 25 % plus longue et donc une dur\u00e9e de vie de la batterie plus \u00e9lev\u00e9e. Une infrastructure de recharge d\u00e9di\u00e9e, d\u00e9velopp\u00e9e et mise en place par ABB, permet une recharge rapide et interm\u00e9diaire, afin que les v\u00e9hicules puissent accomplir leur longue journ\u00e9e de travail sans perte de performance. \u00ab En raison des donn\u00e9es dont nous disposons, nous pouvons effectuer plus de remorquages que pr\u00e9vu dans les simulations. Nos attentes ont \u00e9t\u00e9 largement d\u00e9pass\u00e9es et nous pr\u00e9voyons l&rsquo;acquisition d&rsquo;un autre \u00bbPHOENIX\u00ab E d&rsquo;ici la fin de l&rsquo;ann\u00e9e \u00bb, nous informe Peter Unger.<\/p>\n<p>Photo : \u00a9 Goldhofer<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le chariot d&rsquo;avion sans remorque \u00e0 propulsion \u00e9lectrique par batterie \u00bbPHOENIX\u00ab E de Goldhofer est en service avec succ\u00e8s \u00e0 l&rsquo;a\u00e9roport de Francfort. Sous le slogan<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10579,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558,1557,1561],"tags":[],"class_list":["post-55627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-air-freight","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chariots \u00e9lectriques de Goldhofer en service avec Lufthansa LEOS - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chariots \u00e9lectriques de Goldhofer en service avec Lufthansa LEOS - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Le chariot d&rsquo;avion sans remorque \u00e0 propulsion \u00e9lectrique par batterie \u00bbPHOENIX\u00ab E de Goldhofer est en service avec succ\u00e8s \u00e0 l&rsquo;a\u00e9roport de Francfort. Sous le slogan [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-06T13:11:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Goldhofer_6.4.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1234\" \/>\n\t<meta property=\"og:image:height\" content=\"647\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Chariots \u00e9lectriques de Goldhofer en service avec Lufthansa LEOS\",\"datePublished\":\"2022-04-06T13:11:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/\"},\"wordCount\":589,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Goldhofer_6.4.22.jpg\",\"articleSection\":[\"Air Freight\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/\",\"name\":\"Chariots \u00e9lectriques de Goldhofer en service avec Lufthansa LEOS - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Goldhofer_6.4.22.jpg\",\"datePublished\":\"2022-04-06T13:11:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Goldhofer_6.4.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Goldhofer_6.4.22.jpg\",\"width\":1234,\"height\":647},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/04\\\/06\\\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chariots \u00e9lectriques de Goldhofer en service avec Lufthansa LEOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chariots \u00e9lectriques de Goldhofer en service avec Lufthansa LEOS - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/","og_locale":"fr_FR","og_type":"article","og_title":"Chariots \u00e9lectriques de Goldhofer en service avec Lufthansa LEOS - Loginfo24.","og_description":"Le chariot d&rsquo;avion sans remorque \u00e0 propulsion \u00e9lectrique par batterie \u00bbPHOENIX\u00ab E de Goldhofer est en service avec succ\u00e8s \u00e0 l&rsquo;a\u00e9roport de Francfort. Sous le slogan [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-04-06T13:11:24+00:00","og_image":[{"width":1234,"height":647,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Goldhofer_6.4.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/"},"author":{"name":"","@id":""},"headline":"Chariots \u00e9lectriques de Goldhofer en service avec Lufthansa LEOS","datePublished":"2022-04-06T13:11:24+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/"},"wordCount":589,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Goldhofer_6.4.22.jpg","articleSection":["Air Freight","Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/","url":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/","name":"Chariots \u00e9lectriques de Goldhofer en service avec Lufthansa LEOS - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Goldhofer_6.4.22.jpg","datePublished":"2022-04-06T13:11:24+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Goldhofer_6.4.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Goldhofer_6.4.22.jpg","width":1234,"height":647},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2022\/04\/06\/chariots-electriques-de-goldhofer-en-service-avec-lufthansa-leos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Chariots \u00e9lectriques de Goldhofer en service avec Lufthansa LEOS"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/55627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=55627"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/55627\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/10579"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=55627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=55627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=55627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}