{"id":55254,"date":"2022-03-22T14:38:55","date_gmt":"2022-03-22T13:38:55","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/"},"modified":"2022-03-22T14:38:55","modified_gmt":"2022-03-22T13:38:55","slug":"lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/","title":{"rendered":"LIP Invest acquiert un nouveau centre logistique \u00e0 Leipzig"},"content":{"rendered":"<h5><strong>LIP Invest acquiert \u00e0 Leipzig un nouveau centre de distribution pour le \u00ab LIP REAL ESTATE INVESTMENT FUND \u2013 LOGISTICS GERMANY IV \u00bb. Avec la vendeuse et d\u00e9veloppeuse de projets, Elflein Immobilien GmbH, LIP a conclu hors march\u00e9 une transaction de vente et de location. La propri\u00e9t\u00e9 comprend une surface utile de 9 700 m2 et est situ\u00e9e sur un terrain de 23 000 m2.<\/strong><\/h5>\n<p>(Munich\/Leipzig) Sur une superficie de 23 000 m\u00e8tres carr\u00e9s, un hall logistique a \u00e9t\u00e9 construit avec une surface locative totale de 9 700 m\u00e8tres carr\u00e9s. Parmi ceux-ci, 8 600 m\u00e8tres carr\u00e9s sont consacr\u00e9s aux surfaces de hall, 500 m\u00e8tres carr\u00e9s aux bureaux et espaces sociaux, et pr\u00e8s de 600 m\u00e8tres carr\u00e9s \u00e0 deux tunnels de chargement. Ceux-ci disposent chacun de 2 portes d&rsquo;acc\u00e8s de plain-pied. De plus, il existe des possibilit\u00e9s d&rsquo;acc\u00e8s via 6 portes de rampe pour camions et 2 autres portes de plain-pied, qui sont couvertes.<\/p>\n<p>Le hall, d&rsquo;une hauteur de 10,25 m\u00e8tres, est con\u00e7u pour le stockage de mati\u00e8res dangereuses jusqu&rsquo;\u00e0 WGK-3. La capacit\u00e9 de charge du sol est de 5 tonnes. Lors de la construction, la statique pour une installation photovolta\u00efque a \u00e9t\u00e9 prise en compte, de sorte que les surfaces de toit seront \u00e9quip\u00e9es de panneaux solaires. Les 17 places de stationnement pour camions et 16 pour voitures particuli\u00e8res seront \u00e9quip\u00e9es de stations de recharge \u00e9lectrique. Un abri couvert offre de la place pour plusieurs v\u00e9los. La propri\u00e9t\u00e9 logistique est accessible \u00e0 la fois par le r\u00e9seau cyclable de Leipzig et par les transports en commun.<\/p>\n<h5><strong>Nouvelle construction lou\u00e9e \u00e0 Elflein E. Mobility Leipzig GmbH<\/strong><\/h5>\n<p>L&rsquo;entreprise familiale traditionnelle Elflein de Bamberg relie avec sa sp\u00e9cialisation dans le transport, l&rsquo;entreposage et la logistique diff\u00e9rents domaines d&rsquo;activit\u00e9 sous un m\u00eame toit. En Allemagne, le prestataire logistique est pr\u00e9sent sur 19 sites au total. Dans le nouveau centre logistique, la distribution mondiale de batteries lithium-ion pour un constructeur automobile renomm\u00e9 sera g\u00e9r\u00e9e dans le cadre d&rsquo;un contrat de logistique. Pour Elflein, c&rsquo;est le deuxi\u00e8me site o\u00f9 la logistique des batteries est exclusivement prise en charge, de la r\u00e9ception des marchandises, \u00e0 l&rsquo;inspection de la qualit\u00e9 et au stockage, jusqu&rsquo;\u00e0 l&rsquo;exp\u00e9dition et la conteneurisation des batteries.<\/p>\n<h5><strong>Situ\u00e9 directement \u00e0 c\u00f4t\u00e9 de l&rsquo;usine BMW de Leipzig<\/strong><\/h5>\n<p>La propri\u00e9t\u00e9 logistique a \u00e9t\u00e9 construite en face de l&rsquo;usine BMW de Leipzig dans le parc industriel Nord, qui borde directement le site d&rsquo;exposition de Leipzig. La prochaine sortie de l&rsquo;autoroute A14, qui m\u00e8ne vers Dresde et Magdebourg, est \u00e0 seulement 3 kilom\u00e8tres. L&rsquo;\u00e9changeur autoroutier Schkeuditzer Kreuz est accessible en environ 7 kilom\u00e8tres et relie le site via l&rsquo;A9 en direction de Berlin et Munich.<\/p>\n<p>\u00ab En plus de la bonne connexion routi\u00e8re avec une faible probabilit\u00e9 d&#8217;embouteillage, ce site offre d&rsquo;autres possibilit\u00e9s de distribution attrayantes : d&rsquo;une part via le centre de transport de marchandises de Leipzig, qui est multimodal et permet le transbordement entre route et rail. D&rsquo;autre part, l&rsquo;a\u00e9roport international de Leipzig\/Halle, avec son fonctionnement 24 heures sur 24, peut \u00eatre utilis\u00e9 pour le fret a\u00e9rien sensible au temps \u00bb, d\u00e9clare <strong>Jan-Nicolai Tr\u00f6ndle<\/strong>, responsable des acquisitions chez LIP Invest.<\/p>\n<p>Photo : \u00a9 LIP Invest<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIP Invest acquiert \u00e0 Leipzig un nouveau centre de distribution pour le \u00ab LIP REAL ESTATE INVESTMENT FUND \u2013 LOGISTICS GERMANY IV \u00bb. Avec la vendeuse<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-55254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LIP Invest acquiert un nouveau centre logistique \u00e0 Leipzig - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LIP Invest acquiert un nouveau centre logistique \u00e0 Leipzig - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"LIP Invest acquiert \u00e0 Leipzig un nouveau centre de distribution pour le \u00ab LIP REAL ESTATE INVESTMENT FUND \u2013 LOGISTICS GERMANY IV \u00bb. Avec la vendeuse [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-22T13:38:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LIP_Invest_22.3.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1895\" \/>\n\t<meta property=\"og:image:height\" content=\"752\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"LIP Invest acquiert un nouveau centre logistique \u00e0 Leipzig\",\"datePublished\":\"2022-03-22T13:38:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/\"},\"wordCount\":560,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LIP_Invest_22.3.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/\",\"name\":\"LIP Invest acquiert un nouveau centre logistique \u00e0 Leipzig - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LIP_Invest_22.3.22.jpg\",\"datePublished\":\"2022-03-22T13:38:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LIP_Invest_22.3.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LIP_Invest_22.3.22.jpg\",\"width\":1895,\"height\":752},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/03\\\/22\\\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LIP Invest acquiert un nouveau centre logistique \u00e0 Leipzig\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LIP Invest acquiert un nouveau centre logistique \u00e0 Leipzig - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/","og_locale":"fr_FR","og_type":"article","og_title":"LIP Invest acquiert un nouveau centre logistique \u00e0 Leipzig - Loginfo24.","og_description":"LIP Invest acquiert \u00e0 Leipzig un nouveau centre de distribution pour le \u00ab LIP REAL ESTATE INVESTMENT FUND \u2013 LOGISTICS GERMANY IV \u00bb. Avec la vendeuse [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-03-22T13:38:55+00:00","og_image":[{"width":1895,"height":752,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LIP_Invest_22.3.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/"},"author":{"name":"","@id":""},"headline":"LIP Invest acquiert un nouveau centre logistique \u00e0 Leipzig","datePublished":"2022-03-22T13:38:55+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/"},"wordCount":560,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LIP_Invest_22.3.22.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/","url":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/","name":"LIP Invest acquiert un nouveau centre logistique \u00e0 Leipzig - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LIP_Invest_22.3.22.jpg","datePublished":"2022-03-22T13:38:55+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LIP_Invest_22.3.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LIP_Invest_22.3.22.jpg","width":1895,"height":752},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2022\/03\/22\/lip-invest-acquiert-un-nouveau-centre-logistique-a-leipzig\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"LIP Invest acquiert un nouveau centre logistique \u00e0 Leipzig"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/55254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=55254"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/55254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/10711"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=55254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=55254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=55254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}