{"id":54347,"date":"2022-02-02T18:32:50","date_gmt":"2022-02-02T17:32:50","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/"},"modified":"2022-02-02T18:32:50","modified_gmt":"2022-02-02T17:32:50","slug":"pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/","title":{"rendered":"Pro Mobilit\u00e4t e.V. examine combien de fret le rail peut supporter"},"content":{"rendered":"<h5><strong>Mercredi apr\u00e8s-midi, le vice-pr\u00e9sident de l&rsquo;initiative de transport \u00e0 but non lucratif Pro Mobilit\u00e4t e.V., porte-parole du conseil d&rsquo;administration du BGL, le Prof. Dr. Dirk Engelhardt, a pr\u00e9sent\u00e9 l&rsquo;\u00e9tude \u00ab\u00a0V\u00e9rification des faits sur le transport de marchandises en Allemagne - De l&rsquo;infrastructure manquante au potentiel de transfert\u00a0\u00bb lors d&rsquo;une conf\u00e9rence de presse en ligne. L&rsquo;\u00e9tude a \u00e9t\u00e9 r\u00e9alis\u00e9e par l&rsquo;Institut de l&rsquo;\u00e9conomie allemande de Cologne (IW) e.V. sous la direction de l&rsquo;\u00e9conomiste senior de l&rsquo;IW, Thomas Puls, pour le compte de Pro Mobilit\u00e4t.<\/strong><\/h5>\n<p>(Francfort\/Hambourg) L&rsquo;objectif de la v\u00e9rification des faits \u00e9tait d&rsquo;examiner le potentiel de transfert du rail dans le transport de marchandises. Apr\u00e8s que chaque gouvernement a de nouveau appel\u00e9 \u00e0 un transfert accru vers le rail, il \u00e9tait n\u00e9cessaire de d\u00e9terminer : Combien de fret le rail peut-il vraiment supporter ?<\/p>\n<p><strong>Constatations centrales :<\/strong><\/p>\n<ul>\n<li>Le transport de marchandises est un fondement indispensable et in\u00e9vitable de notre prosp\u00e9rit\u00e9. Les consommateurs utilisent de plus en plus le commerce en ligne, ce qui entra\u00eene une augmentation du transport de marchandises.<\/li>\n<li>L&rsquo;\u00e9tat des infrastructures de transport (routes et rails) et leur capacit\u00e9 ne r\u00e9pondent d\u00e9j\u00e0 pas aux exigences actuelles, et encore moins aux exigences futures : il est n\u00e9cessaire d&rsquo;investir massivement - il faut \u00e9galement r\u00e9duire significativement le temps de planification et optimiser l&rsquo;organisation de l&rsquo;ex\u00e9cution des travaux !<\/li>\n<li>Diff\u00e9rents modes de transport desservent diff\u00e9rents march\u00e9s : le rail et le transport fluvial dominent le transport de marchandises en vrac sur de longues distances, tandis que le camion est leader dans le secteur de la construction, pour les denr\u00e9es alimentaires et dans le transport de distribution.<\/li>\n<li>Conclusion : Le potentiel de transfert est fortement limit\u00e9. Les marchandises traditionnelles transport\u00e9es par rail, comme le charbon et les produits p\u00e9troliers, perdront en importance. En raison de la structure des marchandises transport\u00e9es, un transfert du camion vers le rail est quantitativement simplement limit\u00e9. Le commerce en ligne en plein essor n\u00e9cessite, en raison de la petite taille des envois, une distribution fine par camion.<\/li>\n<li>O\u00f9 y a-t-il encore des possibilit\u00e9s ? Le transport combin\u00e9 route\/rail est depuis des ann\u00e9es le segment de croissance le plus important dans le transport de marchandises par rail, et c&rsquo;est ici que se trouve le plus grand potentiel de transfert pour l&rsquo;avenir, qu&rsquo;il faut exploiter !<\/li>\n<\/ul>\n<h5><strong>Ne pas opposer route et rail<\/strong><\/h5>\n<p>Le vice-pr\u00e9sident de Pro Mobilit\u00e4t, le Prof. Dr. Dirk Engelhardt : \u00ab\u00a0Une telle v\u00e9rification des faits \u00e9tait longtemps attendue. Pendant des d\u00e9cennies, la politique allemande a promu le transfert de transport - avec un succ\u00e8s tr\u00e8s limit\u00e9. Cela a des raisons, comme l&rsquo;\u00e9tude le montre maintenant. D&rsquo;une part, d&rsquo;\u00e9normes efforts financiers, juridiques et organisationnels sont n\u00e9cessaires pour rendre l&rsquo;infrastructure de transport en Allemagne adapt\u00e9e \u00e0 l&rsquo;avenir - cela vaut pour la route comme pour le rail ! D&rsquo;autre part, les deux modes de transport ne doivent pas \u00eatre oppos\u00e9s, mais doivent \u00eatre int\u00e9gr\u00e9s ! Cela r\u00e9ussit le mieux dans le transport combin\u00e9 route\/rail.<\/p>\n<p>Ind\u00e9pendamment de cela, il convient de constater que toutes les pr\u00e9visions consid\u00e8rent le camion comme le mode de transport le plus important en termes de volume m\u00eame en 2050. Cela montre, en ce qui concerne la protection du climat : La cl\u00e9 d&rsquo;un transport de marchandises climatiquement neutre r\u00e9side dans la d\u00e9carbonisation de l&rsquo;approvisionnement \u00e9nerg\u00e9tique du transport routier.\u00a0\u00bb<\/p>\n<h5><strong>Modes de transport individuels dans des syst\u00e8mes globaux<\/strong><\/h5>\n<p>Et Thomas Puls de l&rsquo;Institut de l&rsquo;\u00e9conomie allemande de Cologne explique : \u00ab\u00a0Une couverture de haute qualit\u00e9 et compl\u00e8te des services de transport de marchandises ne sera possible que si les forces des diff\u00e9rents modes de transport sont combin\u00e9es dans un syst\u00e8me global. Un affrontement entre route, rail et voies navigables est le chemin s\u00fbr vers l&rsquo;\u00e9chec, car aucun des modes de transport n&rsquo;est en mesure, \u00e0 court terme, d&rsquo;assumer les t\u00e2ches de transport d&rsquo;un autre.<\/p>\n<p>Tous les modes de transport sont actuellement confront\u00e9s \u00e0 de grands probl\u00e8mes. Les camions et les trains souffrent d&rsquo;un manque perceptible de personnel de conduite. S&rsquo;ajoute \u00e0 cela une infrastructure surcharg\u00e9e. En particulier sur les corridors principaux du transport de marchandises en Allemagne, les capacit\u00e9s sont pleinement utilis\u00e9es et des r\u00e9novations en retard entra\u00eenent des perturbations significatives dans le flux de marchandises.<\/p>\n<p>L&rsquo;Allemagne est le c\u0153ur logistique de l&rsquo;espace \u00e9conomique europ\u00e9en. Les probl\u00e8mes r\u00e9sultant du transport longue distance ne pourront pas \u00eatre r\u00e9solus sans une coordination \u00e9troite avec les voisins.<\/p>\n<h5><strong>Aussi \u00e0 l&rsquo;avenir principalement par la route<\/strong><\/h5>\n<p>Le transport de marchandises en Allemagne continuera de cro\u00eetre. Ainsi, le contrat de coalition pr\u00e9voit par exemple une forte expansion des activit\u00e9s de construction en Allemagne. La construction de logements, la r\u00e9novation des infrastructures mais aussi l&rsquo;expansion de l&rsquo;\u00e9nergie \u00e9olienne n\u00e9cessitent le transport de grandes quantit\u00e9s de mat\u00e9riaux - et cela se fera principalement par camion.<\/h5>\n<h4><a href=\"https:\/\/www.bgl-ev.de\/images\/downloads\/media_3515_2.PDF\" target=\"_blank\" rel=\"noopener\">\u00c9tude Pro Mobilit\u00e4t \u00ab\u00a0V\u00e9rification des faits sur le transport de marchandises en Allemagne\u00a0\u00bb \u00e0 t\u00e9l\u00e9charger<\/a><\/h4>\n<p>Photo : \u00a9 Loginfo24\/Adobe Stock<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercredi apr\u00e8s-midi, le vice-pr\u00e9sident de l&rsquo;initiative de transport \u00e0 but non lucratif Pro Mobilit\u00e4t e.V., porte-parole du conseil d&rsquo;administration du BGL, le Prof. Dr. Dirk Engelhardt,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-54347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pro Mobilit\u00e4t e.V. examine combien de fret le rail peut supporter - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pro Mobilit\u00e4t e.V. examine combien de fret le rail peut supporter - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Mercredi apr\u00e8s-midi, le vice-pr\u00e9sident de l&rsquo;initiative de transport \u00e0 but non lucratif Pro Mobilit\u00e4t e.V., porte-parole du conseil d&rsquo;administration du BGL, le Prof. Dr. Dirk Engelhardt, [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-02T17:32:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BGV_2.2.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1408\" \/>\n\t<meta property=\"og:image:height\" content=\"791\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Pro Mobilit\u00e4t e.V. examine combien de fret le rail peut supporter\",\"datePublished\":\"2022-02-02T17:32:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/\"},\"wordCount\":914,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BGV_2.2.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/\",\"name\":\"Pro Mobilit\u00e4t e.V. examine combien de fret le rail peut supporter - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BGV_2.2.22.jpg\",\"datePublished\":\"2022-02-02T17:32:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BGV_2.2.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BGV_2.2.22.jpg\",\"width\":1408,\"height\":791},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pro Mobilit\u00e4t e.V. examine combien de fret le rail peut supporter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pro Mobilit\u00e4t e.V. examine combien de fret le rail peut supporter - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/","og_locale":"fr_FR","og_type":"article","og_title":"Pro Mobilit\u00e4t e.V. examine combien de fret le rail peut supporter - Loginfo24.","og_description":"Mercredi apr\u00e8s-midi, le vice-pr\u00e9sident de l&rsquo;initiative de transport \u00e0 but non lucratif Pro Mobilit\u00e4t e.V., porte-parole du conseil d&rsquo;administration du BGL, le Prof. Dr. Dirk Engelhardt, [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-02-02T17:32:50+00:00","og_image":[{"width":1408,"height":791,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BGV_2.2.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/"},"author":{"name":"","@id":""},"headline":"Pro Mobilit\u00e4t e.V. examine combien de fret le rail peut supporter","datePublished":"2022-02-02T17:32:50+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/"},"wordCount":914,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BGV_2.2.22.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/","url":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/","name":"Pro Mobilit\u00e4t e.V. examine combien de fret le rail peut supporter - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BGV_2.2.22.jpg","datePublished":"2022-02-02T17:32:50+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BGV_2.2.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BGV_2.2.22.jpg","width":1408,"height":791},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/pro-mobilitat-e-v-examine-combien-de-fret-le-rail-peut-supporter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Pro Mobilit\u00e4t e.V. examine combien de fret le rail peut supporter"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/54347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=54347"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/54347\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/11097"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=54347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=54347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=54347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}