{"id":54335,"date":"2022-02-02T18:13:28","date_gmt":"2022-02-02T17:13:28","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/"},"modified":"2022-02-02T18:13:28","modified_gmt":"2022-02-02T17:13:28","slug":"la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/","title":{"rendered":"La compagnie maritime Finnlines augmente la fr\u00e9quence entre L\u00fcbeck et le sud de la Su\u00e8de"},"content":{"rendered":"<h5><strong>Bonne nouvelle pour la L\u00fcbecker Hafen-Gesellschaft (LHG) et le site : Depuis le 1er f\u00e9vrier, la compagnie maritime Finnlines a modifi\u00e9 son organisation sur la route entre L\u00fcbeck et Malm\u00f6. Cela augmente le nombre de d\u00e9parts quotidiens de trois \u00e0 quatre, r\u00e9pondant ainsi \u00e0 la demande croissante dans le trafic vers le sud de la Su\u00e8de.<\/strong><\/h5>\n<p>(L\u00fcbeck\/Malm\u00f6) Avec les navires \u00ab Finnfellow \u00bb et \u00ab Finnclipper \u00bb, deux vieux amis reviennent au terminal Skandinavienkai. Ils remplacent l&rsquo;\u00ab Europalink \u00bb, qui a \u00e9t\u00e9 affect\u00e9 au service entre la Su\u00e8de et la Finlande. Ensemble, les deux ferries offrent 6 200 m\u00e8tres de chargement, ce qui augmente la capacit\u00e9 quotidienne de 2 000 m\u00e8tres de chargement par direction. Le secteur des passagers b\u00e9n\u00e9ficie \u00e9galement de ce d\u00e9part suppl\u00e9mentaire. Au lieu de 550, 880 passagers peuvent d\u00e9sormais s&rsquo;enregistrer pour les d\u00e9parts du soir.<\/p>\n<p>\u00ab Le renforcement de notre ligne entre Travem\u00fcnde et Malm\u00f6 est un signe important pour nos clients, le port et la ville, que nous croyons fermement au site de Travem\u00fcnde. La demande actuelle pour le transport de marchandises et de passagers sur cette route est tr\u00e8s \u00e9lev\u00e9e. Nous sommes heureux de pouvoir offrir \u00e0 nos clients encore plus de choix et de flexibilit\u00e9 avec quatre d\u00e9parts quotidiens et un total de 48 travers\u00e9es par semaine dans les deux sens \u00bb, commente Antonio Raimo, responsable de la ligne chez Finnlines.<\/p>\n<h5><strong>Les capacit\u00e9s de Baltic Rail Gate seront \u00e9tendues<\/strong><\/h5>\n<p>Tobard Jan Klemke, responsable marketing et ventes de la LHG, ajoute : \u00ab Nous sommes tr\u00e8s heureux de la confiance que Finnlines accorde au site et \u00e0 notre capacit\u00e9 de performance. Nous ferons tout pour continuer \u00e0 cro\u00eetre avec nos clients. Compte tenu de l&rsquo;augmentation des volumes dans le transport intermodal, nous accueillons cette fr\u00e9quence accrue. Pour continuer \u00e0 suivre cette croissance, nous allons bient\u00f4t \u00e9tendre les capacit\u00e9s de Baltic Rail Gate. \u00bb Le terminal intermodal au Skandinavienkai a trait\u00e9 plus de 126 000 unit\u00e9s l&rsquo;ann\u00e9e derni\u00e8re.<\/p>\n<p>Photo : \u00a9 Bernd Pagel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonne nouvelle pour la L\u00fcbecker Hafen-Gesellschaft (LHG) et le site : Depuis le 1er f\u00e9vrier, la compagnie maritime Finnlines a modifi\u00e9 son organisation sur la route<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1561,1559],"tags":[],"class_list":["post-54335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La compagnie maritime Finnlines augmente la fr\u00e9quence entre L\u00fcbeck et le sud de la Su\u00e8de - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La compagnie maritime Finnlines augmente la fr\u00e9quence entre L\u00fcbeck et le sud de la Su\u00e8de - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Bonne nouvelle pour la L\u00fcbecker Hafen-Gesellschaft (LHG) et le site : Depuis le 1er f\u00e9vrier, la compagnie maritime Finnlines a modifi\u00e9 son organisation sur la route [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-02T17:13:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_2.2.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1383\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La compagnie maritime Finnlines augmente la fr\u00e9quence entre L\u00fcbeck et le sud de la Su\u00e8de\",\"datePublished\":\"2022-02-02T17:13:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LHG_2.2.22.jpg\",\"articleSection\":[\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/\",\"name\":\"La compagnie maritime Finnlines augmente la fr\u00e9quence entre L\u00fcbeck et le sud de la Su\u00e8de - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LHG_2.2.22.jpg\",\"datePublished\":\"2022-02-02T17:13:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LHG_2.2.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LHG_2.2.22.jpg\",\"width\":1383,\"height\":718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/02\\\/02\\\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La compagnie maritime Finnlines augmente la fr\u00e9quence entre L\u00fcbeck et le sud de la Su\u00e8de\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La compagnie maritime Finnlines augmente la fr\u00e9quence entre L\u00fcbeck et le sud de la Su\u00e8de - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/","og_locale":"fr_FR","og_type":"article","og_title":"La compagnie maritime Finnlines augmente la fr\u00e9quence entre L\u00fcbeck et le sud de la Su\u00e8de - Loginfo24.","og_description":"Bonne nouvelle pour la L\u00fcbecker Hafen-Gesellschaft (LHG) et le site : Depuis le 1er f\u00e9vrier, la compagnie maritime Finnlines a modifi\u00e9 son organisation sur la route [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-02-02T17:13:28+00:00","og_image":[{"width":1383,"height":718,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_2.2.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/"},"author":{"name":"","@id":""},"headline":"La compagnie maritime Finnlines augmente la fr\u00e9quence entre L\u00fcbeck et le sud de la Su\u00e8de","datePublished":"2022-02-02T17:13:28+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_2.2.22.jpg","articleSection":["Regions","Shipping &amp; Ports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/","url":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/","name":"La compagnie maritime Finnlines augmente la fr\u00e9quence entre L\u00fcbeck et le sud de la Su\u00e8de - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_2.2.22.jpg","datePublished":"2022-02-02T17:13:28+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_2.2.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LHG_2.2.22.jpg","width":1383,"height":718},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2022\/02\/02\/la-compagnie-maritime-finnlines-augmente-la-frequence-entre-lubeck-et-le-sud-de-la-suede\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La compagnie maritime Finnlines augmente la fr\u00e9quence entre L\u00fcbeck et le sud de la Su\u00e8de"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/54335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=54335"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/54335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/11101"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=54335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=54335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=54335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}