{"id":53062,"date":"2021-10-29T18:35:44","date_gmt":"2021-10-29T16:35:44","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/"},"modified":"2021-10-29T18:35:44","modified_gmt":"2021-10-29T16:35:44","slug":"la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/","title":{"rendered":"La soci\u00e9t\u00e9 de transport Robert Kukla certifi\u00e9e selon la r\u00e9glementation \u00e9cologique"},"content":{"rendered":"<h5><strong>La soci\u00e9t\u00e9 de transport internationale Robert Kukla a \u00e9t\u00e9 r\u00e9cemment certifi\u00e9e par Ecocert (DE-\u00d6KO-005) conform\u00e9ment au r\u00e8glement de l&rsquo;UE 834\/2007 \u2013 la soi-disant r\u00e9glementation \u00e9cologique. Cela permet \u00e0 Kukla de commercialiser ses services dans le domaine de l&rsquo;entreposage dans les \u00c9tats membres de l&rsquo;UE comme \u00ab\u00a0biologique\u00a0\u00bb et \u00ab\u00a0\u00e9cologique\u00a0\u00bb \u2013 ou \u00ab\u00a0bio\u00a0\u00bb ou \u00ab\u00a0\u00e9co\u00a0\u00bb.<\/strong><\/h5>\n<p>(Munich) Avec cette \u00e9tape, la Robert Kukla GmbH souhaite marquer un engagement en faveur d&rsquo;une plus grande responsabilit\u00e9 \u00e9cologique dans le domaine du transport et de l&rsquo;entreposage. Kukla est l&rsquo;un des principaux fournisseurs de concepts de transport multimodaux et respectueux du climat et g\u00e8re plus de 200 000 m\u00b2 d&rsquo;espace d&rsquo;entreposage \u00e0 diff\u00e9rents emplacements europ\u00e9ens.<\/p>\n<p>Kukla travaille selon des normes de qualit\u00e9 d\u00e9finies, conformes aux directives strictes du r\u00e8glement de l&rsquo;UE 834\/2007. Cela a \u00e9t\u00e9 confirm\u00e9 par l&rsquo;organisme de certification biologique Ecocert IMO GmbH dans le cadre d&rsquo;un processus d&rsquo;audit. La conformit\u00e9 des services fournis par Kukla avec les exigences \u00e9cologiques \u00e9tablies dans la r\u00e9glementation \u00e9cologique a \u00e9t\u00e9 \u00e9valu\u00e9e. Les certificats d\u00e9livr\u00e9s par Ecocert garantissent et promeuvent les meilleures pratiques respectueuses de l&rsquo;environnement.<\/p>\n<p>\u00ab\u00a0Nous sommes fiers que nos services d&rsquo;entreposage puissent d\u00e9sormais porter officiellement le label \u00e9cologique, ce qui renforce notre engagement durable\u00a0\u00bb, d\u00e9clare le PDG du groupe Knut Sander. Compte tenu de la demande croissante de produits \u00e9cologiquement irr\u00e9prochables, le certificat arrive \u00ab\u00a0au bon moment et constitue une nouvelle \u00e9tape importante dans l&rsquo;ann\u00e9e anniversaire\u00a0\u00bb.<\/p>\n<h5><strong>80 ans d&rsquo;existence<\/strong><\/h5>\n<p>Cette ann\u00e9e, le prestataire logistique traditionnel bas\u00e9 \u00e0 Munich c\u00e9l\u00e8bre ses 80 ans d&rsquo;existence. C&rsquo;est pourquoi la nouvelle distinction a \u00ab\u00a0une signification toute particuli\u00e8re\u00a0\u00bb et compl\u00e8te les certifications pr\u00e9c\u00e9dentes selon ISO 9001, ISO 14001, AEO F, SQAS ou IFS Logistics.<\/p>\n<p>La Robert Kukla GmbH Internationale Spedition est sp\u00e9cialis\u00e9e dans les transports multimodaux et intermodaux, les transports de citerne ainsi que les transports routiers \u00e0 l&rsquo;\u00e9chelle mondiale et poss\u00e8de une grande exp\u00e9rience dans la logistique d&rsquo;entreposage. Le prestataire logistique munichois dispose de succursales \u00e0 Hambourg, Berlin, D\u00fcsseldorf, Milan, Breda, Stockholm, Tunis, Bilbao, Lisbonne et Londres. Kukla existe depuis 1941, travaille dans le monde entier avec un r\u00e9seau dense de partenaires coop\u00e9ratifs performants et emploie environ 200 personnes dans tous les sites.<\/p>\n<p>Photo : \u00a9 Kukla<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La soci\u00e9t\u00e9 de transport internationale Robert Kukla a \u00e9t\u00e9 r\u00e9cemment certifi\u00e9e par Ecocert (DE-\u00d6KO-005) conform\u00e9ment au r\u00e8glement de l&rsquo;UE 834\/2007 \u2013 la soi-disant r\u00e9glementation \u00e9cologique. Cela<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11948,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-53062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La soci\u00e9t\u00e9 de transport Robert Kukla certifi\u00e9e selon la r\u00e9glementation \u00e9cologique - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La soci\u00e9t\u00e9 de transport Robert Kukla certifi\u00e9e selon la r\u00e9glementation \u00e9cologique - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"La soci\u00e9t\u00e9 de transport internationale Robert Kukla a \u00e9t\u00e9 r\u00e9cemment certifi\u00e9e par Ecocert (DE-\u00d6KO-005) conform\u00e9ment au r\u00e8glement de l&rsquo;UE 834\/2007 \u2013 la soi-disant r\u00e9glementation \u00e9cologique. Cela [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-29T16:35:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kukla_29.10.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1254\" \/>\n\t<meta property=\"og:image:height\" content=\"858\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La soci\u00e9t\u00e9 de transport Robert Kukla certifi\u00e9e selon la r\u00e9glementation \u00e9cologique\",\"datePublished\":\"2021-10-29T16:35:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/\"},\"wordCount\":404,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kukla_29.10.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/\",\"name\":\"La soci\u00e9t\u00e9 de transport Robert Kukla certifi\u00e9e selon la r\u00e9glementation \u00e9cologique - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kukla_29.10.21.jpg\",\"datePublished\":\"2021-10-29T16:35:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kukla_29.10.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kukla_29.10.21.jpg\",\"width\":1254,\"height\":858},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/29\\\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La soci\u00e9t\u00e9 de transport Robert Kukla certifi\u00e9e selon la r\u00e9glementation \u00e9cologique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La soci\u00e9t\u00e9 de transport Robert Kukla certifi\u00e9e selon la r\u00e9glementation \u00e9cologique - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/","og_locale":"fr_FR","og_type":"article","og_title":"La soci\u00e9t\u00e9 de transport Robert Kukla certifi\u00e9e selon la r\u00e9glementation \u00e9cologique - Loginfo24.","og_description":"La soci\u00e9t\u00e9 de transport internationale Robert Kukla a \u00e9t\u00e9 r\u00e9cemment certifi\u00e9e par Ecocert (DE-\u00d6KO-005) conform\u00e9ment au r\u00e8glement de l&rsquo;UE 834\/2007 \u2013 la soi-disant r\u00e9glementation \u00e9cologique. Cela [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-10-29T16:35:44+00:00","og_image":[{"width":1254,"height":858,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kukla_29.10.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/"},"author":{"name":"","@id":""},"headline":"La soci\u00e9t\u00e9 de transport Robert Kukla certifi\u00e9e selon la r\u00e9glementation \u00e9cologique","datePublished":"2021-10-29T16:35:44+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/"},"wordCount":404,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kukla_29.10.21.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/","url":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/","name":"La soci\u00e9t\u00e9 de transport Robert Kukla certifi\u00e9e selon la r\u00e9glementation \u00e9cologique - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kukla_29.10.21.jpg","datePublished":"2021-10-29T16:35:44+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kukla_29.10.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kukla_29.10.21.jpg","width":1254,"height":858},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/29\/la-societe-de-transport-robert-kukla-certifiee-selon-la-reglementation-ecologique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La soci\u00e9t\u00e9 de transport Robert Kukla certifi\u00e9e selon la r\u00e9glementation \u00e9cologique"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/53062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=53062"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/53062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/11948"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=53062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=53062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=53062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}