{"id":52924,"date":"2021-10-22T16:53:19","date_gmt":"2021-10-22T14:53:19","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/"},"modified":"2021-10-22T16:53:19","modified_gmt":"2021-10-22T14:53:19","slug":"les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/","title":{"rendered":"Les Pharma Logistics Days \u00e0 B\u00e2le pour la premi\u00e8re fois sur deux jours"},"content":{"rendered":"<h5>Hier, les 2\u00e8mes Pharma Logistics Days se sont termin\u00e9s au parc des expositions de B\u00e2le. Pendant deux jours, des prestataires se sont r\u00e9unis pour une exposition autour de la logistique pharmaceutique. L&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 compl\u00e9t\u00e9 par un programme d&rsquo;accompagnement, comprenant des conf\u00e9rences sp\u00e9cialis\u00e9es, des performances folkloriques et un \u00e9v\u00e9nement de r\u00e9seautage le premier soir. L&rsquo;\u00e9v\u00e9nement professionnel faisait partie int\u00e9grante de l&rsquo;ILMAC B\u00e2le, le principal salon suisse pour la technologie de laboratoire et de processus.<\/h5>\n<p>(B\u00e2le) Jamais le sujet de la logistique pharmaceutique n&rsquo;a \u00e9t\u00e9 aussi actuel qu&rsquo;en ce moment. Cela a \u00e9galement \u00e9t\u00e9 d\u00e9montr\u00e9 par les 2\u00e8mes Pharma Logistics Days, un salon pr\u00e9sentant toutes les facettes de la logistique pharmaceutique. 28 exposants ont r\u00e9pondu \u00e0 l&rsquo;invitation, allant du logisticien sous contrat \u00e0 l&rsquo;entreprise de transport, du fabricant d&#8217;emballages sp\u00e9ciaux \u00e0 la compagnie de navigation fluviale avec des conteneurs r\u00e9frig\u00e9r\u00e9s, en passant par les fabricants de data loggers et m\u00eame des compagnies a\u00e9riennes. Les visiteurs ont ainsi pu obtenir une vue d&rsquo;ensemble compl\u00e8te sur le sujet. L&rsquo;exposition professionnelle \u00e9tait enti\u00e8rement int\u00e9gr\u00e9e \u00e0 l&rsquo;ILMAC B\u00e2le, le principal salon suisse pour la technologie de laboratoire et de processus. Le public cible de l&rsquo;ILMAC B\u00e2le et des Pharma Logistics Days est presque identique, et c&rsquo;est de cette r\u00e9flexion qu&rsquo;est n\u00e9e la combinaison des \u00e9v\u00e9nements.<\/p>\n<h5><strong>De la foire interne au salon professionnel<\/strong><\/h5>\n<p>Urs Suter, Responsable des comptes cl\u00e9s et Chef de projet chez Lamprecht Pharma Logistics AG et fondateur et organisateur des deux premi\u00e8res Pharma Logistics Days en 2018 et 2019 (la version 2021 a \u00e9t\u00e9 organis\u00e9e avec un comit\u00e9 de l&rsquo;industrie logistique et de l&#8217;emballage) sur l&rsquo;histoire de la cr\u00e9ation : \u00ab\u00a0L&rsquo;id\u00e9e de ce salon professionnel m&rsquo;est venue lorsque je recevais sans cesse des invitations \u00e0 de grands \u00e9v\u00e9nements de logistique pharmaceutique. Ceux-ci \u00e9taient pour nous trop grands et beaucoup trop chers. C&rsquo;est ainsi qu&rsquo;est n\u00e9e l&rsquo;id\u00e9e d&rsquo;un salon interne, que nous avons r\u00e9alis\u00e9 en 2018 sur notre site \u00e0 Pratteln. L&rsquo;un des visiteurs \u00e9tait l&rsquo;organisateur de l&rsquo;ILMAC B\u00e2le, et c&rsquo;est ainsi que les Pharma Logistics Days ont vu le jour.<\/p>\n<p>\u00ab\u00a0En 2019, c&rsquo;\u00e9tait d&rsquo;abord un \u00e9v\u00e9nement parall\u00e8le d&rsquo;une journ\u00e9e, et cette ann\u00e9e, pour la premi\u00e8re fois, il a dur\u00e9 deux jours et a \u00e9t\u00e9 int\u00e9gr\u00e9 \u00e0 l&rsquo;ILMAC B\u00e2le\u00a0\u00bb, poursuit Suter. Pour lui, il \u00e9tait \u00e9galement clair que l&rsquo;exposition devait avoir lieu \u00e0 B\u00e2le : \u00ab\u00a0\u00c0 B\u00e2le, la pharmacie est chez elle, donc seul B\u00e2le pouvait \u00eatre envisag\u00e9 comme lieu de l&rsquo;\u00e9v\u00e9nement.\u00a0\u00bb<\/p>\n<p>Pour Suter, il est important que les exposants soient satisfaits, car c&rsquo;est seulement ainsi qu&rsquo;il peut l&rsquo;\u00eatre lui-m\u00eame. Des discussions avec les exposants ont \u00e9galement confirm\u00e9 que l&rsquo;\u00e9v\u00e9nement est sur la bonne voie. Repr\u00e9sentant Kay Metzger, Directeur g\u00e9n\u00e9ral chez le logisticien de conteneurs Danser Switzerland AG : \u00ab\u00a0La pr\u00e9sente \u00e9dition a d\u00e9j\u00e0 \u00e9t\u00e9 une nette am\u00e9lioration par rapport \u00e0 la premi\u00e8re \u00e9dition et nous avons pu avoir de bonnes discussions. De plus, certains co-exposants sont nos clients et nous avons enfin pu nous rencontrer en personne.\u00a0\u00bb N\u00e9anmoins, les Pharma Logistics Days ont \u00e9galement souffert de la pand\u00e9mie, car 12 autres exposants potentiels ont annul\u00e9 leur participation.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15103 size-large\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Pharma_Logistics_Day_21.10.21_2.jpg\" alt=\"\" width=\"1024\" height=\"602\" \/> L&rsquo;ILMAC B\u00e2le et les Pharma Logistics Days n&rsquo;attirent pas les foules, mais un public professionnel de haut niveau.<\/caption>\n<p>&nbsp;<\/p>\n<h5><strong>Programme d&rsquo;accompagnement captivant et vari\u00e9<\/strong><\/h5>\n<p>Le programme d&rsquo;accompagnement s&rsquo;est distingu\u00e9 par des th\u00e8mes vari\u00e9s et de haut niveau, r\u00e9partis sur les deux jours. Au total, 10 intervenants ont pr\u00e9sent\u00e9 des sujets diff\u00e9rents. L&rsquo;ancien pr\u00e9sident du FC B\u00e2le, Dr. Bernhard Heusler, a donn\u00e9 le discours d&rsquo;ouverture sur le th\u00e8me \u00ab Direction d&rsquo;entreprise et d&rsquo;\u00e9quipe - D\u00e9fis et enseignements du sport de haut niveau \u00bb. Les autres intervenants ont ensuite abord\u00e9 divers sujets li\u00e9s \u00e0 la logistique, toujours avec un accent sur le secteur pharmaceutique. \u00c0 la fin de la premi\u00e8re journ\u00e9e, un ap\u00e9ritif de r\u00e9seautage attendait exposants et visiteurs.<\/p>\n<h5><strong>Tous les deux ans ou chaque ann\u00e9e ?<\/strong><\/h5>\n<p>Il est certain qu&rsquo;\u00e0 l&rsquo;occasion de l&rsquo;ILMAC B\u00e2le 2023, les Pharma Logistics Days auront \u00e9galement lieu. \u00ab\u00a0Il y a eu des propositions pour que nous organisions l&rsquo;\u00e9v\u00e9nement chaque ann\u00e9e. Je peux tout \u00e0 fait l&rsquo;imaginer. La question est de savoir \u00e0 quoi cela pourrait ressembler les ann\u00e9es sans ILMAC. Peut-\u00eatre plus de caract\u00e8re de congr\u00e8s avec une exposition d&rsquo;accompagnement et seulement un jour. Nous en discuterons calmement\u00a0\u00bb, r\u00e9fl\u00e9chit Suter \u00e0 l&rsquo;avenir.<\/p>\n<p>\u00ab\u00a0Quoi qu&rsquo;il en soit, nous devons r\u00e9fl\u00e9chir \u00e0 l&rsquo;organisation. Dans sa forme actuelle, nous sommes surcharg\u00e9s et nous devons absolument professionnaliser cela.\u00a0\u00bb<\/p>\n<p>De nombreux \u00e9v\u00e9nements ont commenc\u00e9 petit. De plus, les Pharma Logistics Days de cette ann\u00e9e ont \u00e9t\u00e9 emp\u00each\u00e9s par la pand\u00e9mie d&rsquo;une \u00e9dition encore plus grande. Quoi qu&rsquo;il en soit, l&rsquo;\u00e9v\u00e9nement a le potentiel de devenir une r\u00e9f\u00e9rence dans le domaine des salons de logistique.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15105 size-large\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Pharma_Logistics_Day_21.10.21_3.jpg\" alt=\"\" width=\"1024\" height=\"656\" \/> Aux Pharma Logistics Days, de grands et petits prestataires de services vari\u00e9s ont particip\u00e9.<\/caption>\n<p><em>\u00a0<\/em><\/p>\n<p><strong>Le programme d&rsquo;accompagnement en un coup d&rsquo;\u0153il :<\/strong><\/p>\n<p><a href=\"https:\/\/www.ilmac.ch\/de\/pld-programm\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.ilmac.ch\/de\/pld-programm<\/a><\/p>\n<p><strong>Les exposants<\/strong> (Filtrer par hall) :<\/p>\n<p><a href=\"https:\/\/www.ilmac.ch\/de\/messe#PharmaLogisticsDays\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.ilmac.ch\/de\/messe#PharmaLogisticsDays<\/a><\/p>\n<p>Photos : \u00a9 Loginfo24<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier, les 2\u00e8mes Pharma Logistics Days se sont termin\u00e9s au parc des expositions de B\u00e2le. Pendant deux jours, des prestataires se sont r\u00e9unis pour une exposition<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":12009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-52924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Pharma Logistics Days \u00e0 B\u00e2le pour la premi\u00e8re fois sur deux jours - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Pharma Logistics Days \u00e0 B\u00e2le pour la premi\u00e8re fois sur deux jours - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Hier, les 2\u00e8mes Pharma Logistics Days se sont termin\u00e9s au parc des expositions de B\u00e2le. Pendant deux jours, des prestataires se sont r\u00e9unis pour une exposition [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-22T14:53:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Pharma_Logistics_Day_21.10.21_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1226\" \/>\n\t<meta property=\"og:image:height\" content=\"890\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Les Pharma Logistics Days \u00e0 B\u00e2le pour la premi\u00e8re fois sur deux jours\",\"datePublished\":\"2021-10-22T14:53:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/\"},\"wordCount\":964,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Pharma_Logistics_Day_21.10.21_4.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/\",\"name\":\"Les Pharma Logistics Days \u00e0 B\u00e2le pour la premi\u00e8re fois sur deux jours - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Pharma_Logistics_Day_21.10.21_4.jpg\",\"datePublished\":\"2021-10-22T14:53:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Pharma_Logistics_Day_21.10.21_4.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Pharma_Logistics_Day_21.10.21_4.jpg\",\"width\":1226,\"height\":890},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/22\\\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Pharma Logistics Days \u00e0 B\u00e2le pour la premi\u00e8re fois sur deux jours\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Pharma Logistics Days \u00e0 B\u00e2le pour la premi\u00e8re fois sur deux jours - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Pharma Logistics Days \u00e0 B\u00e2le pour la premi\u00e8re fois sur deux jours - Loginfo24.","og_description":"Hier, les 2\u00e8mes Pharma Logistics Days se sont termin\u00e9s au parc des expositions de B\u00e2le. Pendant deux jours, des prestataires se sont r\u00e9unis pour une exposition [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-10-22T14:53:19+00:00","og_image":[{"width":1226,"height":890,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Pharma_Logistics_Day_21.10.21_4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/"},"author":{"name":"","@id":""},"headline":"Les Pharma Logistics Days \u00e0 B\u00e2le pour la premi\u00e8re fois sur deux jours","datePublished":"2021-10-22T14:53:19+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/"},"wordCount":964,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Pharma_Logistics_Day_21.10.21_4.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/","url":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/","name":"Les Pharma Logistics Days \u00e0 B\u00e2le pour la premi\u00e8re fois sur deux jours - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Pharma_Logistics_Day_21.10.21_4.jpg","datePublished":"2021-10-22T14:53:19+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Pharma_Logistics_Day_21.10.21_4.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Pharma_Logistics_Day_21.10.21_4.jpg","width":1226,"height":890},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/22\/les-pharma-logistics-days-a-bale-pour-la-premiere-fois-sur-deux-jours\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les Pharma Logistics Days \u00e0 B\u00e2le pour la premi\u00e8re fois sur deux jours"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/52924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=52924"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/52924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/12009"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=52924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=52924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=52924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}