{"id":52684,"date":"2021-10-14T08:08:41","date_gmt":"2021-10-14T06:08:41","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/"},"modified":"2021-10-14T08:08:41","modified_gmt":"2021-10-14T06:08:41","slug":"le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/","title":{"rendered":"Le secteur du fret \u00e0 l&rsquo;a\u00e9roport de Francfort continue de cro\u00eetre"},"content":{"rendered":"<h5><strong>La Fraport AG, exploitant de l&rsquo;a\u00e9roport de Francfort et d&rsquo;autres a\u00e9roports, annonce \u00e9galement pour septembre une augmentation significative du volume de fret. En raison des assouplissements des mesures sanitaires li\u00e9es au COVID-19, le nombre de passagers a \u00e9galement consid\u00e9rablement augment\u00e9. Les autres a\u00e9roports du groupe affichent \u00e9galement une \u00e9volution majoritairement positive.<\/strong><\/h5>\n<p>(Francfort\/Main) En septembre, l&rsquo;a\u00e9roport de Francfort a compt\u00e9 environ 3,1 millions de passagers. Par rapport au mois de septembre de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente, qui \u00e9tait tr\u00e8s faible, cela repr\u00e9sente une augmentation de 169,1 %. La raison de cette \u00e9volution positive est principalement due aux trafics touristiques. Comme en ao\u00fbt, pr\u00e8s de la moiti\u00e9 du niveau d&rsquo;avant la crise a \u00e9t\u00e9 atteinte (moins 54,0 % par rapport \u00e0 septembre 2019).<sup>1<\/sup><\/p>\n<p>Cumul\u00e9 sur les neuf premiers mois de l&rsquo;ann\u00e9e, le volume de passagers s&rsquo;\u00e9levait \u00e0 environ 15,8 millions. Cela repr\u00e9sente une baisse de 2,2 % par rapport \u00e0 la p\u00e9riode de r\u00e9f\u00e9rence de 2020, soit une diminution de 70,8 % par rapport \u00e0 2019.<\/p>\n<p>Le volume de fret a de nouveau augment\u00e9, enregistrant une hausse significative de 13,4 % pour atteindre 188.177 tonnes (plus 7,7 % par rapport \u00e0 septembre 2019). Le nombre de mouvements d&rsquo;avions a augment\u00e9 de 66,1 % par rapport au mois de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente, atteignant 28.135 d\u00e9collages et atterrissages. La somme des poids de d\u00e9collage maximum a augment\u00e9 de 61,5 % pour atteindre pr\u00e8s de 1,8 million de tonnes.<\/p>\n<p>La tendance positive des chiffres de passagers s&rsquo;est \u00e9galement poursuivie dans le portefeuille international. \u00c0 l&rsquo;exception de l&rsquo;a\u00e9roport chinois de Xi&rsquo;an, les a\u00e9roports du groupe ont enregistr\u00e9 des augmentations significatives, parfois de plus de cent pour cent, mais sur la base d&rsquo;un trafic a\u00e9rien fortement r\u00e9duit en septembre 2020. Par rapport au mois de septembre 2019, les a\u00e9roports du groupe continuent d&rsquo;afficher majoritairement des baisses. Des destinations de vacances importantes comme les a\u00e9roports grecs ainsi qu&rsquo;Antalya en Turquie ont atteint pr\u00e8s de 80 % du niveau d&rsquo;avant la crise (par rapport \u00e0 septembre 2019).<\/p>\n<p>L&rsquo;a\u00e9roport de Ljubljana en Slov\u00e9nie a enregistr\u00e9 en septembre 65.133 passagers. Dans les a\u00e9roports br\u00e9siliens de Fortaleza et Porto Alegre, le nombre de passagers a augment\u00e9 pour atteindre 820.169. L&rsquo;a\u00e9roport de Lima au P\u00e9rou a enregistr\u00e9 pr\u00e8s de 1,1 million de passagers.<\/p>\n<h5><strong>Les destinations de vacances en Gr\u00e8ce et en Bulgarie augmentent<\/strong><\/h5>\n<p>Dans les 14 a\u00e9roports r\u00e9gionaux grecs, le volume de passagers a augment\u00e9 pour atteindre environ 3,4 millions. Les a\u00e9roports bulgares Twin Star de Burgas et Varna ont enregistr\u00e9 en septembre une augmentation \u00e0 328.990 passagers. Le volume \u00e0 l&rsquo;a\u00e9roport d&rsquo;Antalya en Turquie a augment\u00e9 pour atteindre environ 3,8 millions de passagers. L&rsquo;a\u00e9roport de Saint-P\u00e9tersbourg en Russie a compt\u00e9 pr\u00e8s de 1,9 million de passagers. L&rsquo;a\u00e9roport de Xi&rsquo;an en Chine a enregistr\u00e9 en septembre pr\u00e8s de 2,3 millions de passagers.<\/p>\n<p>Photo : \u00a9 Fraport<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fraport AG, exploitant de l&rsquo;a\u00e9roport de Francfort et d&rsquo;autres a\u00e9roports, annonce \u00e9galement pour septembre une augmentation significative du volume de fret. En raison des assouplissements<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":12105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558,1561],"tags":[],"class_list":["post-52684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-air-freight","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le secteur du fret \u00e0 l&#039;a\u00e9roport de Francfort continue de cro\u00eetre - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le secteur du fret \u00e0 l&#039;a\u00e9roport de Francfort continue de cro\u00eetre - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"La Fraport AG, exploitant de l&rsquo;a\u00e9roport de Francfort et d&rsquo;autres a\u00e9roports, annonce \u00e9galement pour septembre une augmentation significative du volume de fret. En raison des assouplissements [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-14T06:08:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fraport_14.10.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1089\" \/>\n\t<meta property=\"og:image:height\" content=\"523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Le secteur du fret \u00e0 l&rsquo;a\u00e9roport de Francfort continue de cro\u00eetre\",\"datePublished\":\"2021-10-14T06:08:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/\"},\"wordCount\":496,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Fraport_14.10.21.jpg\",\"articleSection\":[\"Air Freight\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/\",\"name\":\"Le secteur du fret \u00e0 l'a\u00e9roport de Francfort continue de cro\u00eetre - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Fraport_14.10.21.jpg\",\"datePublished\":\"2021-10-14T06:08:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Fraport_14.10.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Fraport_14.10.21.jpg\",\"width\":1089,\"height\":523},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/14\\\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le secteur du fret \u00e0 l&rsquo;a\u00e9roport de Francfort continue de cro\u00eetre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le secteur du fret \u00e0 l'a\u00e9roport de Francfort continue de cro\u00eetre - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/","og_locale":"fr_FR","og_type":"article","og_title":"Le secteur du fret \u00e0 l'a\u00e9roport de Francfort continue de cro\u00eetre - Loginfo24.","og_description":"La Fraport AG, exploitant de l&rsquo;a\u00e9roport de Francfort et d&rsquo;autres a\u00e9roports, annonce \u00e9galement pour septembre une augmentation significative du volume de fret. En raison des assouplissements [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-10-14T06:08:41+00:00","og_image":[{"width":1089,"height":523,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fraport_14.10.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/"},"author":{"name":"","@id":""},"headline":"Le secteur du fret \u00e0 l&rsquo;a\u00e9roport de Francfort continue de cro\u00eetre","datePublished":"2021-10-14T06:08:41+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/"},"wordCount":496,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fraport_14.10.21.jpg","articleSection":["Air Freight","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/","url":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/","name":"Le secteur du fret \u00e0 l'a\u00e9roport de Francfort continue de cro\u00eetre - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fraport_14.10.21.jpg","datePublished":"2021-10-14T06:08:41+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fraport_14.10.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fraport_14.10.21.jpg","width":1089,"height":523},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/14\/le-secteur-du-fret-a-laeroport-de-francfort-continue-de-croitre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le secteur du fret \u00e0 l&rsquo;a\u00e9roport de Francfort continue de cro\u00eetre"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/52684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=52684"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/52684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/12105"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=52684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=52684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=52684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}