{"id":52522,"date":"2021-10-07T16:29:02","date_gmt":"2021-10-07T14:29:02","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/"},"modified":"2021-10-07T16:29:02","modified_gmt":"2021-10-07T14:29:02","slug":"le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/","title":{"rendered":"Le bon de livraison num\u00e9rique devrait \u00eatre introduit apr\u00e8s la phase de test"},"content":{"rendered":"<h5><strong>Avec un projet de coop\u00e9ration, la F\u00e9d\u00e9ration f\u00e9d\u00e9rale de logistique (BVL), GS1 Germany et T-Systems lancent un projet pour des processus de livraison plus rapides. Un <\/strong><strong>test pratique avec Open Telekom Cloud et les normes GS1 confirme les avantages et la praticit\u00e9 de la solution standardis\u00e9e. <\/strong><strong>Les premi\u00e8res mises en \u0153uvre sont pr\u00e9vues pour 2022.<\/strong><\/h5>\n<p>(Bonn\/Bremen\/Cologne) Lorsque les entreprises exp\u00e9dient des produits, elles \u00e9tablissent un bon de livraison sur papier qui accompagne la livraison jusqu&rsquo;\u00e0 la r\u00e9ception des marchandises. Il est transmis et trait\u00e9 manuellement. Cela prend du temps, est sujet \u00e0 des erreurs et consomme des ressources. Le bon de livraison num\u00e9rique devrait bient\u00f4t r\u00e9soudre ces probl\u00e8mes. Dans le cadre d&rsquo;un projet pilote commun de la F\u00e9d\u00e9ration f\u00e9d\u00e9rale de logistique (BVL), GS1 Germany et T-Systems, la solution a \u00e9t\u00e9 test\u00e9e en pratique. 20 entreprises de l&rsquo;industrie des biens de consommation, du commerce et de la logistique ont test\u00e9 le bon de livraison num\u00e9rique pendant quatre semaines en ao\u00fbt et septembre. Avec succ\u00e8s : 68 % des utilisateurs interrog\u00e9s souhaiteraient continuer \u00e0 utiliser la solution standardis\u00e9e pour le traitement num\u00e9rique des bons de livraison.<\/p>\n<p>Car, selon les r\u00e9sultats : la dur\u00e9e de certains processus de livraison a \u00e9t\u00e9 r\u00e9duite de jusqu&rsquo;\u00e0 dix jours. \u00ab\u00a0Les transporteurs \u00e9conomisent l&rsquo;ensemble des efforts de documentation des bons de livraison - de la num\u00e9risation \u00e0 l&rsquo;archivage en passant par l&rsquo;obligation d&rsquo;information\u00a0\u00bb, d\u00e9clare Oliver P\u00fcthe, responsable du projet chez GS1 Germany. Les r\u00e9sultats d\u00e9taill\u00e9s du projet pilote ont \u00e9t\u00e9 pr\u00e9sent\u00e9s le 6 octobre 2021 lors du symposium num\u00e9rique \u00ab\u00a0Logistique sans papier\u00a0\u00bb.<\/p>\n<h5><strong>La remise sans contact a particuli\u00e8rement plu<\/strong><\/h5>\n<p>Au cours du projet, les participants ont particuli\u00e8rement appr\u00e9ci\u00e9 la remise sans contact du document gr\u00e2ce \u00e0 la num\u00e9risation du code QR, la signature num\u00e9rique ainsi que l&rsquo;\u00e9conomie d&rsquo;impression des bons de livraison. Ils ont \u00e9galement salu\u00e9 le fait que la qualit\u00e9 du document ne souffre pas de plusieurs passages manuels. Parmi les avantages, ils estiment \u00e9galement qu&rsquo;il y a une disponibilit\u00e9 rapide et compl\u00e8te des preuves de livraison, y compris des informations bien lisibles sur les diff\u00e9rences de livraison.<\/p>\n<p>\u00ab\u00a0Le bon de livraison num\u00e9rique est un \u00e9l\u00e9ment cl\u00e9 pour des processus commerciaux enti\u00e8rement num\u00e9riques dans la logistique de transport\u00a0\u00bb, d\u00e9clare Christian Grotemeier, directeur g\u00e9n\u00e9ral de la BVL. \u00c0 l&rsquo;avenir, chaque partenaire de la cha\u00eene d&rsquo;approvisionnement devrait pouvoir acc\u00e9der num\u00e9riquement \u00e0 ses bons de livraison, les commenter et les signer.<\/p>\n<p>Photo : \u00a9 BVL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec un projet de coop\u00e9ration, la F\u00e9d\u00e9ration f\u00e9d\u00e9rale de logistique (BVL), GS1 Germany et T-Systems lancent un projet pour des processus de livraison plus rapides. Un<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":12167,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-52522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le bon de livraison num\u00e9rique devrait \u00eatre introduit apr\u00e8s la phase de test - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le bon de livraison num\u00e9rique devrait \u00eatre introduit apr\u00e8s la phase de test - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Avec un projet de coop\u00e9ration, la F\u00e9d\u00e9ration f\u00e9d\u00e9rale de logistique (BVL), GS1 Germany et T-Systems lancent un projet pour des processus de livraison plus rapides. Un [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-07T14:29:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BVL_7.10.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1377\" \/>\n\t<meta property=\"og:image:height\" content=\"866\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Le bon de livraison num\u00e9rique devrait \u00eatre introduit apr\u00e8s la phase de test\",\"datePublished\":\"2021-10-07T14:29:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/\"},\"wordCount\":463,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BVL_7.10.21.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/\",\"name\":\"Le bon de livraison num\u00e9rique devrait \u00eatre introduit apr\u00e8s la phase de test - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BVL_7.10.21.jpg\",\"datePublished\":\"2021-10-07T14:29:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BVL_7.10.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BVL_7.10.21.jpg\",\"width\":1377,\"height\":866},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/10\\\/07\\\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le bon de livraison num\u00e9rique devrait \u00eatre introduit apr\u00e8s la phase de test\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le bon de livraison num\u00e9rique devrait \u00eatre introduit apr\u00e8s la phase de test - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/","og_locale":"fr_FR","og_type":"article","og_title":"Le bon de livraison num\u00e9rique devrait \u00eatre introduit apr\u00e8s la phase de test - Loginfo24.","og_description":"Avec un projet de coop\u00e9ration, la F\u00e9d\u00e9ration f\u00e9d\u00e9rale de logistique (BVL), GS1 Germany et T-Systems lancent un projet pour des processus de livraison plus rapides. Un [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-10-07T14:29:02+00:00","og_image":[{"width":1377,"height":866,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BVL_7.10.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/"},"author":{"name":"","@id":""},"headline":"Le bon de livraison num\u00e9rique devrait \u00eatre introduit apr\u00e8s la phase de test","datePublished":"2021-10-07T14:29:02+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/"},"wordCount":463,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BVL_7.10.21.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/","url":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/","name":"Le bon de livraison num\u00e9rique devrait \u00eatre introduit apr\u00e8s la phase de test - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BVL_7.10.21.jpg","datePublished":"2021-10-07T14:29:02+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BVL_7.10.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BVL_7.10.21.jpg","width":1377,"height":866},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/10\/07\/le-bon-de-livraison-numerique-devrait-etre-introduit-apres-la-phase-de-test\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le bon de livraison num\u00e9rique devrait \u00eatre introduit apr\u00e8s la phase de test"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/52522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=52522"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/52522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/12167"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=52522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=52522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=52522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}