{"id":51591,"date":"2021-09-02T16:07:35","date_gmt":"2021-09-02T14:07:35","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/"},"modified":"2021-09-02T16:07:35","modified_gmt":"2021-09-02T14:07:35","slug":"fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/","title":{"rendered":"Fiege et LIP mettent en service un nouveau centre multi-utilisateurs"},"content":{"rendered":"<p>LIP Invest en tant qu&rsquo;investisseur et le prestataire logistique Fiege mettent en service \u00e0 Gengenbach environ 40 000 m\u00e8tres carr\u00e9s d&rsquo;espace logistique pr\u00e8s de la fronti\u00e8re franco-allemande. Il s&rsquo;agit du deuxi\u00e8me accord de financement anticip\u00e9 entre Fiege et LIP. L&rsquo;utilisation du centre sera assur\u00e9e par l&rsquo;unit\u00e9 commerciale Industrie et Pneus de Fiege.<\/p>\n<p>(Gengenbach\/Greven\/Munich) Cela a pris presque exactement un an, et maintenant le nouveau centre logistique est achev\u00e9 : le groupe Fiege met en service son centre multi-utilisateurs \u00e0 Gengenbach, dans le Bade-Wurtemberg. Sur le terrain de 73 000 m\u00e8tres carr\u00e9s pr\u00e8s de la fronti\u00e8re franco-allemande entre Strasbourg, Fribourg et Stuttgart, un b\u00e2timent de bureaux de trois \u00e9tages ainsi que quatre sections d&rsquo;entrep\u00f4t ont \u00e9t\u00e9 construits, offrant environ 40 000 m\u00e8tres carr\u00e9s d&rsquo;espace de stockage pour divers clients, y compris un grand fabricant de pneus. Le d\u00e9marrage op\u00e9rationnel est pr\u00e9vu pour octobre.<\/p>\n<p>Le nouvel actif logistique \u00e0 Gengenbach r\u00e9pond au statut Gold de la Deutsche Gesellschaft f\u00fcr Nachhaltiges Bauen (DGNB). Ainsi, l&rsquo;entreprise familiale Fiege de Greven, en Westphalie, met en \u0153uvre non seulement ses objectifs de croissance, mais aussi ses objectifs de durabilit\u00e9. \u00ab En plus d&rsquo;un \u00e9clairage LED g\u00e9n\u00e9ralis\u00e9, d&rsquo;une installation photovolta\u00efque et de l&rsquo;infrastructure pour la mobilit\u00e9 \u00e9lectrique, nous avons \u00e9galement pr\u00e9vu une prairie de fleurs sauvages sur le site \u00bb, d\u00e9clare Jan Fiege, directeur g\u00e9n\u00e9ral de Fiege Real Estate. \u00ab De plus, la technologie de gestion des b\u00e2timents permet une exploitation durable et interdisciplinaire. \u00bb<\/p>\n<h5><strong>Construction de haute qualit\u00e9 et moderne<\/strong><\/h5>\n<p>LIP Invest avait d\u00e9j\u00e0 acquis le d\u00e9veloppement du projet en tant qu&rsquo;accord anticip\u00e9 et a investi plus de 50 millions d&rsquo;euros dans la nouvelle construction. \u00ab Avec l&rsquo;achat du centre multi-utilisateurs, nous pouvons encore augmenter notre allocation de sites dans le portefeuille. L&rsquo;immobilier se distingue non seulement par son emplacement, mais aussi par sa construction de haute qualit\u00e9 et moderne. Avec la possibilit\u00e9 de diviser facilement l&rsquo;entrep\u00f4t et le grand nombre de quais de chargement, il pr\u00e9sente un haut degr\u00e9 de polyvalence pour des tiers \u00bb, d\u00e9clare Bodo Hollung, associ\u00e9 et directeur g\u00e9n\u00e9ral de LIP Invest.<\/p>\n<p>Le projet de construction a \u00e9t\u00e9 r\u00e9alis\u00e9 par le d\u00e9partement Fiege Real Estate en collaboration avec le bureau d&rsquo;architecture Kr\u00fcger Consult et la Bremer AG en tant qu&rsquo;entrepreneur g\u00e9n\u00e9ral. Le maire de Gengenbach, Thorsten Erny, loue l&rsquo;ach\u00e8vement rapide de la nouvelle construction : \u00ab Il est impressionnant de voir que l&rsquo;ensemble du nouveau b\u00e2timent a \u00e9t\u00e9 r\u00e9alis\u00e9 en seulement un an. Nous sommes maintenant ravis d&rsquo;accueillir l&rsquo;entreprise familiale Fiege ici \u00e0 Gengenbach. \u00bb<\/p>\n<h5><strong>Couvrir mieux le sud de l&rsquo;Allemagne, la Suisse et la France<\/strong><\/h5>\n<p>Le nouveau centre multi-utilisateurs \u00e0 Gengenbach est utilis\u00e9 par l&rsquo;unit\u00e9 commerciale Industrie et Pneus de Fiege. Christian Wierling, directeur g\u00e9n\u00e9ral du d\u00e9partement chez Fiege, explique : \u00ab Gengenbach est pour nous un emplacement strat\u00e9giquement extr\u00eamement pr\u00e9cieux dans la logistique des pneus et offre \u00e0 nos clients la possibilit\u00e9 de mieux couvrir le sud de l&rsquo;Allemagne ainsi que la Suisse et la France. \u00bb De plus, l&#8217;emplacement \u00e0 Gengenbach est l&rsquo;extension parfaite du site Fiege situ\u00e9 \u00e0 environ 30 kilom\u00e8tres \u00e0 Lahr dans la For\u00eat Noire, d\u00e9clare Wierling. \u00ab Avec le nouveau centre multi-utilisateurs \u00e0 Gengenbach, nous servons non seulement notre propre strat\u00e9gie de croissance, mais surtout celle de nos clients. \u00bb<\/p>\n<p>Photo : \u00a9 Fiege<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIP Invest en tant qu&rsquo;investisseur et le prestataire logistique Fiege mettent en service \u00e0 Gengenbach environ 40 000 m\u00e8tres carr\u00e9s d&rsquo;espace logistique pr\u00e8s de la fronti\u00e8re<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-51591","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiege et LIP mettent en service un nouveau centre multi-utilisateurs - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiege et LIP mettent en service un nouveau centre multi-utilisateurs - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"LIP Invest en tant qu&rsquo;investisseur et le prestataire logistique Fiege mettent en service \u00e0 Gengenbach environ 40 000 m\u00e8tres carr\u00e9s d&rsquo;espace logistique pr\u00e8s de la fronti\u00e8re [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-02T14:07:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/09\\\/02\\\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/09\\\/02\\\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fiege et LIP mettent en service un nouveau centre multi-utilisateurs\",\"datePublished\":\"2021-09-02T14:07:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/09\\\/02\\\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\\\/\"},\"wordCount\":595,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/09\\\/02\\\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/09\\\/02\\\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/09\\\/02\\\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\\\/\",\"name\":\"Fiege et LIP mettent en service un nouveau centre multi-utilisateurs - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-09-02T14:07:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/09\\\/02\\\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/09\\\/02\\\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/09\\\/02\\\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiege et LIP mettent en service un nouveau centre multi-utilisateurs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiege et LIP mettent en service un nouveau centre multi-utilisateurs - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/","og_locale":"fr_FR","og_type":"article","og_title":"Fiege et LIP mettent en service un nouveau centre multi-utilisateurs - Loginfo24.","og_description":"LIP Invest en tant qu&rsquo;investisseur et le prestataire logistique Fiege mettent en service \u00e0 Gengenbach environ 40 000 m\u00e8tres carr\u00e9s d&rsquo;espace logistique pr\u00e8s de la fronti\u00e8re [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-09-02T14:07:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/"},"author":{"name":"","@id":""},"headline":"Fiege et LIP mettent en service un nouveau centre multi-utilisateurs","datePublished":"2021-09-02T14:07:35+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/"},"wordCount":595,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/","url":"https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/","name":"Fiege et LIP mettent en service un nouveau centre multi-utilisateurs - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-09-02T14:07:35+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/09\/02\/fiege-et-lip-mettent-en-service-un-nouveau-centre-multi-utilisateurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Fiege et LIP mettent en service un nouveau centre multi-utilisateurs"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/51591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=51591"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/51591\/revisions"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=51591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=51591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=51591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}