{"id":28330,"date":"2021-08-08T17:07:14","date_gmt":"2021-08-08T15:07:14","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/"},"modified":"2025-12-15T13:14:33","modified_gmt":"2025-12-15T12:14:33","slug":"senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/","title":{"rendered":"SENATOR est le meilleur fournisseur de SIEMENS Healthineers en 2021"},"content":{"rendered":"<p>Le prestataire logistique SENATOR INTERNATIONAL remporte le prix du meilleur fournisseur 2021 de SIEMENS Healthineers dans la cat\u00e9gorie \u00ab Overall \u00bb. 233 partenaires du secteur du transport et de la logistique ont postul\u00e9 pour le \u00ab Siemens Healthineers Suppliers Award \u00bb. \u00c0 l&rsquo;occasion d&rsquo;une journ\u00e9e mondiale des fournisseurs, le prix a \u00e9t\u00e9 remis \u00e0 SENATOR.<\/p>\n<p>(Hambourg\/Erlangen) La Siemens Healthineers AG regroupe sous sa houlette les activit\u00e9s de technologie m\u00e9dicale de la Siemens AG. Le concept derri\u00e8re cela : soutenir les m\u00e9decins, le personnel m\u00e9dical et les prestataires de soins de sant\u00e9 dans le diagnostic, le traitement et la pr\u00e9vention des maladies avec des produits et services appropri\u00e9s. Le produit SIEMENS Healthineers sauve des vies. Surtout en p\u00e9riode de pand\u00e9mie, cela aide \u00e0 reconna\u00eetre les impacts de la COVID-19 et \u00e0 intervenir l\u00e0 o\u00f9 l&rsquo;aide est le plus n\u00e9cessaire.<\/p>\n<p>Une fois par an, Siemens Healthineers organise la journ\u00e9e mondiale des fournisseurs. C&rsquo;est ici que se rencontrent les repr\u00e9sentants des partenaires strat\u00e9giques et des fournisseurs cl\u00e9s du monde entier. Lors de cet \u00e9v\u00e9nement, les Siemens Healthineers Supplier Awards sont d\u00e9cern\u00e9s dans plusieurs cat\u00e9gories.<\/p>\n<h5><strong>La diff\u00e9rence est faite par le produit de fret a\u00e9rien \u00ab\u00a0SAB\u00a0\u00bb<\/strong><\/h5>\n<p>Le 1er juillet 2021, la journ\u00e9e des fournisseurs de cette ann\u00e9e a eu lieu pour les 233 partenaires impliqu\u00e9s dans le secteur du transport et de la logistique. C&rsquo;est avec une grande joie que SENATOR INTERNATIONAL a re\u00e7u en 2021 le prix du meilleur fournisseur \u00ab overall \u00bb. Ce prix nous r\u00e9jouit particuli\u00e8rement, car il honore le travail quotidien r\u00e9alis\u00e9 pour le projet. La diff\u00e9rence a une fois de plus \u00e9t\u00e9 faite par le produit de fret a\u00e9rien \u00ab SAB \u00bb. La combinaison de vols contr\u00f4l\u00e9s en propre et d&rsquo;une \u00e9quipe hautement professionnelle et motiv\u00e9e est remarquable et a convaincu. Le 22 juillet, le troph\u00e9e a \u00e9t\u00e9 remis \u00e0 Nuremberg. Stefan Seltsam, responsable des achats logistiques de la Siemens Healthineers AG, a remis le prix \u00e0 Tim-Oliver Kirschbaum, PDG de SENATOR INTERNATIONAL. Waldemar Naumann, KAM de SENATOR INTERNATIONAL ainsi que toute l&rsquo;\u00e9quipe op\u00e9rationnelle \u00e0 Nuremberg.<\/p>\n<p>Photo : \u00a9 SENATOR<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le prestataire logistique SENATOR INTERNATIONAL remporte le prix du meilleur fournisseur 2021 de SIEMENS Healthineers dans la cat\u00e9gorie \u00ab Overall \u00bb. 233 partenaires du secteur du<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558,1557,1561],"tags":[],"class_list":["post-28330","post","type-post","status-publish","format-standard","hentry","category-air-freight","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SENATOR est le meilleur fournisseur de SIEMENS Healthineers en 2021 - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SENATOR est le meilleur fournisseur de SIEMENS Healthineers en 2021 - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Le prestataire logistique SENATOR INTERNATIONAL remporte le prix du meilleur fournisseur 2021 de SIEMENS Healthineers dans la cat\u00e9gorie \u00ab Overall \u00bb. 233 partenaires du secteur du [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-08T15:07:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:14:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/08\\\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/08\\\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"SENATOR est le meilleur fournisseur de SIEMENS Healthineers en 2021\",\"datePublished\":\"2021-08-08T15:07:14+00:00\",\"dateModified\":\"2025-12-15T12:14:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/08\\\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\\\/\"},\"wordCount\":371,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Air Freight\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/08\\\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/08\\\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/08\\\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\\\/\",\"name\":\"SENATOR est le meilleur fournisseur de SIEMENS Healthineers en 2021 - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-08-08T15:07:14+00:00\",\"dateModified\":\"2025-12-15T12:14:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/08\\\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/08\\\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/08\\\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SENATOR est le meilleur fournisseur de SIEMENS Healthineers en 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SENATOR est le meilleur fournisseur de SIEMENS Healthineers en 2021 - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"SENATOR est le meilleur fournisseur de SIEMENS Healthineers en 2021 - Loginfo24.","og_description":"Le prestataire logistique SENATOR INTERNATIONAL remporte le prix du meilleur fournisseur 2021 de SIEMENS Healthineers dans la cat\u00e9gorie \u00ab Overall \u00bb. 233 partenaires du secteur du [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-08-08T15:07:14+00:00","article_modified_time":"2025-12-15T12:14:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/"},"author":{"name":"","@id":""},"headline":"SENATOR est le meilleur fournisseur de SIEMENS Healthineers en 2021","datePublished":"2021-08-08T15:07:14+00:00","dateModified":"2025-12-15T12:14:33+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/"},"wordCount":371,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Air Freight","Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/","url":"https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/","name":"SENATOR est le meilleur fournisseur de SIEMENS Healthineers en 2021 - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-08-08T15:07:14+00:00","dateModified":"2025-12-15T12:14:33+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/08\/08\/senator-est-le-meilleur-fournisseur-de-siemens-healthineers-en-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"SENATOR est le meilleur fournisseur de SIEMENS Healthineers en 2021"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/28330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=28330"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/28330\/revisions"}],"predecessor-version":[{"id":50911,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/28330\/revisions\/50911"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=28330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=28330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=28330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}