{"id":28270,"date":"2021-08-04T18:04:48","date_gmt":"2021-08-04T16:04:48","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/"},"modified":"2025-12-15T13:14:16","modified_gmt":"2025-12-15T12:14:16","slug":"ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/","title":{"rendered":"SSI SCH\u00c4FER automatise l&rsquo;entrep\u00f4t de Mathem \u00e0 Larsboda"},"content":{"rendered":"<p>SSI Sch\u00e4fer automatise le nouvel entrep\u00f4t de Mathem dans la ville su\u00e9doise de Larsboda. Avec le commerce \u00e9lectronique dans le secteur de la vente au d\u00e9tail alimentaire dans les pays scandinaves, le d\u00e9taillant alimentaire en ligne Mathem conna\u00eet \u00e9galement une croissance rapide. La construction de la nouvelle installation logistique \u00e0 Larsboda, au sud de Stockholm, est un \u00e9l\u00e9ment cl\u00e9 de l&rsquo;expansion future.<\/p>\n<p>(Neunkirchen\/Larsboda) Mathem s&rsquo;est \u00e9tabli en 2007 en tant que d\u00e9taillant alimentaire en ligne. Depuis lors, l&rsquo;entreprise conna\u00eet une expansion massive avec un nombre croissant de clients r\u00e9currents. Les op\u00e9rations se d\u00e9roulent actuellement \u00e0 Stockholm, G\u00f6teborg, Malm\u00f6 et dans leurs environs.<\/p>\n<p>L&rsquo;offre du d\u00e9taillant alimentaire en ligne \u00e9volue constamment. Par cons\u00e9quent, un haut degr\u00e9 de flexibilit\u00e9 est indispensable. De plus, la solution doit r\u00e9pondre aux exigences croissantes des clients en mati\u00e8re de disponibilit\u00e9 \u00e0 court terme, ce qui \u00e9tait l&rsquo;un des principaux motifs du projet. Le sp\u00e9cialiste de l&rsquo;intralogistique SSI SCH\u00c4FER a \u00e9t\u00e9 choisi en raison de sa flexibilit\u00e9 et de sa capacit\u00e9 \u00e0 s&rsquo;adapter aux exigences commerciales et aux objectifs \u00e9conomiques de Mathem.<\/p>\n<h5><strong>Une forte croissance dans le secteur alimentaire<\/strong><\/h5>\n<p>\u00ab\u00a0Le commerce \u00e9lectronique dans le secteur alimentaire est un domaine passionnant, o\u00f9 nous avons particuli\u00e8rement observ\u00e9 une forte croissance mondiale au cours de l&rsquo;ann\u00e9e derni\u00e8re. Mathem est un projet tr\u00e8s important pour SSI SCH\u00c4FER. Cela montre clairement que nous pouvons offrir la plus grande efficacit\u00e9 dans le segment de march\u00e9 o\u00f9 nous observons une croissance continue. C&rsquo;est passionnant de contribuer et de soutenir Mathem dans l&rsquo;atteinte de ses objectifs\u00a0\u00bb, explique Hans Ekstr\u00f6m, responsable de la conception des solutions d&rsquo;automatisation chez SSI SCH\u00c4FER.<\/p>\n<p>Avec le projet chez Mathem, SSI SCH\u00c4FER se positionne encore plus fortement dans le domaine du commerce \u00e9lectronique alimentaire. En raison des commandes plus importantes et des exigences de capacit\u00e9 plus \u00e9lev\u00e9es qui en d\u00e9coulent, les conditions pour des solutions automatis\u00e9es dans le secteur du commerce \u00e9lectronique alimentaire sont plus \u00e9lev\u00e9es que dans le commerce de d\u00e9tail en ligne traditionnel. Gr\u00e2ce \u00e0 plusieurs projets majeurs dans les pays scandinaves, SSI SCH\u00c4FER a d\u00e9j\u00e0 acquis une vaste exp\u00e9rience en mati\u00e8re d&rsquo;automatisation dans le secteur alimentaire. Par exemple, SSI SCH\u00c4FER fournit \u00e0 Coop la plus grande solution d&rsquo;automatisation en Europe ainsi qu&rsquo;\u00e0 ASKO une installation fortement ax\u00e9e sur la durabilit\u00e9.<\/p>\n<h5><strong>Solution \u00e9labor\u00e9e en peu de temps - d\u00e9marrage pr\u00e9vu pour 2022<\/strong><\/h5>\n<p>\u00ab\u00a0En peu de temps et en \u00e9troite collaboration avec SSI SCH\u00c4FER, nous avons pu trouver une solution qui nous permet de poursuivre notre formidable trajectoire de croissance et d&rsquo;atteindre nos objectifs \u00e9conomiques. Chaque jour, des dizaines de milliers d&rsquo;articles doivent \u00eatre pr\u00e9par\u00e9s dans toutes les combinaisons aussi rapidement que possible et livr\u00e9s \u00e0 nos clients. La solution cr\u00e9era \u00e9galement le meilleur environnement de travail possible pour nos employ\u00e9s en Su\u00e8de. Nous avons parcouru un long chemin et d\u00fb prendre de nombreuses d\u00e9cisions importantes, mais maintenant le v\u00e9ritable travail commence pour atteindre nos objectifs\u00a0\u00bb, d\u00e9clare Henrik Peitz, COO de Mathem.<\/p>\n<p>Les travaux de montage commenceront \u00e0 l&rsquo;automne. Le nouveau b\u00e2timent devrait \u00eatre mis en service au second semestre 2022.<\/p>\n<p>Photo : \u00a9 SSI Sch\u00e4fer<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SSI Sch\u00e4fer automatise le nouvel entrep\u00f4t de Mathem dans la ville su\u00e9doise de Larsboda. Avec le commerce \u00e9lectronique dans le secteur de la vente au d\u00e9tail<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-28270","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SSI SCH\u00c4FER automatise l&#039;entrep\u00f4t de Mathem \u00e0 Larsboda - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SSI SCH\u00c4FER automatise l&#039;entrep\u00f4t de Mathem \u00e0 Larsboda - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"SSI Sch\u00e4fer automatise le nouvel entrep\u00f4t de Mathem dans la ville su\u00e9doise de Larsboda. Avec le commerce \u00e9lectronique dans le secteur de la vente au d\u00e9tail [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-04T16:04:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:14:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/04\\\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/04\\\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"SSI SCH\u00c4FER automatise l&rsquo;entrep\u00f4t de Mathem \u00e0 Larsboda\",\"datePublished\":\"2021-08-04T16:04:48+00:00\",\"dateModified\":\"2025-12-15T12:14:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/04\\\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\\\/\"},\"wordCount\":574,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/04\\\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/04\\\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/04\\\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\\\/\",\"name\":\"SSI SCH\u00c4FER automatise l'entrep\u00f4t de Mathem \u00e0 Larsboda - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-08-04T16:04:48+00:00\",\"dateModified\":\"2025-12-15T12:14:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/04\\\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/04\\\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/08\\\/04\\\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SSI SCH\u00c4FER automatise l&rsquo;entrep\u00f4t de Mathem \u00e0 Larsboda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SSI SCH\u00c4FER automatise l'entrep\u00f4t de Mathem \u00e0 Larsboda - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/","og_locale":"fr_FR","og_type":"article","og_title":"SSI SCH\u00c4FER automatise l'entrep\u00f4t de Mathem \u00e0 Larsboda - Loginfo24.","og_description":"SSI Sch\u00e4fer automatise le nouvel entrep\u00f4t de Mathem dans la ville su\u00e9doise de Larsboda. Avec le commerce \u00e9lectronique dans le secteur de la vente au d\u00e9tail [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-08-04T16:04:48+00:00","article_modified_time":"2025-12-15T12:14:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/"},"author":{"name":"","@id":""},"headline":"SSI SCH\u00c4FER automatise l&rsquo;entrep\u00f4t de Mathem \u00e0 Larsboda","datePublished":"2021-08-04T16:04:48+00:00","dateModified":"2025-12-15T12:14:16+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/"},"wordCount":574,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/","url":"https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/","name":"SSI SCH\u00c4FER automatise l'entrep\u00f4t de Mathem \u00e0 Larsboda - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-08-04T16:04:48+00:00","dateModified":"2025-12-15T12:14:16+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/08\/04\/ssi-schafer-automatise-lentrepot-de-mathem-a-larsboda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"SSI SCH\u00c4FER automatise l&rsquo;entrep\u00f4t de Mathem \u00e0 Larsboda"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/28270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=28270"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/28270\/revisions"}],"predecessor-version":[{"id":50793,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/28270\/revisions\/50793"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=28270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=28270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=28270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}