{"id":28149,"date":"2021-07-30T17:57:04","date_gmt":"2021-07-30T15:57:04","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/"},"modified":"2025-12-15T13:13:38","modified_gmt":"2025-12-15T12:13:38","slug":"la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/","title":{"rendered":"La compagnie maritime Hapag-Lloyd rel\u00e8ve ses pr\u00e9visions de r\u00e9sultats pour 2021"},"content":{"rendered":"<p>Le r\u00e9sultat semestriel 2021 de la compagnie maritime Hapag-Lloyd a pu \u00eatre consid\u00e9rablement augment\u00e9 par rapport \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. L&rsquo;EBITDA s&rsquo;\u00e9l\u00e8ve \u00e0 environ 3,5 milliards d&rsquo;euros contre 1,2 milliard d&rsquo;euros l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. La demande mondiale de transports de conteneurs reste \u00e0 un niveau \u00e9lev\u00e9. Les pr\u00e9visions de r\u00e9sultats pour l&rsquo;exercice 2021 ont \u00e9t\u00e9 relev\u00e9es.<\/p>\n<p>(Hambourg) Sur la base de chiffres pr\u00e9liminaires, Hapag-Lloyd s&rsquo;attend \u00e0 un EBITDA d&rsquo;environ 4,2 milliards de dollars am\u00e9ricains (environ 3,5 milliards d&rsquo;euros) pour le premier semestre 2021, contre environ 1,3 milliard de dollars am\u00e9ricains (environ 1,2 milliard d&rsquo;euros) pour la m\u00eame p\u00e9riode l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. Dans le m\u00eame temps, l&rsquo;EBIT s&rsquo;\u00e9l\u00e8ve \u00e0 environ 3,5 milliards de dollars am\u00e9ricains (environ 2,9 milliards d&rsquo;euros), apr\u00e8s environ 0,6 milliard de dollars am\u00e9ricains (environ 0,5 milliard d&rsquo;euros) au premier semestre 2020.<\/p>\n<p>La demande mondiale de transports de conteneurs reste \u00e0 un niveau \u00e9lev\u00e9. Cependant, des perturbations op\u00e9rationnelles dans l&rsquo;ensemble de la cha\u00eene d&rsquo;approvisionnement continuent de provoquer des retards importants et contribuent ainsi \u00e0 la p\u00e9nurie de capacit\u00e9s de transport. C&rsquo;est pourquoi Hapag-Lloyd s&rsquo;attend \u00e9galement \u00e0 une dynamique de r\u00e9sultats tr\u00e8s forte pour la seconde moiti\u00e9 de l&rsquo;exercice. Jusqu&rsquo;\u00e0 pr\u00e9sent, une normalisation progressive de la situation des r\u00e9sultats \u00e9tait attendue au second semestre.<\/p>\n<h5><strong>Les tarifs de fret restent constamment \u00e9lev\u00e9s<\/strong><\/h5>\n<p>Pour cette raison, le conseil d&rsquo;administration de Hapag-Lloyd AG a relev\u00e9 ses pr\u00e9visions de r\u00e9sultats pour l&rsquo;exercice 2021. L&rsquo;EBITDA est d\u00e9sormais attendu dans une fourchette de 9,2 \u00e0 11,2 milliards de dollars am\u00e9ricains ou 7,6 \u00e0 9,3 milliards d&rsquo;euros (auparavant : nettement au-dessus de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente) et l&rsquo;EBIT dans une fourchette de 7,5 \u00e0 9,5 milliards de dollars am\u00e9ricains ou 6,2 \u00e0 7,9 milliards d&rsquo;euros (auparavant : nettement au-dessus de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente).<\/p>\n<p>\u00ab Nous avons \u00e9galement b\u00e9n\u00e9fici\u00e9 de meilleurs tarifs de fret au deuxi\u00e8me trimestre et nous avons dans l&rsquo;ensemble un tr\u00e8s bon premier semestre. En m\u00eame temps, nous sommes convaincus que cet \u00e9lan se poursuivra \u00e9galement au cours de la seconde moiti\u00e9 de l&rsquo;ann\u00e9e, ce qui nous a amen\u00e9s \u00e0 relever nos pr\u00e9visions de r\u00e9sultats pour 2021 dans son ensemble. Nous continuerons \u00e0 tout faire pour att\u00e9nuer les impacts des goulets d&rsquo;\u00e9tranglement dans les cha\u00eenes d&rsquo;approvisionnement pour nos clients et \u00e0 am\u00e9liorer la qualit\u00e9 du service \u00bb, a d\u00e9clar\u00e9 Rolf Habben Jansen, PDG de Hapag-Lloyd.<\/p>\n<p>Les chiffres d&rsquo;affaires d\u00e9finitifs pour le premier semestre 2021 seront publi\u00e9s comme pr\u00e9vu le 12 ao\u00fbt 2021.<\/p>\n<p>Photo : \u00a9 Hapag-Lloyd<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00e9sultat semestriel 2021 de la compagnie maritime Hapag-Lloyd a pu \u00eatre consid\u00e9rablement augment\u00e9 par rapport \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. L&rsquo;EBITDA s&rsquo;\u00e9l\u00e8ve \u00e0 environ 3,5 milliards d&rsquo;euros<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-28149","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La compagnie maritime Hapag-Lloyd rel\u00e8ve ses pr\u00e9visions de r\u00e9sultats pour 2021 - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La compagnie maritime Hapag-Lloyd rel\u00e8ve ses pr\u00e9visions de r\u00e9sultats pour 2021 - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Le r\u00e9sultat semestriel 2021 de la compagnie maritime Hapag-Lloyd a pu \u00eatre consid\u00e9rablement augment\u00e9 par rapport \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. L&rsquo;EBITDA s&rsquo;\u00e9l\u00e8ve \u00e0 environ 3,5 milliards d&rsquo;euros [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-30T15:57:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:13:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/30\\\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/30\\\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La compagnie maritime Hapag-Lloyd rel\u00e8ve ses pr\u00e9visions de r\u00e9sultats pour 2021\",\"datePublished\":\"2021-07-30T15:57:04+00:00\",\"dateModified\":\"2025-12-15T12:13:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/30\\\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\\\/\"},\"wordCount\":456,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/30\\\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/30\\\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/30\\\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\\\/\",\"name\":\"La compagnie maritime Hapag-Lloyd rel\u00e8ve ses pr\u00e9visions de r\u00e9sultats pour 2021 - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-07-30T15:57:04+00:00\",\"dateModified\":\"2025-12-15T12:13:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/30\\\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/30\\\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/30\\\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La compagnie maritime Hapag-Lloyd rel\u00e8ve ses pr\u00e9visions de r\u00e9sultats pour 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La compagnie maritime Hapag-Lloyd rel\u00e8ve ses pr\u00e9visions de r\u00e9sultats pour 2021 - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"La compagnie maritime Hapag-Lloyd rel\u00e8ve ses pr\u00e9visions de r\u00e9sultats pour 2021 - Loginfo24.","og_description":"Le r\u00e9sultat semestriel 2021 de la compagnie maritime Hapag-Lloyd a pu \u00eatre consid\u00e9rablement augment\u00e9 par rapport \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. L&rsquo;EBITDA s&rsquo;\u00e9l\u00e8ve \u00e0 environ 3,5 milliards d&rsquo;euros [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-07-30T15:57:04+00:00","article_modified_time":"2025-12-15T12:13:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/"},"author":{"name":"","@id":""},"headline":"La compagnie maritime Hapag-Lloyd rel\u00e8ve ses pr\u00e9visions de r\u00e9sultats pour 2021","datePublished":"2021-07-30T15:57:04+00:00","dateModified":"2025-12-15T12:13:38+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/"},"wordCount":456,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/","url":"https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/","name":"La compagnie maritime Hapag-Lloyd rel\u00e8ve ses pr\u00e9visions de r\u00e9sultats pour 2021 - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-07-30T15:57:04+00:00","dateModified":"2025-12-15T12:13:38+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/30\/la-compagnie-maritime-hapag-lloyd-releve-ses-previsions-de-resultats-pour-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La compagnie maritime Hapag-Lloyd rel\u00e8ve ses pr\u00e9visions de r\u00e9sultats pour 2021"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/28149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=28149"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/28149\/revisions"}],"predecessor-version":[{"id":50553,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/28149\/revisions\/50553"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=28149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=28149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=28149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}