{"id":27592,"date":"2021-07-08T17:16:17","date_gmt":"2021-07-08T15:16:17","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/"},"modified":"2025-12-15T13:10:46","modified_gmt":"2025-12-15T12:10:46","slug":"lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/","title":{"rendered":"Lufthansa Cargo utilise deux A321 en tant que freighters de mani\u00e8re permanente"},"content":{"rendered":"<p>Lufthansa Cargo utilise deux Airbus A321 modifi\u00e9s de mani\u00e8re permanente en tant que freighters. Les avions de ligne moyenne port\u00e9e seront utilis\u00e9s sur des routes continentales en Europe. Les avions recevront des portes de fret pour pouvoir transporter des conteneurs sur le pont principal. Les freighters seront op\u00e9r\u00e9s par Lufthansa CityLine.<\/p>\n<p>(Francfort\/Main) Lufthansa Cargo investit dans l&rsquo;expansion de ses capacit\u00e9s de fret. \u00c0 partir de d\u00e9but 2022, l&rsquo;entreprise proposera \u00e0 ses clients des capacit\u00e9s suppl\u00e9mentaires en Europe gr\u00e2ce \u00e0 la conversion permanente d&rsquo;Airbus 321 passagers en freighters. Les avions bimoteurs de moyenne port\u00e9e recevront de grandes portes de fret pour permettre le transport de conteneurs sur le pont principal. Dans un premier temps, la conversion de deux avions Airbus est pr\u00e9vue. Ces avions seront op\u00e9r\u00e9s par Lufthansa CityLine pour le compte de Lufthansa Cargo. Ils seront stationn\u00e9s \u00e0 Francfort.<\/p>\n<p>La croissance des envois eCommerce transfrontaliers est pr\u00e9vue \u00e0 environ 20 % par an pour les cinq prochaines ann\u00e9es. Les consommateurs s&rsquo;attendent \u00e0 des d\u00e9lais de livraison de plus en plus courts pour leurs marchandises command\u00e9es. Cela augmente \u00e9galement la demande de liaisons a\u00e9riennes en fret au sein de l&rsquo;Europe.<\/p>\n<h5><strong>Demande de services le jour m\u00eame<\/strong><\/h5>\n<p>\u00ab\u00a0Lufthansa Cargo souhaite offrir \u00e0 ses clients des liaisons rapides en Europe dans le segment eCommerce. Avec les A321 modifi\u00e9s, nous r\u00e9pondons \u00e0 la demande croissante de nos clients pour des services le jour m\u00eame et renfor\u00e7ons notre r\u00e9seau dense de liaisons mondiales ainsi que notre offre de produits\u00a0\u00bb, a d\u00e9clar\u00e9 Dorothea von Boxberg, pr\u00e9sidente de Lufthansa Cargo. \u00ab\u00a0Avec le mod\u00e8le d&rsquo;avion choisi, 28 tonnes peuvent \u00eatre transport\u00e9es par vol, soit des volumes de fret consid\u00e9rablement plus importants que dans les soutes des avions de court-courrier. En plus des transporteurs, des int\u00e9grateurs et des services postaux, les fournisseurs de eCommerce seront des clients pour cette offre\u00a0\u00bb, a ajout\u00e9 von Boxberg.<\/p>\n<p>\u00ab\u00a0Avec plus de 60 ans d&rsquo;exp\u00e9rience dans le transport a\u00e9rien europ\u00e9en, Lufthansa CityLine repr\u00e9sente des op\u00e9rations fiables et efficaces en tant que partenaire important du groupe Lufthansa. La flexibilit\u00e9 dans l&rsquo;exploitation et la rapidit\u00e9 dans l&rsquo;identification et la mise en \u0153uvre de nouvelles opportunit\u00e9s sont la base de notre activit\u00e9. Avec ces caract\u00e9ristiques, nous souhaitons nous engager pour Lufthansa Cargo et ses clients\u00a0\u00bb, a d\u00e9clar\u00e9 Steffen Harbarth, directeur g\u00e9n\u00e9ral de Lufthansa CityLine.<\/p>\n<h5><strong>Capacit\u00e9 de charge de 28 tonnes<\/strong><\/h5>\n<p>Les Airbus A321 convertis en avions de fret (A321P2F) offrent une capacit\u00e9 de charge de 28 tonnes avec une port\u00e9e de 3 500 kilom\u00e8tres. La conversion permet l&rsquo;utilisation de palettes de fret standardis\u00e9es \u00e9galement sur le pont principal. L&rsquo;Airbus A321 bimoteur est l&rsquo;un des avions les plus polyvalents de sa cat\u00e9gorie et permet une utilisation continentale tr\u00e8s efficace.<\/p>\n<p>Photo : \u00a9 Lufthansa Cargo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lufthansa Cargo utilise deux Airbus A321 modifi\u00e9s de mani\u00e8re permanente en tant que freighters. Les avions de ligne moyenne port\u00e9e seront utilis\u00e9s sur des routes continentales<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558,1561],"tags":[],"class_list":["post-27592","post","type-post","status-publish","format-standard","hentry","category-air-freight","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lufthansa Cargo utilise deux A321 en tant que freighters de mani\u00e8re permanente - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lufthansa Cargo utilise deux A321 en tant que freighters de mani\u00e8re permanente - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Lufthansa Cargo utilise deux Airbus A321 modifi\u00e9s de mani\u00e8re permanente en tant que freighters. Les avions de ligne moyenne port\u00e9e seront utilis\u00e9s sur des routes continentales [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-08T15:16:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:10:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/08\\\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/08\\\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Lufthansa Cargo utilise deux A321 en tant que freighters de mani\u00e8re permanente\",\"datePublished\":\"2021-07-08T15:16:17+00:00\",\"dateModified\":\"2025-12-15T12:10:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/08\\\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\\\/\"},\"wordCount\":502,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Air Freight\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/08\\\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/08\\\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/08\\\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\\\/\",\"name\":\"Lufthansa Cargo utilise deux A321 en tant que freighters de mani\u00e8re permanente - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-07-08T15:16:17+00:00\",\"dateModified\":\"2025-12-15T12:10:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/08\\\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/08\\\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/08\\\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lufthansa Cargo utilise deux A321 en tant que freighters de mani\u00e8re permanente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lufthansa Cargo utilise deux A321 en tant que freighters de mani\u00e8re permanente - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/","og_locale":"fr_FR","og_type":"article","og_title":"Lufthansa Cargo utilise deux A321 en tant que freighters de mani\u00e8re permanente - Loginfo24.","og_description":"Lufthansa Cargo utilise deux Airbus A321 modifi\u00e9s de mani\u00e8re permanente en tant que freighters. Les avions de ligne moyenne port\u00e9e seront utilis\u00e9s sur des routes continentales [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-07-08T15:16:17+00:00","article_modified_time":"2025-12-15T12:10:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/"},"author":{"name":"","@id":""},"headline":"Lufthansa Cargo utilise deux A321 en tant que freighters de mani\u00e8re permanente","datePublished":"2021-07-08T15:16:17+00:00","dateModified":"2025-12-15T12:10:46+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/"},"wordCount":502,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Air Freight","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/","url":"https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/","name":"Lufthansa Cargo utilise deux A321 en tant que freighters de mani\u00e8re permanente - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-07-08T15:16:17+00:00","dateModified":"2025-12-15T12:10:46+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/08\/lufthansa-cargo-utilise-deux-a321-en-tant-que-freighters-de-maniere-permanente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Lufthansa Cargo utilise deux A321 en tant que freighters de mani\u00e8re permanente"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=27592"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27592\/revisions"}],"predecessor-version":[{"id":49444,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27592\/revisions\/49444"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=27592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=27592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=27592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}