{"id":27463,"date":"2021-07-05T17:02:16","date_gmt":"2021-07-05T15:02:16","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/"},"modified":"2025-12-15T13:10:08","modified_gmt":"2025-12-15T12:10:08","slug":"leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/","title":{"rendered":"Leuze enregistre le plus fort volume de commandes de son histoire"},"content":{"rendered":"<p>Malgr\u00e9 le recul dans le secteur des installations et de la construction de machines et la pand\u00e9mie de Corona, Leuze regarde en arri\u00e8re sur une ann\u00e9e 2020 r\u00e9ussie. Mais ce n&rsquo;est pas tout : en 2021, l&rsquo;entreprise conna\u00eet un v\u00e9ritable boom, enregistrant dans le monde entier un volume de commandes aussi fort que jamais dans son histoire et regarde l&rsquo;avenir avec confiance.<\/p>\n<p>(Owen) L&rsquo;ann\u00e9e 2020 a \u00e9t\u00e9 marqu\u00e9e dans le monde entier par la pand\u00e9mie de Corona ainsi qu&rsquo;une \u00e9conomie r\u00e9cessive. N\u00e9anmoins, Leuze a connu une ann\u00e9e 2020 plut\u00f4t r\u00e9ussie en comparaison avec ses concurrents du secteur. Et depuis le d\u00e9but de 2021, l&rsquo;entreprise a vraiment acc\u00e9l\u00e9r\u00e9 : Le groupe Leuze electronic enregistre actuellement des niveaux historiques en mati\u00e8re de volume de commandes et de chiffre d&rsquo;affaires, et cro\u00eet ainsi de mani\u00e8re sup\u00e9rieure \u00e0 la moyenne.<\/p>\n<h5><strong>Leuze avec des objectifs de croissance clairs<\/strong><\/h5>\n<p>Le directeur g\u00e9n\u00e9ral Ulrich Balbach se r\u00e9jouit des volumes de commandes \u00e9lev\u00e9s et d&rsquo;une croissance du chiffre d&rsquo;affaires qu&rsquo;il n&rsquo;a jamais connue au cours de ses plus de 23 ann\u00e9es d&rsquo;anciennet\u00e9 chez Leuze. Et ce, malgr\u00e9 la crise sanitaire, les confinements li\u00e9s \u00e0 Corona et la p\u00e9nurie de ressources, notamment dans le secteur de l&rsquo;industrie des semi-conducteurs et des composants \u00e9lectroniques, qui s&rsquo;accompagne de d\u00e9lais de livraison plus longs. Selon Balbach, ce succ\u00e8s repose avant tout sur une action pr\u00e9coce, visionnaire et aussi courageuse dans un sens contra-cyclique. \u00ab On ne peut fa\u00e7onner le changement que si l&rsquo;on a une id\u00e9e claire de l&rsquo;avenir et un objectif concret en t\u00eate. Et Leuze l&rsquo;a \u00bb, dit-il et explique : d&rsquo;ici fin 2025, l&rsquo;entreprise vise \u00e0 doubler son chiffre d&rsquo;affaires. \u00bb<\/p>\n<p>Leuze est sur la bonne voie et s&rsquo;appuie sur son parcours de succ\u00e8s des ann\u00e9es pr\u00e9c\u00e9dentes. \u00ab D\u00e9j\u00e0 il y a un an, nous avons toujours soutenu que Corona n&rsquo;est pas une crise \u00e9conomique mais une crise de sant\u00e9 et nous nous y sommes bien pr\u00e9par\u00e9s. Nous avons toujours navigu\u00e9 avec notre mod\u00e8le de travail en alternance, assoupli quand et o\u00f9 cela \u00e9tait possible et autoris\u00e9, et avons red\u00e9marr\u00e9 \u00e0 plein r\u00e9gime d\u00e8s que le volume de commandes a commenc\u00e9 \u00e0 augmenter de mani\u00e8re significative. Cela a d\u00e9j\u00e0 commenc\u00e9 en ao\u00fbt 2020 et se poursuit jusqu&rsquo;\u00e0 aujourd&rsquo;hui. Un fort d\u00e9veloppement est \u00e9galement pr\u00e9vu pour le prochain trimestre \u00bb, d\u00e9clare Balbach avec un regard optimiste vers l&rsquo;avenir.<\/p>\n<h5><strong>Livres de commandes pleins et records de chiffre d&rsquo;affaires mondiaux<\/strong><\/h5>\n<p>Avec une augmentation actuelle du chiffre d&rsquo;affaires mondial de 20 %, Leuze est en pleine chasse \u00e0 la croissance. Les affaires se portent particuli\u00e8rement bien en Asie, mais aussi en Am\u00e9rique, suivies par l&rsquo;Europe. \u00ab Par rapport \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente, le chiffre d&rsquo;affaires a augment\u00e9 de 60 % en Chine \u00bb, d\u00e9clare Balbach. \u00ab L\u00e0-bas, la mobilit\u00e9 \u00e9lectrique dans l&rsquo;industrie automobile est actuellement un facteur moteur. De m\u00eame que le sujet de la photovolta\u00efque. Mais aussi les secteurs de l&rsquo;automatisation des laboratoires et de la logistique interne, sur lesquels Leuze se concentre, se portent tr\u00e8s bien \u00bb, explique-t-il. Leuze a investi et continue d&rsquo;investir dans de nouvelles structures \u00e0 l&rsquo;\u00e9chelle mondiale : gr\u00e2ce au nouveau centre de distribution international \u00e0 Unterlenningen, pr\u00e8s du si\u00e8ge de l&rsquo;entreprise dans le sud de l&rsquo;Allemagne, ouvert en juillet 2020, les capacit\u00e9s logistiques ont \u00e9t\u00e9 doubl\u00e9es.<\/p>\n<p>Ainsi, les volumes de commandes et de stocks \u00e9lev\u00e9s peuvent \u00eatre bien g\u00e9r\u00e9s. \u00c0 Melaka, en Malaisie, Leuze construit un nouveau site de production le long de la nouvelle route de la soie pour mieux r\u00e9pondre aux besoins des clients asiatiques et r\u00e9duire encore les d\u00e9lais de livraison. Son ach\u00e8vement est pr\u00e9vu pour fin 2021. L&rsquo;entreprise recrute de nouveaux employ\u00e9s dans le monde entier. \u00ab Les meilleurs employ\u00e9s sont notre capital le plus pr\u00e9cieux. C&rsquo;est ainsi que nous pouvons relever ensemble les d\u00e9fis de la croissance future \u00bb, explique Balbach.<\/p>\n<p>Photo : \u00a9 Leuze<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Malgr\u00e9 le recul dans le secteur des installations et de la construction de machines et la pand\u00e9mie de Corona, Leuze regarde en arri\u00e8re sur une ann\u00e9e<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1560,1561],"tags":[],"class_list":["post-27463","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leuze enregistre le plus fort volume de commandes de son histoire - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leuze enregistre le plus fort volume de commandes de son histoire - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Malgr\u00e9 le recul dans le secteur des installations et de la construction de machines et la pand\u00e9mie de Corona, Leuze regarde en arri\u00e8re sur une ann\u00e9e [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-05T15:02:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:10:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/05\\\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/05\\\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Leuze enregistre le plus fort volume de commandes de son histoire\",\"datePublished\":\"2021-07-05T15:02:16+00:00\",\"dateModified\":\"2025-12-15T12:10:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/05\\\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\\\/\"},\"wordCount\":718,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/05\\\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/05\\\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/05\\\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\\\/\",\"name\":\"Leuze enregistre le plus fort volume de commandes de son histoire - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-07-05T15:02:16+00:00\",\"dateModified\":\"2025-12-15T12:10:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/05\\\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/05\\\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/05\\\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leuze enregistre le plus fort volume de commandes de son histoire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leuze enregistre le plus fort volume de commandes de son histoire - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/","og_locale":"fr_FR","og_type":"article","og_title":"Leuze enregistre le plus fort volume de commandes de son histoire - Loginfo24.","og_description":"Malgr\u00e9 le recul dans le secteur des installations et de la construction de machines et la pand\u00e9mie de Corona, Leuze regarde en arri\u00e8re sur une ann\u00e9e [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-07-05T15:02:16+00:00","article_modified_time":"2025-12-15T12:10:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/"},"author":{"name":"","@id":""},"headline":"Leuze enregistre le plus fort volume de commandes de son histoire","datePublished":"2021-07-05T15:02:16+00:00","dateModified":"2025-12-15T12:10:08+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/"},"wordCount":718,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Categories","Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/","url":"https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/","name":"Leuze enregistre le plus fort volume de commandes de son histoire - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-07-05T15:02:16+00:00","dateModified":"2025-12-15T12:10:08+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/05\/leuze-enregistre-le-plus-fort-volume-de-commandes-de-son-histoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Leuze enregistre le plus fort volume de commandes de son histoire"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=27463"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27463\/revisions"}],"predecessor-version":[{"id":49190,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27463\/revisions\/49190"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=27463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=27463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=27463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}