{"id":27450,"date":"2021-07-03T17:49:47","date_gmt":"2021-07-03T15:49:47","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/"},"modified":"2025-12-15T13:10:00","modified_gmt":"2025-12-15T12:10:00","slug":"rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/","title":{"rendered":"Rhenus Midgard mise \u00e0 nouveau sur Liebherr pour le transbordement \u00e0 Hambourg"},"content":{"rendered":"<p>Rhenus Midgard remplace un Liebherr LHM 320 vieux de plus de 20 ans par une nouvelle machine Liebherr. Le LHM 420 r\u00e9cemment livr\u00e9 par le sp\u00e9cialiste de la logistique de projet Rhenus Project Logistics sera utilis\u00e9 au port de Hambourg au terminal Dradenau principalement pour le transbordement de breakbulk et de conteneurs. En plus d&rsquo;une augmentation significative de la productivit\u00e9, la grue permet \u00e9galement \u00e0 Rhenus, gr\u00e2ce \u00e0 une technologie de pointe, de r\u00e9duire les \u00e9missions au port de Hambourg.<\/p>\n<p>(Hambourg\/Rostock) Rhenus Midgard effectue principalement le transbordement de breakbulk et de conteneurs au terminal Dradenau \u00e0 Hambourg. Une grue mobile portuaire Liebherr de type LHM 320 acquise en 1999 a toujours g\u00e9r\u00e9 le transbordement de marchandises de mani\u00e8re fiable. Au terminal Dradenau, \u00e0 proximit\u00e9 des grands terminaux \u00e0 conteneurs de HHLA et Eurogate, une installation polyvalente de Rhenus Midgard est exploit\u00e9e. Ici, le LHM 320 a, au cours des derni\u00e8res ann\u00e9es, principalement transbord\u00e9 des machines, des \u00e9quipements et des installations pour des usines industrielles et de production ainsi que du papier, accumulant plus de 40 000 heures de fonctionnement.<\/p>\n<h5><strong>R\u00e9duire les temps d&rsquo;attente avec la nouvelle grue portuaire<\/strong><\/h5>\n<p>Dans le but de r\u00e9duire les temps d&rsquo;attente et de r\u00e9pondre aux volumes de transbordement en constante augmentation, Rhenus Midgard a command\u00e9 une nouvelle grue mobile portuaire Liebherr de type LHM 420, qui est en service au port de Hambourg depuis fin juin. La nouvelle machine remplace la grue mobile portuaire actuellement en service. Rhenus Midgard b\u00e9n\u00e9ficie gr\u00e2ce \u00e0 la nouvelle grue de vitesses de transbordement plus \u00e9lev\u00e9es, d&rsquo;une capacit\u00e9 de charge maximale accrue et d&rsquo;une plus grande port\u00e9e. Cet investissement fait partie d&rsquo;autres \u00e9tapes vers une augmentation de la productivit\u00e9 de l&rsquo;entreprise. De plus, la nouvelle grue Liebherr, avec sa technologie de moteur et d&rsquo;\u00e9chappement de pointe, offre l&rsquo;opportunit\u00e9 d&rsquo;une r\u00e9duction suppl\u00e9mentaire des \u00e9missions au port de Hambourg.<\/p>\n<h5><strong>Augmentation de la productivit\u00e9 et r\u00e9duction des \u00e9missions<\/strong><\/h5>\n<p>Helge Behrend, directeur g\u00e9n\u00e9ral de Rhenus Midgard Hambourg : \u00ab Avec la nouvelle grue mobile portuaire, nous allons enregistrer d&rsquo;autres augmentations des volumes de transbordement et, en combinaison avec le concept \u2018Greenliner\u2019 \u00e9tabli avec succ\u00e8s depuis plus de dix ans - amener des marchandises de la route vers l&rsquo;eau - contribuer encore davantage \u00e0 Hambourg, r\u00e9duire les \u00e9missions et all\u00e9ger les routes. \u00bbLe LHM 420 a \u00e9t\u00e9 livr\u00e9 en \u00e9tat enti\u00e8rement mont\u00e9 de Rostock \u00e0 Hambourg. Apr\u00e8s un voyage maritime d&rsquo;environ 10 heures avec le transporteur Open Deck \u00ab Aura \u00bb, la nouvelle machine \u00e9tait d\u00e9j\u00e0 pr\u00eate \u00e0 l&#8217;emploi peu apr\u00e8s son arriv\u00e9e. La nouvelle machine a une capacit\u00e9 de levage maximale allant jusqu&rsquo;\u00e0 124 tonnes et un bras de 48 m\u00e8tres de long pour une port\u00e9e optimale. \u00ab Nous nous r\u00e9jouissons de la poursuite de notre collaboration de confiance avec le groupe Rhenus. La nouvelle grue repr\u00e9sente pour Rhenus Midgard Hambourg \u00e0 la fois des augmentations de productivit\u00e9 et des r\u00e9ductions de co\u00fbts. Liebherr est fier de faire partie du \u2018concept Greenliner\u2019 initi\u00e9 par Rhenus Midgard avec le LHM 420 et ainsi de r\u00e9duire les \u00e9missions \u00bb, d\u00e9clare Eric Hein, responsable des ventes Liebherr pour les grues mobiles portuaires dans la r\u00e9gion DACH. Photo : \u00a9 Liebherr<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rhenus Midgard remplace un Liebherr LHM 320 vieux de plus de 20 ans par une nouvelle machine Liebherr. Le LHM 420 r\u00e9cemment livr\u00e9 par le sp\u00e9cialiste<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561,1559],"tags":[],"class_list":["post-27450","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rhenus Midgard mise \u00e0 nouveau sur Liebherr pour le transbordement \u00e0 Hambourg - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rhenus Midgard mise \u00e0 nouveau sur Liebherr pour le transbordement \u00e0 Hambourg - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Rhenus Midgard remplace un Liebherr LHM 320 vieux de plus de 20 ans par une nouvelle machine Liebherr. Le LHM 420 r\u00e9cemment livr\u00e9 par le sp\u00e9cialiste [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-03T15:49:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:10:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/03\\\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/03\\\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Rhenus Midgard mise \u00e0 nouveau sur Liebherr pour le transbordement \u00e0 Hambourg\",\"datePublished\":\"2021-07-03T15:49:47+00:00\",\"dateModified\":\"2025-12-15T12:10:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/03\\\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\\\/\"},\"wordCount\":556,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/03\\\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/03\\\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/03\\\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\\\/\",\"name\":\"Rhenus Midgard mise \u00e0 nouveau sur Liebherr pour le transbordement \u00e0 Hambourg - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-07-03T15:49:47+00:00\",\"dateModified\":\"2025-12-15T12:10:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/03\\\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/03\\\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/07\\\/03\\\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rhenus Midgard mise \u00e0 nouveau sur Liebherr pour le transbordement \u00e0 Hambourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rhenus Midgard mise \u00e0 nouveau sur Liebherr pour le transbordement \u00e0 Hambourg - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/","og_locale":"fr_FR","og_type":"article","og_title":"Rhenus Midgard mise \u00e0 nouveau sur Liebherr pour le transbordement \u00e0 Hambourg - Loginfo24.","og_description":"Rhenus Midgard remplace un Liebherr LHM 320 vieux de plus de 20 ans par une nouvelle machine Liebherr. Le LHM 420 r\u00e9cemment livr\u00e9 par le sp\u00e9cialiste [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-07-03T15:49:47+00:00","article_modified_time":"2025-12-15T12:10:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/"},"author":{"name":"","@id":""},"headline":"Rhenus Midgard mise \u00e0 nouveau sur Liebherr pour le transbordement \u00e0 Hambourg","datePublished":"2021-07-03T15:49:47+00:00","dateModified":"2025-12-15T12:10:00+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/"},"wordCount":556,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions","Shipping &amp; Ports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/","url":"https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/","name":"Rhenus Midgard mise \u00e0 nouveau sur Liebherr pour le transbordement \u00e0 Hambourg - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-07-03T15:49:47+00:00","dateModified":"2025-12-15T12:10:00+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/07\/03\/rhenus-midgard-mise-a-nouveau-sur-liebherr-pour-le-transbordement-a-hambourg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Rhenus Midgard mise \u00e0 nouveau sur Liebherr pour le transbordement \u00e0 Hambourg"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=27450"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27450\/revisions"}],"predecessor-version":[{"id":49164,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27450\/revisions\/49164"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=27450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=27450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=27450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}