{"id":27319,"date":"2021-06-29T17:14:32","date_gmt":"2021-06-29T15:14:32","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/"},"modified":"2025-12-15T13:09:21","modified_gmt":"2025-12-15T12:09:21","slug":"le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/","title":{"rendered":"Le groupe HGK avec de bons r\u00e9sultats en 2020, ann\u00e9e du Corona"},"content":{"rendered":"<p>Avec 10,3 millions d&rsquo;euros, la H\u00e4fen und G\u00fcterverkehr K\u00f6ln AG (HGK) a confirm\u00e9 son r\u00e9sultat record de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente malgr\u00e9 la pand\u00e9mie de Covid-19. L&rsquo;acquisition et l&rsquo;int\u00e9gration de HGK Shipping ont notamment contribu\u00e9 \u00e0 ce r\u00e9sultat. Un projet organisationnel interne a \u00e9t\u00e9 mis en place pour favoriser une croissance suppl\u00e9mentaire.<\/p>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">(Cologne) \u00ab Sur le plan op\u00e9rationnel, ce n&rsquo;\u00e9tait pas une ann\u00e9e facile pour nous. Presque tous les segments de march\u00e9 dans lesquels nous op\u00e9rons ont \u00e9t\u00e9 massivement affect\u00e9s par la crise du Corona. Nous sommes donc satisfaits d&rsquo;avoir maintenu le bon r\u00e9sultat de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. L&rsquo;acquisition de HGK Shipping et son mod\u00e8le commercial stable et orient\u00e9 vers l&rsquo;avenir ont jou\u00e9 un r\u00f4le essentiel \u00e0 cet \u00e9gard \u00bb, a d\u00e9clar\u00e9 Uwe Wedig, pr\u00e9sident du conseil d&rsquo;administration de la H\u00e4fen und G\u00fcterverkehr K\u00f6ln AG.<\/span><\/p>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">Le chiffre d&rsquo;affaires de la HGK AG dans les secteurs op\u00e9rationnels r\u00e9seau, technique et immobilier s&rsquo;est \u00e9lev\u00e9 en 2020 \u00e0 71,2 millions d&rsquo;euros, contre 75,4 millions d&rsquo;euros l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. L&rsquo;impact du Corona sur ces secteurs op\u00e9rationnels directement int\u00e9gr\u00e9s \u00e0 la soci\u00e9t\u00e9 \u00e9tait en r\u00e9alit\u00e9 moins important qu&rsquo;il n&rsquo;y para\u00eet au premier abord. Le chiffre d&rsquo;affaires plus \u00e9lev\u00e9 de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente \u00e9tait notamment d\u00fb \u00e0 des effets ponctuels dans le secteur immobilier.<\/span><\/p>\n<h5 class=\"Default\"><b><span style=\"font-family: 'Cambria',serif\">La pand\u00e9mie entra\u00eene des baisses de trafic et de chiffre d&rsquo;affaires<\/span><\/b><\/h5>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">Les effets du Corona deviennent plus \u00e9vidents en ce qui concerne les performances de manutention des participations logistiques de la HGK. Dans le secteur HGK Logistics and Intermodal (groupe neska), pr\u00e8s d&rsquo;un million de tonnes de marchandises ont \u00e9t\u00e9 transport\u00e9es et manutentionn\u00e9es en moins (6,25 millions de t contre 7,18 millions de t en 2019). La filiale \u00e0 100 % HTAG a manutentionn\u00e9 et transport\u00e9 au total 8,33 millions de t (ann\u00e9e pr\u00e9c\u00e9dente 10,06 millions de t). Rhein-Cargo, une coentreprise entre HGK et Neuss D\u00fcsseldorfer H\u00e4fen, a d\u00fb enregistrer une baisse significative, notamment dans le transport ferroviaire de marchandises, ne transportant en 2020 que 18,63 millions de t (ann\u00e9e pr\u00e9c\u00e9dente 21,86 millions de t). La manutention dans les sept ports de RheinCargo a \u00e9t\u00e9 moins fortement affect\u00e9e par la crise \u00e9conomique li\u00e9e au Corona, avec 15,25 millions de t (ann\u00e9e pr\u00e9c\u00e9dente 15,99 millions de t).<\/span><\/p>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">\u00a0<\/span><span style=\"font-family: 'Cambria',serif\">Apr\u00e8s l&rsquo;acquisition et l&rsquo;int\u00e9gration de HGK Shipping dans le portefeuille logistique du groupe HGK en ao\u00fbt 2020, la nouvelle filiale \u00e0 100 % a contribu\u00e9 positivement au r\u00e9sultat global du groupe HGK. Malgr\u00e9 les baisses des volumes de manutention et de transport dans tous les secteurs op\u00e9rationnels, la HGK AG a donc pu cl\u00f4turer l&rsquo;exercice 2020 exactement au niveau de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente, atteignant un r\u00e9sultat d&rsquo;entreprise de 10,3 millions d&rsquo;euros.<\/span><\/p>\n<h5 class=\"Default\"><b><span style=\"font-family: 'Cambria',serif\">Le groupe HGK fait avancer le d\u00e9veloppement vers un groupe logistique int\u00e9gr\u00e9<\/span><\/b><\/h5>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">L&rsquo;acquisition et l&rsquo;int\u00e9gration de HGK Shipping ont \u00e9galement marqu\u00e9 un \u00e9l\u00e9ment important pour l&rsquo;orientation et le d\u00e9veloppement ult\u00e9rieur de la HGK vers un groupe logistique int\u00e9gr\u00e9. Le groupe HGK peut aujourd&rsquo;hui offrir des services de transport et de logistique sur l&rsquo;ensemble du parcours du transport combin\u00e9 et ma\u00eetrise l&rsquo;ensemble du partage modal. Ce potentiel et les comp\u00e9tences particuli\u00e8res pour certains groupes de marchandises et segments industriels seront \u00e0 l&rsquo;avenir encore plus \u00e9troitement li\u00e9s, notamment gr\u00e2ce \u00e0 l&rsquo;utilisation intelligente d&rsquo;outils et de processus num\u00e9riques.<\/span><\/p>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">Cette strat\u00e9gie se refl\u00e8te d\u00e9sormais \u00e9galement dans une nouvelle marque, une nouvelle architecture de marque et, enfin, dans la r\u00e9orientation de l&rsquo;organisation de la HGK AG. Dans le cadre d&rsquo;un projet organisationnel interne, il a \u00e9t\u00e9 commenc\u00e9 au quatri\u00e8me trimestre 2020 \u00e0 d\u00e9finir des principes uniformes pour la conception des processus et la r\u00e9partition des t\u00e2ches entre les domaines op\u00e9rationnels, de contr\u00f4le et de soutien. Cela pose les bases d&rsquo;une croissance suppl\u00e9mentaire dans de nouveaux et anciens domaines d&rsquo;activit\u00e9.<\/span><\/p>\n<h5 class=\"Default\"><b><span style=\"font-family: 'Cambria',serif\">Extension du conseil d&rsquo;administration avec le secteur COO<\/span><\/b><\/h5>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">Ainsi, la HGK AG \u00e9volue vers une holding de gestion avec un accent sur le d\u00e9veloppement de l&rsquo;entreprise et la coordination des t\u00e2ches strat\u00e9giques centrales, par exemple dans le domaine de la durabilit\u00e9, de la qualit\u00e9 et de la num\u00e9risation. L&rsquo;extension d\u00e9j\u00e0 annonc\u00e9e et pr\u00e9vue pour d\u00e9but 2022 du conseil d&rsquo;administration de la HGK avec le secteur d&rsquo;un COO (Chief Operating Officer) est une autre \u00e9tape importante dans cette direction.<\/span><\/p>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">Photo : \u00a9 HGK<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec 10,3 millions d&rsquo;euros, la H\u00e4fen und G\u00fcterverkehr K\u00f6ln AG (HGK) a confirm\u00e9 son r\u00e9sultat record de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente malgr\u00e9 la pand\u00e9mie de Covid-19. L&rsquo;acquisition et<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-27319","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le groupe HGK avec de bons r\u00e9sultats en 2020, ann\u00e9e du Corona - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le groupe HGK avec de bons r\u00e9sultats en 2020, ann\u00e9e du Corona - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Avec 10,3 millions d&rsquo;euros, la H\u00e4fen und G\u00fcterverkehr K\u00f6ln AG (HGK) a confirm\u00e9 son r\u00e9sultat record de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente malgr\u00e9 la pand\u00e9mie de Covid-19. L&rsquo;acquisition et [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-29T15:14:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:09:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/29\\\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/29\\\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Le groupe HGK avec de bons r\u00e9sultats en 2020, ann\u00e9e du Corona\",\"datePublished\":\"2021-06-29T15:14:32+00:00\",\"dateModified\":\"2025-12-15T12:09:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/29\\\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\\\/\"},\"wordCount\":807,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/29\\\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/29\\\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/29\\\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\\\/\",\"name\":\"Le groupe HGK avec de bons r\u00e9sultats en 2020, ann\u00e9e du Corona - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-06-29T15:14:32+00:00\",\"dateModified\":\"2025-12-15T12:09:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/29\\\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/29\\\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/29\\\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le groupe HGK avec de bons r\u00e9sultats en 2020, ann\u00e9e du Corona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le groupe HGK avec de bons r\u00e9sultats en 2020, ann\u00e9e du Corona - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/","og_locale":"fr_FR","og_type":"article","og_title":"Le groupe HGK avec de bons r\u00e9sultats en 2020, ann\u00e9e du Corona - Loginfo24.","og_description":"Avec 10,3 millions d&rsquo;euros, la H\u00e4fen und G\u00fcterverkehr K\u00f6ln AG (HGK) a confirm\u00e9 son r\u00e9sultat record de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente malgr\u00e9 la pand\u00e9mie de Covid-19. L&rsquo;acquisition et [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-06-29T15:14:32+00:00","article_modified_time":"2025-12-15T12:09:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/"},"author":{"name":"","@id":""},"headline":"Le groupe HGK avec de bons r\u00e9sultats en 2020, ann\u00e9e du Corona","datePublished":"2021-06-29T15:14:32+00:00","dateModified":"2025-12-15T12:09:21+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/"},"wordCount":807,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/","url":"https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/","name":"Le groupe HGK avec de bons r\u00e9sultats en 2020, ann\u00e9e du Corona - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-06-29T15:14:32+00:00","dateModified":"2025-12-15T12:09:21+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/29\/le-groupe-hgk-avec-de-bons-resultats-en-2020-annee-du-corona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le groupe HGK avec de bons r\u00e9sultats en 2020, ann\u00e9e du Corona"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=27319"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27319\/revisions"}],"predecessor-version":[{"id":48904,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27319\/revisions\/48904"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=27319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=27319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=27319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}