{"id":27238,"date":"2021-06-27T19:14:07","date_gmt":"2021-06-27T17:14:07","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/"},"modified":"2025-12-15T13:08:54","modified_gmt":"2025-12-15T12:08:54","slug":"les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/","title":{"rendered":"Les membres du BME s&rsquo;attendent \u00e0 une p\u00e9nurie de mati\u00e8res premi\u00e8res prolong\u00e9e"},"content":{"rendered":"<p>L&rsquo;un des r\u00e9sultats centraux de la r\u00e9cente enqu\u00eate rapide du BME : De nombreux membres de l&rsquo;association des acheteurs s&rsquo;attendent \u00e0 ce que les p\u00e9nuries persistent jusqu&rsquo;\u00e0 la fin de l&rsquo;ann\u00e9e 2022. Environ 700 membres ont particip\u00e9 \u00e0 une enqu\u00eate correspondante. La p\u00e9nurie persistante de mati\u00e8res premi\u00e8res se fait surtout sentir dans les secteurs de l&rsquo;acier, des semi-conducteurs et des plastiques.<\/p>\n<p>(Eschborn) La p\u00e9nurie de mati\u00e8res premi\u00e8res dans les entreprises industrielles allemandes devrait durer encore longtemps. \u00ab\u00a0Plus de 60 % des membres que nous avons interrog\u00e9s ne s&rsquo;attendent pas \u00e0 un assouplissement sur les march\u00e9s des mati\u00e8res premi\u00e8res cette ann\u00e9e. Au contraire : les p\u00e9nuries devraient persister jusqu&rsquo;\u00e0 la fin de l&rsquo;ann\u00e9e 2022\u00a0\u00bb, a d\u00e9clar\u00e9 Gundula Ullah, pr\u00e9sidente de l&rsquo;Association f\u00e9d\u00e9rale de la gestion des mat\u00e9riaux, des achats et de la logistique e.V. (BME), \u00e0 Eschborn. Les acheteurs industriels doivent donc se concentrer sur l&rsquo;assurance de l&rsquo;approvisionnement dans leurs entreprises. Des pr\u00e9visions fiables sont, selon l&rsquo;\u00e9valuation du BME, une condition essentielle.<\/p>\n<p>Pour \u00e9tablir un \u00e9tat des lieux actuel parmi ses membres, l&rsquo;association des acheteurs a men\u00e9 une enqu\u00eate sur l&rsquo;approvisionnement en mati\u00e8res premi\u00e8res et la durabilit\u00e9 dans les entreprises entre le 7 et le 14 juin 2021. Sur la base de plus de 700 r\u00e9ponses d&rsquo;environ 9 000 membres en Allemagne, un tableau pr\u00e9cis de la situation a pu \u00eatre \u00e9tabli en un temps record.<\/p>\n<h5><strong>Harmonisation \u00e0 l&rsquo;\u00e9chelle de l&rsquo;UE de la loi sur la cha\u00eene d&rsquo;approvisionnement est importante<\/strong><\/h5>\n<p>Selon la derni\u00e8re enqu\u00eate, la p\u00e9nurie persistante de mati\u00e8res premi\u00e8res se fait surtout sentir dans les secteurs de l&rsquo;acier, des semi-conducteurs et des plastiques. Ainsi, presque toutes les entreprises \u2013 \u00e0 travers tous les secteurs \u2013 sont directement ou indirectement touch\u00e9es par les p\u00e9nuries. Seules les transports terrestres semblent avoir une disponibilit\u00e9 apparemment bonne (trois pour cent) \u2013 bien qu&rsquo;un effet Bullwhip (fluctuations de la demande le long de cha\u00eenes d&rsquo;approvisionnement multi-niveaux) puisse \u00eatre attendu si la disponibilit\u00e9 des mati\u00e8res premi\u00e8res venait \u00e0 s&rsquo;am\u00e9liorer.<\/p>\n<p>Plus de 50 % des membres du BME interrog\u00e9s s&rsquo;attendent \u00e9galement \u00e0 ce que le th\u00e8me de la \u00ab\u00a0durabilit\u00e9\u00a0\u00bb perde de sa pertinence apr\u00e8s les \u00e9lections f\u00e9d\u00e9rales \u2013 bien que plus de 80 % ressentiront directement les effets de cette m\u00e9gatendance ainsi que de la loi sur la cha\u00eene d&rsquo;approvisionnement dans leur activit\u00e9 quotidienne. Ullah : \u00ab\u00a0Les achats doivent se pr\u00e9parer \u00e0 cela.\u00a0\u00bb<\/p>\n<p>Il est \u00e9galement important pour les membres d&rsquo;avoir une approche harmonis\u00e9e de la loi sur la cha\u00eene d&rsquo;approvisionnement \u00e0 l&rsquo;\u00e9chelle de l&rsquo;UE \u00e0 l&rsquo;avenir. Cela permettrait de maintenir la bureaucratie et les efforts n\u00e9cessaires pour respecter les r\u00e9glementations l\u00e9gales \u00e0 un niveau g\u00e9rable. Selon l&rsquo;avis de la pr\u00e9sidente du BME, la politique doit intervenir ici. Elle doit proposer des solutions orient\u00e9es vers les entreprises.<\/p>\n<h4><a href=\"https:\/\/assets.bme.de\/public\/uploads\/f501a0ffd71f05976d09436df4b9a2884a8d535a05ab3110317eefc0c191\"><strong>R\u00e9sultats de la r\u00e9cente enqu\u00eate rapide du BME de juin 2021<\/strong><\/a><\/h4>\n<p>Graphique : \u00a9 BME \/ <strong><em>L\u00e9gende de l&rsquo;image :<\/em><\/strong><em> L&rsquo;acier fait partie des mati\u00e8res premi\u00e8res rares avec les plastiques et les semi-conducteurs<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;un des r\u00e9sultats centraux de la r\u00e9cente enqu\u00eate rapide du BME : De nombreux membres de l&rsquo;association des acheteurs s&rsquo;attendent \u00e0 ce que les p\u00e9nuries persistent<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-27238","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les membres du BME s&#039;attendent \u00e0 une p\u00e9nurie de mati\u00e8res premi\u00e8res prolong\u00e9e - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les membres du BME s&#039;attendent \u00e0 une p\u00e9nurie de mati\u00e8res premi\u00e8res prolong\u00e9e - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;un des r\u00e9sultats centraux de la r\u00e9cente enqu\u00eate rapide du BME : De nombreux membres de l&rsquo;association des acheteurs s&rsquo;attendent \u00e0 ce que les p\u00e9nuries persistent [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-27T17:14:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:08:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/27\\\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/27\\\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Les membres du BME s&rsquo;attendent \u00e0 une p\u00e9nurie de mati\u00e8res premi\u00e8res prolong\u00e9e\",\"datePublished\":\"2021-06-27T17:14:07+00:00\",\"dateModified\":\"2025-12-15T12:08:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/27\\\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\\\/\"},\"wordCount\":556,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/27\\\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/27\\\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/27\\\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\\\/\",\"name\":\"Les membres du BME s'attendent \u00e0 une p\u00e9nurie de mati\u00e8res premi\u00e8res prolong\u00e9e - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-06-27T17:14:07+00:00\",\"dateModified\":\"2025-12-15T12:08:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/27\\\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/27\\\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/27\\\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les membres du BME s&rsquo;attendent \u00e0 une p\u00e9nurie de mati\u00e8res premi\u00e8res prolong\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les membres du BME s'attendent \u00e0 une p\u00e9nurie de mati\u00e8res premi\u00e8res prolong\u00e9e - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/","og_locale":"fr_FR","og_type":"article","og_title":"Les membres du BME s'attendent \u00e0 une p\u00e9nurie de mati\u00e8res premi\u00e8res prolong\u00e9e - Loginfo24.","og_description":"L&rsquo;un des r\u00e9sultats centraux de la r\u00e9cente enqu\u00eate rapide du BME : De nombreux membres de l&rsquo;association des acheteurs s&rsquo;attendent \u00e0 ce que les p\u00e9nuries persistent [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-06-27T17:14:07+00:00","article_modified_time":"2025-12-15T12:08:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/"},"author":{"name":"","@id":""},"headline":"Les membres du BME s&rsquo;attendent \u00e0 une p\u00e9nurie de mati\u00e8res premi\u00e8res prolong\u00e9e","datePublished":"2021-06-27T17:14:07+00:00","dateModified":"2025-12-15T12:08:54+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/"},"wordCount":556,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/","url":"https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/","name":"Les membres du BME s'attendent \u00e0 une p\u00e9nurie de mati\u00e8res premi\u00e8res prolong\u00e9e - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-06-27T17:14:07+00:00","dateModified":"2025-12-15T12:08:54+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/27\/les-membres-du-bme-sattendent-a-une-penurie-de-matieres-premieres-prolongee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les membres du BME s&rsquo;attendent \u00e0 une p\u00e9nurie de mati\u00e8res premi\u00e8res prolong\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=27238"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27238\/revisions"}],"predecessor-version":[{"id":48742,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/27238\/revisions\/48742"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=27238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=27238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=27238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}