{"id":26820,"date":"2021-06-09T19:26:55","date_gmt":"2021-06-09T17:26:55","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/"},"modified":"2025-12-15T13:07:02","modified_gmt":"2025-12-15T12:07:02","slug":"dematic-automatise-le-nouveau-centre-logistique-divf-hartmann","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/","title":{"rendered":"Dematic automatise le nouveau centre logistique d&rsquo;IVF HARTMANN"},"content":{"rendered":"<p>Dematic a automatis\u00e9 le nouveau centre logistique du sp\u00e9cialiste suisse de la sant\u00e9 IVF HARTMANN situ\u00e9 \u00e0 Neuhausen am Rheinfall. Le sp\u00e9cialiste de l&rsquo;intralogistique a d\u00e9velopp\u00e9 pour le fournisseur de biens m\u00e9dicaux une solution compacte compos\u00e9e d&rsquo;un syst\u00e8me de multishuttle haute vitesse \u00e0 trois all\u00e9es et d&rsquo;une zone de pr\u00e9paration des commandes en dessous, \u00e9quip\u00e9e d&rsquo;un syst\u00e8me Put-to-Light.<\/p>\n<p>(Heusenstamm\/Neuhausen am Rheinfall) Les solutions Dematic permettent une automatisation compl\u00e8te des op\u00e9rations de stockage et de d\u00e9stockage, ainsi que de la pr\u00e9paration des commandes et de l&rsquo;ensemble du flux de mat\u00e9riaux, qui \u00e9taient auparavant manuelles. Cela permet au fabricant de biens m\u00e9dicaux de livrer ses clients encore plus rapidement tout en optimisant la s\u00e9curit\u00e9 d&rsquo;approvisionnement.<\/p>\n<p>\u00ab La solution d\u00e9velopp\u00e9e par Dematic s&rsquo;est r\u00e9v\u00e9l\u00e9e optimale pour nous. La zone de stockage et la zone de pr\u00e9paration des commandes sont d\u00e9sormais directement superpos\u00e9es, ce qui \u00e9vite de perdre du temps avec des trajets de transport internes complexes \u00bb, d\u00e9clare Thomas Mayer, responsable logistique chez IVF HARTMANN AG. Gr\u00e2ce \u00e0 la construction sur deux niveaux, l&rsquo;entreprise am\u00e9liore non seulement l&rsquo;efficacit\u00e9 de ses processus logistiques, mais utilise \u00e9galement au mieux les conditions locales. En m\u00eame temps, le sp\u00e9cialiste de la sant\u00e9 continue de faire avancer la modernisation et la num\u00e9risation de ses processus.<\/p>\n<h5><strong>Nouvelles technologies en combinaison avec des processus \u00e9prouv\u00e9s<\/strong><\/h5>\n<p>Le centre logistique r\u00e9cemment ouvert combine les derni\u00e8res technologies avec des processus \u00e9prouv\u00e9s. Pour la mise en \u0153uvre des solutions enti\u00e8rement automatis\u00e9es, IVF HARTMANN a fait confiance au concept de Dematic. \u00c0 l&rsquo;\u00e9tage sup\u00e9rieur, le sp\u00e9cialiste de l&rsquo;intralogistique a install\u00e9 un entrep\u00f4t multishuttle haute vitesse \u00e0 trois all\u00e9es, comprenant environ 10 000 emplacements de conteneurs. L&rsquo;entr\u00e9e et la sortie automatiques des marchandises sur des \u00e9tag\u00e8res sont assur\u00e9es par 60 shuttles Dematic. Par l&rsquo;interm\u00e9diaire de trois paires de levage, les conteneurs sont ensuite transport\u00e9s vers la zone de pr\u00e9paration des commandes au rez-de-chauss\u00e9e. Avec une vitesse allant jusqu&rsquo;\u00e0 quatre m\u00e8tres par seconde, les shuttles r\u00e9alisent des mouvements de mat\u00e9riaux rapides et efficaces.<\/p>\n<p>Une fois arriv\u00e9es dans la zone de pr\u00e9paration des commandes, les marchandises sont r\u00e9parties sur l&rsquo;une des trois stations de pr\u00e9l\u00e8vement. Un syst\u00e8me Put-to-Light indique au pr\u00e9parateur de commandes le conteneur dans lequel l&rsquo;article demand\u00e9 doit \u00eatre plac\u00e9. \u00ab Cela r\u00e9duit consid\u00e9rablement le risque d&rsquo;erreurs lors de la pr\u00e9paration des commandes \u00bb, explique Mayer. En plus des deux zones de pr\u00e9l\u00e8vement, la zone de pr\u00e9paration des commandes dispose \u00e9galement de quatre stations d&#8217;emballage et de deux postes de travail pour la r\u00e9ception des marchandises et la d\u00e9consolidation des palettes. Pour relier les diff\u00e9rentes zones, un total de seulement 290 m\u00e8tres de technologie de transport a \u00e9t\u00e9 install\u00e9. Des zones de stockage manuelles \u00e9tendues ont \u00e9galement \u00e9t\u00e9 int\u00e9gr\u00e9es.<\/p>\n<h5><strong>Paysage syst\u00e8me et maintenance simplifi\u00e9s<\/strong><\/h5>\n<p>L&rsquo;ancien entrep\u00f4t manuel \u00e9tait g\u00e9r\u00e9 par une solution SAP WM vieillissante. En collaboration avec les employ\u00e9s de HARTMANN, les consultants de Dematic ont r\u00e9vis\u00e9 les processus existants et d\u00e9fini un syst\u00e8me mod\u00e8le pour les futurs d\u00e9ploiements. L&rsquo;entrep\u00f4t est d\u00e9sormais g\u00e9r\u00e9 par le logiciel SAP Extended Warehouse Management (SAP EWM) avec le syst\u00e8me de flux de mat\u00e9riaux SAP Dematic. Cela permet \u00e9galement une connexion directe de la couche de contr\u00f4le (SPS) \u2013 en utilisant les normes de communication Dematic, ce qui a permis d&rsquo;\u00e9viter compl\u00e8tement les mises en \u0153uvre sp\u00e9cifiques au projet. \u00ab Gr\u00e2ce \u00e0 l&rsquo;utilisation de normes \u00e9prouv\u00e9es, nous avons consid\u00e9rablement simplifi\u00e9 le paysage syst\u00e8me ainsi que la maintenance et le service \u00bb, explique Mayer.<\/p>\n<p>Photo : \u00a9 Dematic<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dematic a automatis\u00e9 le nouveau centre logistique du sp\u00e9cialiste suisse de la sant\u00e9 IVF HARTMANN situ\u00e9 \u00e0 Neuhausen am Rheinfall. Le sp\u00e9cialiste de l&rsquo;intralogistique a d\u00e9velopp\u00e9<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1560,1561],"tags":[],"class_list":["post-26820","post","type-post","status-publish","format-standard","hentry","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dematic automatise le nouveau centre logistique d&#039;IVF HARTMANN - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dematic automatise le nouveau centre logistique d&#039;IVF HARTMANN - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Dematic a automatis\u00e9 le nouveau centre logistique du sp\u00e9cialiste suisse de la sant\u00e9 IVF HARTMANN situ\u00e9 \u00e0 Neuhausen am Rheinfall. Le sp\u00e9cialiste de l&rsquo;intralogistique a d\u00e9velopp\u00e9 [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-09T17:26:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:07:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/09\\\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/09\\\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Dematic automatise le nouveau centre logistique d&rsquo;IVF HARTMANN\",\"datePublished\":\"2021-06-09T17:26:55+00:00\",\"dateModified\":\"2025-12-15T12:07:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/09\\\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\\\/\"},\"wordCount\":671,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/09\\\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/09\\\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/09\\\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\\\/\",\"name\":\"Dematic automatise le nouveau centre logistique d'IVF HARTMANN - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-06-09T17:26:55+00:00\",\"dateModified\":\"2025-12-15T12:07:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/09\\\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/09\\\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/06\\\/09\\\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dematic automatise le nouveau centre logistique d&rsquo;IVF HARTMANN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dematic automatise le nouveau centre logistique d'IVF HARTMANN - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/","og_locale":"fr_FR","og_type":"article","og_title":"Dematic automatise le nouveau centre logistique d'IVF HARTMANN - Loginfo24.","og_description":"Dematic a automatis\u00e9 le nouveau centre logistique du sp\u00e9cialiste suisse de la sant\u00e9 IVF HARTMANN situ\u00e9 \u00e0 Neuhausen am Rheinfall. Le sp\u00e9cialiste de l&rsquo;intralogistique a d\u00e9velopp\u00e9 [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-06-09T17:26:55+00:00","article_modified_time":"2025-12-15T12:07:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/"},"author":{"name":"","@id":""},"headline":"Dematic automatise le nouveau centre logistique d&rsquo;IVF HARTMANN","datePublished":"2021-06-09T17:26:55+00:00","dateModified":"2025-12-15T12:07:02+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/"},"wordCount":671,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/","url":"https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/","name":"Dematic automatise le nouveau centre logistique d'IVF HARTMANN - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-06-09T17:26:55+00:00","dateModified":"2025-12-15T12:07:02+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/06\/09\/dematic-automatise-le-nouveau-centre-logistique-divf-hartmann\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Dematic automatise le nouveau centre logistique d&rsquo;IVF HARTMANN"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/26820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=26820"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/26820\/revisions"}],"predecessor-version":[{"id":47932,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/26820\/revisions\/47932"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=26820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=26820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=26820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}