{"id":26653,"date":"2022-01-20T16:33:46","date_gmt":"2022-01-20T15:33:46","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/"},"modified":"2022-01-20T16:33:46","modified_gmt":"2022-01-20T15:33:46","slug":"heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/","title":{"rendered":"HEINLOTH construit un centre logistique \u00e0 Roth pr\u00e8s de Nuremberg"},"content":{"rendered":"<h4 class=\"Default\"><b><span style=\"font-family: 'Cambria',serif\">Depuis septembre de l&rsquo;ann\u00e9e derni\u00e8re, les travaux de construction sont en cours, et le fonctionnement doit commencer en septembre 2022 : Un nouveau centre logistique du groupe d&rsquo;entreprises HEINLOTH \u2013 les experts logistiques \u2013 est actuellement en construction \u00e0 Roth. Avec ce projet, l&rsquo;entreprise d\u00e9veloppe de mani\u00e8re coh\u00e9rente son secteur de la logistique contractuelle et affirme ainsi clairement son attachement \u00e0 son site d&rsquo;origine en Franconie moyenne.<\/span><\/b><\/h4>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">(Roth pr\u00e8s de Nuremberg) \u00ab La bonne connexion de la Franconie moyenne \u00e0 l&rsquo;ensemble de l&rsquo;Allemagne et au sud de l&rsquo;Europe, la puissance \u00e9conomique et la croissance prospective de la r\u00e9gion avec un march\u00e9 client int\u00e9ressant ont \u00e9t\u00e9 d\u00e9cisives pour le site de Roth \u00bb, d\u00e9clare Roland Heinloth, PDG de l&rsquo;entreprise et responsable des domaines de la logistique strat\u00e9gique et du d\u00e9veloppement immobilier.<\/span><\/p>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">Le nouveau b\u00e2timent est la plus grande propri\u00e9t\u00e9 logistique de HEINLOTH et repr\u00e9sente en m\u00eame temps le plus grand investissement unique de l&rsquo;histoire de l&rsquo;entreprise. Pour utiliser au mieux la surface disponible, un entrep\u00f4t \u00e0 all\u00e9es \u00e9troites de 20 m\u00e8tres de haut a \u00e9t\u00e9 choisi, g\u00e9n\u00e9rant ainsi plus de 16 000 emplacements de palettes. \u00c0 pleine capacit\u00e9, jusqu&rsquo;\u00e0 50 emplois seront cr\u00e9\u00e9s ici \u2013 \u00e9galement en raison de l&rsquo;espace de pr\u00e9paration et de conditionnement con\u00e7u sp\u00e9cifiquement. Gr\u00e2ce \u00e0 l&rsquo;utilisation de techniques d&rsquo;entreposage modernes, un tr\u00e8s haut d\u00e9bit de palettes peut \u00eatre atteint, en particulier pour les \u00ab marchandises \u00e0 rotation rapide \u00bb. \u00ab Un syst\u00e8me de gestion d&rsquo;entrep\u00f4t innovant pour des exigences clients \u00e9lev\u00e9es et la semi-automatisation des \u00e9quipements de manutention cr\u00e9ent des processus durables et efficaces, qui facilitent \u00e9galement le travail de nos employ\u00e9s \u00bb, d\u00e9crit Frederik Pleick, responsable de la logistique contractuelle chez HEINLOTH, l&rsquo;\u00ab \u00e9tat actuel de la technique \u00bb.<\/span><\/p>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">Gr\u00e2ce \u00e0 ce nouveau b\u00e2timent, HEINLOTH renforce son expansion sur le march\u00e9 de la logistique contractuelle, intensifie les relations commerciales existantes et attire de nouveaux clients. \u00ab La demande en logistique et en stockage avec des services \u00e0 valeur ajout\u00e9e est in\u00e9branlable. Nos capacit\u00e9s actuelles sont presque \u00e9puis\u00e9es \u00bb, explique Frederik Pleick la n\u00e9cessit\u00e9 de ce nouveau b\u00e2timent, qui respecte \u00e9galement les nouvelles r\u00e9glementations de la loi sur la gestion de l&rsquo;eau pour le stockage de biens dangereux pour l&rsquo;eau gr\u00e2ce \u00e0 sa conception.<\/span><\/p>\n<h4 class=\"Default\"><b><span style=\"font-family: 'Cambria',serif\">Construction durable et installation photovolta\u00efque<\/span><\/b><\/h4>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">Un point essentiel \u00e9tait \u00e9galement \u2013 comme pour le nouveau centre logistique \u00e0 Rostock, qui commencera ses op\u00e9rations au d\u00e9but de l&rsquo;ann\u00e9e \u2013 la construction durable. L&rsquo;utilisation d&rsquo;installations photovolta\u00efques et d&rsquo;une gestion intelligente de la maison contribue \u00e0 r\u00e9duire la consommation d&rsquo;\u00e9nergie et \u00e0 une utilisation durable de l&rsquo;espace. \u00c0 ce sujet, Roland Heinloth d\u00e9clare : \u00ab Avec les normes \u00e9lev\u00e9es de protection de l&rsquo;environnement, la certification biologique et la certification IFS pr\u00e9par\u00e9e, nous poursuivons notre chemin de mani\u00e8re coh\u00e9rente. Ainsi, nous montrons que les domaines de la logistique et de la durabilit\u00e9 peuvent aller de pair. \u00bb<\/span><\/p>\n<p class=\"Default\"><span style=\"font-family: 'Cambria',serif\">Photo : \u00a9 Heinloth<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis septembre de l&rsquo;ann\u00e9e derni\u00e8re, les travaux de construction sont en cours, et le fonctionnement doit commencer en septembre 2022 : Un nouveau centre logistique du<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-26653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HEINLOTH construit un centre logistique \u00e0 Roth pr\u00e8s de Nuremberg - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HEINLOTH construit un centre logistique \u00e0 Roth pr\u00e8s de Nuremberg - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Depuis septembre de l&rsquo;ann\u00e9e derni\u00e8re, les travaux de construction sont en cours, et le fonctionnement doit commencer en septembre 2022 : Un nouveau centre logistique du [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-20T15:33:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Heinloth_20.1.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1311\" \/>\n\t<meta property=\"og:image:height\" content=\"755\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"HEINLOTH construit un centre logistique \u00e0 Roth pr\u00e8s de Nuremberg\",\"datePublished\":\"2022-01-20T15:33:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/\"},\"wordCount\":524,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Heinloth_20.1.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/\",\"name\":\"HEINLOTH construit un centre logistique \u00e0 Roth pr\u00e8s de Nuremberg - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Heinloth_20.1.22.jpg\",\"datePublished\":\"2022-01-20T15:33:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Heinloth_20.1.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Heinloth_20.1.22.jpg\",\"width\":1311,\"height\":755},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2022\\\/01\\\/20\\\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HEINLOTH construit un centre logistique \u00e0 Roth pr\u00e8s de Nuremberg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HEINLOTH construit un centre logistique \u00e0 Roth pr\u00e8s de Nuremberg - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/","og_locale":"fr_FR","og_type":"article","og_title":"HEINLOTH construit un centre logistique \u00e0 Roth pr\u00e8s de Nuremberg - Loginfo24.","og_description":"Depuis septembre de l&rsquo;ann\u00e9e derni\u00e8re, les travaux de construction sont en cours, et le fonctionnement doit commencer en septembre 2022 : Un nouveau centre logistique du [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-01-20T15:33:46+00:00","og_image":[{"width":1311,"height":755,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Heinloth_20.1.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/"},"author":{"name":"","@id":""},"headline":"HEINLOTH construit un centre logistique \u00e0 Roth pr\u00e8s de Nuremberg","datePublished":"2022-01-20T15:33:46+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/"},"wordCount":524,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Heinloth_20.1.22.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/","url":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/","name":"HEINLOTH construit un centre logistique \u00e0 Roth pr\u00e8s de Nuremberg - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Heinloth_20.1.22.jpg","datePublished":"2022-01-20T15:33:46+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Heinloth_20.1.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Heinloth_20.1.22.jpg","width":1311,"height":755},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2022\/01\/20\/heinloth-construit-un-centre-logistique-a-roth-pres-de-nuremberg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"HEINLOTH construit un centre logistique \u00e0 Roth pr\u00e8s de Nuremberg"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/26653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=26653"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/26653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/11227"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=26653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=26653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=26653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}