{"id":26153,"date":"2021-12-16T18:44:09","date_gmt":"2021-12-16T17:44:09","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/"},"modified":"2021-12-16T18:44:09","modified_gmt":"2021-12-16T17:44:09","slug":"la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/","title":{"rendered":"La promesse de qualit\u00e9 \u00ab\u00a0Toujours Accessible\u00a0\u00bb de Hapag-Lloyd"},"content":{"rendered":"<h5><strong>Avec l&rsquo;introduction aujourd&rsquo;hui de la neuvi\u00e8me promesse de qualit\u00e9 \u00ab\u00a0Toujours Accessible\u00a0\u00bb, Hapag-Lloyd aborde un facteur cl\u00e9 de la satisfaction client : la rapidit\u00e9 d&rsquo;acc\u00e8s lorsque de l&rsquo;aide est n\u00e9cessaire. Avec des millions d&rsquo;appels chaque ann\u00e9e, Hapag-Lloyd est conscient de l&rsquo;importance d&rsquo;un service t\u00e9l\u00e9phonique fiable et rapide pour maintenir une bonne relation avec sa client\u00e8le.<\/strong><\/h5>\n<p>(Hambourg) Afin d&rsquo;am\u00e9liorer l&rsquo;accessibilit\u00e9 de son service client, l&rsquo;entreprise s&rsquo;est fix\u00e9 l&rsquo;ambitieux objectif de r\u00e9pondre aux appels des clients dans au moins 90 % des cas dans les 12 secondes et d&rsquo;assurer un taux de r\u00e9ponse global de 97 %. Pour atteindre ces objectifs et mesurer leur mise en \u0153uvre, la compagnie maritime introduit progressivement de nouveaux processus et syst\u00e8mes \u00e0 l&rsquo;\u00e9chelle mondiale.<\/p>\n<p>\u00ab\u00a0Chacun d&rsquo;entre nous l&rsquo;a d\u00e9j\u00e0 v\u00e9cu : passer un temps pr\u00e9cieux \u00e0 attendre que l&rsquo;appel soit pris. Surtout dans le monde des affaires, les clients ne peuvent pas se permettre de perdre du temps \u00e0 attendre. Avec la promesse d&rsquo;\u00eatre toujours accessible, nous soulignons notre volont\u00e9 de r\u00e9pondre rapidement aux besoins de notre client\u00e8le\u00a0\u00bb, d\u00e9clare Juan Carlos Duk, Directeur G\u00e9n\u00e9ral du D\u00e9veloppement Commercial Mondial. \u00ab\u00a0Un haut niveau de service client est un aspect important de notre strat\u00e9gie 2023. Lorsque nous r\u00e9pondons rapidement au t\u00e9l\u00e9phone, \u00e9vitons les retards et r\u00e9duisons consid\u00e9rablement le nombre d&rsquo;appels abandonn\u00e9s, c&rsquo;est un grand pas pour am\u00e9liorer l&rsquo;exp\u00e9rience de notre client\u00e8le lors de leurs contacts avec notre service client. Nous nous sentons responsables de respecter leur temps.\u00a0\u00bb<\/p>\n<h5><strong>Standardiser les processus internes<\/strong><\/h5>\n<p>Pour mettre cette promesse en pratique, Hapag-Lloyd a commenc\u00e9 \u00e0 standardiser ses processus internes, \u00e0 r\u00e9organiser les points de contact et \u00e0 introduire un centre de contact unifi\u00e9. Avec un nouveau syst\u00e8me de gestion des cas et un syst\u00e8me t\u00e9l\u00e9phonique moderne, la communication avec la client\u00e8le sera personnalis\u00e9e. \u00c0 l&rsquo;avenir, les clients seront directement connect\u00e9s au bon contact du service client apr\u00e8s avoir saisi un certain code PIN, num\u00e9ro de dossier ou num\u00e9ro d&rsquo;envoi dans le syst\u00e8me. Apr\u00e8s le d\u00e9ploiement mondial, chaque appel devrait \u00eatre trait\u00e9 en quelques secondes. Pour \u00e9viter les incoh\u00e9rences, le syst\u00e8me t\u00e9l\u00e9phonique dans chaque pays disposera des m\u00eames options de menu et fonctions.<\/p>\n<h5><strong>Des aper\u00e7us via le tableau de bord client<\/strong><\/h5>\n<p>Hapag-Lloyd offre des aper\u00e7us des r\u00e9sultats de sa derni\u00e8re promesse de qualit\u00e9 \u00ab\u00a0Toujours Accessible\u00a0\u00bb via son tableau de bord client. Les clients peuvent y consulter les temps de r\u00e9ponse aux appels et le nombre d&rsquo;appels abandonn\u00e9s de la part de Hapag-Lloyd, tant au niveau mondial qu&rsquo;au niveau individuel.<\/p>\n<p>Gr\u00e2ce \u00e0 un service rapide, sur mesure et sp\u00e9cifique au secteur, Hapag-Lloyd souhaite renforcer sa fid\u00e9lisation client et se rapprocher un peu plus de son objectif global de devenir \u00ab\u00a0Num\u00e9ro Un en Qualit\u00e9\u00a0\u00bb.<\/p>\n<p>Photo : \u00a9 Hapag-Lloyd<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec l&rsquo;introduction aujourd&rsquo;hui de la neuvi\u00e8me promesse de qualit\u00e9 \u00ab\u00a0Toujours Accessible\u00a0\u00bb, Hapag-Lloyd aborde un facteur cl\u00e9 de la satisfaction client : la rapidit\u00e9 d&rsquo;acc\u00e8s lorsque de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561,1559],"tags":[],"class_list":["post-26153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La promesse de qualit\u00e9 &quot;Toujours Accessible&quot; de Hapag-Lloyd - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La promesse de qualit\u00e9 &quot;Toujours Accessible&quot; de Hapag-Lloyd - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Avec l&rsquo;introduction aujourd&rsquo;hui de la neuvi\u00e8me promesse de qualit\u00e9 \u00ab\u00a0Toujours Accessible\u00a0\u00bb, Hapag-Lloyd aborde un facteur cl\u00e9 de la satisfaction client : la rapidit\u00e9 d&rsquo;acc\u00e8s lorsque de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-16T17:44:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hapag_Lloyd_16.12.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1493\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La promesse de qualit\u00e9 \u00ab\u00a0Toujours Accessible\u00a0\u00bb de Hapag-Lloyd\",\"datePublished\":\"2021-12-16T17:44:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/\"},\"wordCount\":515,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hapag_Lloyd_16.12.21.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/\",\"name\":\"La promesse de qualit\u00e9 \\\"Toujours Accessible\\\" de Hapag-Lloyd - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hapag_Lloyd_16.12.21.jpg\",\"datePublished\":\"2021-12-16T17:44:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hapag_Lloyd_16.12.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hapag_Lloyd_16.12.21.jpg\",\"width\":1493,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/16\\\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La promesse de qualit\u00e9 &#8222;Toujours Accessible&#8220; de Hapag-Lloyd\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La promesse de qualit\u00e9 \"Toujours Accessible\" de Hapag-Lloyd - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/","og_locale":"fr_FR","og_type":"article","og_title":"La promesse de qualit\u00e9 \"Toujours Accessible\" de Hapag-Lloyd - Loginfo24.","og_description":"Avec l&rsquo;introduction aujourd&rsquo;hui de la neuvi\u00e8me promesse de qualit\u00e9 \u00ab\u00a0Toujours Accessible\u00a0\u00bb, Hapag-Lloyd aborde un facteur cl\u00e9 de la satisfaction client : la rapidit\u00e9 d&rsquo;acc\u00e8s lorsque de [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-12-16T17:44:09+00:00","og_image":[{"width":1493,"height":865,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hapag_Lloyd_16.12.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/"},"author":{"name":"","@id":""},"headline":"La promesse de qualit\u00e9 \u00ab\u00a0Toujours Accessible\u00a0\u00bb de Hapag-Lloyd","datePublished":"2021-12-16T17:44:09+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/"},"wordCount":515,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hapag_Lloyd_16.12.21.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/","url":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/","name":"La promesse de qualit\u00e9 \"Toujours Accessible\" de Hapag-Lloyd - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hapag_Lloyd_16.12.21.jpg","datePublished":"2021-12-16T17:44:09+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hapag_Lloyd_16.12.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hapag_Lloyd_16.12.21.jpg","width":1493,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/16\/la-promesse-de-qualite-toujours-accessible-de-hapag-lloyd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La promesse de qualit\u00e9 &#8222;Toujours Accessible&#8220; de Hapag-Lloyd"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/26153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=26153"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/26153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media\/11448"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=26153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=26153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=26153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}